﻿{"id":15096,"date":"2010-07-29T18:41:45","date_gmt":"2010-07-29T17:41:45","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=15096"},"modified":"2013-04-08T09:30:52","modified_gmt":"2013-04-08T07:30:52","slug":"fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/","title":{"rendered":"Fiocco azzurro per Xin Min Giuseppe: riscoprire il mondo con gli occhi di un bimbo"},"content":{"rendered":"<p>Xin Min Giuseppe \u00e8 uno dei bambini rientrati da poco con Salvatore e Elisabetta in Italia. Dal momento dell\u2019incontro in Cina, negli uffici dell\u2019autorit\u00e0 centrale a Guandong, sono passate poco pi\u00f9 di quattro settimane ma Xin Min Giuseppe sembra che viva con i suoi genitori da sempre.<\/p>\n<p>Ci racconta la storia di adozione la neo-mamma Elisabetta:<\/p>\n<p><strong>Ci parla del vostro primo momento di incontro?<\/strong><\/p>\n<p>E\u2019 stato un momento estremamente emozionante, anche se caotico. Eravamo negli uffici dell\u2019autorit\u00e0 centrale insieme ad altre 24 coppie italiane e americane. Mio marito ed io siamo arrivati qualche minuto prima degli altri e cos\u00ec ci siamo trovati di fronte a questo gruppo ordinato di pi\u00f9 di venti bambini..\u00e8 stato incredibile perch\u00e9 tra tanti pulcini ho capito subito chi era Xin Min Giuseppe, prima ancora che ce lo presentassero. Ho detto a mio marito \u201cL\u2019ho riconosciuto, \u00e8 lui!\u201d e, qualche minuto dopo, l\u2019educatrice si \u00e8 fatta avanti con Xin Min Giuseppe. Incredibile il cambiamento nella sua espressione e in quella di tutti gli altri bambini quando hanno dato il loro primo abbraccio.<\/p>\n<p><strong>Come \u00e8 andato il rientro?<\/strong><\/p>\n<p>Bene, non ci saremmo mai aspettati che un bambino di sei anni si adattasse cos\u00ec velocemente in luoghi totalmente nuovi. E\u2019 un bambino molto sveglio, oltre che affettuoso e solare. Sta imparando in fretta l\u2019italiano e anche se parla ancora poco la lingua riesce a farsi capire perfettamente. Al mare fa subito amicizia con i bambini anche se non conosce bene l\u2019italiano. E\u2019 meraviglioso vedere il mondo attraverso i suoi occhi. Ogni giorno scopre qualcosa di nuovo ed \u00e8 entusiasta per questo, a noi cos\u00ec sembra di riuscire ad apprezzare le cose pi\u00f9 semplici.<\/p>\n<p><strong>Come avete reagito quando \u00e8 stato proposto l\u2019abbinamento di un bambino special need?<\/strong><\/p>\n<p>In realt\u00e0 adottare un bambino con bisogni speciali \u00e8 stata una disponibilit\u00e0 che abbiamo dato fin dal primo momento mio marito ed io. Era una convinzione che abbiamo maturato nel tempo. Quando abbiamo visto Xin Min Giuseppe e abbiamo capito quanti bambini come lui vedono svanire la possibilit\u00e0 di diventare figli solo perch\u00e9 hanno il labbro leporino e non trovano famiglie disposte ad adottarli siamo rimasti profondamente scandalizzati. Pensare che un bambino possa rimanere bloccato in un istituto perch\u00e9 ha il labbro leporino non ci sembra accettabile, ma durante la nostra permanenza in Cina ci siamo resi conti che si crea una sorta di pregiudizio nei confronti di questi bambini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Xin Min Giuseppe \u00e8 uno dei bambini rientrati da poco con Salvatore e Elisabetta in Italia. Dal momento dell\u2019incontro in Cina, negli uffici dell\u2019autorit\u00e0 centrale a Guandong, sono passate poco pi\u00f9 di quattro settimane ma Xin Min Giuseppe sembra che viva con i suoi genitori da sempre.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-15096","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fiocco azzurro per Xin Min Giuseppe: riscoprire il mondo con gli occhi di un bimbo - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiocco azzurro per Xin Min Giuseppe: riscoprire il mondo con gli occhi di un bimbo\" \/>\n<meta property=\"og:description\" content=\"Xin Min Giuseppe \u00e8 uno dei bambini rientrati da poco con Salvatore e Elisabetta in Italia. Dal momento dell\u2019incontro in Cina, negli uffici dell\u2019autorit\u00e0 centrale a Guandong, sono passate poco pi\u00f9 di quattro settimane ma Xin Min Giuseppe sembra che viva con i suoi genitori da sempre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-29T17:41:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-04-08T07:30:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Fiocco azzurro per Xin Min Giuseppe: riscoprire il mondo con gli occhi di un bimbo\",\"datePublished\":\"2010-07-29T17:41:45+00:00\",\"dateModified\":\"2013-04-08T07:30:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\\\/\"},\"wordCount\":413,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\\\/\",\"name\":\"Fiocco azzurro per Xin Min Giuseppe: riscoprire il mondo con gli occhi di un bimbo - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2010-07-29T17:41:45+00:00\",\"dateModified\":\"2013-04-08T07:30:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fiocco azzurro per Xin Min Giuseppe: riscoprire il mondo con gli occhi di un bimbo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fiocco azzurro per Xin Min Giuseppe: riscoprire il mondo con gli occhi di un bimbo - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/","og_locale":"it_IT","og_type":"article","og_title":"Fiocco azzurro per Xin Min Giuseppe: riscoprire il mondo con gli occhi di un bimbo","og_description":"Xin Min Giuseppe \u00e8 uno dei bambini rientrati da poco con Salvatore e Elisabetta in Italia. Dal momento dell\u2019incontro in Cina, negli uffici dell\u2019autorit\u00e0 centrale a Guandong, sono passate poco pi\u00f9 di quattro settimane ma Xin Min Giuseppe sembra che viva con i suoi genitori da sempre.","og_url":"https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-07-29T17:41:45+00:00","article_modified_time":"2013-04-08T07:30:52+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Fiocco azzurro per Xin Min Giuseppe: riscoprire il mondo con gli occhi di un bimbo","datePublished":"2010-07-29T17:41:45+00:00","dateModified":"2013-04-08T07:30:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/"},"wordCount":413,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/","url":"https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/","name":"Fiocco azzurro per Xin Min Giuseppe: riscoprire il mondo con gli occhi di un bimbo - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2010-07-29T17:41:45+00:00","dateModified":"2013-04-08T07:30:52+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/fiocco-azzurro-per-xin-min-giuseppe-riscoprire-il-mondo-con-gli-occhi-di-un-bimbo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Fiocco azzurro per Xin Min Giuseppe: riscoprire il mondo con gli occhi di un bimbo"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:49:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/15096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=15096"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/15096\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=15096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=15096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=15096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}