﻿


{"id":151413,"date":"2018-01-22T17:47:13","date_gmt":"2018-01-22T16:47:13","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=151413"},"modified":"2018-01-22T17:47:13","modified_gmt":"2018-01-22T16:47:13","slug":"adozione-internazionale-affido-familiare-toscana-aibi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/","title":{"rendered":"Adozioni internazionali e affido familiare. Michela Della Porta (Ai.Bi. Firenze): &#8220;per un bambino abbandonato l&#8217;unica risposta \u00e8 la famiglia&#8221;"},"content":{"rendered":"<p><strong>Le adozioni internazionali e l&#8217;affido familiare arrivano negli studi di RTV38 nella voce di Michela Della Porta, responsabile della sede di Ai.Bi. a Firenze<\/strong>. Un\u2019intervista dettagliata sulle cause del drastico crollo dell\u2019adozione che, nel 2017, ha visto diminuire drasticamenteaffido familiareaffido familiare il numero di bambini accolti in famiglia.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/cpjGgqV9thE\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>\u201cEsistono milioni di problematiche: esiste la fame nel mondo, esiste la mancanza di una istruzione, la mancanza di strutture sanitarie adeguate e, in questi casi, il sostegno da parte di enti pubblici o privati, delle politiche governative atte a sistematizzare degli interventi\u00a0 che possono essere la risposta; <strong>nel caso dell\u2019abbandono, l\u2019unica risposta \u00e8 la famiglia\u201d<\/strong> conclude Michela, ricordando <strong>i pi\u00f9 di tremila bambini cui \u00e8 stata restituita una famiglia negli ultimi trent\u2019anni di operato di Ai.Bi. ma ricordando, soprattutto, che l\u2019adozione \u00e8 una cosa meravigliosa!<\/strong><\/p>\n<p>Guarda l&#8217;intervista a questo <a href=\"https:\/\/www.youtube.com\/watch?v=cpjGgqV9thE&amp;feature=youtu.be\"><strong>link\u00a0<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le adozioni internazionali e l&#8217;affido familiare arrivano negli studi di RTV38 nella voce di Michela Della Porta, responsabile della sede di Ai.Bi. a Firenze.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"author":4,"featured_media":151418,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-151413","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni e affido familiare: &quot;per un bambino l&#039;unica risposta \u00e8 famiglia&quot;<\/title>\n<meta name=\"description\" content=\"Le adozioni internazionali e l&#039;affido familiare arrivano negli studi di RTV38 nella voce di Michela Della Porta, responsabile della sede di Ai.Bi. a Firenze.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni internazionali e affido familiare. Michela Della Porta (Ai.Bi. Firenze): &quot;per un bambino abbandonato l&#039;unica risposta \u00e8 la famiglia&quot;\" \/>\n<meta property=\"og:description\" content=\"Le adozioni internazionali e l&#039;affido familiare arrivano negli studi di RTV38 nella voce di Michela Della Porta, responsabile della sede di Ai.Bi. a Firenze.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-22T16:47:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/aibi-firenze.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-affido-familiare-toscana-aibi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-affido-familiare-toscana-aibi\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni internazionali e affido familiare. Michela Della Porta (Ai.Bi. Firenze): &#8220;per un bambino abbandonato l&#8217;unica risposta \u00e8 la famiglia&#8221;\",\"datePublished\":\"2018-01-22T16:47:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-affido-familiare-toscana-aibi\\\/\"},\"wordCount\":164,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-affido-familiare-toscana-aibi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aibi-firenze.png\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-affido-familiare-toscana-aibi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-affido-familiare-toscana-aibi\\\/\",\"name\":\"Adozioni e affido familiare: \\\"per un bambino l'unica risposta \u00e8 famiglia\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-affido-familiare-toscana-aibi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-affido-familiare-toscana-aibi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aibi-firenze.png\",\"datePublished\":\"2018-01-22T16:47:13+00:00\",\"description\":\"Le adozioni internazionali e l'affido familiare arrivano negli studi di RTV38 nella voce di Michela Della Porta, responsabile della sede di Ai.Bi. a Firenze.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-affido-familiare-toscana-aibi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-affido-familiare-toscana-aibi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-affido-familiare-toscana-aibi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aibi-firenze.png\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aibi-firenze.png\",\"width\":1200,\"height\":606,\"caption\":\"aibi firenze adozioni internazionali\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-affido-familiare-toscana-aibi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni internazionali e affido familiare. Michela Della Porta (Ai.Bi. Firenze): &#8220;per un bambino abbandonato l&#8217;unica risposta \u00e8 la famiglia&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni e affido familiare: \"per un bambino l'unica risposta \u00e8 famiglia\"","description":"Le adozioni internazionali e l'affido familiare arrivano negli studi di RTV38 nella voce di Michela Della Porta, responsabile della sede di Ai.Bi. a Firenze.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni internazionali e affido familiare. Michela Della Porta (Ai.Bi. Firenze): \"per un bambino abbandonato l'unica risposta \u00e8 la famiglia\"","og_description":"Le adozioni internazionali e l'affido familiare arrivano negli studi di RTV38 nella voce di Michela Della Porta, responsabile della sede di Ai.Bi. a Firenze.","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2018-01-22T16:47:13+00:00","og_image":[{"width":1200,"height":606,"url":"https:\/\/www.aibi.it\/ita\/images\/aibi-firenze.png","type":"image\/png"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni internazionali e affido familiare. Michela Della Porta (Ai.Bi. Firenze): &#8220;per un bambino abbandonato l&#8217;unica risposta \u00e8 la famiglia&#8221;","datePublished":"2018-01-22T16:47:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/"},"wordCount":164,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aibi-firenze.png","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/","name":"Adozioni e affido familiare: \"per un bambino l'unica risposta \u00e8 famiglia\"","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aibi-firenze.png","datePublished":"2018-01-22T16:47:13+00:00","description":"Le adozioni internazionali e l'affido familiare arrivano negli studi di RTV38 nella voce di Michela Della Porta, responsabile della sede di Ai.Bi. a Firenze.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/aibi-firenze.png","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/aibi-firenze.png","width":1200,"height":606,"caption":"aibi firenze adozioni internazionali"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-affido-familiare-toscana-aibi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"Adozioni internazionali e affido familiare. Michela Della Porta (Ai.Bi. Firenze): &#8220;per un bambino abbandonato l&#8217;unica risposta \u00e8 la famiglia&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:51:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/151413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=151413"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/151413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/151418"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=151413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=151413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=151413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}