﻿


{"id":152634,"date":"2018-02-15T14:51:35","date_gmt":"2018-02-15T13:51:35","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=152634"},"modified":"2018-02-15T14:51:35","modified_gmt":"2018-02-15T13:51:35","slug":"adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/","title":{"rendered":"Adozione internazionale. Ecco gli impegni programmatici di Berlusconi, Di Maio e Renzi per il rilancio della adozione"},"content":{"rendered":"<h2><b>Il periodico <em>Vita<\/em> ha posto ai tre leader dei principali partiti, in vista delle elezioni del 4 marzo, una domanda chiara sul futuro delle adozioni internazionali in base ai rispettivi programmi politici, alla luce della grave crisi che ha caratterizzato le adozioni negli ultimi anni<\/b><\/h2>\n<h3><b>Berlusconi punta il dito sul &#8220;<em>malfunzionamento della CAI<\/em>&#8221; e sull&#8217;urgenza di &#8220;<em>sbloccare il pagamento dei rimborsi<\/em>&#8220;, per Di Maio &#8220;<em>la normativa va modificata<\/em>&#8221; con il passaggio della CAI &#8220;<em>alle dipendenze della Farnesina<\/em>&#8221; e la creazione di &#8220;<em>un unico data base nazionale dei bambini adottabili<\/em>&#8220;; Renzi ricorda la creazione e l&#8217;aumento del Fondo per le adozioni e chiede una &#8220;<em>modifica legislativa<\/em>&#8221; per l&#8217;adozione nazionale<\/b><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-152640\" src=\"https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460-457x300.jpg\" alt=\"la voce di Berlusconi, Di Maio e Renzi sul futuro dell'adozione internazionale\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>Mentre <strong>20 Enti Autorizzati incontrano le forze politiche<\/strong> <strong>al Senato<\/strong> per <strong>chiedere a gran voce il rilancio concreto dell&#8217;adozione internazionale<\/strong> superando l&#8217;emergenza attuale attraverso l&#8217;attivazione urgente di un<strong> bonus adozione da 10mila euro per ogni bambino straniero che entra in Italia<\/strong> attraverso il meccanismo adottivo, il periodico <strong><em>Vita<\/em> pubblica le risposte che i leader dei tre principali partiti in lizza<\/strong> alle elezioni del prossimo 4 marzo hanno fornito rispetto al tema, in base ai rispettivi programmi di governo.<\/p>\n<p>La domanda relativa al futuro dell&#8217;adozione internazionale, in particolare, era questa: &#8220;<em><strong>Negli ultimi cinque anni le adozioni internazionali hanno vissuto una crisi notevole<\/strong>. In Italia nel 2015, ultimo dato disponibile, sono stati adottati 2.216 bambini, circa la met\u00e0 rispetto ai 4.130 entrati nel 2010. Sul fronte nazionale le cose non vanno meglio, nel 2016 sono state presentate 8.305 domande di disponibilit\u00e0 all\u2019adozione nazionale, la met\u00e0 rispetto al 2006. <strong>Come intervenire?<\/strong><\/em>&#8220;.<\/p>\n<p>Ecco le risposte che <strong>Silvio Berlusconi<\/strong> (Forza Italia), <strong>Luigi Di Maio<\/strong> (Movimento 5 Stelle) e <strong>Matteo Renzi<\/strong> (Partito Democratico) hanno fornito.<\/p>\n<p>Per <strong>Silvio Berlusconi <\/strong>in questa legislatura &#8220;<em>il mal funzionamento della CAI che di fatto per lunghi anni ha bloccato i propri lavori, ha allontanato le famiglie italiane dalle adozioni. Tornati al governo, vigileremo che la nuova conduzione della CAI sia finalmente all\u2019altezza<\/em>&#8220;. Concretamente, il leader di Forza Italia parla poi di &#8220;<em>sbloccare il pagamento dei rimborsi<\/em>&#8221; e &#8220;<em>ragionare su come portare in detrazione almeno una parte delle spese<\/em>&#8220;. Lunga e articolata la risposta di <strong>Luigi Di Maio<\/strong>, secondo cui &#8220;<em>la normativa va modificata<\/em>&#8220;: il candidato pentastellato chiede in particolare che &#8220;<em>la CAI passi alle dipendenze della Fanersina e che le nostre ambasciate si dotino \u2013 soprattutto nei paesi dove pi\u00f9 numerose sono le domande di adozione \u2013 di una figura specifica<\/em>&#8220;. Sulle adozioni nazionali, &#8220;<em>non c\u2019\u00e8 dubbio che la prima cosa da fare sia creare un unico data base nazionale dei bambini adottabili<\/em>&#8220;. Infine, il Pd con <strong>Matteo Renzi<\/strong>, che ricorda la creazione e l\u2019aumento a 25 milioni del Fondo per le adozioni internazionali e aggiunge che &#8220;l<em>a CAI pu\u00f2 finalmente superare le difficolt\u00e0 del passato e ha avuto risorse maggiori, stabili e sicure<\/em>&#8220;. Per l\u2019adozione nazionale sottolinea che &#8220;<em>\u00e8 maturo il tempo per una modifica legislativa che ci metta davanti alla realt\u00e0, che \u00e8 ben diversa rispetto a quella della normativa precedente<\/em>&#8220;.<\/p>\n<p><strong>Fonte: <a href=\"http:\/\/www.vita.it\/it\/article\/2018\/02\/15\/come-cambieremo-le-adozioni-gli-impegni-dei-tre-leader\/145972\/\" target=\"_blank\" rel=\"noopener\">Vita.it<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il periodico Vita ha posto ai tre leader dei principali partiti, in vista delle elezioni del 4 marzo, una domanda chiara sul futuro delle adozioni internazionali in base ai rispettivi programmi politici, alla luce della grave crisi che ha caratterizzato le adozioni negli ultimi anni Berlusconi punta il dito sul [&hellip;]<\/p>\n","protected":false},"author":83,"featured_media":152640,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-152634","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione internazionale. Ecco gli impegni programmatici di Berlusconi, Di Maio e Renzi per il rilancio della adozione<\/title>\n<meta name=\"description\" content=\"Adozione internazionale, quali interventi per uscire dalla crisi? La risposta dai 3 leader dei principali partiti in vista delle elezioni del 4 marzo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione internazionale. Ecco gli impegni programmatici di Berlusconi, Di Maio e Renzi per il rilancio della adozione\" \/>\n<meta property=\"og:description\" content=\"Adozione internazionale, quali interventi per uscire dalla crisi? La risposta dai 3 leader dei principali partiti in vista delle elezioni del 4 marzo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-15T13:51:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\\\/\"},\"author\":{\"name\":\"francescoM\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/d5f95c80d81b6d6ff3b13256e4009e8e\"},\"headline\":\"Adozione internazionale. Ecco gli impegni programmatici di Berlusconi, Di Maio e Renzi per il rilancio della adozione\",\"datePublished\":\"2018-02-15T13:51:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\\\/\"},\"wordCount\":505,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-politica_700X460.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\\\/\",\"name\":\"Adozione internazionale. Ecco gli impegni programmatici di Berlusconi, Di Maio e Renzi per il rilancio della adozione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-politica_700X460.jpg\",\"datePublished\":\"2018-02-15T13:51:35+00:00\",\"description\":\"Adozione internazionale, quali interventi per uscire dalla crisi? La risposta dai 3 leader dei principali partiti in vista delle elezioni del 4 marzo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-politica_700X460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-politica_700X460.jpg\",\"width\":700,\"height\":460,\"caption\":\"la voce di Berlusconi, Di Maio e Renzi sul futuro dell'adozione internazionale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione internazionale. Ecco gli impegni programmatici di Berlusconi, Di Maio e Renzi per il rilancio della adozione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/d5f95c80d81b6d6ff3b13256e4009e8e\",\"name\":\"francescoM\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescom\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione internazionale. Ecco gli impegni programmatici di Berlusconi, Di Maio e Renzi per il rilancio della adozione","description":"Adozione internazionale, quali interventi per uscire dalla crisi? La risposta dai 3 leader dei principali partiti in vista delle elezioni del 4 marzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione internazionale. Ecco gli impegni programmatici di Berlusconi, Di Maio e Renzi per il rilancio della adozione","og_description":"Adozione internazionale, quali interventi per uscire dalla crisi? La risposta dai 3 leader dei principali partiti in vista delle elezioni del 4 marzo","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2018-02-15T13:51:35+00:00","og_image":[{"width":700,"height":460,"url":"https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460.jpg","type":"image\/jpeg"}],"author":"francescoM","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoM","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/"},"author":{"name":"francescoM","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/d5f95c80d81b6d6ff3b13256e4009e8e"},"headline":"Adozione internazionale. Ecco gli impegni programmatici di Berlusconi, Di Maio e Renzi per il rilancio della adozione","datePublished":"2018-02-15T13:51:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/"},"wordCount":505,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/","name":"Adozione internazionale. Ecco gli impegni programmatici di Berlusconi, Di Maio e Renzi per il rilancio della adozione","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460.jpg","datePublished":"2018-02-15T13:51:35+00:00","description":"Adozione internazionale, quali interventi per uscire dalla crisi? La risposta dai 3 leader dei principali partiti in vista delle elezioni del 4 marzo","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-politica_700X460.jpg","width":700,"height":460,"caption":"la voce di Berlusconi, Di Maio e Renzi sul futuro dell'adozione internazionale"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-gli-impegni-programmatici-berlusconi-maio-renzi-rilancio-della-adozione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozione internazionale. Ecco gli impegni programmatici di Berlusconi, Di Maio e Renzi per il rilancio della adozione"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/d5f95c80d81b6d6ff3b13256e4009e8e","name":"francescoM","url":"https:\/\/www.aibi.it\/ita\/author\/francescom\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:45:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/152634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=152634"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/152634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/152640"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=152634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=152634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=152634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}