﻿


{"id":155383,"date":"2018-05-10T12:49:40","date_gmt":"2018-05-10T10:49:40","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=155383"},"modified":"2018-05-10T12:49:40","modified_gmt":"2018-05-10T10:49:40","slug":"milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/","title":{"rendered":"Milano. \u201cAdozione una cosa meravigliosa: vi presentiamo l\u2019officina dei miracoli\u201d: comincia il Tour nazionale dell\u2019accoglienza!"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p><strong>Comincia oggi a Milano, 10 maggio 2018, il tour nazionale di sensibilizzazione e promozione dell\u2019adozione internazionale: \u201c<a href=\"https:\/\/www.aibi.it\/ita\/images\/locandina-acm-milano.pdf\">L\u2019adozione \u00e8 una cosa meravigliosa: vi presentiamo l\u2019officina dei miracoli<\/a><\/strong>!\u201d.<br \/>\nToccher\u00e0 10 tappe in tutta Italia, cominciando con il capoluogo Lombardo, il tour che fa conoscere la bellezza alle coppie e alle famiglie italiane e a chiunque abbia nel cuore il desiderio di adottare un minore senza famiglia.<\/p>\n<p><strong><a href=\"https:\/\/www.aibi.it\/lp\/officina-miracoli\/\">Iscriviti gratuitamente<\/a><\/strong> ad una delle tappe del tour: vieni anche tu a conoscere l\u2019officina dei miracoli!<\/p>\n<a href=\"#\"class=\"wpz-sc-button large\" style=\";background:#0f95fc\"><span><i class=\"fa fa-check-square-o\" style=\"padding-right:6px;\"><\/i>ISCRIVITI gratuitamente<\/span><\/a>[\/box][\/vc_column_text][\/vc_column][\/vc_row]\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-155223 aligncenter\" src=\"https:\/\/www.aibi.it\/ita\/images\/adozione-cosa-meravigliosa_fb-571x300.jpg\" alt=\"adozione, una cosa meravigliosa! Dal 10 maggio il tour nazionale 2018 di Ai.Bi. per promuovere l'adozione internazionale\" width=\"712\" height=\"374\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/adozione-cosa-meravigliosa_fb-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/adozione-cosa-meravigliosa_fb-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/adozione-cosa-meravigliosa_fb-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/adozione-cosa-meravigliosa_fb.jpg 1200w, https:\/\/www.aibi.it\/ita\/images\/adozione-cosa-meravigliosa_fb-105x55.jpg 105w\" sizes=\"auto, (max-width: 712px) 100vw, 712px\" \/><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Comincia oggi a Milano, 10 maggio 2018, il tour nazionale di sensibilizzazione e promozione dell&rsquo;adozione internazionale: &ldquo;L&rsquo;adozione &egrave; una cosa meravigliosa: vi presentiamo l&rsquo;officina dei miracoli!&rdquo;. Toccher&agrave; 10 tappe in tutta Italia, cominciando con il capoluogo Lombardo, il tour che fa conoscere la bellezza alle coppie e alle famiglie italiane [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":155222,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-155383","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Milano. \u201cAdozione una cosa meravigliosa: vi presentiamo l\u2019officina dei miracoli\u201d: Tour nazionale dell\u2019accoglienza!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milano. \u201cAdozione una cosa meravigliosa: vi presentiamo l\u2019officina dei miracoli\u201d: comincia il Tour nazionale dell\u2019accoglienza!\" \/>\n<meta property=\"og:description\" content=\"Comincia oggi a Milano, 10 maggio 2018, il tour nazionale di sensibilizzazione e promozione dell&rsquo;adozione internazionale: &ldquo;L&rsquo;adozione &egrave; una cosa meravigliosa: vi presentiamo l&rsquo;officina dei miracoli!&rdquo;. Toccher&agrave; 10 tappe in tutta Italia, cominciando con il capoluogo Lombardo, il tour che fa conoscere la bellezza alle coppie e alle famiglie italiane [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-10T10:49:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/adozione-cosa-meravigliosa_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Milano. \u201cAdozione una cosa meravigliosa: vi presentiamo l\u2019officina dei miracoli\u201d: comincia il Tour nazionale dell\u2019accoglienza!\",\"datePublished\":\"2018-05-10T10:49:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\\\/\"},\"wordCount\":124,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-cosa-meravigliosa_700X460.jpg\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\\\/\",\"name\":\"Milano. \u201cAdozione una cosa meravigliosa: vi presentiamo l\u2019officina dei miracoli\u201d: Tour nazionale dell\u2019accoglienza!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-cosa-meravigliosa_700X460.jpg\",\"datePublished\":\"2018-05-10T10:49:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-cosa-meravigliosa_700X460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-cosa-meravigliosa_700X460.jpg\",\"width\":700,\"height\":460,\"caption\":\"adozione internazionale, una cosa meravigliosa! Dal 10 maggio il tour nazionale 2018 di Ai.Bi. per promuovere l'adozione internazionale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Milano. \u201cAdozione una cosa meravigliosa: vi presentiamo l\u2019officina dei miracoli\u201d: comincia il Tour nazionale dell\u2019accoglienza!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Milano. \u201cAdozione una cosa meravigliosa: vi presentiamo l\u2019officina dei miracoli\u201d: Tour nazionale dell\u2019accoglienza!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/","og_locale":"it_IT","og_type":"article","og_title":"Milano. \u201cAdozione una cosa meravigliosa: vi presentiamo l\u2019officina dei miracoli\u201d: comincia il Tour nazionale dell\u2019accoglienza!","og_description":"Comincia oggi a Milano, 10 maggio 2018, il tour nazionale di sensibilizzazione e promozione dell&rsquo;adozione internazionale: &ldquo;L&rsquo;adozione &egrave; una cosa meravigliosa: vi presentiamo l&rsquo;officina dei miracoli!&rdquo;. Toccher&agrave; 10 tappe in tutta Italia, cominciando con il capoluogo Lombardo, il tour che fa conoscere la bellezza alle coppie e alle famiglie italiane [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2018-05-10T10:49:40+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/adozione-cosa-meravigliosa_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Milano. \u201cAdozione una cosa meravigliosa: vi presentiamo l\u2019officina dei miracoli\u201d: comincia il Tour nazionale dell\u2019accoglienza!","datePublished":"2018-05-10T10:49:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/"},"wordCount":124,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-cosa-meravigliosa_700X460.jpg","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/","url":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/","name":"Milano. \u201cAdozione una cosa meravigliosa: vi presentiamo l\u2019officina dei miracoli\u201d: Tour nazionale dell\u2019accoglienza!","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-cosa-meravigliosa_700X460.jpg","datePublished":"2018-05-10T10:49:40+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/adozione-cosa-meravigliosa_700X460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-cosa-meravigliosa_700X460.jpg","width":700,"height":460,"caption":"adozione internazionale, una cosa meravigliosa! Dal 10 maggio il tour nazionale 2018 di Ai.Bi. per promuovere l'adozione internazionale"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/milano-tour-adozione-una-cosa-meravigliosa-officina-dei-miracoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"Milano. \u201cAdozione una cosa meravigliosa: vi presentiamo l\u2019officina dei miracoli\u201d: comincia il Tour nazionale dell\u2019accoglienza!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:56:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/155383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=155383"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/155383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/155222"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=155383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=155383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=155383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}