﻿


{"id":155632,"date":"2018-05-21T16:41:06","date_gmt":"2018-05-21T14:41:06","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=155632"},"modified":"2018-05-21T16:41:06","modified_gmt":"2018-05-21T14:41:06","slug":"rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/","title":{"rendered":"RDC. Con la corsa nei sacchi, si lascia l\u2019abbandono nella polvere e si ride insieme"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-155634 aligncenter\" src=\"https:\/\/www.aibi.it\/ita\/images\/aggiornamenti-congo-adozione-a-distanza1200x630.jpg\" alt=\"\" width=\"1200\" height=\"630\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/aggiornamenti-congo-adozione-a-distanza1200x630.jpg 1200w, https:\/\/www.aibi.it\/ita\/images\/aggiornamenti-congo-adozione-a-distanza1200x630-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/aggiornamenti-congo-adozione-a-distanza1200x630-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/aggiornamenti-congo-adozione-a-distanza1200x630-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/aggiornamenti-congo-adozione-a-distanza1200x630-105x55.jpg 105w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Un pomeriggio di divertimenti e risate, per i bambini ospiti del <a href=\"https:\/\/www.aibi.it\/adozioneadistanza\/congo\/\">centro Fed sostenuto da Ai.Bi. a Goma, in Repubblica Democratica del Congo<\/a>.<br \/>\n<strong>Grazie al contributo dei sostenitori, \u00e8 stato possibile organizzare un pomeriggio ricreativo, divertente e pieno di sorprese per tutti i bambini\u00a0!<br \/>\n<\/strong> <strong>Pronti, partenza\u2026. Via\u00a0!<br \/>\nLa corsa nei sacchi \u00e8 stata un successone e ha scatenato grasse risate nell\u2019arco dell\u2019intera giornata.<\/strong> Purtroppo, i fondi per organizzare queste attivit\u00e0 sono pochissime e il personale non ha abbastanza tempo per organizzarle, a causa di altre priorit\u00e0 che spesso scavalcano il divertimento\u00a0!<br \/>\nPer questo, <strong>abbiamo bisogno del tuo aiuto\u00a0: solo cos\u00ec, ogni giorno, potr\u00e0 nascere un nuovo sorriso<\/strong>.<\/p>\n<p><a href=\"https:\/\/www.aibi.it\/adozioneadistanza\/congo\/\">Attiva un\u2019Adozione a Distanza in Congo<\/a>.<\/p>\n[btnsx_dual id=&#8221;148460&#8243; css_inline=&#8221;1&#8243;]\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Un pomeriggio di divertimenti e risate, per i bambini ospiti del centro Fed sostenuto da Ai.Bi. a Goma, in Repubblica Democratica del Congo. Grazie al contributo dei sostenitori, &egrave; stato possibile organizzare un pomeriggio ricreativo, divertente e pieno di sorprese per tutti i bambini&nbsp;! Pronti, partenza&hellip;. Via&nbsp;! La corsa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":155634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-155632","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>RDC. Con la corsa nei sacchi, si lascia l\u2019abbandono nella polvere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RDC. Con la corsa nei sacchi, si lascia l\u2019abbandono nella polvere e si ride insieme\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Un pomeriggio di divertimenti e risate, per i bambini ospiti del centro Fed sostenuto da Ai.Bi. a Goma, in Repubblica Democratica del Congo. Grazie al contributo dei sostenitori, &egrave; stato possibile organizzare un pomeriggio ricreativo, divertente e pieno di sorprese per tutti i bambini&nbsp;! Pronti, partenza&hellip;. Via&nbsp;! La corsa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-21T14:41:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/aggiornamenti-congo-adozione-a-distanza1200x630.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"RDC. Con la corsa nei sacchi, si lascia l\u2019abbandono nella polvere e si ride insieme\",\"datePublished\":\"2018-05-21T14:41:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\\\/\"},\"wordCount\":139,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aggiornamenti-congo-adozione-a-distanza1200x630.jpg\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\\\/\",\"name\":\"RDC. Con la corsa nei sacchi, si lascia l\u2019abbandono nella polvere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aggiornamenti-congo-adozione-a-distanza1200x630.jpg\",\"datePublished\":\"2018-05-21T14:41:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aggiornamenti-congo-adozione-a-distanza1200x630.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aggiornamenti-congo-adozione-a-distanza1200x630.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RDC. Con la corsa nei sacchi, si lascia l\u2019abbandono nella polvere e si ride insieme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"RDC. Con la corsa nei sacchi, si lascia l\u2019abbandono nella polvere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/","og_locale":"it_IT","og_type":"article","og_title":"RDC. Con la corsa nei sacchi, si lascia l\u2019abbandono nella polvere e si ride insieme","og_description":"&nbsp; Un pomeriggio di divertimenti e risate, per i bambini ospiti del centro Fed sostenuto da Ai.Bi. a Goma, in Repubblica Democratica del Congo. Grazie al contributo dei sostenitori, &egrave; stato possibile organizzare un pomeriggio ricreativo, divertente e pieno di sorprese per tutti i bambini&nbsp;! Pronti, partenza&hellip;. Via&nbsp;! La corsa [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2018-05-21T14:41:06+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/aggiornamenti-congo-adozione-a-distanza1200x630.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"RDC. Con la corsa nei sacchi, si lascia l\u2019abbandono nella polvere e si ride insieme","datePublished":"2018-05-21T14:41:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/"},"wordCount":139,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aggiornamenti-congo-adozione-a-distanza1200x630.jpg","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/","url":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/","name":"RDC. Con la corsa nei sacchi, si lascia l\u2019abbandono nella polvere","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aggiornamenti-congo-adozione-a-distanza1200x630.jpg","datePublished":"2018-05-21T14:41:06+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/aggiornamenti-congo-adozione-a-distanza1200x630.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/aggiornamenti-congo-adozione-a-distanza1200x630.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/rdc-con-la-corsa-nei-sacchi-si-lascia-labbandono-nella-polvere-e-si-ride-insieme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"RDC. Con la corsa nei sacchi, si lascia l\u2019abbandono nella polvere e si ride insieme"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:57:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/155632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=155632"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/155632\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/155634"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=155632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=155632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=155632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}