﻿


{"id":15574,"date":"2010-09-03T17:38:02","date_gmt":"2010-09-03T16:38:02","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=15574"},"modified":"2010-09-03T17:38:02","modified_gmt":"2010-09-03T16:38:02","slug":"colombia-i-risultati-dellintermediazione-al-lavoro","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/","title":{"rendered":"Colombia: i risultati dell&#8217;intermediazione al lavoro"},"content":{"rendered":"<p>Le attivit\u00e0 di intermediazione al lavoro previste nel progetto finanziato dalla Conferenza Episcopale Italiana e la Fondazione Cariplo, prevedevano una strategia che avrebbe potuto dare un ottimo risultato per molti beneficiari. Tuttavia, la realta\u2019 sia dei ragazzi, che non hanno una preparazione accademica adeguata, sia degli imprenditori che non erano disposti ad essere coinvolti in attivit\u00e0 di reinserimento lavorativo, ha fatto si che i risultati del primo anno di progetto non siano stati soddisfascenti.<\/p>\n<p>Davanti a questo risultato, l\u2019equipe psicosociale \u00e8 stata costretta a modificare la strategia giungendo a risultati soddisfacenti.<\/p>\n<p>In questo momento abbiamo un gruppo di 15 ragazzi\/e che stanno lavorando i cui ottimi risultati sono stati rilevati dagli imprenditori. Questo gruppo di ragazzi lavora ormai da tre mesi in diverse aziende. I beneficiari del progetto si sono distinti per essere dei lavoratori seri ed affidabili al punto che altre imprese hanno chiesto di poter lavorare con altri ragazzi del progetto. I 15 beneficiari sono sempre seguiti dall\u2019equipe psicosociale per garantire un inserimento efficace nelle societ\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le attivit&agrave; di intermediazione al lavoro previste nel progetto finanziato dalla Conferenza Episcopale Italiana e la Fondazione Cariplo, prevedevano una strategia che avrebbe potuto dare un ottimo risultato per molti beneficiari. Tuttavia, la realta&rsquo; sia dei ragazzi, che non hanno una preparazione accademica adeguata, sia degli imprenditori che non erano [&hellip;]<\/p>\n","protected":false},"author":78,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-15574","post","type-post","status-publish","format-standard","category-cooperazione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Colombia: i risultati dell&#039;intermediazione al lavoro - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colombia: i risultati dell&#039;intermediazione al lavoro\" \/>\n<meta property=\"og:description\" content=\"Le attivit&agrave; di intermediazione al lavoro previste nel progetto finanziato dalla Conferenza Episcopale Italiana e la Fondazione Cariplo, prevedevano una strategia che avrebbe potuto dare un ottimo risultato per molti beneficiari. Tuttavia, la realta&rsquo; sia dei ragazzi, che non hanno una preparazione accademica adeguata, sia degli imprenditori che non erano [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-03T16:38:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/colombia-i-risultati-dellintermediazione-al-lavoro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/colombia-i-risultati-dellintermediazione-al-lavoro\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/62a70a45489f2c0e66a23f8e5c904471\"},\"headline\":\"Colombia: i risultati dell&#8217;intermediazione al lavoro\",\"datePublished\":\"2010-09-03T16:38:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/colombia-i-risultati-dellintermediazione-al-lavoro\\\/\"},\"wordCount\":175,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/colombia-i-risultati-dellintermediazione-al-lavoro\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/colombia-i-risultati-dellintermediazione-al-lavoro\\\/\",\"name\":\"Colombia: i risultati dell'intermediazione al lavoro - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2010-09-03T16:38:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/colombia-i-risultati-dellintermediazione-al-lavoro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/colombia-i-risultati-dellintermediazione-al-lavoro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/colombia-i-risultati-dellintermediazione-al-lavoro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Colombia: i risultati dell&#8217;intermediazione al lavoro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/62a70a45489f2c0e66a23f8e5c904471\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/adozione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Colombia: i risultati dell'intermediazione al lavoro - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/","og_locale":"it_IT","og_type":"article","og_title":"Colombia: i risultati dell'intermediazione al lavoro","og_description":"Le attivit&agrave; di intermediazione al lavoro previste nel progetto finanziato dalla Conferenza Episcopale Italiana e la Fondazione Cariplo, prevedevano una strategia che avrebbe potuto dare un ottimo risultato per molti beneficiari. Tuttavia, la realta&rsquo; sia dei ragazzi, che non hanno una preparazione accademica adeguata, sia degli imprenditori che non erano [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-09-03T16:38:02+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/62a70a45489f2c0e66a23f8e5c904471"},"headline":"Colombia: i risultati dell&#8217;intermediazione al lavoro","datePublished":"2010-09-03T16:38:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/"},"wordCount":175,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/","url":"https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/","name":"Colombia: i risultati dell'intermediazione al lavoro - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2010-09-03T16:38:02+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/colombia-i-risultati-dellintermediazione-al-lavoro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Colombia: i risultati dell&#8217;intermediazione al lavoro"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/62a70a45489f2c0e66a23f8e5c904471","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/adozione\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:15:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/15574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/78"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=15574"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/15574\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=15574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=15574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=15574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}