﻿


{"id":156005,"date":"2018-06-01T18:15:57","date_gmt":"2018-06-01T16:15:57","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=156005"},"modified":"2018-06-01T19:43:04","modified_gmt":"2018-06-01T17:43:04","slug":"crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/","title":{"rendered":"Come rimediare al crollo delle adozioni internazionali? Il nuovo governo non ripeta gli errori di Riccardi, Kyenge e soprattutto Renzi"},"content":{"rendered":"<h2>\u00a0A livello mondiale dal 2004 al 2016 le adozioni internazionali sono calate quasi dell&#8217;80%. Pur non facendo eccezione, rispetto al resto del pianeta\u00a0il nostro Bel Paese <strong>sembra tenere meglio \u2018botta\u2019<\/strong> registrando un calo\u00a0<strong>del 55%<\/strong> e dimostrando \u2013 dati alla mano &#8211; di essere ancora il <strong>Paese pi\u00f9 accogliente<\/strong>. <b>Nonostante ci\u00f2 la crisi delle adozioni internazionali in Italia \u00e8 un fatto reale e tutt&#8217;altro che superato. Cosa \u00e8 realmente accaduto? Cosa far\u00e0 il nuovo Governo?<\/b><\/h2>\n<h3>In tutto il pianeta dal 2004 al 2016 le adozioni internazionali sono calate quasi dell&#8217;80% mentre in Italia del 55%. Le famiglie italiane si distinguono cos\u00ec per essere \u2013 nonostante la crisi mondiale dell\u2019adozione &#8211; \u00a0le pi\u00f9 accoglienti e custodi di un\u2019attitudine familiare tutta italiana verso l\u2019adozione internazionale nonostante l\u2019assenza di politiche familiari di sostegno alla scelta adottiva.<\/h3>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-156006\" src=\"https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/><\/strong><\/p>\n<p><strong><u>Le famiglie italiane sono le pi\u00f9 accoglienti <\/u><\/strong><\/p>\n<p>Come non essere d\u2019accordo con l\u2019attenta disamina di Luciano Moia in <a href=\"https:\/\/www.avvenire.it\/opinioni\/pagine\/il-mondo-non-adotta-pi-solo-litalia-a-braccia-aperte\">un articolo pubblicato qualche giorno fa su\u00a0<em>Avvenire<\/em><\/a>. I dati lo dimostrano.<\/p>\n<p>Se per tutti gli altri Paesi quali USA, Francia e\u00a0 Spagna &#8211;\u00a0 per limitarci a quelli che da sempre fanno pi\u00f9 adozioni internazionali &#8211; la crisi \u00e8 iniziata nel 2006, l\u2019Italia proprio in quell&#8217;anno saliva la china con dati dal 2006 in poi sempre in costante crescita fino al <strong>2010<\/strong>,\u00a0 l\u2019anno pi\u00f9 fecondo con <strong>4.130 <\/strong>bambiniadottati (<em>fonte: Commissione Adozioni Internazionali<\/em>).<\/p>\n<p>Le coppie italiane non solo sono le pi\u00f9 accoglienti ma si vedono\u00a0 genitori di bambini grandi, fratrie allargate e minori con bisogni sanitari e patologie di varia natura,<strong>\u00a0 <\/strong>non di rado \u2018scartati\u2019 da altri Paesi europei che godono di politiche familiari di certo pi\u00f9 strutturate.<\/p>\n<p>Nonostante le coppie italiane siano \u2013 dati alla mano &#8211; le pi\u00f9 accoglienti, la crisi delle adozioni internazionali in Italia \u00e8 un fatto reale e tutt&#8217;altro che superato. <strong>Cerchiamo di comprenderne le cause.<\/strong><\/p>\n<p><strong><u>Il 2012, l\u2019inizio della crisi<\/u><\/strong><\/p>\n<p>Se le famiglie italiane sono le pi\u00f9 accoglienti, <strong>perch\u00e9 dal 2012 ha avuto inizio una progressiva caduta libera delle adozioni internazionali con 3.106 minori adottati rispetto i 4.014 dell\u2019anno prima<\/strong>? Non c\u2019erano pi\u00f9 famiglie italiane desiderose d\u2019incontrare i loro figli adottivi? Tutt&#8217;altro!<\/p>\n<p>La causa di questo inspiegabile \u201cdefault\u201d delle adozioni internazionali\u00a0 risiede nel fatto che la macchina politica della Commissione per le adozioni internazionali \u00a0&#8211;\u00a0\u00a0 vero motore del sistema adozione internazionale \u2013 ha smesso di funzionare.<strong>\u00a0<\/strong><\/p>\n<p><strong><u>C\u2019era una volta una politica per le adozioni internazionali \u2026<\/u><\/strong><\/p>\n<p>Una macchina politica delle adozioni \u2013 la Commissione &#8211;\u00a0 in realt\u00e0 esisteva e negli anni &#8220;belli&#8221;,\u00a0 prima con il Ministro Bindi, poi con il sottosegretario Carlo Giovanardi, entrambi alla presidenza della Commissione, funzionava a meraviglia. Governi, questi, che credevano nell\u2019adozione internazionale,\u00a0 nell\u2019importanza delle missioni all&#8217;estero guidate dagli stessi presidenti,\u00a0\u00a0nell\u2019accoglienza delle delegazioni delle autorit\u00e0 centrali straniere, nei tavoli e incontri di coordinamento con gli enti adottivi e nell\u2019apertura di sempre nuovi Paesi.<\/p>\n<p><strong>Il risultato di questo impegno \u201cpolitico\u201d \u00e8 stato il fiorire di nuovi accordi bilaterali con i Paesi di adozione<\/strong> come\u00a0 &#8211; solo per citarne alcuni \u2013 la Federazione Russa, la Bolivia, il Per\u00f9, la Cambogia e il Vietnam. Non tutti sanno, infatti,\u00a0 che l&#8217;Italia \u00e8 il Paese che in assoluto vanta il maggior numero di accordi bilaterali con i Paese di provenienza dei minori adottati.<\/p>\n<p><strong>Cosa \u00e8 successo? Come si spiega il baratro delle adozioni internazionale di questi anni raggiungendo il suo apice nel 2017 con 1.439 bambini adottati.<\/strong><\/p>\n<p><strong><u>L\u2019avvento dei Governi Tecnici e l\u2019immobilismo della CAI<\/u><\/strong><\/p>\n<p>Con l&#8217;avvento dei\u00a0Governi tecnici, <strong>l&#8217;adozione internazionale \u00e8 stata relegata in fondo all\u2019agenda politica<\/strong> delle istituzioni preposte alla famiglia.<\/p>\n<p>Disastrosa la gestione del <strong>Ministro Riccardi<\/strong>. Nei due anni di presidenza della Commissione per le Adozioni Internazionali si ricorda una sola riunione di commissione, nessuna missione all&#8217; estero e nessun nuovo accordo. Poi l&#8217;avvento del <strong>Ministro Kyenge<\/strong>, rimasto pochi mesi alla presidenza CAI\u00a0\u00a0e invischiato nella difficile gestione del blocco delle adozioni in Repubblica Democratica del Congo, senza il supporto di un Vicepresidente. Al termine del mandato della vicepresidente alla Commissione &#8211; la <strong>dott.ssa Bacchetta<\/strong> &#8211;\u00a0 nel novembre 2013,\u00a0 nessuno Governo si era, infatti, preoccupato di procedere con una nuova nomina.<\/p>\n<p><strong><u>Gli anni bui della CAI. Il danno \u00e8 fatto.<\/u><\/strong><\/p>\n<p>E poi &#8211; dulcis in fundo- i tre anni \u201cdisgraziati\u201d della <strong>gestione Renzi<\/strong>, dove l&#8217; adozione internazionale, eretta\u00a0a \u201csistema\u201d\u00a0 ha registrato la crisi pi\u00f9 spaventosa di una storia ormai quasi ventennale di accoglienza di minori stranieri.<\/p>\n<p>La grande responsabilit\u00e0 di Renzi \u00e8 certamente quella di aver accentrato tutto il potere nelle mani dell\u2019allora Vicepresidente \u2013 la dott.ssa Silvia Della Monica\u00a0 &#8211; alla quale il premier aveva delegato, con una inspiegabile e ingiustificata decisione, anche le competenze della presidenza della Commissione.<\/p>\n<p>Sulla discutibile e irregolare gestione della <strong>ex vicepresidente Silvia Della Monica<\/strong>\u00a0non vale la pena dilungarsi oltre, essendo oggetto di comunicati pubblicati dalla stessa autorit\u00e0 centrale a conclusione del suo mandato: accordi bilaterali sospesi o non rinnovati, commissione mai riunita ed enti mai convocati. \u201c<em>Quanto alla precedente gestione dell\u2019ex Vicepresidente si \u00e8 fornita ampia documentazione a tutti i commissari attestante\u00a0 numerose irregolarit\u00e0<\/em>\u201d si legge nel <a href=\"http:\/\/www.commissioneadozioni.it\/it\/notizie\/2017\/riunione-della-commissione-per-le-adozioni-internazionali.aspx\">comunicato seguito alla prima riunione della Commissione il 12 settembre scorso<\/a>.<\/p>\n<p>Ci auguriamo &#8211; ma ne avremo certezza solo nei prossimi anni &#8211; che questo non sia stato\u00a0il colpo mortale inferto alle adozioni internazionali in Italia.<\/p>\n<p>In extremis, l\u2019ex premier Renzi, accortosi degli incalcolabili danni seguiti alla sua decisone ha tentato di correre ai ripari revocando la presidenza della Commissione alla dott.ssa Silvia Della Monica per delegarla al <strong>Ministro Maria Elena Boschi<\/strong>.\u00a0 Mossa \u201cintempestiva\u201d del ex premier perch\u00e9 a danno gi\u00e0 arrecato e all\u2019indomani di un Referendum che indeboliva qualsiasi azione governativa.<\/p>\n<p><strong><u>5 anni di mala gestione e coppie sfiduciate \u2026 poi un barlume di speranza<\/u><\/strong><\/p>\n<p>Gli ultimi cinque anni di immobilismo della Commissione e di disinteresse politico dei Governi hanno prodotto, <strong>in Italia, una mancanza di fiducia<\/strong> nelle coppie italiane aperte all\u2019adozione,\u00a0 <strong>all&#8217;estero<\/strong>, presso i Paese di origine dei minori adottati,\u00a0 <strong>un grande disinteresse<\/strong> nei confronti del nostro Paese e delle nostre capacit\u00e0 di rispondere al bisogno di famiglia dei minori in stato di abbandono.<\/p>\n<p>Occorre attendere il governo di transizione di <strong>Gentiloni<\/strong> e la nomina della nuova Vicepresidente \u2013 la dott. Laura Laera &#8211; per ridare un minimo di fiducia alle adozioni internazionali nonostante non sia mai stato nominato un Direttore Generale e Gentiloni, purtroppo non abbia mai delegato la presidenza della Commissione, lasciando, ancora una volta la commissione sprovvista di una guida politica in grado di far fronte alla crisi e invertire il trend negativo delle adozioni.<strong>\u00a0<\/strong><\/p>\n<p><strong><u>L\u2019adozione internazionale pu\u00f2 essere salvata? Le sfide del nuovo Governo<\/u><\/strong><\/p>\n<p>A poche ore dalla formazione dalla formazione del nuovo Governo, ci chiediamo se \u00e8\u00a0 possibile salvare le adozioni internazionali.<\/p>\n<p><strong>Cosa dovr\u00e0 fare il nuovo governo per non sprecare la tensione all\u2019accoglienza delle famiglie italiane e dare una risposta ai milioni di bambini abbandonati?<\/strong><\/p>\n<p>Nell&#8217;immediato, tre le azioni urgenti. In primis, si nomini un Presidente politico della Commissione per le Adozioni Internazionali e un Direttore generale che diano un rinnovato impulso alla tensione verso il rilancio dell\u2019adozione che, finalmente, si respira da un anno a questa parte.<\/p>\n<p>E poi un segnale, immediato, urgente e di controtendenza per ridare fiducia alle coppie italiane, riconoscendo <strong>un\u00a0 bonus da 10mila euro per ogni famiglia adottiva a conclusione dell\u2019adozione internazionale:<\/strong> \u00e8 la misura di emergenza che 20 Enti Autorizzati avevano chiesto con forza alla politica lo scorso 4 marzo nel corso della <a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-un-bonus-10mila-euro-adozione-la-proposta-degli-enti-autorizzati-al-governo-verra\/\">Conferenza \u2018<strong>Adozioni internazionali: un bene per tutti\u2019<\/strong><\/a>, svoltasi presso la Sala \u2018Caduti di Nassirya\u2019 del Senato della Repubblica.<\/p>\n<p><strong>Le domande di disponibilit\u00e0 all\u2019adozione internazionali sono passate da 7882 nel 2005 alle 3668 nel 2015, con un calo del 53% in 10 anni.<\/strong><\/p>\n<p>Nel medio termine, ci sia aspetta, una forte azione in Europa che porti l\u2019adozione internazionale nell\u2019agenda europea con particolare interesse al tema dell\u2019adozione europea, uno dei tasselli alla base di un sistema di protezione dell\u2019infanzia pi\u00f9 omogeneo, mentre oggi \u00abgli standard di protezione dei minori e tutto il funzionamento del sistema della protezione dell\u2019infanzia, dall\u2019affido famigliare alle strutture di accoglienza alle adozioni sono diverse e, spesso, in deroga alle convenzioni europee e internazionali di tutela dei diritti dei minori.<\/p>\n<p>Se \u00e8 vero che l\u2019Europa ha una cultura unica, \u00e8 doveroso cominciare a pensare all\u2019Europa come un unico territorio e affrontare i problemi dell\u2019infanzia come obiettivo comune. <strong>Un primo passo da compiere in questa direzione \u00e8 sicuramente quello della creazione di una banca dati europea dei minori adottabili. <\/strong><\/p>\n<p>L\u2019approfondita analisi di Luciano Moia mette in luce il rischio di uno \u201cspreco di accoglienza\u201d\u00a0 propria delle famiglie italiane al quale stiamo assistendo negli ultimi anni a fronte di un numero crescente di minori abbandonati nel mondo e, in particolare n Africa, con oltre 100 milioni di bambini fuori famiglia.<\/p>\n<p>Un numero a nove cifre che impone un forte impegno dell&#8217; Europa\u00a0tutta per offrire ai minori africani in stato di abbandono un futuro possibile. La strada e l&#8217;emigrazione non possono essere la soluzione. C&#8217;\u00e8, infatti, bisogno di un &#8220;Piano Africa per l&#8217;infanzia in difficolt\u00e0 familiare\u201d in cui l\u2019 adozione internazionale rappresenti un concreto strumento di tutela familiare per tutti quei minori abbandonati che non trovano protezione in patria.<\/p>\n<p>Tutto questo \u00e8 possibile, occorre solo una volont\u00e0 politica che auspichiamo contraddistingua l\u2019operato del Nuovo Governo e il Nuovo Ministro della Famiglia e della Disabilit\u00e0, <strong>Lorenzo Fontana<\/strong>.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;A livello mondiale dal 2004 al 2016 le adozioni internazionali sono calate quasi dell&rsquo;80%. Pur non facendo eccezione, rispetto al resto del pianeta&nbsp;il nostro Bel Paese sembra tenere meglio &lsquo;botta&rsquo; registrando un calo&nbsp;del 55% e dimostrando &ndash; dati alla mano &ndash; di essere ancora il Paese pi&ugrave; accogliente. Nonostante ci&ograve; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":156006,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-156005","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Come rimediare al crollo delle adozioni internazionali? Il nuovo governo non ripeta gli errori di Riccardi, Kyenge e soprattutto Renzi - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come rimediare al crollo delle adozioni internazionali? Il nuovo governo non ripeta gli errori di Riccardi, Kyenge e soprattutto Renzi\" \/>\n<meta property=\"og:description\" content=\"&nbsp;A livello mondiale dal 2004 al 2016 le adozioni internazionali sono calate quasi dell&rsquo;80%. Pur non facendo eccezione, rispetto al resto del pianeta&nbsp;il nostro Bel Paese sembra tenere meglio &lsquo;botta&rsquo; registrando un calo&nbsp;del 55% e dimostrando &ndash; dati alla mano &ndash; di essere ancora il Paese pi&ugrave; accogliente. Nonostante ci&ograve; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-01T16:15:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-01T17:43:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Come rimediare al crollo delle adozioni internazionali? Il nuovo governo non ripeta gli errori di Riccardi, Kyenge e soprattutto Renzi\",\"datePublished\":\"2018-06-01T16:15:57+00:00\",\"dateModified\":\"2018-06-01T17:43:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\\\/\"},\"wordCount\":1552,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/grafico-dati-adozione.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\\\/\",\"name\":\"Come rimediare al crollo delle adozioni internazionali? Il nuovo governo non ripeta gli errori di Riccardi, Kyenge e soprattutto Renzi - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/grafico-dati-adozione.jpg\",\"datePublished\":\"2018-06-01T16:15:57+00:00\",\"dateModified\":\"2018-06-01T17:43:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/grafico-dati-adozione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/grafico-dati-adozione.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come rimediare al crollo delle adozioni internazionali? Il nuovo governo non ripeta gli errori di Riccardi, Kyenge e soprattutto Renzi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Come rimediare al crollo delle adozioni internazionali? Il nuovo governo non ripeta gli errori di Riccardi, Kyenge e soprattutto Renzi - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/","og_locale":"it_IT","og_type":"article","og_title":"Come rimediare al crollo delle adozioni internazionali? Il nuovo governo non ripeta gli errori di Riccardi, Kyenge e soprattutto Renzi","og_description":"&nbsp;A livello mondiale dal 2004 al 2016 le adozioni internazionali sono calate quasi dell&rsquo;80%. Pur non facendo eccezione, rispetto al resto del pianeta&nbsp;il nostro Bel Paese sembra tenere meglio &lsquo;botta&rsquo; registrando un calo&nbsp;del 55% e dimostrando &ndash; dati alla mano &ndash; di essere ancora il Paese pi&ugrave; accogliente. Nonostante ci&ograve; [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2018-06-01T16:15:57+00:00","article_modified_time":"2018-06-01T17:43:04+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Come rimediare al crollo delle adozioni internazionali? Il nuovo governo non ripeta gli errori di Riccardi, Kyenge e soprattutto Renzi","datePublished":"2018-06-01T16:15:57+00:00","dateModified":"2018-06-01T17:43:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/"},"wordCount":1552,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/","url":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/","name":"Come rimediare al crollo delle adozioni internazionali? Il nuovo governo non ripeta gli errori di Riccardi, Kyenge e soprattutto Renzi - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione.jpg","datePublished":"2018-06-01T16:15:57+00:00","dateModified":"2018-06-01T17:43:04+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/grafico-dati-adozione.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/crollo-adozioni-internazioni-nuovo-governo-non-ripeta-errori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Come rimediare al crollo delle adozioni internazionali? Il nuovo governo non ripeta gli errori di Riccardi, Kyenge e soprattutto Renzi"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:07:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/156005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=156005"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/156005\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/156006"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=156005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=156005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=156005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}