﻿


{"id":156224,"date":"2018-06-08T15:41:40","date_gmt":"2018-06-08T13:41:40","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=156224"},"modified":"2018-06-11T10:17:50","modified_gmt":"2018-06-11T08:17:50","slug":"africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/","title":{"rendered":"#Africainfamiglia. L\u2019Unico vero piano Marshall per l\u2019Africa si chiama \u201cAdozione a Distanza\u201d. Obiettivo di Ai.Bi.: salvare 1800 bambini dall&#8217;abbandono"},"content":{"rendered":"<h2>\u201c<strong><em>C\u2019\u00e8 solo un modo per poter cambiare concretamente il destino di migliaia di bambini e famiglie africani in difficolt\u00e0: si chiama Adozione a Distanza<\/em><\/strong>\u201d \u00e8 il messaggio che Marco Griffini, presidente di Ai.Bi. Amici dei Bambini, associazione impegnata in Africa da 25 anni, lancia subito dopo le ultime notizie relative allo sfruttamento dei migranti e del caporalato straniero in Italia in un\u2019intervista a <em><a href=\"https:\/\/www.tempi.it\/lunico-vero-piano-marshall-per-lafrica-si-chiama-adozione-a-distanza#.WxpTde6FPDc\">tempi.it<\/a><\/em> a cura di Caterina Giojelli.<\/h2>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-156209 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/><\/h2>\n<p>Mentre in Italia \u00e8 appena nato un esecutivo che fa del cambiamento, anche sul fronte dell\u2019attenzione all&#8217;infanzia abbandonata, la propria \u2019mission\u2019 dichiarata, aumentano i \u00a0numeri dei minori fuori famiglia in Africa e il tema \u201cimmigrazione\u201d e dei \u201cminori stranieri non accompagnati\u201d continua a far discutere gran parte della politica e dell\u2019opinione pubblica nazionale. Ai.Bi. Rilancia <a href=\"https:\/\/www.aibi.it\/lp\/adozione-a-distanza-africa\/\">Africa in Famiglia<\/a>, la campagna di <a href=\"https:\/\/www.aibi.it\/lp\/adozione-a-distanza-africa\/\">Adozione a Distanza di AIBI in Africa<\/a> per restituire una famiglia a 1.800 minori e cambiare concretamente il destino di migliaia di bambini e famiglie africani in difficolt\u00e0.<\/p>\n<p>\u201cProteggiamo la famiglia anche nel continente africano\u201d \u00e8 l\u2019appello di solidariet\u00e0 che Marco Griffini, presidente di\u00a0Ai.Bi., Associazione Amici dei Bambini, affida a <a href=\"http:\/\/tempi.it\">tempi.it<\/a>\u00a0 dopo le ultime notizie relative allo sfruttamento dei migranti e del caporalato straniero in Italia. \u00ab<em>Dobbiamo riuscire a proteggere la famiglia anche nel continente africano\u00a0e il diritto di ogni bambino a crescere all&#8217;interno\u00a0di un nucleo familiare porta proprio verso l\u2019adozione a distanza. Un\u00a0mezzo alla portata di tutti: non richiede manovre di bilancio o strategie governative, ciascuno pu\u00f2 fare concretamente qualcosa e diventare, soprattutto in un periodo come questo, protagonista degli interventi realizzati grazie a un sostegno continuativo, che permette un piano di vita e accompagnamento del minore e della famigli<\/em>a\u00bb.\u00a0\u00c8 il bello della cooperazione famigliare e popolare, come la chiama Griffini, che ancora crede nella cultura del dono.<\/p>\n<p><strong>PIANO MARSHALL. \u00a0<\/strong><\/p>\n<p>Il nostro paese vanta una sorta di primato dell\u2019accoglienza famigliare, lo ha spiegato bene Luciano Moia su\u00a0<a href=\"https:\/\/www.avvenire.it\/opinioni\/pagine\/il-mondo-non-adotta-pi-solo-litalia-a-braccia-aperte\">Avvenire<\/a>: dal 2004 al 2016 le adozioni sono calate quasi dell\u201980 per cento a livello mondiale, eppure non sono scomparsi i bambini da adottare, anzi, aumentano drammaticamente. L\u2019ultimo dato Unicef parla di circa 120 milioni di minori senza famiglia in tutto il mondo, ma \u00ab<em>al momento continuiamo ad essere orfani di un coordinamento da parte delle istituzioni. Tutti continuano a parlare di piani Africa, piani Marshall, piani di sviluppo e miliardi all\u2019Africa, pochi del paradosso che vede migliaia di famiglie disponibili ad accogliere milioni di bambini abbandonati. Oggi l\u2019adozione internazionale \u00e8 diventata la cosa pi\u00f9 difficile, la chimera da raggiungere. A livello europeo non \u00e8 ancora diventato un tema degli Stati e in attesa di vedere cosa far\u00e0 il governo dobbiamo muoverci no<\/em>i\u00bb. Per questo\u00a0Ai.Bi. ha rilanciato l\u2019iniziativa <a href=\"https:\/\/www.aibi.it\/lp\/adozione-a-distanza-africa\/\">#AfricainFamiglia\u00a0<\/a>per\u00a0l\u2019adozione\u00a0a distanza dei bambini abbandonati nel continente africano. Quattro, in particolare, i Paesi in cui opera l\u2019associazione da anni per offrire risposte e aiuto a chi accoglie e fa crescere questi orfani: i dati sono impressionanti.<\/p>\n<p><strong>MIGLIAIA NEL BISOGNO.\u00a0<\/strong><\/p>\n<p><strong>In Kenya, da 1,4 milioni di minorenni fuori famiglia del 1998 si \u00e8 passati a 2,4 milioni del 2014, con\u00a0443 mila orfani <\/strong>di entrambi i genitori\u00a0a causa dell\u2019Aids: di questi, 200 mila minori vivono in istituti e centri di accoglienza come quelli di Ai.Bi, dove 700 bimbi attendono\u00a0ancora\u00a0di essere adottati a distanza.<\/p>\n<p><strong>In\u00a0Ghana oltre 4 mila bambini vivono in orfanotrofi<\/strong>, che nel 94 per cento dei casi operano illegalmente, con abusi e maltrattamenti: da quando \u00e8 arrivata nel 2011, Ai.Bi supporta 64 bambini, sostenendo le loro 54 famiglie poverissime.<\/p>\n<p><strong>STIME IN CRESCITA.\u00a0<\/strong><\/p>\n<p><strong>In Marocco\u00a0non esistono dati ufficiali\u00a0sull\u2019abbandono dei minori, solo stime: si calcolano 70 mila bambini fuori famiglia, in crescita di oltre il 20 per cento ogni anno<\/strong>. Le statistiche fornite da associazioni della societ\u00e0 civile, come\u00a0Insaf, stimano infatti 24 bambini abbandonati ogni giorno (oltre 8.500 all&#8217;anno): qui 482 su 717 minori accolti nei cinque centri di accoglienza di Ai.Bi. stanno aspettando un sostegno a distanza.<\/p>\n<p><strong>I \u201cBAMBINI STREGONI\u201d.\u00a0<\/strong><\/p>\n<p>E veniamo alla <strong>Repubblica Democratica del Congo, il Paese bambino, una popolazione di 73,5 milioni di abitanti, il 55 per cento dei quali con meno di 18 anni.<\/strong> Qui, spiegano da Ai.Bi, che coopera per sostenere quanti pi\u00f9 bimbi tra gli 89 ospitati nel centro Fed, orfani o in condizione di gravissima vulnerabilit\u00e0 sociale, i conflitti succedutisi nel 1996 e nel 2003 hanno prodotto\u00a0sfracelli sull&#8217;integrit\u00e0 familiare, con\u00a023 mila\u00a0minori abbandonati dalle famiglie che vivono ai margini della societ\u00e0,\u00a0\u00abconsiderati \u201cbambini stregoni\u201d portatori di sventura e per questo stuprati e uccisi\u00a0se non accolti in tempo negli orfanotrofi del paese\u00bb.<\/p>\n<p>Tutte le informazioni sull&#8217;<a href=\"https:\/\/www.aibi.it\/adozioneadistanza\/\">adozione a distanza<\/a> e le attivit\u00e0 del\u00a0progetto <a href=\"https:\/\/www.aibi.it\/lp\/adozione-a-distanza-africa\/\">#AfricainFamiglia<\/a>, soprattutto le storie dei piccoli e delle strutture che accolgono ad oggi\u00a0quasi 1.800 bimbi e adolescenti\u00a0da zero a 20 anni sostenute da Ai.Bi., sono\u00a0disponibili sul sito web dell\u2019Adozione a Distanza<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&ldquo;C&rsquo;&egrave; solo un modo per poter cambiare concretamente il destino di migliaia di bambini e famiglie africani in difficolt&agrave;: si chiama Adozione a Distanza&rdquo; &egrave; il messaggio che Marco Griffini, presidente di Ai.Bi. Amici dei Bambini, associazione impegnata in Africa da 25 anni, lancia subito dopo le ultime notizie relative [&hellip;]<\/p>\n","protected":false},"author":75,"featured_media":156209,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-156224","post","type-post","status-publish","format-standard","has-post-thumbnail","category-campagne-ed-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>#Africainfamiglia. L\u2019Unico vero piano Marshall per l\u2019Africa si chiama \u201cAdozione a Distanza\u201d. Obiettivo di Ai.Bi.: salvare 1800 bambini dall&#039;abbandono - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#Africainfamiglia. L\u2019Unico vero piano Marshall per l\u2019Africa si chiama \u201cAdozione a Distanza\u201d. Obiettivo di Ai.Bi.: salvare 1800 bambini dall&#039;abbandono\" \/>\n<meta property=\"og:description\" content=\"&ldquo;C&rsquo;&egrave; solo un modo per poter cambiare concretamente il destino di migliaia di bambini e famiglie africani in difficolt&agrave;: si chiama Adozione a Distanza&rdquo; &egrave; il messaggio che Marco Griffini, presidente di Ai.Bi. Amici dei Bambini, associazione impegnata in Africa da 25 anni, lancia subito dopo le ultime notizie relative [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-08T13:41:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-11T08:17:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"stefaniaP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"stefaniaP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\\\/\"},\"author\":{\"name\":\"stefaniaP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/dfce5bd678ad0f650527cc2172949970\"},\"headline\":\"#Africainfamiglia. L\u2019Unico vero piano Marshall per l\u2019Africa si chiama \u201cAdozione a Distanza\u201d. Obiettivo di Ai.Bi.: salvare 1800 bambini dall&#8217;abbandono\",\"datePublished\":\"2018-06-08T13:41:40+00:00\",\"dateModified\":\"2018-06-11T08:17:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\\\/\"},\"wordCount\":811,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/africa-in-famiglia-logo_700x460.jpg\",\"articleSection\":[\"Campagne ed Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\\\/\",\"name\":\"#Africainfamiglia. L\u2019Unico vero piano Marshall per l\u2019Africa si chiama \u201cAdozione a Distanza\u201d. Obiettivo di Ai.Bi.: salvare 1800 bambini dall'abbandono - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/africa-in-famiglia-logo_700x460.jpg\",\"datePublished\":\"2018-06-08T13:41:40+00:00\",\"dateModified\":\"2018-06-11T08:17:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/africa-in-famiglia-logo_700x460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/africa-in-famiglia-logo_700x460.jpg\",\"width\":700,\"height\":460,\"caption\":\"africa in famiglia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne ed Eventi\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/campagne-ed-eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"#Africainfamiglia. L\u2019Unico vero piano Marshall per l\u2019Africa si chiama \u201cAdozione a Distanza\u201d. Obiettivo di Ai.Bi.: salvare 1800 bambini dall&#8217;abbandono\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/dfce5bd678ad0f650527cc2172949970\",\"name\":\"stefaniaP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/stefaniap\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"#Africainfamiglia. L\u2019Unico vero piano Marshall per l\u2019Africa si chiama \u201cAdozione a Distanza\u201d. Obiettivo di Ai.Bi.: salvare 1800 bambini dall'abbandono - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/","og_locale":"it_IT","og_type":"article","og_title":"#Africainfamiglia. L\u2019Unico vero piano Marshall per l\u2019Africa si chiama \u201cAdozione a Distanza\u201d. Obiettivo di Ai.Bi.: salvare 1800 bambini dall'abbandono","og_description":"&ldquo;C&rsquo;&egrave; solo un modo per poter cambiare concretamente il destino di migliaia di bambini e famiglie africani in difficolt&agrave;: si chiama Adozione a Distanza&rdquo; &egrave; il messaggio che Marco Griffini, presidente di Ai.Bi. Amici dei Bambini, associazione impegnata in Africa da 25 anni, lancia subito dopo le ultime notizie relative [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2018-06-08T13:41:40+00:00","article_modified_time":"2018-06-11T08:17:50+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_fb.jpg","type":"image\/jpeg"}],"author":"stefaniaP","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"stefaniaP","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/"},"author":{"name":"stefaniaP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/dfce5bd678ad0f650527cc2172949970"},"headline":"#Africainfamiglia. L\u2019Unico vero piano Marshall per l\u2019Africa si chiama \u201cAdozione a Distanza\u201d. Obiettivo di Ai.Bi.: salvare 1800 bambini dall&#8217;abbandono","datePublished":"2018-06-08T13:41:40+00:00","dateModified":"2018-06-11T08:17:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/"},"wordCount":811,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460.jpg","articleSection":["Campagne ed Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/","url":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/","name":"#Africainfamiglia. L\u2019Unico vero piano Marshall per l\u2019Africa si chiama \u201cAdozione a Distanza\u201d. Obiettivo di Ai.Bi.: salvare 1800 bambini dall'abbandono - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460.jpg","datePublished":"2018-06-08T13:41:40+00:00","dateModified":"2018-06-11T08:17:50+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/africa-in-famiglia-logo_700x460.jpg","width":700,"height":460,"caption":"africa in famiglia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/africainfamiglia-unico-vero-piano-marshall-africa-adozione-a-distanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Campagne ed Eventi","item":"https:\/\/www.aibi.it\/ita\/category\/campagne-ed-eventi\/"},{"@type":"ListItem","position":3,"name":"#Africainfamiglia. L\u2019Unico vero piano Marshall per l\u2019Africa si chiama \u201cAdozione a Distanza\u201d. Obiettivo di Ai.Bi.: salvare 1800 bambini dall&#8217;abbandono"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/dfce5bd678ad0f650527cc2172949970","name":"stefaniaP","url":"https:\/\/www.aibi.it\/ita\/author\/stefaniap\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:31:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/156224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=156224"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/156224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/156209"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=156224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=156224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=156224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}