﻿


{"id":158074,"date":"2018-08-23T17:11:32","date_gmt":"2018-08-23T15:11:32","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=158074"},"modified":"2018-08-23T17:11:32","modified_gmt":"2018-08-23T15:11:32","slug":"bomboniere-solidali-bottoncini-di-porcellana","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/","title":{"rendered":"Bomboniere solidali: il mondo a colori di Ai.Bi. prende forma nei bottoncini di porcellana!"},"content":{"rendered":"<p><strong>Pronte a partire per rendere solidale un altro Battesimo: i bottoncini di porcella di Ai.Bi. sono prossimi alla spedizione.<\/strong><\/p>\n<p>Questi bottoncini di porcellana solidali sono infatti <strong>realizzati da un laboratorio che offre opportunit\u00e0 di lavoro a utenti dei servizi sociali e sanitari con disabilit\u00e0<\/strong>.<br \/>\nI proventi degli acquisti sono <strong>devoluti ai progetti di Amici dei Bambini in Italia e nel mondo, in favore dei bambini in gravi difficolt\u00e0 familiari.<\/strong><\/p>\n<p>Scopri di pi\u00f9 sul sito: <a href=\"http:\/\/www.fondazioneaibi.it\">www.fondazioneaibi.it<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-158046\" src=\"https:\/\/www.aibi.it\/ita\/images\/bomboniere-solidali-bottoncino-porcellana1200x630.jpg\" alt=\"\" width=\"1200\" height=\"630\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/bomboniere-solidali-bottoncino-porcellana1200x630.jpg 1200w, https:\/\/www.aibi.it\/ita\/images\/bomboniere-solidali-bottoncino-porcellana1200x630-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/bomboniere-solidali-bottoncino-porcellana1200x630-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/bomboniere-solidali-bottoncino-porcellana1200x630-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/bomboniere-solidali-bottoncino-porcellana1200x630-105x55.jpg 105w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pronte a partire per rendere solidale un altro Battesimo: i bottoncini di porcella di Ai.Bi. sono prossimi alla spedizione. Questi bottoncini di porcellana solidali sono infatti realizzati da un laboratorio che offre opportunit&agrave; di lavoro a utenti dei servizi sociali e sanitari con disabilit&agrave;. I proventi degli acquisti sono devoluti [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":158046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-158074","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bomboniere solidali: il mondo a colori di Ai.Bi. prende forma nei bottoncini di porcellana!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bomboniere solidali: il mondo a colori di Ai.Bi. prende forma nei bottoncini di porcellana!\" \/>\n<meta property=\"og:description\" content=\"Pronte a partire per rendere solidale un altro Battesimo: i bottoncini di porcella di Ai.Bi. sono prossimi alla spedizione. Questi bottoncini di porcellana solidali sono infatti realizzati da un laboratorio che offre opportunit&agrave; di lavoro a utenti dei servizi sociali e sanitari con disabilit&agrave;. I proventi degli acquisti sono devoluti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-23T15:11:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/bomboniere-solidali-bottoncino-porcellana1200x630.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniere-solidali-bottoncini-di-porcellana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniere-solidali-bottoncini-di-porcellana\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Bomboniere solidali: il mondo a colori di Ai.Bi. prende forma nei bottoncini di porcellana!\",\"datePublished\":\"2018-08-23T15:11:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniere-solidali-bottoncini-di-porcellana\\\/\"},\"wordCount\":93,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniere-solidali-bottoncini-di-porcellana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bomboniere-solidali-bottoncino-porcellana1200x630.jpg\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniere-solidali-bottoncini-di-porcellana\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniere-solidali-bottoncini-di-porcellana\\\/\",\"name\":\"Bomboniere solidali: il mondo a colori di Ai.Bi. prende forma nei bottoncini di porcellana!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniere-solidali-bottoncini-di-porcellana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniere-solidali-bottoncini-di-porcellana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bomboniere-solidali-bottoncino-porcellana1200x630.jpg\",\"datePublished\":\"2018-08-23T15:11:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniere-solidali-bottoncini-di-porcellana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniere-solidali-bottoncini-di-porcellana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniere-solidali-bottoncini-di-porcellana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bomboniere-solidali-bottoncino-porcellana1200x630.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bomboniere-solidali-bottoncino-porcellana1200x630.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bomboniere-solidali-bottoncini-di-porcellana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bomboniere solidali: il mondo a colori di Ai.Bi. prende forma nei bottoncini di porcellana!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bomboniere solidali: il mondo a colori di Ai.Bi. prende forma nei bottoncini di porcellana!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/","og_locale":"it_IT","og_type":"article","og_title":"Bomboniere solidali: il mondo a colori di Ai.Bi. prende forma nei bottoncini di porcellana!","og_description":"Pronte a partire per rendere solidale un altro Battesimo: i bottoncini di porcella di Ai.Bi. sono prossimi alla spedizione. Questi bottoncini di porcellana solidali sono infatti realizzati da un laboratorio che offre opportunit&agrave; di lavoro a utenti dei servizi sociali e sanitari con disabilit&agrave;. I proventi degli acquisti sono devoluti [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2018-08-23T15:11:32+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/bomboniere-solidali-bottoncino-porcellana1200x630.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Bomboniere solidali: il mondo a colori di Ai.Bi. prende forma nei bottoncini di porcellana!","datePublished":"2018-08-23T15:11:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/"},"wordCount":93,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bomboniere-solidali-bottoncino-porcellana1200x630.jpg","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/","url":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/","name":"Bomboniere solidali: il mondo a colori di Ai.Bi. prende forma nei bottoncini di porcellana!","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bomboniere-solidali-bottoncino-porcellana1200x630.jpg","datePublished":"2018-08-23T15:11:32+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/bomboniere-solidali-bottoncino-porcellana1200x630.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/bomboniere-solidali-bottoncino-porcellana1200x630.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bomboniere-solidali-bottoncini-di-porcellana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"Bomboniere solidali: il mondo a colori di Ai.Bi. prende forma nei bottoncini di porcellana!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:58:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/158074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=158074"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/158074\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/158046"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=158074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=158074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=158074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}