﻿{"id":15835,"date":"2010-09-15T17:09:47","date_gmt":"2010-09-15T16:09:47","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=15835"},"modified":"2010-09-15T17:09:47","modified_gmt":"2010-09-15T16:09:47","slug":"il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/","title":{"rendered":"Il Tar della Puglia boccia Vendola: Si all\u2019obiezione di coscienza"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"margin: 5px;\" src=\"https:\/\/www.aibi.it\/ita\/images\/tribunale_mart.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Bari- \u201c Una procedura selettiva che escluda aprioristicamente i medici specialisti obiettori dall\u2019accesso ai consultori , appare discriminatoria oltre che irrazionale, poich\u00e9 non giustificata da alcuna plausibile ragione oggettiva\u201d. Queste le motivazioni della sentenza con cui Il Tar della Puglia ha annullato la delibera della giunta regionale che escludeva i medici obiettori di coscienza esclusi dai consultori ambulatoriali.<\/p>\n<p>Per i giudici amministrativi, il provvedimento viola il principio costituzionale di eguaglianza, oltre che i principi posti a fondamento dell&#8217;obiezione di coscienza.  La sentenza obbliga la Regione Puglia a \u201criservare\u201d il 50% dei posti nei consultori pubblici agli obiettori in quanto \u201cla presenza o meno di medici obiettori- scrivono i giudici- \u00e8 assolutamente irrilevante dato che all\u2019interno dei consultori non si pratica materialmente l\u2019interruzione, bens\u00ec soltanto attivit\u00e0 di assistenza psicologica e di informazione\/ consulenza della gestante, ovvero vengono svolte funzioni di ginecologo che esulano l\u2019iter abortivo\u201d.<\/p>\n<p>Esulta Nicol\u00f2 Mastropasqua, rappresentante in giudizio dei medici obiettori che hanno presentato il ricorso : \u201cannullati gli atti , la regione dovr\u00e0 provvedere ad assicurare nei bandi questa \u201criserva\u201d di cui parla la sentenza e lo dovr\u00e0 fare entro 30 giorni dalla notifica\u201d.<\/p>\n<p><em> (Fonte Avvenire)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Una procedura selettiva che escluda aprioristicamente i medici specialisti obiettori dall\u2019accesso ai consultori , appare discriminatoria oltre che irrazionale, poich\u00e9 non giustificata da alcuna plausibile ragione oggettiva\u201d. Queste le motivazioni della sentenza con cui Il Tar della Puglia ha annullato la delibera della giunta regionale che escludeva i medici obiettori di coscienza esclusi dai consultori ambulatoriali.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-15835","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il Tar della Puglia boccia Vendola: Si all\u2019obiezione di coscienza - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all\u2019obiezione-di-coscienza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Tar della Puglia boccia Vendola: Si all\u2019obiezione di coscienza\" \/>\n<meta property=\"og:description\" content=\"Una procedura selettiva che escluda aprioristicamente i medici specialisti obiettori dall\u2019accesso ai consultori , appare discriminatoria oltre che irrazionale, poich\u00e9 non giustificata da alcuna plausibile ragione oggettiva\u201d. Queste le motivazioni della sentenza con cui Il Tar della Puglia ha annullato la delibera della giunta regionale che escludeva i medici obiettori di coscienza esclusi dai consultori ambulatoriali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all\u2019obiezione-di-coscienza\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-15T16:09:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/tribunale_mart.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Il Tar della Puglia boccia Vendola: Si all\u2019obiezione di coscienza\",\"datePublished\":\"2010-09-15T16:09:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\\\/\"},\"wordCount\":198,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/tribunale_mart.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\\\/\",\"name\":\"Il Tar della Puglia boccia Vendola: Si all\u2019obiezione di coscienza - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/tribunale_mart.jpg\",\"datePublished\":\"2010-09-15T16:09:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/tribunale_mart.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/tribunale_mart.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il Tar della Puglia boccia Vendola: Si all\u2019obiezione di coscienza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il Tar della Puglia boccia Vendola: Si all\u2019obiezione di coscienza - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all\u2019obiezione-di-coscienza\/","og_locale":"it_IT","og_type":"article","og_title":"Il Tar della Puglia boccia Vendola: Si all\u2019obiezione di coscienza","og_description":"Una procedura selettiva che escluda aprioristicamente i medici specialisti obiettori dall\u2019accesso ai consultori , appare discriminatoria oltre che irrazionale, poich\u00e9 non giustificata da alcuna plausibile ragione oggettiva\u201d. Queste le motivazioni della sentenza con cui Il Tar della Puglia ha annullato la delibera della giunta regionale che escludeva i medici obiettori di coscienza esclusi dai consultori ambulatoriali.","og_url":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all\u2019obiezione-di-coscienza\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-09-15T16:09:47+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/tribunale_mart.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Il Tar della Puglia boccia Vendola: Si all\u2019obiezione di coscienza","datePublished":"2010-09-15T16:09:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/"},"wordCount":198,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/tribunale_mart.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/","url":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/","name":"Il Tar della Puglia boccia Vendola: Si all\u2019obiezione di coscienza - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/tribunale_mart.jpg","datePublished":"2010-09-15T16:09:47+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/tribunale_mart.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/tribunale_mart.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/il-tar-della-puglia-boccia-vendola-si-all%e2%80%99obiezione-di-coscienza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Il Tar della Puglia boccia Vendola: Si all\u2019obiezione di coscienza"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:37:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/15835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=15835"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/15835\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=15835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=15835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=15835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}