﻿


{"id":15935,"date":"2010-09-21T10:09:40","date_gmt":"2010-09-21T09:09:40","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=15935"},"modified":"2010-09-21T10:10:26","modified_gmt":"2010-09-21T09:10:26","slug":"sri-lanka-vedere-il-mondo-attraverso-la-fotografia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/","title":{"rendered":"Sri Lanka: Vedere il mondo attraverso la fotografia"},"content":{"rendered":"<p><em>L\u2019assistente sociale di Ai.Bi. Sri Lanka, Bryan, ci racconta come durante le attivita\u2019 di Life Skills e Vocational Training per i Care Leavers vengono affrontate una serie di tematiche di maggiore interesse e significato per i beneficiari che presto lascerano il sistema residenziale. <\/em><\/p>\n<p>Per cca 3 settimane il tema di discussione e\u2019 stato \u201cla protezione dell\u2019ambiente\u201d, dove le ragazze sono venute a conoscenza dei vari metodi di protezione della natura e dell\u2019ambiente che ci circonda. Alcune beneficiarie hanno espresso evidente interesse per il mondo selvaggio, fatto che ci a premesso di organizzare un workshop di fotografia sulla natura selvaggia, in particolare sugli animali.<\/p>\n<p>Il workshop si e\u2019 svolto il 9 di settembre nell\u2019istituto Viharamahadevi CDC ed e\u2019 stato condotto dal fotografo professionista Gamini Mayadunne, supportato dalla nostra collaboratrice Sara.<\/p>\n<p>La sessione si e\u2019 svolta in due tappe, la prima essendo quella teorica durante il quale lo specialista aveva spiegato come utilizzare la macchina fotografica, vari modelli utilizzati in passato e modelli pi\u00f9 recenti, l\u2019importanza della fotografia, come editare le fotografie, mercato della fotografia ecc. Nella seconda parte invece le beneficiarie hanno avuto modo di sperimentare, dovendo fare delle fotografie in mezzo alla natura, nei pressi dell\u2019istituto che e\u2019 circondato da varie risorse naturali. Questo e\u2019 stato il giorno in cui hanno toccato per la prima volta una macchina fotografica.<\/p>\n<p>La discussione piu\u2019 accesa e\u2019 stata durante la seconda parte, dopo aver mostrato le proprie fotografie e l\u2019analisi di come sono venute, se possibile migliorare ecc. Le beneficiarie hanno identificato nuovi metodi su come fare le fotografie. La cosa piu\u2019 importante e\u2019 che loro non avevano mai pensato che siano in grado di fare fotografia, quindi alcune delle ragazze hanno espresso la voglia di continuare come un attivit\u00e0 lavorativa o hobby in alcuni casi.<\/p>\n<p>Attraverso questo tipo di attivit\u00e0 lo staff di Ai.Bi. Sri Lanka offre la possibilit\u00e0 ai Care Leavers di esporsi a nuove realta\u2019, nuove idee e nuovi provocazioni. Questa iniziativa fa parte della strategia di orientamento professionale e socializzazione adottata dall\u2019equipe multidisciplinare del progetto.<\/p>\n<p><em>Questo programma viene svolto nell\u2019ambito del progetto sui Care Laevers \u201cInsieme per un futuro migliore: azioni contro lo sfruttamento minorile in Sri Lanka\u201d, co-finanziato dalla Regione Toscana.\u00a0\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;assistente sociale di Ai.Bi. Sri Lanka, Bryan, ci racconta come durante le attivita&rsquo; di Life Skills e Vocational Training per i Care Leavers vengono affrontate una serie di tematiche di maggiore interesse e significato per i beneficiari che presto lascerano il sistema residenziale. Per cca 3 settimane il tema di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-15935","post","type-post","status-publish","format-standard","category-cooperazione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sri Lanka: Vedere il mondo attraverso la fotografia  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sri Lanka: Vedere il mondo attraverso la fotografia\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;assistente sociale di Ai.Bi. Sri Lanka, Bryan, ci racconta come durante le attivita&rsquo; di Life Skills e Vocational Training per i Care Leavers vengono affrontate una serie di tematiche di maggiore interesse e significato per i beneficiari che presto lascerano il sistema residenziale. Per cca 3 settimane il tema di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-21T09:09:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-09-21T09:10:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Sri Lanka: Vedere il mondo attraverso la fotografia\",\"datePublished\":\"2010-09-21T09:09:40+00:00\",\"dateModified\":\"2010-09-21T09:10:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\\\/\"},\"wordCount\":380,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\\\/\",\"name\":\"Sri Lanka: Vedere il mondo attraverso la fotografia - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2010-09-21T09:09:40+00:00\",\"dateModified\":\"2010-09-21T09:10:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sri Lanka: Vedere il mondo attraverso la fotografia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sri Lanka: Vedere il mondo attraverso la fotografia  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/","og_locale":"it_IT","og_type":"article","og_title":"Sri Lanka: Vedere il mondo attraverso la fotografia","og_description":"L&rsquo;assistente sociale di Ai.Bi. Sri Lanka, Bryan, ci racconta come durante le attivita&rsquo; di Life Skills e Vocational Training per i Care Leavers vengono affrontate una serie di tematiche di maggiore interesse e significato per i beneficiari che presto lascerano il sistema residenziale. Per cca 3 settimane il tema di [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-09-21T09:09:40+00:00","article_modified_time":"2010-09-21T09:10:26+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Sri Lanka: Vedere il mondo attraverso la fotografia","datePublished":"2010-09-21T09:09:40+00:00","dateModified":"2010-09-21T09:10:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/"},"wordCount":380,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/","url":"https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/","name":"Sri Lanka: Vedere il mondo attraverso la fotografia - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2010-09-21T09:09:40+00:00","dateModified":"2010-09-21T09:10:26+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/sri-lanka-vedere-il-mondo-attraverso-la-fotografia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Sri Lanka: Vedere il mondo attraverso la fotografia"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:40:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/15935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=15935"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/15935\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=15935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=15935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=15935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}