﻿


{"id":159358,"date":"2018-10-02T16:36:19","date_gmt":"2018-10-02T14:36:19","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=159358"},"modified":"2018-10-02T16:36:19","modified_gmt":"2018-10-02T14:36:19","slug":"nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/","title":{"rendered":"Nel Corno d\u2019Africa \u2018scoppia\u2019 la pace: \u00e8 il momento di aiutarli con #Africainfamiglia"},"content":{"rendered":"<h2><strong>Qualcosa sta cambiando, ed \u00e8 parecchio significativo per il\u00a0Corno\u00a0d\u2019Africa: dopo decenni di conflitti, morte e impoverimento della popolazione, finalmente sembra che nel silenzio generale dei media la fine delle lotte tra Paesi confinanti possa diventare una realt\u00e0. Ecco perch\u00e9 non \u00e8 pi\u00f9 una chimera pensare a un piano di aiuti all\u2019Africa<\/strong><strong>\u00a0<\/strong><\/h2>\n<h3><strong>Anche per questo, \u00e8 importante rilanciare il contributo possibile di un progetto di sostegno a distanza come <em>#Africainfamiglia<\/em>, che certifica l\u2019impegno pluriennale di <em>Amici dei Bambini<\/em> per l\u2019infanzia e le famiglie in difficolt\u00e0 nel continente africano. Un \u2018piano Marshall\u2019 per 1.800 bambini abbandonati<\/strong><strong>\u00a0<\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-159256\" src=\"https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460-457x300.jpg\" alt=\"Africa. La pace nel 'Corno' autorizza la nascita di un piano Marshall, Ai.Bi. in prima fila\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>Sembra \u2013 nonostante l\u2019assordante silenzio mediatico \u2013 che\u00a0<strong>sia \u2018scoppiata\u2019 la pace tra i Paesi del\u00a0Corno\u00a0d\u2019Africa<\/strong>. Dopo la riconciliazione tra\u00a0<strong>Etiopia ed Eritrea<\/strong>, certificata dal nuovo premier di Addis Abeba, Abiy Ahmed, ecco che\u00a0<strong>anche la Somalia<\/strong>\u00a0sembrerebbe finalmente vicina a una importante stretta di mano con gli altri due storici \u2018contendenti\u2019 in quella porzione di continente africano: \u201c<em>c\u2019\u00e8 stato un vertice ad Asmara tra i presidenti di Eritrea, Etiopia e Somalia<\/em>\u201d, come racconta\u00a0<strong>il sito web\u00a0<em>Africa Rivista<\/em><\/strong>. Che aggiunge: \u201c<em>Anche la Somalia era in rotta con l\u2019Eritrea perch\u00e9 il regime di Isaias Afworki veniva accusato di sostenere, proteggere e armare il gruppo jihadista al Shabaab che continua a realizzare attacchi e attentati contro Mogadiscio<\/em>\u201d. E prosegue: \u201c<strong><em>Ora a questo gruppo si \u00e8 aggiunto anche Gibuti<\/em><\/strong><em>, piccolo Paese ma di cruciale importanza strategica che confina con tutti e tre i paesi e soprattutto ospita nel suo territorio truppe di Stati Uniti, Francia, Cina, Italia.\u00a0<strong>Anche con Gibuti l\u2019Eritrea aveva una controversia territoriale<\/strong>\u00a0che era cominciata nel 1996 quando Gibuti aveva accusato Asmara di un attacco armato nel villaggio di Ras Doumeirah, abitato dall\u2019etnia nomade degli Afar<\/em>\u201d.<\/p>\n<p><strong>In questo contesto favorevole, dopo decenni di penuria, rischio della vita e stenti per la popolazione<\/strong>\u00a0dei Paesi coinvolti, non \u00e8 pi\u00f9 impossibile pensare a un piano di aiuti strutturato e coerente per l\u2019Africa. C\u2019\u00e8 spazio per\u00a0<strong>poter agire e portare sostegno concreto<\/strong>\u00a0e nuova linfa a questi e\u00a0<strong>anche ad altri Paesi dell\u2019Africa<\/strong>. Quello che, da anni, \u00e8 l\u2019obiettivo di\u00a0<em>Ai.Bi. Associazione Amici dei Bambini<\/em>, che\u00a0<strong>attraverso\u00a0<em>#Africainfamiglia<\/em><\/strong>, vero e proprio \u2018piano Marshall\u2019 per l\u2019aiuto dei bambini abbandonati,\u00a0<strong>si prende cura di 1.800 bambini senza famiglia in Africa<\/strong>.<\/p>\n<p><strong>Goccia nell\u2019oceano, ma primo passo verso una rinascita,\u00a0<em>#AfricainFamiglia<\/em>\u00a0\u00e8 la Campagna di\u00a0<em>Amici dei Bambini<\/em>\u00a0per quei bambini senza futuro che, in istituto o ai margini delle strade, aspettano la concretezza di un aiuto che non pu\u00f2 essere deciso ai vertici delle istituzioni<\/strong>.<\/p>\n<p>Fin\u00a0dal 2006\u00a0<em>Ai.Bi.<\/em>\u00a0opera infatti in\u00a0<strong>Marocco\u00a0<\/strong>prendendosi cura, in cinque centri di accoglienza, di quasi mille minori tra zero e 18 anni, la met\u00e0 dei quali aspettano l\u2019abbraccio di una mamma o un pap\u00e0, anche se a distanza.\u00a0<strong>In\u00a0<a href=\"https:\/\/www.aibi.it\/adozioneadistanza\/kenya\/\">Kenya<\/a><\/strong>\u00a0Ai.Bi.\u00a0\u00e8 invece attiva dal 2008; sostenendo a distanza 218 minori accolti in tre centri e una scuola, ma quasi 700 sono ancora in attesa di essere \u2018adottati a distanza\u2019. In\u00a0<a href=\"https:\/\/www.aibi.it\/adozioneadistanza\/ghana\/\"><strong>Ghana<\/strong>, dove oltre 4mila bambini vivono in orfanotrofi<\/a>,\u00a0<em>Amici dei Bambini<\/em>\u00a0opera dal settembre 2011; supportando 64 bambini particolarmente bisognosi e sostenendo le 54 rispettive famiglie. Infine, in<strong>\u00a0<a href=\"https:\/\/www.aibi.it\/adozioneadistanza\/congo\/\">Repubblica Democratica del Congo<\/a><\/strong>\u00a0<em>Amici dei Bambini<\/em>\u00a0coopera per\u00a0sostenere almeno alcuni degli 89 bambini ospiti del\u00a0centro FED\u00a0(<em>Femme et D\u00e9velopement<\/em>) di Goma, orfani o in condizioni di grave vulnerabilit\u00e0 sociale.<\/p>\n<p>\u00c8 alle famiglie e ai minori abbandonati che la campagna di\u00a0<em>Ai.Bi.<\/em>\u00a0si rivolge, in questo momento in cui \u00e8 particolarmente possibile e necessario aiutarli: \u2018<a href=\"https:\/\/www.aibi.it\/lp\/adozione-a-distanza-africa\/\">Africa in Famiglia<\/a>\u2019 \u00e8 un\u00a0impegno decisivo per il destino di milioni di bambini!\u00a0<strong>Scegliendo di diventare \u2018genitori a distanza\u2019 \u00e8 possibile stare al fianco di un bambino abbandonato e lottare con lui perch\u00e9 possa rinascere come figlio e (ri-)entrare nella sua famiglia<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte:\u00a0<a href=\"https:\/\/www.africarivista.it\/corsa-alla-pace-nel-corno-dafrica\/128768\/\">Africa Rivista<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qualcosa sta cambiando, ed &egrave; parecchio significativo per il&nbsp;Corno&nbsp;d&rsquo;Africa: dopo decenni di conflitti, morte e impoverimento della popolazione, finalmente sembra che nel silenzio generale dei media la fine delle lotte tra Paesi confinanti possa diventare una realt&agrave;. Ecco perch&eacute; non &egrave; pi&ugrave; una chimera pensare a un piano di aiuti [&hellip;]<\/p>\n","protected":false},"author":83,"featured_media":159256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-159358","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nel Corno d\u2019Africa \u2018scoppia\u2019 la pace: \u00e8 il momento di aiutarli con #Africainfamiglia - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Africa. Qualcosa sta cambiando, ed \u00e8 parecchio significativo per il Corno d\u2019Africa: dopo decenni di conflitti, morte e impoverimento della popolazione, finalmente sembra che nel silenzio generale dei media la fine delle lotte tra Paesi confinanti possa diventare una realt\u00e0. Ecco perch\u00e9 non \u00e8 pi\u00f9 una chimera pensare a un piano di aiuti all\u2019Africa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nel Corno d\u2019Africa \u2018scoppia\u2019 la pace: \u00e8 il momento di aiutarli con #Africainfamiglia\" \/>\n<meta property=\"og:description\" content=\"Africa. Qualcosa sta cambiando, ed \u00e8 parecchio significativo per il Corno d\u2019Africa: dopo decenni di conflitti, morte e impoverimento della popolazione, finalmente sembra che nel silenzio generale dei media la fine delle lotte tra Paesi confinanti possa diventare una realt\u00e0. Ecco perch\u00e9 non \u00e8 pi\u00f9 una chimera pensare a un piano di aiuti all\u2019Africa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-02T14:36:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\\\/\"},\"author\":{\"name\":\"francescoM\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/d5f95c80d81b6d6ff3b13256e4009e8e\"},\"headline\":\"Nel Corno d\u2019Africa \u2018scoppia\u2019 la pace: \u00e8 il momento di aiutarli con #Africainfamiglia\",\"datePublished\":\"2018-10-02T14:36:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\\\/\"},\"wordCount\":631,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/etiopia-eritrea_700x460.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\\\/\",\"name\":\"Nel Corno d\u2019Africa \u2018scoppia\u2019 la pace: \u00e8 il momento di aiutarli con #Africainfamiglia - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/etiopia-eritrea_700x460.jpg\",\"datePublished\":\"2018-10-02T14:36:19+00:00\",\"description\":\"Africa. Qualcosa sta cambiando, ed \u00e8 parecchio significativo per il Corno d\u2019Africa: dopo decenni di conflitti, morte e impoverimento della popolazione, finalmente sembra che nel silenzio generale dei media la fine delle lotte tra Paesi confinanti possa diventare una realt\u00e0. Ecco perch\u00e9 non \u00e8 pi\u00f9 una chimera pensare a un piano di aiuti all\u2019Africa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/etiopia-eritrea_700x460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/etiopia-eritrea_700x460.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nel Corno d\u2019Africa \u2018scoppia\u2019 la pace: \u00e8 il momento di aiutarli con #Africainfamiglia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/d5f95c80d81b6d6ff3b13256e4009e8e\",\"name\":\"francescoM\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescom\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nel Corno d\u2019Africa \u2018scoppia\u2019 la pace: \u00e8 il momento di aiutarli con #Africainfamiglia - Ai.Bi. Amici dei Bambini","description":"Africa. Qualcosa sta cambiando, ed \u00e8 parecchio significativo per il Corno d\u2019Africa: dopo decenni di conflitti, morte e impoverimento della popolazione, finalmente sembra che nel silenzio generale dei media la fine delle lotte tra Paesi confinanti possa diventare una realt\u00e0. Ecco perch\u00e9 non \u00e8 pi\u00f9 una chimera pensare a un piano di aiuti all\u2019Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/","og_locale":"it_IT","og_type":"article","og_title":"Nel Corno d\u2019Africa \u2018scoppia\u2019 la pace: \u00e8 il momento di aiutarli con #Africainfamiglia","og_description":"Africa. Qualcosa sta cambiando, ed \u00e8 parecchio significativo per il Corno d\u2019Africa: dopo decenni di conflitti, morte e impoverimento della popolazione, finalmente sembra che nel silenzio generale dei media la fine delle lotte tra Paesi confinanti possa diventare una realt\u00e0. Ecco perch\u00e9 non \u00e8 pi\u00f9 una chimera pensare a un piano di aiuti all\u2019Africa","og_url":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2018-10-02T14:36:19+00:00","og_image":[{"width":700,"height":460,"url":"https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460.jpg","type":"image\/jpeg"}],"author":"francescoM","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoM","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/"},"author":{"name":"francescoM","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/d5f95c80d81b6d6ff3b13256e4009e8e"},"headline":"Nel Corno d\u2019Africa \u2018scoppia\u2019 la pace: \u00e8 il momento di aiutarli con #Africainfamiglia","datePublished":"2018-10-02T14:36:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/"},"wordCount":631,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/","url":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/","name":"Nel Corno d\u2019Africa \u2018scoppia\u2019 la pace: \u00e8 il momento di aiutarli con #Africainfamiglia - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460.jpg","datePublished":"2018-10-02T14:36:19+00:00","description":"Africa. Qualcosa sta cambiando, ed \u00e8 parecchio significativo per il Corno d\u2019Africa: dopo decenni di conflitti, morte e impoverimento della popolazione, finalmente sembra che nel silenzio generale dei media la fine delle lotte tra Paesi confinanti possa diventare una realt\u00e0. Ecco perch\u00e9 non \u00e8 pi\u00f9 una chimera pensare a un piano di aiuti all\u2019Africa","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/etiopia-eritrea_700x460.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/nel-corno-dafrica-scoppia-la-pace-e-il-momento-di-aiutarli-con-africainfamiglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Nel Corno d\u2019Africa \u2018scoppia\u2019 la pace: \u00e8 il momento di aiutarli con #Africainfamiglia"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/d5f95c80d81b6d6ff3b13256e4009e8e","name":"francescoM","url":"https:\/\/www.aibi.it\/ita\/author\/francescom\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:11:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/159358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=159358"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/159358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/159256"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=159358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=159358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=159358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}