﻿{"id":160616,"date":"2018-11-20T13:19:37","date_gmt":"2018-11-20T12:19:37","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=160616"},"modified":"2018-11-20T15:28:56","modified_gmt":"2018-11-20T14:28:56","slug":"trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/","title":{"rendered":"Trasmissione Radio Mater: si parla del rilancio dell&#8217;adozione internazionale"},"content":{"rendered":"<h2>Intervista con Pietro Ardizzi e una testimonianza sul miracolo dell&#8217;adozione<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-158512 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/ulss-sabati-adozione_700x460-457x300.jpg\" alt=\"\" width=\"411\" height=\"270\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/ulss-sabati-adozione_700x460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/ulss-sabati-adozione_700x460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/ulss-sabati-adozione_700x460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/ulss-sabati-adozione_700x460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/ulss-sabati-adozione_700x460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/ulss-sabati-adozione_700x460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/ulss-sabati-adozione_700x460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/ulss-sabati-adozione_700x460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/ulss-sabati-adozione_700x460-165x109.jpg 165w\" sizes=\"auto, (max-width: 411px) 100vw, 411px\" \/>Questo pomeriggio, marted\u00ec 20 novembre, in onda il consueto appuntamento con la trasmissione\u00a0<strong>Radio Mater<\/strong>. Tema della puntata la possibilit\u00e0 di rilanciare l\u2019adozione internazionale e una testimonianza sulla meravigliosa esperienza del diventare genitori adottivi.<\/p>\n<p><strong>Ore 17.30 introduzione e saluti con Ermes Carretta e, a seguire, la bella notizia del mese<\/strong><\/p>\n<p><strong>Ore 17.40 Pietro Ardizzi: l&#8217;adozione internazionale si pu\u00f2 rilanciare?<\/strong><\/p>\n<p><strong>Ore 18.05 Carla e Luca: l&#8217;adozione \u00e8 una cosa meravigliosa. Il miracolo dell&#8217;adozione<\/strong><\/p>\n<p><strong>Ore 18.30 chiusura della trasmissione<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Intervista con Pietro Ardizzi e una testimonianza sul miracolo dell&rsquo;adozione Questo pomeriggio, marted&igrave; 20 novembre, in onda il consueto appuntamento con la trasmissione&nbsp;Radio Mater. Tema della puntata la possibilit&agrave; di rilanciare l&rsquo;adozione internazionale e una testimonianza sulla meravigliosa esperienza del diventare genitori adottivi. Ore 17.30 introduzione e saluti con Ermes [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":160173,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[279,282,281,280],"class_list":["post-160616","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-adozione","tag-miracolo","tag-pietro-ardizzi","tag-radio-mater"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Trasmissione Radio Mater: si parla del rilancio dell&#039;adozione internazionale - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Radio Mater: si parla del rilancio dell&#039;adozione internazionale\" \/>\n<meta property=\"og:description\" content=\"Intervista con Pietro Ardizzi e una testimonianza sul miracolo dell&#039;adozione su Radio Mater\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-20T12:19:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-20T14:28:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-psiconalista_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Trasmissione Radio Mater: si parla del rilancio dell&#039;adozione internazionale\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Trasmissione Radio Mater: si parla del rilancio dell&#8217;adozione internazionale\",\"datePublished\":\"2018-11-20T12:19:37+00:00\",\"dateModified\":\"2018-11-20T14:28:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\\\/\"},\"wordCount\":96,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-internazionale-psiconalista_fb.jpg\",\"keywords\":[\"adozione\",\"miracolo\",\"Pietro Ardizzi\",\"Radio Mater\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\\\/\",\"name\":\"Trasmissione Radio Mater: si parla del rilancio dell'adozione internazionale - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-internazionale-psiconalista_fb.jpg\",\"datePublished\":\"2018-11-20T12:19:37+00:00\",\"dateModified\":\"2018-11-20T14:28:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-internazionale-psiconalista_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-internazionale-psiconalista_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Trasmissione Radio Mater: si parla del rilancio dell&#8217;adozione internazionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Trasmissione Radio Mater: si parla del rilancio dell'adozione internazionale - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/","og_locale":"it_IT","og_type":"article","og_title":"Radio Mater: si parla del rilancio dell'adozione internazionale","og_description":"Intervista con Pietro Ardizzi e una testimonianza sul miracolo dell'adozione su Radio Mater","og_url":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2018-11-20T12:19:37+00:00","article_modified_time":"2018-11-20T14:28:56+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-psiconalista_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Trasmissione Radio Mater: si parla del rilancio dell'adozione internazionale","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Trasmissione Radio Mater: si parla del rilancio dell&#8217;adozione internazionale","datePublished":"2018-11-20T12:19:37+00:00","dateModified":"2018-11-20T14:28:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/"},"wordCount":96,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-psiconalista_fb.jpg","keywords":["adozione","miracolo","Pietro Ardizzi","Radio Mater"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/","url":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/","name":"Trasmissione Radio Mater: si parla del rilancio dell'adozione internazionale - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-psiconalista_fb.jpg","datePublished":"2018-11-20T12:19:37+00:00","dateModified":"2018-11-20T14:28:56+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-psiconalista_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-psiconalista_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/trasmissione-radio-mater-si-parla-del-rilancio-delladozione-internazionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Trasmissione Radio Mater: si parla del rilancio dell&#8217;adozione internazionale"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:50:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/160616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=160616"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/160616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/160173"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=160616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=160616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=160616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}