﻿{"id":16207,"date":"2010-10-04T16:06:02","date_gmt":"2010-10-04T15:06:02","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=16207"},"modified":"2010-10-04T16:09:10","modified_gmt":"2010-10-04T15:09:10","slug":"adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/","title":{"rendered":"Adozione contro aborto: le domande dell\u2019On. Mussolini"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-16195\" style=\"margin: 5px;\" title=\"alessandra mussolini\" src=\"https:\/\/www.aibi.it\/ita\/images\/mussolini_ales.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Nel dibattito in corso sull\u2019adozione dei bambini appena nati dagli USA, si \u00e8 inserita anche la <strong>Presidente della Commissione bicamerale per l\u2019infanzia<\/strong>, <strong>On. Alessandra Mussolini<\/strong>, che teme il via ad <em>\u201cuna compravendita inaccettabile\u201d<\/em>. <em>\u201cChi seguirebbe le coppie?\u201d, <\/em><em>\u201cchi prenderebbe i bambini pi\u00f9 grandicelli\u201d<\/em>, <em>\u201c\u00e8 davvero una pratica che riduce gli aborti?\u201d<\/em>: tanti i quesiti posti dalla Presidente, alcuni anche legittimi, a cui <strong>Ai.Bi.<\/strong> tenta di dare oggi una risposta.<\/p>\n<p>In questa procedura <strong>non c\u2019\u00e8 spazio per il mercato<\/strong>: adozione diretta non vuol dire adozione \u201cfai da te\u201d quando si tratta di adozioni monitorate dagli enti autorizzati. Nelle adozioni proposte da Ai.Bi. la procedura sarebbe seguita, sin dall\u2019inizio e fino al periodo post-adottivo, dagli enti autorizzati dei due paesi. La famiglia d\u2019origine \u00e8 consigliata e seguita dagli esperti delle agenzie statunitensi, mentre quella adottiva residente all\u2019estero sarebbe seguita dall\u2019ente autorizzato del Paese ricevente, come gi\u00e0 avviene per ogni altra procedura rispettosa della Convenzione de L\u2019Aja del 1993 sulla cooperazione in materia di adozione internazionale, ratificata dagli Stati Uniti. Non c\u2019\u00e8 compravendita non essendoci alcun denaro che passa direttamente in mano tra le due famiglie.<\/p>\n<p>Nella procedura di adozione dei neonati dagli USA, tutta la fase che va dalla <strong>consulenza alle gestanti <\/strong>alla nascita del minore, e poi fino all\u2019accompagnamento delle madri nella scelta di consentire all\u2019adozione del proprio figlio dinanzi al Giudice statunitense, \u00e8 sotto la responsabilit\u00e0 dello Stato americano che segue le proprie procedure. Tali procedure, oltre ad essere conformi alla Convenzione de L\u2019Aja, garantiscono alla madre il diritto di prendere una scelta consapevole e meditata.<\/p>\n<p>Quanto alla temuta riduzione dell\u2019adozione dei minori pi\u00f9 grandicelli, si tratta di una preoccupazione che esula dal punto della questione: se non trovano una famiglia idonea negli USA i minori appena nati dichiarati adottabili vengono comunque inseriti nel sistema dell\u2019affidamento tramite \u201cfoster care\u201d in attesa che si trovi una diversa famiglia. E\u2019 noto, invece, che &#8211; secondo il <strong>principio di sussidiariet\u00e0<\/strong> &#8211; trovare immediatamente una famiglia stabile corrisponde al superiore interesse del minore piuttosto che essere affidato in via temporanea.<\/p>\n<p>Secondo l\u2019On. Mussolini <em>\u201cnon si possono fare le liberalizzazioni sui bambini\u201d. <\/em>Quelle che Ai.Bi. ha proposto, per\u00f2, non sono certo liberalizzazioni, n\u00e9 procedure volte a <em>\u201ctogliere regole a garanzia dei pi\u00f9 piccoli\u201d<\/em> ma si tratta, al contrario, dell\u2019inclusione, tra le \u201ccandidature\u201d per queste adozioni, di coppie idonee residenti in Italia che possano contribuire a dare ai pi\u00f9 piccoli la garanzia di trovare immediatamente una famiglia, nel momento in cui ne viene dichiarata l\u2019adottabilit\u00e0, senza dovere attendere che l\u2019ingresso nel circolo del \u201cfoster care\u201d imprima nelle loro anime gli indelebili segni di una vita \u201cfuori famiglia\u201d.<\/p>\n<p>La vera novit\u00e0 per l\u2019Italia \u00e8 il riconoscimento alle madri un ruolo fondamentale e responsabilizzato nella scelta del futuro del proprio figlio, qualunque sia questo futuro: la madre statunitense \u00e8 inclusa tra i soggetti  che operano la scelta della famiglia adottiva; <strong>non sceglie per\u00f2 da sola<\/strong>: la selezione \u00e8 limitata alle famiglie gi\u00e0 dichiarate idonee e, comunque, sia gli esperti autorizzati dei due paesi che il giudice competente devono confermare quella scelta. Sono adozioni <strong>rigorosamente giudiziali<\/strong>.<\/p>\n<p>L\u2019incidenza che questa procedura pu\u00f2 avere nell\u2019ottica di<strong> combattere gli aborti <\/strong>\u00e8 un quesito che potrebbe e dovrebbe essere posto \u2013 insieme ad altri &#8211; direttamente alle autorit\u00e0 e agli esperti statunitensi, che potrebbero fornirci ottimi spunti per sviluppare le attivit\u00e0 da realizzare in Italia in adempimento della legge che regolamenta la pratica dell\u2019aborto. L\u2019Italia dovrebbe, da parte sua, occuparsi dell\u2019attuazione degli articoli 1 e 2 della legge n. 194\/1978 non essendosi ancora giunti sul territorio nazionale ad una realizzazione capillare degli interventi necessari a sostenere la maternit\u00e0 ed ogni scelta ad essa collegata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel dibattito in corso sull\u2019adozione dei bambini appena nati dagli USA, si \u00e8 inserita anche la <strong>Presidente della Commissione bicamerale per l\u2019infanzia On. Alessandra Mussolini<\/strong>, che teme il via ad <em>\u201cuna compravendita inaccettabile\u201d. \u201cChi seguirebbe le coppie?\u201d,<\/em> <em>\u201cchi prenderebbe i bambini pi\u00f9 grandicelli<\/em>\u201d, <em>\u201c\u00e8 davvero una pratica che riduce gli aborti?\u201d<\/em>: tanti i quesiti posti dalla Presidente, alcuni anche legittimi, a cui<strong> Ai.Bi.<\/strong> tenta di dare oggi una risposta.<a rel=\"attachment wp-att-16208\" href=\"https:\/\/www.aibi.it\/ita\/?attachment_id=16208\"><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-16207","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione contro aborto: le domande dell\u2019On. Mussolini - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell\u2019on-mussolini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione contro aborto: le domande dell\u2019On. Mussolini\" \/>\n<meta property=\"og:description\" content=\"Nel dibattito in corso sull\u2019adozione dei bambini appena nati dagli USA, si \u00e8 inserita anche la Presidente della Commissione bicamerale per l\u2019infanzia On. Alessandra Mussolini, che teme il via ad \u201cuna compravendita inaccettabile\u201d. \u201cChi seguirebbe le coppie?\u201d, \u201cchi prenderebbe i bambini pi\u00f9 grandicelli\u201d, \u201c\u00e8 davvero una pratica che riduce gli aborti?\u201d: tanti i quesiti posti dalla Presidente, alcuni anche legittimi, a cui Ai.Bi. tenta di dare oggi una risposta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell\u2019on-mussolini\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-04T15:06:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-10-04T15:09:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/mussolini_ales.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozione contro aborto: le domande dell\u2019On. Mussolini\",\"datePublished\":\"2010-10-04T15:06:02+00:00\",\"dateModified\":\"2010-10-04T15:09:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\\\/\"},\"wordCount\":621,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/mussolini_ales.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\\\/\",\"name\":\"Adozione contro aborto: le domande dell\u2019On. Mussolini - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/mussolini_ales.jpg\",\"datePublished\":\"2010-10-04T15:06:02+00:00\",\"dateModified\":\"2010-10-04T15:09:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/mussolini_ales.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/mussolini_ales.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione contro aborto: le domande dell\u2019On. Mussolini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione contro aborto: le domande dell\u2019On. Mussolini - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell\u2019on-mussolini\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione contro aborto: le domande dell\u2019On. Mussolini","og_description":"Nel dibattito in corso sull\u2019adozione dei bambini appena nati dagli USA, si \u00e8 inserita anche la Presidente della Commissione bicamerale per l\u2019infanzia On. Alessandra Mussolini, che teme il via ad \u201cuna compravendita inaccettabile\u201d. \u201cChi seguirebbe le coppie?\u201d, \u201cchi prenderebbe i bambini pi\u00f9 grandicelli\u201d, \u201c\u00e8 davvero una pratica che riduce gli aborti?\u201d: tanti i quesiti posti dalla Presidente, alcuni anche legittimi, a cui Ai.Bi. tenta di dare oggi una risposta.","og_url":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell\u2019on-mussolini\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-10-04T15:06:02+00:00","article_modified_time":"2010-10-04T15:09:10+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/mussolini_ales.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozione contro aborto: le domande dell\u2019On. Mussolini","datePublished":"2010-10-04T15:06:02+00:00","dateModified":"2010-10-04T15:09:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/"},"wordCount":621,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/mussolini_ales.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/","url":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/","name":"Adozione contro aborto: le domande dell\u2019On. Mussolini - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/mussolini_ales.jpg","datePublished":"2010-10-04T15:06:02+00:00","dateModified":"2010-10-04T15:09:10+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/mussolini_ales.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/mussolini_ales.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-contro-aborto-le-domande-dell%e2%80%99on-mussolini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozione contro aborto: le domande dell\u2019On. Mussolini"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:37:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=16207"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16207\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=16207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=16207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=16207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}