﻿


{"id":162447,"date":"2018-10-24T09:53:44","date_gmt":"2018-10-24T07:53:44","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=162447"},"modified":"2019-02-06T09:54:41","modified_gmt":"2019-02-06T08:54:41","slug":"storie-di-conciliazione-lavoro-famiglia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/","title":{"rendered":"Storie di conciliazione lavoro-famiglia"},"content":{"rendered":"<p>Vari aspetti legati alla famiglia, alla condizione dell\u2019anziano fragile o dei bambini con disabilit\u00e0, tra situazioni specifiche e impegnative, per tratteggiare alla fine un racconto fatto di storie provenienti da diverse citt\u00e0 d\u2019Italia: consiste in questo \u201cIeri come oggi. Storie di conciliazione lavoro-famiglia\u201d, il nuovo documentario di Alessia Bottone, che tratta di un tema quanto mai attuale, come quello della conciliazione tra il lavoro e la famiglia, e che verr\u00e0 presentato il 29 ottobre a Verona<\/p>\n<p>Verr\u00e0 presentato il\u00a0<strong>29 ottobre<\/strong>\u00a0prossimo a\u00a0<strong>Verona<\/strong>, presso la Sala Convegni del Palazzo della Gran Guardia, il documentario intitolato\u00a0<strong><em>Ieri come oggi. Storie di conciliazione lavoro-famiglia<\/em><\/strong>, realizzato dalla giornalista e regista\u00a0<strong>Alessia Bottone<\/strong>\u00a0\u2013 gi\u00e0 ben nota ai nostri Lettori per docufilm quali\u00a0<em><a href=\"http:\/\/www.superando.it\/2017\/10\/09\/vorrei-ma-non-posso-ovvero-il-sogno-di-una-vita-alla-pari\/\"><strong>Vorrei ma non posso: quando le barriere architettoniche limitano i sogni<\/strong><\/a><\/em>\u00a0e\u00a0<em><a href=\"https:\/\/www.cinemaitaliano.info\/ritrattiincontroluce\"><strong>Ritratti in controluce. Cecit\u00e0, stereotipi e successi a confronto<\/strong><\/a><\/em>\u00a0\u2013 grazie al sostegno della Fondazione Cattolica Assicurazioni, con il contributo della Societ\u00e0 AGSM Verona, di Endes-Organizzazione Eventi e Globo Giocattoli.<br \/>\nL\u2019evento, co-organizzato dall\u2019Assessorato alle Pari Opportunit\u00e0 del Comune di Verona, sar\u00e0 aperto al pubblico e patrocinato dal Consiglio Regionale del Veneto, dall\u2019Ufficio della Consigliera di Parit\u00e0 Citt\u00e0 Metropolitana di Napoli, dalla Provincia di Verona, dal Comune di Padova, dall\u2019Ordine dei Giornalisti del Veneto, dalla Lega del Filo d\u2019Oro, dalla FAND (Federazione tra le Associazioni Nazionali delle Persone con Disabilit\u00e0), dalla CISL del Veneto e dal Centro Servizi Volontariato di Verona.<\/p>\n<p><em>Ieri come oggi\u00a0<\/em>concede uno spazio di approfondimento, dando voce alle mamme, ai pap\u00e0, ai nonni, agli imprenditori, ma anche alle Associazioni e alle Istituzioni locali e nazionali che, con modalit\u00e0 diverse, si occupano di fornire risposte concrete, servizi e assistenza per ci\u00f2 che concerne la\u00a0<strong>conciliazione dei tempi di vita e di lavoro<\/strong>. Lo scopo principale \u00e8 mettere in evidenza le reali necessit\u00e0 e i bisogni delle famiglie moderne, letteralmente \u201cincastrate\u201d in una vita frenetica che non concede molto spazio agli affetti.<br \/>\nIl ruolo di noi donne \u2013 sia nell\u2019\u00e0mbito domestico che in quello lavorativo \u2013 \u00e8 sempre messo davanti a\u00a0<strong>scelte difficili<\/strong>: \u00e8 meglio favorire la carriera lavorativa, trascurando la famiglia e i figli? Il mondo del lavoro non d\u00e0 spazio a valutazioni: l\u2019impegno \u00e8 costante e quasi mai si concilia con il resto del tempo da dedicare ai figli o genitori anziani.<br \/>\nPersonalmente, anch\u2019io che scrivo vivo questa \u201cesperienza\u201d di madre che lavora; una volta mi \u00e8 stato detto: \u00abNella vita \u00e8 una questione di scelte\u00bb; ma non lo ritengo giusto, anzi,\u00a0 trovo riduttivo pensare di trovarmi di fronte ad un bivio su quale sia la strada \u201cgiusta\u201d da percorrere. Quella della crescita lavorativa o quella della famiglia, dove senz\u2019altro potrei trovare il calore e l\u2019affetto che servono per riempire la mia vita della vera\u00a0<em>Felicit\u00e0.\u00a0<\/em>No, non \u00e8 certo solo una questione di scelte, ma\u00a0<strong>spesso \u00e8 una necessit\u00e0<\/strong>, per mandare avanti una famiglia quando un solo stipendio non basta.<\/p>\n<p>Nel documentario di Alessia Bottone, lo sguardo si posa in particolare su vari aspetti legati alla\u00a0<strong>famiglia<\/strong>, sulla condizione dell\u2019<strong>anziano fragile<\/strong>, dei\u00a0<strong>bambini con disabilit\u00e0<\/strong>, proponendo quindi situazioni specifiche ed impegnative.<br \/>\n\u00c8 un vero e proprio percorso che attraversa\u00a0<strong>otto citt\u00e0<\/strong>, da Nord a Sud d\u2019Italia, da Belluno a Napoli, ponendo sotto i riflettori anche Confindustria, l\u2019Assessorato alle Pari Opportunit\u00e0 del Comune di Padova, la Consigliera alle Pari Opportunit\u00e0 della Citt\u00e0 Metropolitana di Napoli, i Sindacati UIL e CISL, un\u2019Associazione come la Lega del Filo d\u2019Oro, impegnata da oltre cinquant\u2019anni sul fronte della\u00a0<strong>sordocecit\u00e0<\/strong>, e molte aziende.<br \/>\nIl documentario \u2013 ed \u00e8 anche ci\u00f2 che accadr\u00e0 durante l\u2019evento di Verona \u2013 analizza la normativa vigente, le forme di lavoro flessibile, il welfare aziendale e i progetti di mutuo aiuto per genitori.<br \/>\n<strong>Tanti sono i quesiti<\/strong>\u00a0che emergono: dalla carenza di posti negli asili pubblici, ai costi di iscrizione, dalla necessit\u00e0 di ripensare agli orari di apertura e chiusura degli asili per rispondere alle esigenze dei genitori che lavorano a turni, all\u2019innalzamento dell\u2019et\u00e0 pensionabile che rende i nonni indisponibili per ci\u00f2 che riguarda la cura dei nipoti, fino alla paura di un possibile licenziamento in seguito alla gravidanza.<br \/>\nE c\u2019\u00e8 anche un riferimento \u00a0al passato e alla condizione della lavoratrice madre italiana negli Anni Sessanta, una comparazione resa possibile grazie a cinegiornali e documentari dell\u2019epoca, messi a disposizione dalla\u00a0<strong>Fondazione Aamod\u00a0<\/strong>(Archivio Audiovisivo del Movimento Operaio e Democratico) e montati ad arte da\u00a0<strong>Francesca Stella<\/strong>.<\/p>\n<p><em>Ieri come oggi\u00a0<\/em>non si limita a definire il quadro della situazione attuale, ma si focalizza anche\u00a0<strong>sui progetti e sulle persone<\/strong>\u00a0che, giorno dopo giorno, si impegnano per raggiungere un obiettivo comune:\u00a0<strong>tutelare la maternit\u00e0 quale valore sociale<\/strong>.<br \/>\nUna madre che lavora ha bisogno di maggiori tutele, ha bisogno di essere gratificata con la giusta qualifica, con uno stipendio adeguato, ma soprattutto ha la necessit\u00e0 di poter conciliare il lavoro con la famiglia. Da sempre il suo ruolo \u00e8 considerato fondamentale ed \u00e8 riconosciuto a livello sociale, come un pilastro fondamentale della famiglia. Ma\u00a0<strong>quante responsabilit\u00e0 ci sono nell\u2019universo femminile?<\/strong>\u00a0La famiglia, la gestione della casa, il lavoro, l\u2019educazione dei figli, una complessit\u00e0 di relazioni che ci impegnano quotidianamente.<br \/>\nOltre al mestiere svolto, infatti, ne esiste uno probabilmente ancor pi\u00f9 impegnativo, a cui le donne non possono venir meno: quello di mamme. Questo \u00e8 fondamentale per la crescita della famiglia.<br \/>\nA tal proposito, \u00e8 opportuno ricordare il messaggio diffuso a suo tempo, in occasione di una\u00a0<strong>Giornata Internazionale della Famiglia<\/strong>, nel mese di maggio, dall\u2019allora segretario generale delle Nazioni Unite\u00a0<strong>Ban Ki-moon<\/strong>, quando rimarc\u00f2 \u00abl\u2019importanza delle mamme e del loro inestimabile contributo nel crescere le future generazioni; solo ricompensando i loro sforzi e migliorando le condizioni di vita \u2013 e qui aggiungerei anche di lavoro \u2013 delle donne, possiamo assicurare migliore futuro per tutti\u00bb.<br \/>\nDa qui, pertanto \u00a0cresce l\u2019esigenza di trovare quelle\u00a0<strong>reali politiche per le pari opportunit\u00e0<\/strong>, all\u2019insegna, per\u00f2, di un aiuto e un supporto concreto verso le donne, perch\u00e9 possano conciliare lavoro e famiglia senza trascurare il ruolo di madri, cos\u00ec fondamentale per ciascuno di noi.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: superando.it24<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vari aspetti legati alla famiglia, alla condizione dell&rsquo;anziano fragile o dei bambini con disabilit&agrave;, tra situazioni specifiche e impegnative, per tratteggiare alla fine un racconto fatto di storie provenienti da diverse citt&agrave; d&rsquo;Italia: consiste in questo &ldquo;Ieri come oggi. Storie di conciliazione lavoro-famiglia&rdquo;, il nuovo documentario di Alessia Bottone, che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[],"class_list":["post-162447","post","type-post","status-publish","format-standard","category-family-audit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Storie di conciliazione lavoro-famiglia - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Storie di conciliazione lavoro-famiglia\" \/>\n<meta property=\"og:description\" content=\"Vari aspetti legati alla famiglia, alla condizione dell&rsquo;anziano fragile o dei bambini con disabilit&agrave;, tra situazioni specifiche e impegnative, per tratteggiare alla fine un racconto fatto di storie provenienti da diverse citt&agrave; d&rsquo;Italia: consiste in questo &ldquo;Ieri come oggi. Storie di conciliazione lavoro-famiglia&rdquo;, il nuovo documentario di Alessia Bottone, che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-24T07:53:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-06T08:54:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/storie-di-conciliazione-lavoro-famiglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/storie-di-conciliazione-lavoro-famiglia\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Storie di conciliazione lavoro-famiglia\",\"datePublished\":\"2018-10-24T07:53:44+00:00\",\"dateModified\":\"2019-02-06T08:54:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/storie-di-conciliazione-lavoro-famiglia\\\/\"},\"wordCount\":1001,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"Family Audit\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/storie-di-conciliazione-lavoro-famiglia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/storie-di-conciliazione-lavoro-famiglia\\\/\",\"name\":\"Storie di conciliazione lavoro-famiglia - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2018-10-24T07:53:44+00:00\",\"dateModified\":\"2019-02-06T08:54:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/storie-di-conciliazione-lavoro-famiglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/storie-di-conciliazione-lavoro-famiglia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/storie-di-conciliazione-lavoro-famiglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Family Audit\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/family-audit\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Storie di conciliazione lavoro-famiglia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Storie di conciliazione lavoro-famiglia - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/","og_locale":"it_IT","og_type":"article","og_title":"Storie di conciliazione lavoro-famiglia","og_description":"Vari aspetti legati alla famiglia, alla condizione dell&rsquo;anziano fragile o dei bambini con disabilit&agrave;, tra situazioni specifiche e impegnative, per tratteggiare alla fine un racconto fatto di storie provenienti da diverse citt&agrave; d&rsquo;Italia: consiste in questo &ldquo;Ieri come oggi. Storie di conciliazione lavoro-famiglia&rdquo;, il nuovo documentario di Alessia Bottone, che [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2018-10-24T07:53:44+00:00","article_modified_time":"2019-02-06T08:54:41+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Storie di conciliazione lavoro-famiglia","datePublished":"2018-10-24T07:53:44+00:00","dateModified":"2019-02-06T08:54:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/"},"wordCount":1001,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["Family Audit"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/","url":"https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/","name":"Storie di conciliazione lavoro-famiglia - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2018-10-24T07:53:44+00:00","dateModified":"2019-02-06T08:54:41+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/storie-di-conciliazione-lavoro-famiglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Family Audit","item":"https:\/\/www.aibi.it\/ita\/category\/family-audit\/"},{"@type":"ListItem","position":3,"name":"Storie di conciliazione lavoro-famiglia"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:40:55","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/162447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=162447"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/162447\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=162447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=162447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=162447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}