﻿


{"id":163175,"date":"2019-03-08T16:27:05","date_gmt":"2019-03-08T15:27:05","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=163175"},"modified":"2019-03-12T17:12:22","modified_gmt":"2019-03-12T16:12:22","slug":"adozioni-congo-archiviata-indagine-infondatezza-reato-aibi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/","title":{"rendered":"Adozioni Congo. Archiviata indagine su Ai.Bi. per totale infondatezza di notizia di reato"},"content":{"rendered":"<h2>Le accuse contro Ai.Bi. sono totalmente infondate. Scritta la parola fine alla stagione dei veleni. Il ringraziamento di Ai.Bi. a famiglie, sostenitori e amici<\/h2>\n<h3>Marco Griffini, presidente di Ai.Bi. \u201c<em>Ringrazio a nome dell\u2019Associazione quanti hanno creduto nell\u2019infondatezza delle accuse mosse contro Ai.Bi. e ci hanno dato la forza e la determinazione a continuare, con rinnovato slancio, la strada intrapresa insieme pi\u00f9 di 35 anni fa <\/em>\u201d<\/h3>\n<p class=\"Default\"><span style=\"font-size: 11.0pt;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-163169\" src=\"https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/><\/a>Nel rispetto delle famiglie e dei minori coinvolti nella vicenda delle adozioni in <strong>Repubblica Democratica del Congo<\/strong>, i principali danneggiati, Amici dei Bambini ringrazia e manifesta profonda e immensa gratitudine a quanti, e sono tantissimi, hanno creduto all\u2019infondatezza delle accuse, dimostrando solidariet\u00e0, stima e affetto nei confronti di Amici dei Bambini e dei suoi collaboratori. <\/span><\/p>\n<p>Fiducia nello svolgimento del delicato ruolo di difesa e tutela del diritto di ogni bambino a vivere e crescere in famiglia, che trova riscontro nella decisione del Tribunale di Milano di procedere con l\u2019archiviazione delle indagini su presunte irregolarit\u00e0 nelle procedure adottive di Amici dei Bambini in Repubblica Democratica del Congo.<\/p>\n<p>Accogliendo la richiesta della Procura di Milano del 2 gennaio 2018, presentata al GIP il 15 febbraio 2018, il <b>decreto di archiviazione del Tribunale di Milano del 5 marzo 2019 ordina l&#8217;archiviazione del procedimento di indagine preliminare per &#8220;infondatezza della notizia di reato&#8221;<\/b>, <b>pertanto tutte le accuse mosse contro i vertici di Ai.Bi. risultano totalmente prive di qualsiasi fondamento. <\/b><\/p>\n<p>Si mette cos\u00ec la parola \u201cfine&#8221; alla stagione dei veleni nelle adozioni internazionali in Italia<span style=\"font-size: 11.0pt;\">, inaugurata, nel lontano giugno 2014, dall&#8217;allora Vicepresidente della Commissione per le Adozioni Internazionali (CAI), Silvia Della Monica, con la strumentalizzazione di vicende legate allo svolgimento delle procedure adottive di alcuni minori provenienti dalla Repubblica Democratica del Congo, sfociate in un esposto contro Ai.Bi. e all\u2019avvio delle indagini preliminari.<\/span><\/p>\n<p><span style=\"font-size: 11.0pt;\"><br \/>\n&#8220;Il voluminoso esposto, di oltre 600 pagine, presentato dall&#8217;allora Vicepresidente della CAI, viene definito dal GIP di Milano &#8221; [\u2026] <b><i>un assemblamento storico e cronologico di atti tradotti dalla lingua francese, privo di un impianto accusatorio preciso e di una concreta formulazione di un&#8217;ipotesi di reato a carico degli esponenti di Ai.Bi<\/i><\/b>.&#8221;<br \/>\nAltres\u00ec, lo stesso GIP, in ben 31 pagine di decreto di archiviazione, in una disamina delle vicende connesse alle accuse rivolte all\u2019 Associazione, chiarisce il ruolo attivo avuto dall&#8217;ente autorizzato, e, in particolare, dal presidente Marco Griffini, nell&#8217; &#8220;<b><i>ammonire a gran voce in Italia, nell\u2019interesse dei minori e delle coppie adottandi in Italia, che la condotta posta in essere dalla C.A.I., rischiava di compromettere ogni possibilit\u00e0 di collaborazione con le autorit\u00e0 congolesi e di dar vita ad uno scontro istituzionale a tutto svantaggio degli aspiranti genitori e dei loro bambini<\/i>&#8220;. <\/b><\/span><\/p>\n<p><span style=\"font-size: 11.0pt;\"><br \/>\nIl Tribunale di Milano sottolinea come, nella gestione di parti delle procedure adottive in RDC, la scelta della <b>Presidente della CAI <\/b>&#8211; all\u2019epoca investita, su delega dell\u2019allora premier, anche delle funzioni di Presidente \u2013 abbia <b>\u201c <\/b>[\u2026] <b><i>all&#8217;evidenza travalicato i propri poteri istituzionali e commesso un abuso di potere<\/i>\u201d <\/b>giustamente censurato dalle autorit\u00e0 del paese africano.<br \/>\nComportamento che &#8211; come notato dal GIP in base alle circa 3 mila pagine dei documenti delle indagini -&#8220;<b><i>in concreto non ha certo agevolato il buon esito della vicenda<\/i><\/b>&#8220;.<br \/>\n\u201c<i>Con il decreto di archiviazione del Tribunale di Milano, cala definitivamente il sipario su un triste capitolo delle adozioni internazionali in Italia che ha danneggiato in primis i minori e le famiglie coinvolte <\/i>\u2013 <b>\u00e8 il commento di Marco Griffini, presidente di Ai.Bi. <\/b>\u2013 <i>A nome dell\u2019Associazione un doveroso e sentito ringraziamento alle famiglie adottive e affidatarie, ai sostenitori a distanza, ai donatori, ai volontari, agli amici, alle aziende, alle associazioni partner e a quanti hanno creduto nell\u2019infondatezza delle accuse mosse contro Ai.Bi. e ci hanno dato la forza e la determinazione a continuare, con rinnovato slancio, la strada intrapresa insieme pi\u00f9 di 35 anni fa<\/i>\u201d.<br \/>\nIl presidente, il consiglio direttivo e gli operatori dell\u2019Associazione Amici dei Bambini<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le accuse contro Ai.Bi. sono totalmente infondate. Scritta la parola fine alla stagione dei veleni. Il ringraziamento di Ai.Bi. a famiglie, sostenitori e amici Marco Griffini, presidente di Ai.Bi. &ldquo;Ringrazio a nome dell&rsquo;Associazione quanti hanno creduto nell&rsquo;infondatezza delle accuse mosse contro Ai.Bi. e ci hanno dato la forza e la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":163169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-163175","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni Congo. Archiviata indagine su Ai.Bi. per totale infondatezza di notizia di reato<\/title>\n<meta name=\"description\" content=\"Adozioni internazionali Congo: le accuse contro Ai.Bi. sono totalmente infondate. Scritta la parola fine alla stagione dei veleni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni Congo. Archiviata indagine su Ai.Bi. per totale infondatezza di notizia di reato\" \/>\n<meta property=\"og:description\" content=\"Adozioni internazionali Congo: le accuse contro Ai.Bi. sono totalmente infondate. Scritta la parola fine alla stagione dei veleni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-08T15:27:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-12T16:12:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni Congo. Archiviata indagine su Ai.Bi. per totale infondatezza di notizia di reato\",\"datePublished\":\"2019-03-08T15:27:05+00:00\",\"dateModified\":\"2019-03-12T16:12:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\\\/\"},\"wordCount\":661,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/archiviazione-indagine-1_700x460.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\\\/\",\"name\":\"Adozioni Congo. Archiviata indagine su Ai.Bi. per totale infondatezza di notizia di reato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/archiviazione-indagine-1_700x460.jpg\",\"datePublished\":\"2019-03-08T15:27:05+00:00\",\"dateModified\":\"2019-03-12T16:12:22+00:00\",\"description\":\"Adozioni internazionali Congo: le accuse contro Ai.Bi. sono totalmente infondate. Scritta la parola fine alla stagione dei veleni.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/archiviazione-indagine-1_700x460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/archiviazione-indagine-1_700x460.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni Congo. Archiviata indagine su Ai.Bi. per totale infondatezza di notizia di reato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni Congo. Archiviata indagine su Ai.Bi. per totale infondatezza di notizia di reato","description":"Adozioni internazionali Congo: le accuse contro Ai.Bi. sono totalmente infondate. Scritta la parola fine alla stagione dei veleni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni Congo. Archiviata indagine su Ai.Bi. per totale infondatezza di notizia di reato","og_description":"Adozioni internazionali Congo: le accuse contro Ai.Bi. sono totalmente infondate. Scritta la parola fine alla stagione dei veleni.","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2019-03-08T15:27:05+00:00","article_modified_time":"2019-03-12T16:12:22+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni Congo. Archiviata indagine su Ai.Bi. per totale infondatezza di notizia di reato","datePublished":"2019-03-08T15:27:05+00:00","dateModified":"2019-03-12T16:12:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/"},"wordCount":661,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/","name":"Adozioni Congo. Archiviata indagine su Ai.Bi. per totale infondatezza di notizia di reato","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460.jpg","datePublished":"2019-03-08T15:27:05+00:00","dateModified":"2019-03-12T16:12:22+00:00","description":"Adozioni internazionali Congo: le accuse contro Ai.Bi. sono totalmente infondate. Scritta la parola fine alla stagione dei veleni.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/archiviazione-indagine-1_700x460.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-congo-archiviata-indagine-infondatezza-reato-aibi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni Congo. Archiviata indagine su Ai.Bi. per totale infondatezza di notizia di reato"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:01:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/163175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=163175"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/163175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/163169"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=163175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=163175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=163175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}