﻿


{"id":16364,"date":"2010-10-08T16:30:53","date_gmt":"2010-10-08T15:30:53","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=16364"},"modified":"2017-04-18T12:14:48","modified_gmt":"2017-04-18T10:14:48","slug":"figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/","title":{"rendered":"Figli in attesa: una guida alle adozioni di bambini con bisogni speciali"},"content":{"rendered":"<p><strong><a href=\"http:\/\/www.aibishop.it\/shopping-solidale\/pubblicazioni\/49-figli-in-attesa-guida-alle-adozioni-di-bambini-con-bisogni-speciali.html\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-16365 size-full\" style=\"margin: 5px;\" title=\"cop_figli\" src=\"https:\/\/www.aibi.it\/ita\/images\/cop_figli.jpg\" width=\"150\" height=\"150\" \/><\/a><\/strong>Oggi le adozioni internazionali si stanno indirizzando sempre pi\u00f9 verso i minori con bisogni speciali. Eppure sono ancor tantissime le coppie che si spaventano quando sentono il termine \u201cspecial need.\u201d<\/p>\n<p>Per questo motivo Ai.Bi che oramai da molti anni sta lavorando con alcuni paesi sulle adozioni dei bambini con bisogni speciali, ha pensato di mettere a disposizione delle coppie adottive il libro <a href=\"http:\/\/www.aibishop.it\/shopping-solidale\/pubblicazioni\/49-figli-in-attesa-guida-alle-adozioni-di-bambini-con-bisogni-speciali.html\"><strong>Figli in attesa: Guida alle adozioni di bambini con bisogni speciali<\/strong><\/a>, un nuovo interessante volume edito dalla Casa editrice Ancora. disponibile in libreria e on line sul nostro e-commerce.<\/p>\n<p><strong>Tra i bambini in attesa di adozione<\/strong>, quelli con &#8220;bisogni speciali&#8221; rischiano di attendere una famiglia per sempre: l&#8217;adozione internazionale \u00e8 per loro l&#8217;unica chance per diventare figli, la sola alternativa a crescere in un orfanotrofio fino alla maggior et\u00e0.<\/p>\n<p><strong>Chi sono dunque \u00a0questi bambini con<\/strong> <strong>bisogni speciali<\/strong>? Non sono disabili, n\u00e8 hanno un handicap, ma sono bambini con pi\u00f9 di 7 anni di et\u00e0 o con qualche problema di salute risolvibile nel tempo, oppure fratelli che \u00e8 meglio non separare. Se il percorso dei bambini con \u201cbisogni speciali\u201d non \u00e8 diverso da un qualsiasi iter adottivo, alle coppie \u00e8 dunque richiesta una disponibilit\u00e0 pi\u00f9 ampia all\u2019accoglienza.<\/p>\n<p>Questa guida destinata a chi si avvicina al mondo dell\u2019adozione approfondisce i contenuti del libro <strong><a href=\"https:\/\/www.bookrepublic.it\/book\/9788851412500-ladozione-internazionale\/\" target=\"_blank\">L&#8217;adozione internazionale. 161 domande, 160 risposte<\/a>\u00a0<\/strong>e inquadra un fenomeno in espansione in tutti i Paesi, in particolar modo in Europa. Grazie a\u00a0<strong>un percorso a domande e risposte e a due questionari finali per testare la propria disponibilit\u00e0 all&#8217;adozione<\/strong>, il lettore scoprir\u00e0 che l&#8217;affetto e l&#8217;amore di due genitori \u00e8 l&#8217;unico, vero bisogno speciale di ogni bambino.<\/p>\n<p><a title=\"Aquista il libro su Aibishop\" href=\"http:\/\/www.aibishop.it\/shopping-solidale\/pubblicazioni\/49-figli-in-attesa-guida-alle-adozioni-di-bambini-con-bisogni-speciali.html\" target=\"_blank\"><strong>Acquista su Aibishop&gt;&gt;<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Disponibile\u00a0<a title=\"Figli in attesa su Aibishop\" href=\"http:\/\/www.fondazioneaibi.it\/shop\/product.php?id_product=128\" target=\"_blank\">on line <\/a>e \u00a0in libreria \u201cFigli in attesa:<\/strong> Guida alle adozioni di bambini con bisogni speciali\u201d, un nuovo interessante volume edito dalla Casa editrice Ancora.\u00a0<strong>Tra i bambini in attesa di adozione<\/strong>, quelli con &#8220;bisogni speciali&#8221; rischiano di attendere una famiglia per sempre: l&#8217;adozione internazionale \u00e8 per loro l&#8217;unica chance per diventare figli, la sola alternativa a crescere in un orfanotrofio fino alla maggior et\u00e0.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-16364","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Figli in attesa: una guida alle adozioni di bambini con bisogni speciali - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Figli in attesa: una guida alle adozioni di bambini con bisogni speciali\" \/>\n<meta property=\"og:description\" content=\"Disponibile\u00a0on line e \u00a0in libreria \u201cFigli in attesa: Guida alle adozioni di bambini con bisogni speciali\u201d, un nuovo interessante volume edito dalla Casa editrice Ancora.\u00a0Tra i bambini in attesa di adozione, quelli con &quot;bisogni speciali&quot; rischiano di attendere una famiglia per sempre: l&#039;adozione internazionale \u00e8 per loro l&#039;unica chance per diventare figli, la sola alternativa a crescere in un orfanotrofio fino alla maggior et\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-08T15:30:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-18T10:14:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/cop_figli.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Figli in attesa: una guida alle adozioni di bambini con bisogni speciali\",\"datePublished\":\"2010-10-08T15:30:53+00:00\",\"dateModified\":\"2017-04-18T10:14:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\\\/\"},\"wordCount\":290,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/cop_figli.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\\\/\",\"name\":\"Figli in attesa: una guida alle adozioni di bambini con bisogni speciali - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/cop_figli.jpg\",\"datePublished\":\"2010-10-08T15:30:53+00:00\",\"dateModified\":\"2017-04-18T10:14:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/cop_figli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/cop_figli.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Figli in attesa: una guida alle adozioni di bambini con bisogni speciali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Figli in attesa: una guida alle adozioni di bambini con bisogni speciali - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/","og_locale":"it_IT","og_type":"article","og_title":"Figli in attesa: una guida alle adozioni di bambini con bisogni speciali","og_description":"Disponibile\u00a0on line e \u00a0in libreria \u201cFigli in attesa: Guida alle adozioni di bambini con bisogni speciali\u201d, un nuovo interessante volume edito dalla Casa editrice Ancora.\u00a0Tra i bambini in attesa di adozione, quelli con \"bisogni speciali\" rischiano di attendere una famiglia per sempre: l'adozione internazionale \u00e8 per loro l'unica chance per diventare figli, la sola alternativa a crescere in un orfanotrofio fino alla maggior et\u00e0.","og_url":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-10-08T15:30:53+00:00","article_modified_time":"2017-04-18T10:14:48+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/cop_figli.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Figli in attesa: una guida alle adozioni di bambini con bisogni speciali","datePublished":"2010-10-08T15:30:53+00:00","dateModified":"2017-04-18T10:14:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/"},"wordCount":290,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/cop_figli.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/","url":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/","name":"Figli in attesa: una guida alle adozioni di bambini con bisogni speciali - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/cop_figli.jpg","datePublished":"2010-10-08T15:30:53+00:00","dateModified":"2017-04-18T10:14:48+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/cop_figli.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/cop_figli.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/figli-in-attesa-una-guida-alle-adozioni-di-bambini-con-bisogni-speciali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Figli in attesa: una guida alle adozioni di bambini con bisogni speciali"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:06:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=16364"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16364\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=16364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=16364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=16364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}