﻿{"id":164153,"date":"2019-04-26T14:24:08","date_gmt":"2019-04-26T12:24:08","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=164153"},"modified":"2019-04-26T15:37:38","modified_gmt":"2019-04-26T13:37:38","slug":"adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/","title":{"rendered":"Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste"},"content":{"rendered":"<h2>Grande fermento per l\u2019attivit\u00e0 della locale sede di Ai.Bi. \u2013 Amici dei Bambini con adozioni da Cina, Brasile e Moldavia<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-159237\" src=\"https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>La <strong>Puglia<\/strong>, in ambito nazionale, \u00e8 una delle isole felici nel campo delle adozioni internazionali, confermandosi pi\u00f9 o meno stabilmente come la regione del sud Italia pi\u00f9 &#8220;feconda&#8221; . Nel primo semestre del 2018 (ultimo dato certificato dalla <strong>CAI \u2013 Commissione Adozioni Internazionali<\/strong>) le famiglie pugliesi hanno adottato dal resto del mondo <strong>ben 33 bimbi, il 6,6% delle adozioni internazionali italiane.<\/strong><\/p>\n<p>Una riprova di questa propensione e della predisposizione all\u2019accoglienza delle famiglie pugliesi viene dall\u2019attivit\u00e0 della sede di <strong>Ai.Bi. \u2013 Amici dei Bambini<\/strong> di <strong>Barletta<\/strong>, che non si \u00e8 fermata neppure durante le festivit\u00e0 pasquali e i ponti collegati.<\/p>\n<p>Anzi. La sede registra infatti la partenza di tre coppie adottive. Una \u00e8 partita proprio il giorno della Santa Pasqua alla volta della <strong>Cina<\/strong>, dove andr\u00e0 a prendere, per poterlo finalmente portare in Italia, il proprio bimbo di due anni e otto mesi di et\u00e0.<\/p>\n<p>La seconda coppia \u00e8 invece pronta a partire, il prossimo 1 maggio, per il<strong> Brasile<\/strong>. Qui adotteranno non uno, ma ben quattro bimbi: due gemellini di cinque anni e altri due bambini di otto e sette anni rispettivamente. Per questi due genitori si prospetta una famiglia ampia e calorosa. Sempre lo stesso giorno un\u2019altra coppia partir\u00e0 alla volta della <strong>Moldavia<\/strong> per incontrare i due bimbi che hanno deciso di adottare, rispettivamente di otto e sei anni. Nel contempo, ancora dal Brasile sta per rientrare una coppia che ha adottato due bellissime bimbe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande fermento per l&rsquo;attivit&agrave; della locale sede di Ai.Bi. &ndash; Amici dei Bambini con adozioni da Cina, Brasile e Moldavia La Puglia, in ambito nazionale, &egrave; una delle isole felici nel campo delle adozioni internazionali, confermandosi pi&ugrave; o meno stabilmente come la regione del sud Italia pi&ugrave; &ldquo;feconda&rdquo; . Nel [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":159237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[347,370,463,434,498,497],"class_list":["post-164153","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-adozione-internazionale","tag-barletta","tag-brasile","tag-cina","tag-moldavia","tag-pasqua"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"In Puglia grande fermento per l\u2019attivit\u00e0 della locale sede di Ai.Bi. \u2013 Amici dei Bambini con adozioni da Cina, Brasile e Moldavia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste\" \/>\n<meta property=\"og:description\" content=\"In Puglia grande fermento per l\u2019attivit\u00e0 della locale sede di Ai.Bi. \u2013 Amici dei Bambini con adozioni da Cina, Brasile e Moldavia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-26T12:24:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-26T13:37:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste\" \/>\n<meta name=\"twitter:description\" content=\"In Puglia grande fermento per l\u2019attivit\u00e0 della locale sede di Ai.Bi. \u2013 Amici dei Bambini con adozioni da Cina, Brasile e Moldavia.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/bambini-cina-aibi-asilo_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste\",\"datePublished\":\"2019-04-26T12:24:08+00:00\",\"dateModified\":\"2019-04-26T13:37:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\\\/\"},\"wordCount\":264,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/comunitario-appello-cina_700x460.jpg\",\"keywords\":[\"Adozione Internazionale\",\"Barletta\",\"Brasile\",\"Cina\",\"Moldavia\",\"Pasqua\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\\\/\",\"name\":\"Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/comunitario-appello-cina_700x460.jpg\",\"datePublished\":\"2019-04-26T12:24:08+00:00\",\"dateModified\":\"2019-04-26T13:37:38+00:00\",\"description\":\"In Puglia grande fermento per l\u2019attivit\u00e0 della locale sede di Ai.Bi. \u2013 Amici dei Bambini con adozioni da Cina, Brasile e Moldavia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/comunitario-appello-cina_700x460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/comunitario-appello-cina_700x460.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste - Ai.Bi. Amici dei Bambini","description":"In Puglia grande fermento per l\u2019attivit\u00e0 della locale sede di Ai.Bi. \u2013 Amici dei Bambini con adozioni da Cina, Brasile e Moldavia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste","og_description":"In Puglia grande fermento per l\u2019attivit\u00e0 della locale sede di Ai.Bi. \u2013 Amici dei Bambini con adozioni da Cina, Brasile e Moldavia.","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2019-04-26T12:24:08+00:00","article_modified_time":"2019-04-26T13:37:38+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste","twitter_description":"In Puglia grande fermento per l\u2019attivit\u00e0 della locale sede di Ai.Bi. \u2013 Amici dei Bambini con adozioni da Cina, Brasile e Moldavia.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/bambini-cina-aibi-asilo_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste","datePublished":"2019-04-26T12:24:08+00:00","dateModified":"2019-04-26T13:37:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/"},"wordCount":264,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460.jpg","keywords":["Adozione Internazionale","Barletta","Brasile","Cina","Moldavia","Pasqua"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/","name":"Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460.jpg","datePublished":"2019-04-26T12:24:08+00:00","dateModified":"2019-04-26T13:37:38+00:00","description":"In Puglia grande fermento per l\u2019attivit\u00e0 della locale sede di Ai.Bi. \u2013 Amici dei Bambini con adozioni da Cina, Brasile e Moldavia.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/comunitario-appello-cina_700x460.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-grande-cuore-della-puglia-non-si-ferma-neanche-con-le-feste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozione internazionale. Il grande cuore della Puglia non si ferma neanche con le feste"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:33:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/164153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=164153"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/164153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/159237"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=164153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=164153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=164153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}