﻿


{"id":164212,"date":"2019-04-29T16:11:20","date_gmt":"2019-04-29T14:11:20","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=164212"},"modified":"2019-04-29T17:18:39","modified_gmt":"2019-04-29T15:18:39","slug":"adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/","title":{"rendered":"Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica"},"content":{"rendered":"<h2>Fondamentale il ruolo dei referenti locali Ai.Bi., veri e propri angeli custodi dei genitori adottivi<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-164206\" src=\"https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>La primavera \u00e8 arrivata. E non solo per il clima. Sembra infatti che con l\u2019arrivo della bella stagione (e nonostante le festivit\u00e0 consecutive) in diverse parti d\u2019Italia il cuore delle aspiranti famiglie adottive stia battendo sempre pi\u00f9 forte. Anche nel Veneto, una regione messa a dura prova dalla prassi illegale dei decreti vincolati in uso da parecchi anni nel Tribunale dei minorenni di Venezia, le partenze si susseguono. A dirlo sono i dati che provengono dalla sede territoriale di<strong> Ai.Bi. \u2013 Amici dei Bambini<\/strong> di <strong>Mestre (VE)<\/strong>.<\/p>\n<p>Racconta infatti Alice Paolin di Ai.Bi. Veneto che \u201c<em>marted\u00ec 23 aprile, tornando in sede dopo le ferie pasquali, mi sono trovata sulla scrivania ben quattro adozioni. Quattro bei maschietti che finalmente potranno essere accolti dall\u2019amore di una famiglia\u201d<\/em>.<\/p>\n<p>Nel giro di pochi giorni infatti tre coppie sono partite rispettivamente verso la Cina, la Russia e il Cile. Ad essere adottati un bimbo russo di un anno e mezzo, due bimbi cinesi di quattro e cinque anni e un bimbo cileno di otto anni. \u201c<em>La sede operativa<\/em> \u2013 spiega Alice Paolin &#8211;<em> cerca di tenere i contatti con le proprie coppie all&#8217;estero, compatibilmente con gli stravolgimenti della vita famigliare, che l&#8217;adozione comporta. Qualche mail veloce con poche parole di gioia e una foto, che testimonia come il miracolo dell&#8217;adozione si sia avvenuto, &#8230;come sempre. Un messaggio via whatsapp con le testuali parole: \u2018Stiamo benone, qui \u00e8 un turbinio di nuove emozioni e ce le vogliamo vivere appieno<\/em>\u2019.\u201d<\/p>\n<p>Ma un grande lavoro, spiega ancora la Paolin, <em>\u201c\u00e8 svolto dai nostri referenti locali, veri e propri angeli custodi dell\u2019adozione e delle nostre coppie adottive, che accompagnano e aiutano all&#8217;estero e che mandano a noi gli aggiornamenti costanti, facendoci capire che i genitori sono in buone, anzi, in ottime mani. Credo sia fondamentale per una coppia che si accinge a compiere un passo cos\u00ec importante, sapere di avere al proprio fianco un professionista preparato in tutto l&#8217;iter, che conosce ogni aspetto delle procedure estere, esperto di adozioni, avendone seguite tante, e dotato di sensibilit\u00e0 e passione che vanno oltre il semplice \u2018lavoro\u2019<\/em>\u201d.<\/p>\n<p>\u201c<em>Questo significa anche<\/em> \u2013 prosegue la referente Ai.Bi. \u2013 <em>che in Italia le coppie sono informate, trovano confronto, sono formate, sostenute dai professionisti e dal movimento di famiglie e si \u2018allenano\u2019 ad ogni possibile situazione possa accadere, una volta \u2018soli\u2019 all&#8217;estero col proprio figlio. Ma sapere di non essere soli e di avere un angelo custode, un aiuto sempre pronto, un sostegno di giorno e di notte, che li accompagna nelle difficolt\u00e0 del momento e nelle differenze culturali e linguistiche, mentre si sentono fragili e affaticati (soprattutto davanti a giudici e Servizi stranieri, che si conoscono poco) o anche perch\u00e8 l&#8217;affiatamento col figlio non \u00e8 una strada sempre e solo in discesa. All&#8217;estero le coppie sono aiutate e sostenute, per dedicarsi solo al proprio figlio, mentre tutta la parte della documentazione \u00e8 affare del team di Ai.Bi. locale: cos\u00ec si pu\u00f2 affrontare serenamente e al meglio il proprio nuovo ruolo genitoriale e imparare a diventare pap\u00e0 e mamma, con la consapevolezza di un alleato al proprio fianco, a cui chiedere consigli\u201d<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fondamentale il ruolo dei referenti locali Ai.Bi., veri e propri angeli custodi dei genitori adottivi La primavera &egrave; arrivata. E non solo per il clima. Sembra infatti che con l&rsquo;arrivo della bella stagione (e nonostante le festivit&agrave; consecutive) in diverse parti d&rsquo;Italia il cuore delle aspiranti famiglie adottive stia battendo [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":164206,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[347,429],"class_list":["post-164212","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-adozione-internazionale","tag-mestre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Adozione internazionale. A Mestre riprendono le partenze. Fondamentale il ruolo dei referenti Ai.Bi., veri e propri angeli custodi dei genitori adottivi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica\" \/>\n<meta property=\"og:description\" content=\"Adozione internazionale. A Mestre riprendono le partenze. Fondamentale il ruolo dei referenti Ai.Bi., veri e propri angeli custodi dei genitori adottivi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-29T14:11:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-29T15:18:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica\" \/>\n<meta name=\"twitter:description\" content=\"Adozione internazionale. A Mestre riprendono le partenze. Fondamentale il ruolo dei referenti Ai.Bi., veri e propri angeli custodi dei genitori adottivi.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/mano_nella_mano.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica\",\"datePublished\":\"2019-04-29T14:11:20+00:00\",\"dateModified\":\"2019-04-29T15:18:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\\\/\"},\"wordCount\":551,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-aibi-mestre_700x460.jpg\",\"keywords\":[\"Adozione Internazionale\",\"Mestre\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\\\/\",\"name\":\"Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-aibi-mestre_700x460.jpg\",\"datePublished\":\"2019-04-29T14:11:20+00:00\",\"dateModified\":\"2019-04-29T15:18:39+00:00\",\"description\":\"Adozione internazionale. A Mestre riprendono le partenze. Fondamentale il ruolo dei referenti Ai.Bi., veri e propri angeli custodi dei genitori adottivi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-aibi-mestre_700x460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-aibi-mestre_700x460.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica - Ai.Bi. Amici dei Bambini","description":"Adozione internazionale. A Mestre riprendono le partenze. Fondamentale il ruolo dei referenti Ai.Bi., veri e propri angeli custodi dei genitori adottivi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica","og_description":"Adozione internazionale. A Mestre riprendono le partenze. Fondamentale il ruolo dei referenti Ai.Bi., veri e propri angeli custodi dei genitori adottivi.","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2019-04-29T14:11:20+00:00","article_modified_time":"2019-04-29T15:18:39+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica","twitter_description":"Adozione internazionale. A Mestre riprendono le partenze. Fondamentale il ruolo dei referenti Ai.Bi., veri e propri angeli custodi dei genitori adottivi.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/mano_nella_mano.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica","datePublished":"2019-04-29T14:11:20+00:00","dateModified":"2019-04-29T15:18:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/"},"wordCount":551,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460.jpg","keywords":["Adozione Internazionale","Mestre"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/","name":"Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460.jpg","datePublished":"2019-04-29T14:11:20+00:00","dateModified":"2019-04-29T15:18:39+00:00","description":"Adozione internazionale. A Mestre riprendono le partenze. Fondamentale il ruolo dei referenti Ai.Bi., veri e propri angeli custodi dei genitori adottivi.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-aibi-mestre_700x460.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-anche-a-mestre-scoppia-la-primavera-riprendono-le-partenze-a-raffica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozione internazionale. Anche a Mestre scoppia la primavera: riprendono le partenze a raffica"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:11:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/164212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=164212"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/164212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/164206"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=164212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=164212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=164212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}