﻿{"id":16450,"date":"2010-10-13T17:23:59","date_gmt":"2010-10-13T16:23:59","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=16450"},"modified":"2010-10-13T17:23:59","modified_gmt":"2010-10-13T16:23:59","slug":"veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/","title":{"rendered":"Veneto: perplessit\u00e0 per il tavolo di consultazione tra Regione e famiglie adottive."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"margin: 5px;\" src=\"https:\/\/www.aibi.it\/ita\/images\/colombia_pic.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>L\u2019Assessore regionale alle politiche sociali, Remo Sernagiotto, ha annunciato che sar\u00e0 istituito <strong>un tavolo di consultazione tra Regione Veneto e famiglie adottive. <\/strong><\/p>\n<p>L\u2019obiettivo dovrebbe essere quello di ascoltare le esigenze e le proposte provenienti dalle coppie che vivono l\u2019esperienza dell\u2019adozione.<\/p>\n<p><em>\u201cVogliamo essere collegati con immediatezza alle famiglie, per capire i bisogni del territorio in questo settore\u201d<\/em> \u2013 ha dichiarato l\u2019assessore a Padova all\u2019apertura del ciclo di incontri di formazione sul tema \u201cL\u2019Adozione e il Sistema veneto Adozioni\u201d.<\/p>\n<p>\u201c<em>L\u2019adozione<\/em> \u2013 ricorda Sernagiotto \u2013 <em>\u00e8 un fenomeno sociale ed umano importante che sempre di pi\u00f9 in questi anni, in modo particolare nel Veneto, ha coinvolto e continua a coinvolgere centinaia di coppie. Nella nostra regione sono attivi dei protocolli operativi che hanno coinvolto sia gli enti autorizzati del privato sociale sia il Tribunale per i minorenni di Venezia\u201d<\/em>.<\/p>\n<p><strong>In realt\u00e0 facciamo fatica a capire la vera utilit\u00e0 di questo tavolo di discussione, in quanto esiste gi\u00e0 un collegamento tra Regione Veneto ed Enti autorizzati che rappresentano le famiglie adottive.<\/strong><\/p>\n<p><em>\u201cPer venire incontro alle esigenze delle coppie adottive gli enti sono i primi ad attivarsi attraverso colloqui di sostegno, incontri post adozione e cercando di farsi da interprete dei bisogni delle famiglie\u201d<\/em> dichiara Irene Bertuzzi responsabile Adozioni Internazionali per AiBi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Assessore regionale alle politiche sociali, Remo Sernagiotto, ha annunciato che sar\u00e0 istituito un tavolo di consultazione tra Regione Veneto e famiglie adottive.<strong> In realt\u00e0 facciamo fatica a capire la vera utilit\u00e0 di questo tavolo di discussione, in quanto esiste gi\u00e0 un collegamento tra Regione Veneto ed Enti autorizzati che rappresentano le famiglie adottive.<\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-16450","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Veneto: perplessit\u00e0 per il tavolo di consultazione tra Regione e famiglie adottive. - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veneto: perplessit\u00e0 per il tavolo di consultazione tra Regione e famiglie adottive.\" \/>\n<meta property=\"og:description\" content=\"L\u2019Assessore regionale alle politiche sociali, Remo Sernagiotto, ha annunciato che sar\u00e0 istituito un tavolo di consultazione tra Regione Veneto e famiglie adottive. In realt\u00e0 facciamo fatica a capire la vera utilit\u00e0 di questo tavolo di discussione, in quanto esiste gi\u00e0 un collegamento tra Regione Veneto ed Enti autorizzati che rappresentano le famiglie adottive.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-13T16:23:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/colombia_pic.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Veneto: perplessit\u00e0 per il tavolo di consultazione tra Regione e famiglie adottive.\",\"datePublished\":\"2010-10-13T16:23:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\\\/\"},\"wordCount\":223,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/colombia_pic.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\\\/\",\"name\":\"Veneto: perplessit\u00e0 per il tavolo di consultazione tra Regione e famiglie adottive. - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/colombia_pic.jpg\",\"datePublished\":\"2010-10-13T16:23:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/colombia_pic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/colombia_pic.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Veneto: perplessit\u00e0 per il tavolo di consultazione tra Regione e famiglie adottive.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Veneto: perplessit\u00e0 per il tavolo di consultazione tra Regione e famiglie adottive. - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/","og_locale":"it_IT","og_type":"article","og_title":"Veneto: perplessit\u00e0 per il tavolo di consultazione tra Regione e famiglie adottive.","og_description":"L\u2019Assessore regionale alle politiche sociali, Remo Sernagiotto, ha annunciato che sar\u00e0 istituito un tavolo di consultazione tra Regione Veneto e famiglie adottive. In realt\u00e0 facciamo fatica a capire la vera utilit\u00e0 di questo tavolo di discussione, in quanto esiste gi\u00e0 un collegamento tra Regione Veneto ed Enti autorizzati che rappresentano le famiglie adottive.","og_url":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-10-13T16:23:59+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/colombia_pic.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Veneto: perplessit\u00e0 per il tavolo di consultazione tra Regione e famiglie adottive.","datePublished":"2010-10-13T16:23:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/"},"wordCount":223,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/colombia_pic.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/","url":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/","name":"Veneto: perplessit\u00e0 per il tavolo di consultazione tra Regione e famiglie adottive. - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/colombia_pic.jpg","datePublished":"2010-10-13T16:23:59+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/colombia_pic.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/colombia_pic.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/veneto-perplessita-per-il-tavolo-di-consultazione-tra-regione-e-famiglie-adottive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Veneto: perplessit\u00e0 per il tavolo di consultazione tra Regione e famiglie adottive."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:50:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=16450"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16450\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=16450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=16450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=16450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}