﻿{"id":16549,"date":"2010-10-15T17:52:19","date_gmt":"2010-10-15T16:52:19","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=16549"},"modified":"2010-10-15T17:53:36","modified_gmt":"2010-10-15T16:53:36","slug":"finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/","title":{"rendered":"Finanziamenti agevolati: stanziati 85 milioni per i neo genitori."},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-12594\" style=\"margin: 5px;\" title=\"famiglia\" src=\"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Stanziate risorse finanziarie per un totale di 85 milioni di euro<\/strong> <strong>spendibili nel triennio 2009-2011 a favore di genitori di bambini nati o adottati nel periodo considerato<\/strong>. Queste agevolazioni arrivano in seguito al Decreto di settembre 2010 frutto dell\u2019intesa siglata tra \u00a0Consiglio dei Ministri e ABI \u2013 Associazione Bancaria Italiana.<\/p>\n<p><strong>Il Fondo Nuovi Nati<\/strong> prevede l\u2019accesso ai finanziamenti agevolati per un importo non superiore ai 5 mila euro, senza ipoteca e rimborsabili entro 5 anni, in un\u2019unica soluzione o rateizzandone il debito, ad un tasso d\u2019interesse agevolato, che l\u2019Istituto di Credito erogatore avr\u00e0 gi\u00e0 stabilito: viene applicato un TEGM (tasso effettivo globale medio rappresentante il valore medio tra tasso effettivamente applicato dal sistema bancario e creditizio e categorie omogenee di operazioni creditizie) ridotto dal 50% al 65%.<\/p>\n<p><strong>Il Fondo di Garanzia, \u00e8 stato pensato per le famiglie con uno o pi\u00f9 figli<\/strong> (per ogni nato pu\u00f2 essere richiesto un solo prestito e per l\u2019importo non eccedente i 5 mila euro), <strong>nati o adottati nel triennio 2009-2011<\/strong> <strong>che versano in condizioni economiche poco felici e strettamente connesse alla nascita ed all\u2019assistenza del\/i nascituri.<\/strong><\/p>\n<p>I neogenitori, per beneficiare del prestito, devono <strong>inoltrare istanza presso gli Istituti Creditizi che facoltativamente hanno aderito all\u2019iniziativa<\/strong>, previa compilazione di un modulo prestampato autocertificante la sussistenza dei requisiti richiesti (generalit\u00e0 anagrafiche dei genitori e del minore nato o adottato) <strong>entro il termine perentorio del 30 giugno dell\u2019anno successivo a quello di nascita<\/strong>. In primis l\u2019esercizio della potest\u00e0 genitoriale specificando se esercitata da solo o congiuntamente con un altro soggetto o affido condiviso: in quest\u2019ultimo caso sar\u00e0 necessario indicare le generalit\u00e0 dell\u2019altro soggetto specificando che si chiede un solo prestito per ogni minore.<\/p>\n<p>Nel momento in cui il nascituro o l\u2019adottato dovesse essere affetto da malattie rare la documentazione descritta dovr\u00e0 essere, altres\u00ec, completata con un certificato prodotto da una struttura sanitaria pubblica attestante la patologia sofferta.<\/p>\n<p><strong>Il prestito di liquidit\u00e0 elargito sar\u00e0 assistito da un ulteriore contributo in conto interessi<\/strong>, grazie ad un surplus finanziato e pari a 10 milioni di euro. L\u2019istanza per l\u2019ottenimento dell\u2019agevolazione finanziaria \u00e8 differita al 31.12.2011.<\/p>\n<p>Oltre al bonus-beb\u00e8, finanziamenti sono previsti anche per sopportare le spese di apertura pratica inerenti le adozioni internazionali. <strong>I termini prescritti per la presentazione dell\u2019istanza al prestito si rifanno alla data della sentenza di affidamento preadottivo o di adozione definitiva<\/strong>, <strong>per le adozioni nazionali<\/strong>. <strong>Per le adozioni internazionali si rimanda alla data del provvedimento di autorizzazione all\u2019ingresso ed alla residenza permanente del minore rilasciato dalla commissione per le adozioni internazionali<\/strong>.<\/p>\n<p>Il documento di identit\u00e0 sar\u00e0 accompagnato dalla dichiarazione dei redditi, dalla copia del decreto di idoneit\u00e0 e dalla copia dell\u2019atto di conferimento dell\u2019incarico all\u2019ente autorizzato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stanziate risorse finanziarie per un totale di 85 milioni di euro <strong>spendibili nel triennio 2009-2011 a favore di genitori di bambini nati o adottati nel periodo considerato<\/strong>. Queste agevolazioni arrivano in seguito al Decreto di settembre 2010 frutto dell\u2019intesa siglata tra \u00a0Consiglio dei Ministri e ABI \u2013 Associazione Bancaria Italiana.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-16549","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Finanziamenti agevolati: stanziati 85 milioni per i neo genitori. - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finanziamenti agevolati: stanziati 85 milioni per i neo genitori.\" \/>\n<meta property=\"og:description\" content=\"Stanziate risorse finanziarie per un totale di 85 milioni di euro spendibili nel triennio 2009-2011 a favore di genitori di bambini nati o adottati nel periodo considerato. Queste agevolazioni arrivano in seguito al Decreto di settembre 2010 frutto dell\u2019intesa siglata tra \u00a0Consiglio dei Ministri e ABI \u2013 Associazione Bancaria Italiana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-15T16:52:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-10-15T16:53:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Finanziamenti agevolati: stanziati 85 milioni per i neo genitori.\",\"datePublished\":\"2010-10-15T16:52:19+00:00\",\"dateModified\":\"2010-10-15T16:53:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\\\/\"},\"wordCount\":456,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia1.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\\\/\",\"name\":\"Finanziamenti agevolati: stanziati 85 milioni per i neo genitori. - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia1.jpg\",\"datePublished\":\"2010-10-15T16:52:19+00:00\",\"dateModified\":\"2010-10-15T16:53:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Finanziamenti agevolati: stanziati 85 milioni per i neo genitori.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Finanziamenti agevolati: stanziati 85 milioni per i neo genitori. - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/","og_locale":"it_IT","og_type":"article","og_title":"Finanziamenti agevolati: stanziati 85 milioni per i neo genitori.","og_description":"Stanziate risorse finanziarie per un totale di 85 milioni di euro spendibili nel triennio 2009-2011 a favore di genitori di bambini nati o adottati nel periodo considerato. Queste agevolazioni arrivano in seguito al Decreto di settembre 2010 frutto dell\u2019intesa siglata tra \u00a0Consiglio dei Ministri e ABI \u2013 Associazione Bancaria Italiana.","og_url":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-10-15T16:52:19+00:00","article_modified_time":"2010-10-15T16:53:36+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Finanziamenti agevolati: stanziati 85 milioni per i neo genitori.","datePublished":"2010-10-15T16:52:19+00:00","dateModified":"2010-10-15T16:53:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/"},"wordCount":456,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/","url":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/","name":"Finanziamenti agevolati: stanziati 85 milioni per i neo genitori. - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg","datePublished":"2010-10-15T16:52:19+00:00","dateModified":"2010-10-15T16:53:36+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/finanziamenti-agevolati-stanziati-85-milioni-per-i-neo-genitori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Finanziamenti agevolati: stanziati 85 milioni per i neo genitori."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:50:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=16549"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16549\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=16549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=16549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=16549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}