﻿


{"id":165855,"date":"2019-06-26T19:00:45","date_gmt":"2019-06-26T17:00:45","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=165855"},"modified":"2019-06-26T17:42:19","modified_gmt":"2019-06-26T15:42:19","slug":"cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/","title":{"rendered":"Cina. Una sorpresa inattesa per bimbi della Casa di Accoglienza \u201cVittorino Colombo\u201d di Ai.Bi. a Xi\u2019an, in Cina, al loro risveglio"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-165856\" src=\"https:\/\/www.aibi.it\/ita\/images\/storia-cina-frutta_fb.jpg\" alt=\"\" width=\"1200\" height=\"630\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/storia-cina-frutta_fb.jpg 1200w, https:\/\/www.aibi.it\/ita\/images\/storia-cina-frutta_fb-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/storia-cina-frutta_fb-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/storia-cina-frutta_fb-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/storia-cina-frutta_fb-105x55.jpg 105w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Dalla fattoria di campagna dove spesso i nostri bimbi sono ospiti erano infatti arrivati due ceste di pesche e mele appena raccolte, e tata Liu ha raccontato ai pi\u00f9 grandicelli che erano la ricompensa per aver aiutato a raccogliere le pannocchie durante la gita alla fattoria la settimana prima. Nella foto il gruppo al gran completo che al ritorno dall\u2019asilo non ha perso tempo per assaggiare il regalo ricevuto, questa volta molto gradito anche dalla tate.<\/p>\n<p>La Casa di Accoglienza \u201cVittorino Colombo\u201d di Ai.Bi. a Xi\u2019An, Cina, \u00e8 stata fondata da Ai.Bi nel 2012 allo scopo di dare un aiuto concreto ed efficace ai bambini affetti da disabilit\u00e0 provenienti dall\u2019Istituto di Assistenza all\u2019Infanzia di Xi\u2019An. Nella Casa questi bambini non solo possono godere di un clima pi\u00f9 familiare, ma possono anche essere seguiti da esperti che verificano periodicamente le loro condizioni modificando, e se necessario integrando, ogni volta la loro fisioterapia. Qui i bambini ritrovano la speranza di diventare figli tra le braccia di una famiglia adottiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalla fattoria di campagna dove spesso i nostri bimbi sono ospiti erano infatti arrivati due ceste di pesche e mele appena raccolte, e tata Liu ha raccontato ai pi&ugrave; grandicelli che erano la ricompensa per aver aiutato a raccogliere le pannocchie durante la gita alla fattoria la settimana prima. Nella [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":165856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-165855","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cina. Una sorpresa inattesa per bimbi della Casa di Accoglienza \u201cVittorino Colombo\u201d di Ai.Bi. a Xi\u2019an, in Cina, al loro risveglio - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cina. Una sorpresa inattesa per bimbi della Casa di Accoglienza \u201cVittorino Colombo\u201d di Ai.Bi. a Xi\u2019an, in Cina, al loro risveglio\" \/>\n<meta property=\"og:description\" content=\"Dalla fattoria di campagna dove spesso i nostri bimbi sono ospiti erano infatti arrivati due ceste di pesche e mele appena raccolte, e tata Liu ha raccontato ai pi&ugrave; grandicelli che erano la ricompensa per aver aiutato a raccogliere le pannocchie durante la gita alla fattoria la settimana prima. Nella [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-26T17:00:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/storia-cina-frutta_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Cina. Una sorpresa inattesa per bimbi della Casa di Accoglienza \u201cVittorino Colombo\u201d di Ai.Bi. a Xi\u2019an, in Cina, al loro risveglio\",\"datePublished\":\"2019-06-26T17:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\\\/\"},\"wordCount\":195,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/storia-cina-frutta_fb.jpg\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\\\/\",\"name\":\"Cina. Una sorpresa inattesa per bimbi della Casa di Accoglienza \u201cVittorino Colombo\u201d di Ai.Bi. a Xi\u2019an, in Cina, al loro risveglio - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/storia-cina-frutta_fb.jpg\",\"datePublished\":\"2019-06-26T17:00:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/storia-cina-frutta_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/storia-cina-frutta_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cina. Una sorpresa inattesa per bimbi della Casa di Accoglienza \u201cVittorino Colombo\u201d di Ai.Bi. a Xi\u2019an, in Cina, al loro risveglio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cina. Una sorpresa inattesa per bimbi della Casa di Accoglienza \u201cVittorino Colombo\u201d di Ai.Bi. a Xi\u2019an, in Cina, al loro risveglio - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/","og_locale":"it_IT","og_type":"article","og_title":"Cina. Una sorpresa inattesa per bimbi della Casa di Accoglienza \u201cVittorino Colombo\u201d di Ai.Bi. a Xi\u2019an, in Cina, al loro risveglio","og_description":"Dalla fattoria di campagna dove spesso i nostri bimbi sono ospiti erano infatti arrivati due ceste di pesche e mele appena raccolte, e tata Liu ha raccontato ai pi&ugrave; grandicelli che erano la ricompensa per aver aiutato a raccogliere le pannocchie durante la gita alla fattoria la settimana prima. Nella [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2019-06-26T17:00:45+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/storia-cina-frutta_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Cina. Una sorpresa inattesa per bimbi della Casa di Accoglienza \u201cVittorino Colombo\u201d di Ai.Bi. a Xi\u2019an, in Cina, al loro risveglio","datePublished":"2019-06-26T17:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/"},"wordCount":195,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/storia-cina-frutta_fb.jpg","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/","url":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/","name":"Cina. Una sorpresa inattesa per bimbi della Casa di Accoglienza \u201cVittorino Colombo\u201d di Ai.Bi. a Xi\u2019an, in Cina, al loro risveglio - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/storia-cina-frutta_fb.jpg","datePublished":"2019-06-26T17:00:45+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/storia-cina-frutta_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/storia-cina-frutta_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/cina-una-sorpresa-per-bimbi-della-casa-di-accoglienza-vittorino-colombo-di-ai-bi-a-xian-in-cina-al-loro-risveglio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"Cina. Una sorpresa inattesa per bimbi della Casa di Accoglienza \u201cVittorino Colombo\u201d di Ai.Bi. a Xi\u2019an, in Cina, al loro risveglio"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:32:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/165855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=165855"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/165855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/165856"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=165855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=165855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=165855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}