﻿


{"id":16632,"date":"2010-10-21T12:19:09","date_gmt":"2010-10-21T11:19:09","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=16632"},"modified":"2010-10-21T12:20:53","modified_gmt":"2010-10-21T11:20:53","slug":"bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/","title":{"rendered":"Bologna: AiBi e Acli insieme per sostenere le famiglie."},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/famiglia-numeorsa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9348\" style=\"margin: 5px;\" title=\"famiglia numeorsa\" src=\"https:\/\/www.aibi.it\/ita\/images\/famiglia-numeorsa.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Prosegue e si fa pi\u00f9 forte <strong>l\u2019accordo di collaborazione tra AiBi e Acli a sostegno delle famiglie<\/strong>.<\/p>\n<p><strong>Sabato 23 ottobre alle ore 17.00<\/strong>, presso il <strong>Punto Famiglia <\/strong>di Via Marzabotto 7\/b, <strong>Ai.Bi e Acli Bologna inaugureranno la nuova collaborazione che dar\u00e0 vita ad un importante servizio per le famiglie bolognesi<\/strong>.<\/p>\n<p>In un momento storico in cui la famiglia \u00e8 esposta sempre pi\u00f9 a rischi di carattere sociale ed economico, ACLI e Ai.Bi. hanno deciso di mettere in cantiere nuove attivit\u00e0 per sostenere le famiglie del territorio.<\/p>\n<p>Presso il Punto famiglia <strong>sar\u00e0 attivo a partire dal 28 ottobre uno sportello informativo aperto alle famiglie desiderose di avere informazioni sulle tematiche dell\u2019accoglienza familiare.<\/strong><\/p>\n<p><strong>Tutti i gioved\u00ec dalle 15.30 alle 17.30 un volontario esperto in adozione e affido sar\u00e0 a disposizione<\/strong> per rispondere alle domande in materia e favorire la promozione dell\u2019accoglienza familiare.<\/p>\n<p><strong>I Punti famiglia, sono rivolti a tutte le famiglie <\/strong>che cercano un modo di crescere insieme nel confronto e nella condivisione.<\/p>\n<p><strong>ACLI e Ai.Bi. intendono dare risposte concrete ai problemi quotidiani che incontrano le famiglie italiane<\/strong> e diventare cos\u00ec un luogo di riferimento per i nuclei che intendono confrontarsi sulle questioni pi\u00f9 delicate.<\/p>\n<p>L\u2019incontro di presentazione si concluder\u00e0 con un momento conviviale grazie ai soci del circolo che offriranno un momento di ristoro a tutti i presenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prosegue e si fa pi\u00f9 forte <strong>l\u2019accordo di collaborazione tra AiBi e Acli a sostegno delle famiglie<\/strong>.\u00a0 <strong>Sabato 23 ottobre alle ore 17.00<\/strong>, presso il <strong>Punto Famiglia <\/strong>di Via Marzabotto 7\/b,\u00a0 <strong>Ai.Bi e Acli Bologna inaugureranno la nuova collaborazione che dar\u00e0 vita ad un importante servizio per le famiglie bolognesi<\/strong>.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-16632","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bologna: AiBi e Acli insieme per sostenere le famiglie. - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bologna: AiBi e Acli insieme per sostenere le famiglie.\" \/>\n<meta property=\"og:description\" content=\"Prosegue e si fa pi\u00f9 forte l\u2019accordo di collaborazione tra AiBi e Acli a sostegno delle famiglie.\u00a0 Sabato 23 ottobre alle ore 17.00, presso il Punto Famiglia di Via Marzabotto 7\/b,\u00a0 Ai.Bi e Acli Bologna inaugureranno la nuova collaborazione che dar\u00e0 vita ad un importante servizio per le famiglie bolognesi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-21T11:19:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-10-21T11:20:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/famiglia-numeorsa.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Bologna: AiBi e Acli insieme per sostenere le famiglie.\",\"datePublished\":\"2010-10-21T11:19:09+00:00\",\"dateModified\":\"2010-10-21T11:20:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\\\/\"},\"wordCount\":227,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia-numeorsa.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\\\/\",\"name\":\"Bologna: AiBi e Acli insieme per sostenere le famiglie. - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia-numeorsa.jpg\",\"datePublished\":\"2010-10-21T11:19:09+00:00\",\"dateModified\":\"2010-10-21T11:20:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia-numeorsa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia-numeorsa.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bologna: AiBi e Acli insieme per sostenere le famiglie.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bologna: AiBi e Acli insieme per sostenere le famiglie. - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/","og_locale":"it_IT","og_type":"article","og_title":"Bologna: AiBi e Acli insieme per sostenere le famiglie.","og_description":"Prosegue e si fa pi\u00f9 forte l\u2019accordo di collaborazione tra AiBi e Acli a sostegno delle famiglie.\u00a0 Sabato 23 ottobre alle ore 17.00, presso il Punto Famiglia di Via Marzabotto 7\/b,\u00a0 Ai.Bi e Acli Bologna inaugureranno la nuova collaborazione che dar\u00e0 vita ad un importante servizio per le famiglie bolognesi.","og_url":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-10-21T11:19:09+00:00","article_modified_time":"2010-10-21T11:20:53+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/famiglia-numeorsa.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Bologna: AiBi e Acli insieme per sostenere le famiglie.","datePublished":"2010-10-21T11:19:09+00:00","dateModified":"2010-10-21T11:20:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/"},"wordCount":227,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/famiglia-numeorsa.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/","url":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/","name":"Bologna: AiBi e Acli insieme per sostenere le famiglie. - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/famiglia-numeorsa.jpg","datePublished":"2010-10-21T11:19:09+00:00","dateModified":"2010-10-21T11:20:53+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/famiglia-numeorsa.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/famiglia-numeorsa.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bologna-aibi-e-acli-insieme-per-sostenere-le-famiglie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Bologna: AiBi e Acli insieme per sostenere le famiglie."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:40:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=16632"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16632\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=16632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=16632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=16632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}