﻿{"id":16705,"date":"2010-10-25T15:59:07","date_gmt":"2010-10-25T14:59:07","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=16705"},"modified":"2010-10-25T15:59:07","modified_gmt":"2010-10-25T14:59:07","slug":"adozioni-internazionali-la-risposta-del-guatemala-agli-usa","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/","title":{"rendered":"Adozioni Internazionali: la risposta del Guatemala agli USA."},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/guatemala-stan-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8703\" style=\"margin: 5px;\" title=\"guatemala-stan-4\" src=\"https:\/\/www.aibi.it\/ita\/images\/guatemala-stan-4.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Il Consiglio Nazionale di Adozione (CNA)<\/strong>, Autorit\u00e0 Centrale guatemalteca istituita nel 2008, risponde alla dura presa di posizione da parte del Dipartimento di Stato degli Stati Uniti d\u2019America in merito all\u2019attuale situazione delle adozioni internazionali in Guatemala.<\/p>\n<p>Il <strong>CNA informa che il piano pilota strutturato per la ripresa delle Adozioni Internazionali si basa sui principi della Convenzione dell\u2019Aja <\/strong>ed \u00e8 stato elaborato con l\u2019assistenza tecnica di esperti della Conferenza dell\u2019Aja e di Unicef Guatemala.<\/p>\n<p><strong>L\u2019obiettivo del piano pilota \u00e8 quello di dare una famiglia a quei bambini per i quali non \u00e8 stato possibile trovarne una in Guatemala<\/strong>, a causa dei loro bisogni speciali.<\/p>\n<p>Le politiche del Guatemala saranno quindi <strong>in linea con quelle dei principali Paesi sudamericani<\/strong> e quindi saranno i bambini in et\u00e0 scolare, gruppi di fratelli e minori con problemi di salute ad essere abbinati a una famiglia straniera.<\/p>\n<p>Nel 2008 il Consiglio Nazionale di Adozione aveva sospeso le adozioni internazionali, che avvenivano soprattutto da parte di coppie statunitensi, <strong>per bloccare un \u201cmercato\u201d che arricchiva avvocati, giudici e dottori<\/strong>; il Guatemala era il quarto Paese nel mondo in termini assoluti di minori dati in adozione, dopo la Russia, la Cina e la Corea del Sud.<\/p>\n<p>Ad oggi, il <strong>Piano Pilota adottato dal Guatemala si basa principalmente su due azioni: il rafforzamento del Sistema Nazionale di Protezione dell\u2019Infanzia e dell\u2019Adolescenza<\/strong> e la sottoscrizione <strong>di convenzioni di cooperazione con un numero limitato di Autorit\u00e0 Centrali di Stati di Ricezione e Organismi Accreditati<\/strong>. Questo per offrire garanzie di alta qualit\u00e0 per i minori dichiarati adottabili.<\/p>\n<p>Ad oggi il CNA non ha preselezionato gli organismi stranieri accreditati per le adozioni internazionali, in quanto sta raddoppiando i suoi sforzi <strong>per fortificare il Sistema di Protezione dell\u2019Infanzia e dell\u2019Adolescenza<\/strong>, insieme alle altre istituzioni che ne fanno parte.<\/p>\n<p>A prova di quanto detto, sono state portare a termine le seguenti azioni: <strong>rafforzare l\u2019adozione nazionale<\/strong>, <strong>regolamentazione della figura della famiglia sostitutiva<\/strong>, <strong>approvazione di standard di qualit\u00e0 per gli istituti<\/strong>, <strong>creazione di un registro nazionale<\/strong> di minori istituzionalizzati e <strong>promozione dell\u2019adozione nazionale<\/strong> di minori con bisogni speciali, e altro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Il Consiglio Nazionale di Adozione (CNA)<\/strong>, risponde alla dura presa di posizione da parte del Dipartimento di Stato degli Stati Uniti d\u2019America in merito all\u2019attuale situazione delle adozioni internazionali in Guatemala. Il <strong>CNA informa che il piano pilota strutturato per la ripresa delle Adozioni Internazionali si basa sui principi della Convenzione dell\u2019Aja. <\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-16705","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni Internazionali: la risposta del Guatemala agli USA. - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni Internazionali: la risposta del Guatemala agli USA.\" \/>\n<meta property=\"og:description\" content=\"Il Consiglio Nazionale di Adozione (CNA), risponde alla dura presa di posizione da parte del Dipartimento di Stato degli Stati Uniti d\u2019America in merito all\u2019attuale situazione delle adozioni internazionali in Guatemala. Il CNA informa che il piano pilota strutturato per la ripresa delle Adozioni Internazionali si basa sui principi della Convenzione dell\u2019Aja.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-25T14:59:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/guatemala-stan-4.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni Internazionali: la risposta del Guatemala agli USA.\",\"datePublished\":\"2010-10-25T14:59:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\\\/\"},\"wordCount\":358,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/guatemala-stan-4.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\\\/\",\"name\":\"Adozioni Internazionali: la risposta del Guatemala agli USA. - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/guatemala-stan-4.jpg\",\"datePublished\":\"2010-10-25T14:59:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/guatemala-stan-4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/guatemala-stan-4.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni Internazionali: la risposta del Guatemala agli USA.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni Internazionali: la risposta del Guatemala agli USA. - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni Internazionali: la risposta del Guatemala agli USA.","og_description":"Il Consiglio Nazionale di Adozione (CNA), risponde alla dura presa di posizione da parte del Dipartimento di Stato degli Stati Uniti d\u2019America in merito all\u2019attuale situazione delle adozioni internazionali in Guatemala. Il CNA informa che il piano pilota strutturato per la ripresa delle Adozioni Internazionali si basa sui principi della Convenzione dell\u2019Aja.","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-10-25T14:59:07+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/guatemala-stan-4.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni Internazionali: la risposta del Guatemala agli USA.","datePublished":"2010-10-25T14:59:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/"},"wordCount":358,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/guatemala-stan-4.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/","name":"Adozioni Internazionali: la risposta del Guatemala agli USA. - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/guatemala-stan-4.jpg","datePublished":"2010-10-25T14:59:07+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/guatemala-stan-4.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/guatemala-stan-4.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-la-risposta-del-guatemala-agli-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni Internazionali: la risposta del Guatemala agli USA."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:37:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=16705"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16705\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=16705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=16705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=16705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}