﻿


{"id":168087,"date":"2019-10-01T12:17:21","date_gmt":"2019-10-01T10:17:21","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=168087"},"modified":"2019-10-01T14:07:59","modified_gmt":"2019-10-01T12:07:59","slug":"sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/","title":{"rendered":"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua?"},"content":{"rendered":"<h2>Le gravi responsabilit\u00e0 di un sistema istituzionale che ha lasciato questa giovane donna da sola con i suoi problemi<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-168090 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>La vicenda del neonato abbandonato dalla madre, <a href=\"https:\/\/www.altoadige.it\/cronaca\/neonato-morto-fermata-la-madre-1.2126035\" target=\"_blank\" rel=\"noopener noreferrer\">una giovane donna rumena venuta per lavorare in Trentino come raccoglitrice di mele<\/a>, nelle campagne nei pressi di Merano, nelle vicinanze di Lana di Sopra, con il cordone ombelicale ancora avvolto attorno al collo e il piccolo corpo coperto soltanto da un panno, ha (comprensibilmente) sconvolto il territorio.<a href=\"https:\/\/www.aibi.it\/ita\/benevento-e-merano-due-infanticidi-in-poche-ore-che-lasciano-sgomenti\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong> Ma come \u00e8 possibile che, nel 2019, possano ancora avvenire tragedie del genere?<\/strong> <\/a><strong>Come \u00e8 possibile che questa giovane madre, che ha scelto di abbandonare un neonato al proprio destino, non sapesse dell\u2019esistenza di una legge sul parto in anonimato?<\/strong><\/p>\n<p><strong>E, in tal caso, di chi \u00e8 la colpa?<\/strong> Perch\u00e9, quando si leggono queste notizie il primo pensiero va a quel bimbo che non ha potuto vivere la gioia della vita, certo, ma anche a quanto quella madre debba essersi sentita sola. Questo gesto \u00e8 anche una sconfitta per la nostra societ\u00e0 che non \u00e8 riuscita a proteggere un neonato e una mamma in difficolt\u00e0.<\/p>\n<p>Ci si chiede perch\u00e9 questa mamma non abbia chiesto aiuto. La campagna di informazione sul parto in anonimato, in forma multilingue, \u00e8 stata fatta ormai 10 anni fa ma dovrebbe proseguire in modo continuativo, con gli opuscoli lasciati in posti pubblici il pi\u00f9 neutri possibile, come pure far conoscere dei vari servizi che possono esser di aiuto. E invece questo non \u00e8 accaduto. E questa donna lasciata sola con tutte le sue difficolt\u00e0.<\/p>\n<p>Una donna, una madre che, ora, dopo essere stata individuata, <strong>rischia una pena di sette anni di carcere.<\/strong> Quella punizione che, per\u00f2, dovrebbe toccare anche a <strong>quanti la hanno lasciata a confrontarsi soltanto con se stessa. Quanta solitudine. Che tragedia.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le gravi responsabilit&agrave; di un sistema istituzionale che ha lasciato questa giovane donna da sola con i suoi problemi La vicenda del neonato abbandonato dalla madre, una giovane donna rumena venuta per lavorare in Trentino come raccoglitrice di mele, nelle campagne nei pressi di Merano, nelle vicinanze di Lana di [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":168090,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[297,363],"class_list":["post-168087","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-famiglia","tag-figli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua? Le gravi responsabilit\u00e0 del sistema istituzionale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua?\" \/>\n<meta property=\"og:description\" content=\"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua? Le gravi responsabilit\u00e0 del sistema istituzionale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-01T10:17:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-01T12:07:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua?\" \/>\n<meta name=\"twitter:description\" content=\"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua? Le gravi responsabilit\u00e0 del sistema istituzionale.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste1.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua?\",\"datePublished\":\"2019-10-01T10:17:21+00:00\",\"dateModified\":\"2019-10-01T12:07:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\\\/\"},\"wordCount\":302,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/donna_sola_triste2.jpg\",\"keywords\":[\"famiglia\",\"figli\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\\\/\",\"name\":\"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/donna_sola_triste2.jpg\",\"datePublished\":\"2019-10-01T10:17:21+00:00\",\"dateModified\":\"2019-10-01T12:07:59+00:00\",\"description\":\"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua? Le gravi responsabilit\u00e0 del sistema istituzionale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/donna_sola_triste2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/donna_sola_triste2.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua? - Ai.Bi. Amici dei Bambini","description":"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua? Le gravi responsabilit\u00e0 del sistema istituzionale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/","og_locale":"it_IT","og_type":"article","og_title":"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua?","og_description":"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua? Le gravi responsabilit\u00e0 del sistema istituzionale.","og_url":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2019-10-01T10:17:21+00:00","article_modified_time":"2019-10-01T12:07:59+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste1.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua?","twitter_description":"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua? Le gravi responsabilit\u00e0 del sistema istituzionale.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste1.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua?","datePublished":"2019-10-01T10:17:21+00:00","dateModified":"2019-10-01T12:07:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/"},"wordCount":302,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2.jpg","keywords":["famiglia","figli"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/","url":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/","name":"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2.jpg","datePublished":"2019-10-01T10:17:21+00:00","dateModified":"2019-10-01T12:07:59+00:00","description":"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua? Le gravi responsabilit\u00e0 del sistema istituzionale.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/donna_sola_triste2.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/sette-anni-di-carcere-alla-madre-del-neonato-abbandonato-senza-vita-a-merano-ma-la-colpa-e-solo-sua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Sette anni di carcere alla madre del neonato abbandonato senza vita a Merano. Ma la colpa \u00e8 solo sua?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:27:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/168087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=168087"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/168087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/168090"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=168087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=168087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=168087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}