﻿


{"id":168190,"date":"2019-03-22T07:30:08","date_gmt":"2019-03-22T06:30:08","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=168190"},"modified":"2019-12-09T11:00:53","modified_gmt":"2019-12-09T10:00:53","slug":"i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/","title":{"rendered":"Donne, la sfida (quasi) impossibile per conciliare lavoro e famiglia"},"content":{"rendered":"<h2><em>Ieri l&#8217;Istat ha reso noti i dati sui servizi all&#8217;infanzia, fondamentali per cercare di aiutare la conciliazione lavoro e famiglia delle donne<\/em><\/h2>\n<p>Istat ha reso noti i dati censiti per l\u2019anno scolastico <strong>2016\/2017<\/strong> dei servizi socio-educativi per l\u2019infanzia che in Italia sono <strong>13.147<\/strong>, con solo <strong>354.000<\/strong> posti autorizzati al funzionamento, pubblici in poco pi\u00f9 della met\u00e0 dei casi. L\u2019analisi consegna il trend significativo storico per cui a partire dall&#8217;anno scolastico <strong>2011\/12<\/strong> si registra un calo dei bambini iscritti nei nidi comunali e convenzionati e dal 2012 si riducono anche le risorse pubbliche disponibili sul territorio rimanendo nel triennio <strong>2014-2016<\/strong> sostanzialmente stabili sia gli utenti serviti, sia la spesa dei Comuni. Il parametro europeo fissato dall&#8217;Unione \u00e8 del <strong>33%<\/strong> per sostenere la conciliazione della vita familiare e lavorativa e promuovere la partecipazione delle donne al mercato del lavoro e la percentuale di posti disponibili nel nostro Paese, coprendo solo il <strong>24%<\/strong> del numero di bambini residenti fino a tre anni, \u00e8 desolatamente inadeguata.<\/p>\n<p>Consideriamo che la crisi economica ha comportato un accrescimento dei bisogni di cura, inclusione e contrasto alla povert\u00e0, e la dinamica della spesa socio-assistenziale, invece di segnare un incremento, ha registrato nel periodo <strong>2013\/2017<\/strong> una tendenziale stagnazione, pur se con andamenti altalenanti, e peraltro si \u00e8 andata riducendo in particolare proprio nella componente pi\u00f9 importante del welfare territoriale e dei servizi. Tra i fattori che determinano la maggiore incidenza della povert\u00e0 nelle famiglie con figli minori ci sono l\u2019insufficienza e la frammentazione di prestazioni e servizi pubblici a sostegno dei figli, che siano capaci di favorire la piena occupazione dei genitori, in particolar modo delle donne.<\/p>\n<p>Sono necessarie pertanto politiche di conciliazione tra lavoro e responsabilit\u00e0 familiari che intervengano in maniera coordinata su\u00a0<a href=\"https:\/\/www.ilsussidiario.net\/news\/cronaca\/2018\/12\/14\/maternita-al-lavoro-fino-al-9-mese-una-pari-opportunita-che-darebbe-molti-vantaggi\/1820979\/\"><strong>congedi e permessi<\/strong><\/a>, sull&#8217;organizzazione del lavoro, su istituti innovativi disciplinati dalla contrattazione collettiva e, soprattutto, sul sistema dei servizi all&#8217;infanzia, che risultano ancora troppo scarsamente diffusi. In confronto ai Paesi Ue, l\u2019Italia investe molto meno per l\u2019esclusione sociale rispetto al proprio Pil <strong>(0,77%<\/strong> contro <strong>1,8%<\/strong>), per la famiglia e i minori (<strong>5,98%<\/strong> contro <strong>8,08%<\/strong>) (dati Eurostat 2018). Secondo la Corte dei Conti, infatti, nel 2017 la spesa per prestazioni assistenziali della Pubblica amministrazione era composta per <strong>38,2 miliardi<\/strong> da misure in denaro e soltanto per poco pi\u00f9 di 10 miliardi in servizi, per lo pi\u00f9 a carico dei Comuni.<\/p>\n<p>Oltretutto si conferma la disomogeneit\u00e0 della spesa media dei servizi per gestire i servizi pubblici o privati convenzionati, molto variabile tra regioni con un minimo di <strong>88 euro<\/strong> l\u2019anno per un bambino calabrese e un massimo di <strong>2.209 euro<\/strong> per bambino trentino con un\u2019ulteriore crescita delle disuguaglianze tra territorio ed ente locale. Fondamentale \u00e8 l\u2019adozione di politiche pubbliche per l\u2019inclusione educativa, sociale e lavorativa che operino in stretto coordinamento tra loro con la pluralit\u00e0 di strumenti, prestazioni e servizi necessari a ciascuna politica, a partire dalla diffusione e qualificazione del sistema di servizi per le famiglie con carichi di assistenza e cura e per la prima infanzia (integrato con lo 0-6 e il tempo pieno per l\u2019inclusione educativa) e dal rafforzamento degli strumenti per il contrasto alla povert\u00e0 assoluta e delle politiche attive per l\u2019inserimento lavorativo. Mentre la realt\u00e0 \u00e8 che gli interventi verso la famiglia sono scarsi e insufficienti, complessivamente incoerenti, diseguali per categoria lavorativa e rapporto di lavoro, per area territoriale (nord-sud, citt\u00e0-provincia), e in alcuni casi variano in virt\u00f9 del tipo di legame che unisce la coppia, pi\u00f9 che rispetto alla presenza di minori\/figli e, d&#8217;altronde, il modello preferenziale di riferimento delle politiche continua a essere quello della famiglia di tipo tradizionale per legami, composizione, preferenze, condizione lavorativa dei partner.<\/p>\n<p>Uno degli effetti maggiormente inquietanti di questa situazione \u00e8 il tasso di povert\u00e0 appunto delle famiglie con minori che \u00e8 il pi\u00f9 alto in Europa, cresce al crescere del numero di figli, nelle situazioni in cui vi sia un unico percettore di reddito (specie ne casi in cui la madre \u00e8 molto giovane) e in caso di genitore solo. Il sistema di trasferimenti italiano \u00e8 il meno efficace nel ridurre la povert\u00e0 tra i minori e inoltre in Italia non esiste a tutt&#8217;oggi una tutela universale, n\u00e9 un programma universale virtuoso di sostegno al reddito.<\/p>\n<p>Gli studi comparati hanno dimostrato come i paesi che hanno avuto la miglior performance nel ridurre i livelli di povert\u00e0 tra i minori siano quelli scandinavi che nel corso degli anni \u201890 hanno puntato su: politiche di piena occupazione, in particolare finalizzate a incrementare quella femminile; qualificate politiche sociali (che hanno il merito anche di aver creato un ampio sostegno politico); \u0192 diritti sociali basati sulla cittadinanza e non sullo status occupazionale; un forte investimento in servizi di cura per l\u2019infanzia per facilitare\u00a0<a href=\"https:\/\/www.ilsussidiario.net\/news\/lavoro\/2019\/3\/8\/festa-delle-donne-tra-lavoro-e-pensioni-non-ce-niente-da-festeggiare\/1856515\/\"><strong>l&#8217;occupazione femminile<\/strong><\/a>; una forte enfasi su una migliore redistribuzione della ricchezza; un forte accento posto sulle questioni di equit\u00e0 di genere; un\u2019attenzione sul bilanciamento tra lavoro e famiglia (quindi congedi parentali, educazione e cura per i bambini pi\u00f9 piccoli in modo da supportare l\u2019occupazione femminile); una forte volont\u00e0 di sostegno a livelli di tassazione e spesa sociale elevati.<\/p>\n<p>Gli strumenti utilizzati in Italia, spesso di natura economica e associati alle misure di contrasto alla povert\u00e0, sono invece stati realizzati attraverso una molteplicit\u00e0 di strumenti sui quali \u00e8 unanime il giudizio di farraginosit\u00e0, categoricit\u00e0, scarsa efficacia distributiva. \u00c8 fondamentale una misura universale di sostegno al costo dei figli, di reddito minimo in grado di tutelare il cittadino dai rischi sociali, e che sia di supporto non solo alle fasce pi\u00f9 deboli ma anche a quelle a rischio di povert\u00e0 e di esclusione sociale. Allo stesso modo la disponibilit\u00e0 di servizi di cura dell\u2019infanzia, che aiutano in modo sostanziale la conciliazione tra vita familiare e vita lavorativa, consentendo il rientro a lavoro della donna e quindi riducendo la penalizzazione del lavoro della madre.<\/p>\n<p>La spesa locale \u2013 essendo il livello locale quello che ha il compito prevalente di erogare servizi e in particolare servizi sociali \u2013 \u00e8 in generale infatti molto bassa rispetto a quella centrale; inoltre, la legislazione, e la cultura stessa dei giuristi italiani \u2013 e le ideologie da cui sono ancora influenzati -, sono rimaste a lungo connotate da una legislazione blanda rispetto alla realt\u00e0 socio-economica, alle mutate condizioni di vita delle famiglie, limitandosi a slogan che dimostravano quanto il Pil sarebbe stato premiato dalla presenza di lavoratrici sul mercato del lavoro ma non procedendo sulle riforme necessarie. Oggi \u00e8 urgente realizzare politiche di conciliazione tra vita familiare e vita lavorativa, ovvero il set di interventi che possono utilmente rendere pi\u00f9 armoniosa e bilanciata la gestione congiunta dei due ambiti anche recuperando le direttive Ue e le indicazioni comunitarie in riferimento alle politiche di conciliazione e di sostegno alla genitorialit\u00e0, che nel corso degli ultimi anni si sono andate consolidando e fatte pi\u00f9 incisive.<\/p>\n<p>La Commissione ha adottato nell\u2019aprile 2017 la sua proposta per una direttiva sul bilanciamento tra vita familiare e lavorativa come parte di uno dei tre pacchetti di iniziative connesse Pilastro Sociale. Il tema oggetto di questa proposta, oltre a essere riconducile al principio n. 2 (parit\u00e0 di genere) e al principio n. 3 (parit\u00e0 di opportunit\u00e0), \u00e8 infatti esplicitamente richiamato dal principio n. 9 del Pilastro che sancisce \u201cil diritto per i genitori e le persone con responsabilit\u00e0\u0300 di assistenza a un congedo appropriato, modalit\u00e0\u0300 di lavoro flessibili e accesso a servizi di assistenza e di cura. Gli uomini e le donne hanno pari accesso ai congedi speciali al fine di adempiere le loro responsabilit\u00e0\u0300 di assistenza e sono incoraggiati a usufruirne in modo equilibrato\u201d.<\/p>\n<p>In buona sostanza dagli odierni dati Istat emerge quante energie il lavoro di cura (materno per definizione, nel nostro Paese) draga dalla partecipazione al mercato del lavoro, e possibilmente da un mercato del lavoro che consista in un impiego full-time. La mancanza di servizi per la cura e le conseguenze che tale mancanza ha sull&#8217;occupabilit\u00e0 delle donne \u00e8 certamente significativa, in un\u2019ottica lavoristica oggi \u00e8 opportunamente ben sostenuta dalle stesse lavoratrici che non si rassegnano a essere costrette all&#8217;interruzione dell\u2019attivit\u00e0 lavorativa dopo la nascita del figlio per mancanza di servizi di nido; comunque \u00e8 sconcertante il dato che dal Rapporto annuale del ministero del Lavoro sulle dimissioni emerge: una donna su quattro lascia il lavoro dopo la maternit\u00e0.<\/p>\n<p><strong>Fonte: ilsussidiario.net<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ieri l&rsquo;Istat ha reso noti i dati sui servizi all&rsquo;infanzia, fondamentali per cercare di aiutare la conciliazione lavoro e famiglia delle donne Istat ha reso noti i dati censiti per l&rsquo;anno scolastico 2016\/2017 dei servizi socio-educativi per l&rsquo;infanzia che in Italia sono 13.147, con solo 354.000 posti autorizzati al funzionamento, [&hellip;]<\/p>\n","protected":false},"author":75,"featured_media":164089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[],"class_list":["post-168190","post","type-post","status-publish","format-standard","has-post-thumbnail","category-family-audit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Donne, la sfida (quasi) impossibile per conciliare lavoro e famiglia - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"l&#039;Istat ha reso noti i dati sui servizi all&#039;infanzia, fondamentali per cercare di aiutare la conciliazione lavoro e famiglia delle donne\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donne, la sfida (quasi) impossibile per conciliare lavoro e famiglia\" \/>\n<meta property=\"og:description\" content=\"l&#039;Istat ha reso noti i dati sui servizi all&#039;infanzia, fondamentali per cercare di aiutare la conciliazione lavoro e famiglia delle donne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-22T06:30:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-09T10:00:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/family-audit_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"stefaniaP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/family-audit_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"stefaniaP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\\\/\"},\"author\":{\"name\":\"stefaniaP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/dfce5bd678ad0f650527cc2172949970\"},\"headline\":\"Donne, la sfida (quasi) impossibile per conciliare lavoro e famiglia\",\"datePublished\":\"2019-03-22T06:30:08+00:00\",\"dateModified\":\"2019-12-09T10:00:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\\\/\"},\"wordCount\":1365,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/family-audit-2019_fb.jpg\",\"articleSection\":[\"Family Audit\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\\\/\",\"name\":\"Donne, la sfida (quasi) impossibile per conciliare lavoro e famiglia - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/family-audit-2019_fb.jpg\",\"datePublished\":\"2019-03-22T06:30:08+00:00\",\"dateModified\":\"2019-12-09T10:00:53+00:00\",\"description\":\"l'Istat ha reso noti i dati sui servizi all'infanzia, fondamentali per cercare di aiutare la conciliazione lavoro e famiglia delle donne\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/family-audit-2019_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/family-audit-2019_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Family Audit\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/family-audit\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Donne, la sfida (quasi) impossibile per conciliare lavoro e famiglia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/dfce5bd678ad0f650527cc2172949970\",\"name\":\"stefaniaP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/stefaniap\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Donne, la sfida (quasi) impossibile per conciliare lavoro e famiglia - Ai.Bi. Amici dei Bambini","description":"l'Istat ha reso noti i dati sui servizi all'infanzia, fondamentali per cercare di aiutare la conciliazione lavoro e famiglia delle donne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/","og_locale":"it_IT","og_type":"article","og_title":"Donne, la sfida (quasi) impossibile per conciliare lavoro e famiglia","og_description":"l'Istat ha reso noti i dati sui servizi all'infanzia, fondamentali per cercare di aiutare la conciliazione lavoro e famiglia delle donne","og_url":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2019-03-22T06:30:08+00:00","article_modified_time":"2019-12-09T10:00:53+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/family-audit_fb.jpg","type":"image\/jpeg"}],"author":"stefaniaP","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/family-audit_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"stefaniaP","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/"},"author":{"name":"stefaniaP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/dfce5bd678ad0f650527cc2172949970"},"headline":"Donne, la sfida (quasi) impossibile per conciliare lavoro e famiglia","datePublished":"2019-03-22T06:30:08+00:00","dateModified":"2019-12-09T10:00:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/"},"wordCount":1365,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/family-audit-2019_fb.jpg","articleSection":["Family Audit"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/","url":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/","name":"Donne, la sfida (quasi) impossibile per conciliare lavoro e famiglia - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/family-audit-2019_fb.jpg","datePublished":"2019-03-22T06:30:08+00:00","dateModified":"2019-12-09T10:00:53+00:00","description":"l'Istat ha reso noti i dati sui servizi all'infanzia, fondamentali per cercare di aiutare la conciliazione lavoro e famiglia delle donne","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/family-audit-2019_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/family-audit-2019_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/i-numeri-donne-la-sfida-quasi-impossibile-per-conciliare-lavoro-e-famiglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Family Audit","item":"https:\/\/www.aibi.it\/ita\/category\/family-audit\/"},{"@type":"ListItem","position":3,"name":"Donne, la sfida (quasi) impossibile per conciliare lavoro e famiglia"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/dfce5bd678ad0f650527cc2172949970","name":"stefaniaP","url":"https:\/\/www.aibi.it\/ita\/author\/stefaniap\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:18:12","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/168190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=168190"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/168190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/164089"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=168190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=168190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=168190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}