﻿{"id":16917,"date":"2010-11-02T14:37:14","date_gmt":"2010-11-02T13:37:14","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=16917"},"modified":"2010-11-02T16:34:04","modified_gmt":"2010-11-02T15:34:04","slug":"usanepal-la-prova-provata-dellabbandono","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/","title":{"rendered":"Adozioni Usa\/Nepal: la prova dell&#8217;abbandono"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/nepal4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8233\" style=\"margin: 5px;\" title=\"nepal4\" src=\"https:\/\/www.aibi.it\/ita\/images\/nepal4.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Il Dipartimento di Stato americano sospende la concessione di visti per i bambini nepalesi in attesa di adozione<\/strong>, salvo che non venga dimostrato l\u2019abbandono.<\/p>\n<p>Per far fronte alle problematiche legate al traffico di minori in Nepal, i funzionari degli Stati Uniti richiedono <strong>la prova dell\u2019abbandono del minore<\/strong>, lasciando cos\u00ec nel limbo diverse famiglie americane in attesa di adozione, che non possono portare i bambini negli Stati Uniti.<\/p>\n<p>Gli Stati Uniti si uniscono cos\u00ec ad altri 12 paesi che hanno adottato la stessa linea d\u2019azione.<\/p>\n<p>In questo contesto si inserisce la storia di Jenni Lund di Seattle.<strong> La giovane americana si \u00e8 recata in Nepal per incontrare Pukar, il bambino di 2 anni che le \u00e8 stato assegnato in seguito all\u2019iter adottivo<\/strong>. Nonostante ci\u00f2 Jenny non potr\u00e0 portare a casa Pukar finch\u00e9 non verr\u00e0 rilasciato il visto. Al momento i due sono ancora \u201cbloccati\u201d in Nepal, mentre il Dipartimento di Stato sta indagando sul caso, alla ricerca di \u201cprove sufficienti\u201d che possano confermare lo stato di abbandono del bambino.<\/p>\n<p>Da una lettera inviata alla donna il 27 ottobre 2010 da parte del Dipartimento di Stato, sembra che da un\u2019analisi preliminare sulla vita del bambino ci possano essere le condizioni necessarie per concludere l\u2019adozione e rientrare in USA.<\/p>\n<p><strong>Secondo il Times negli Stati Uniti sono circa 80 le famiglie che si trovano a vivere una situazione simile.<\/strong><\/p>\n<p><strong>John Meske<\/strong>, direttore esecutivo della <strong>Faith International<\/strong>, la principale autorit\u00e0 americana in materia di adozioni in Nepal, dichiara che <strong>il divieto dei visti non prende in considerazione la cultura e la realt\u00e0 della vita in Nepal, uno dei paesi pi\u00f9 poveri del mondo<\/strong>.<br \/>\nLe donne non sposate in attesa sono oggetto di persecuzioni e di delitti d&#8217;onore.<br \/>\n<em>&#8220;La situazione in Nepal \u00e8 inimmaginabile&#8221;<\/em>, ha dichiarato Meske. <em>&#8220;Alla fine, le azioni intraprese rischiano di danneggiare non solo le famiglie americane, ma &#8230; i bambini orfani che hanno bisogno di famiglie in modo permanente&#8221;<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Il Dipartimento di Stato americano sospende la concessione di visti per i bambini nepalesi in attesa di adozione<\/strong>, salvo che non venga dimostrato l\u2019abbandono. Per far fronte alle problematiche legate al traffico di minori in Nepal, i funzionari degli Stati Uniti richiedono <strong>la prova dell\u2019abbandono del minore<\/strong>, lasciando cos\u00ec nel limbo diverse famiglie americane in attesa di adozione, che non possono portare i bambini negli Stati Uniti.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-16917","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni Usa\/Nepal: la prova dell&#039;abbandono - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni Usa\/Nepal: la prova dell&#039;abbandono\" \/>\n<meta property=\"og:description\" content=\"Il Dipartimento di Stato americano sospende la concessione di visti per i bambini nepalesi in attesa di adozione, salvo che non venga dimostrato l\u2019abbandono. Per far fronte alle problematiche legate al traffico di minori in Nepal, i funzionari degli Stati Uniti richiedono la prova dell\u2019abbandono del minore, lasciando cos\u00ec nel limbo diverse famiglie americane in attesa di adozione, che non possono portare i bambini negli Stati Uniti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-11-02T13:37:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-11-02T15:34:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/nepal4.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/usanepal-la-prova-provata-dellabbandono\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/usanepal-la-prova-provata-dellabbandono\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni Usa\\\/Nepal: la prova dell&#8217;abbandono\",\"datePublished\":\"2010-11-02T13:37:14+00:00\",\"dateModified\":\"2010-11-02T15:34:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/usanepal-la-prova-provata-dellabbandono\\\/\"},\"wordCount\":322,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/usanepal-la-prova-provata-dellabbandono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/nepal4.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/usanepal-la-prova-provata-dellabbandono\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/usanepal-la-prova-provata-dellabbandono\\\/\",\"name\":\"Adozioni Usa\\\/Nepal: la prova dell'abbandono - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/usanepal-la-prova-provata-dellabbandono\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/usanepal-la-prova-provata-dellabbandono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/nepal4.jpg\",\"datePublished\":\"2010-11-02T13:37:14+00:00\",\"dateModified\":\"2010-11-02T15:34:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/usanepal-la-prova-provata-dellabbandono\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/usanepal-la-prova-provata-dellabbandono\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/usanepal-la-prova-provata-dellabbandono\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/nepal4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/nepal4.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/usanepal-la-prova-provata-dellabbandono\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni Usa\\\/Nepal: la prova dell&#8217;abbandono\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni Usa\/Nepal: la prova dell'abbandono - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni Usa\/Nepal: la prova dell'abbandono","og_description":"Il Dipartimento di Stato americano sospende la concessione di visti per i bambini nepalesi in attesa di adozione, salvo che non venga dimostrato l\u2019abbandono. Per far fronte alle problematiche legate al traffico di minori in Nepal, i funzionari degli Stati Uniti richiedono la prova dell\u2019abbandono del minore, lasciando cos\u00ec nel limbo diverse famiglie americane in attesa di adozione, che non possono portare i bambini negli Stati Uniti.","og_url":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-11-02T13:37:14+00:00","article_modified_time":"2010-11-02T15:34:04+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/nepal4.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni Usa\/Nepal: la prova dell&#8217;abbandono","datePublished":"2010-11-02T13:37:14+00:00","dateModified":"2010-11-02T15:34:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/"},"wordCount":322,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/nepal4.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/","url":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/","name":"Adozioni Usa\/Nepal: la prova dell'abbandono - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/nepal4.jpg","datePublished":"2010-11-02T13:37:14+00:00","dateModified":"2010-11-02T15:34:04+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/nepal4.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/nepal4.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/usanepal-la-prova-provata-dellabbandono\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni Usa\/Nepal: la prova dell&#8217;abbandono"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:37:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=16917"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/16917\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=16917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=16917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=16917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}