﻿


{"id":169574,"date":"2019-11-21T11:17:28","date_gmt":"2019-11-21T10:17:28","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=169574"},"modified":"2019-11-21T11:17:28","modified_gmt":"2019-11-21T10:17:28","slug":"adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/","title":{"rendered":"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d"},"content":{"rendered":"<h2>Per conferire l\u2019incarico a un ente autorizzato bisogna sempre tenere d\u2019occhio la scadenza del decreto<\/h2>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-157320 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>Il decreto di idoneit\u00e0 all\u2019adozione internazionale ha una scadenza, che deve essere presa attentamente in considerazione<\/strong> quando si decide di conferire l\u2019incarico a un ente autorizzato. Capita, purtroppo, che a volte qualcuno si dimentichi. A volte perch\u00e9 si perde motivazione, perch\u00e9 si torna a pensare a un\u2019adozione nazionale, per problemi economici.<\/p>\n<p><strong>A volte, per quanto possa sembrare assurdo, succede anche perch\u00e9\u2026 il tempo passa in fretta<\/strong>. Cos\u00ec, recentemente, nell\u2019ufficio di una delle sedi regionali di <strong>Ai.Bi. \u2013 Amici dei Bambini<\/strong> \u00e8 arrivata una coppia che si \u00e8 accorta di avere il decreto in scadenza entro due settimane. Gi\u00e0, ed \u00e8 una storia che merita di essere raccontata. Perch\u00e9 lo<em> staff<\/em> ha infatti dovuto spiegare che, essendo molto tardi, l\u2019ente difficilmente avrebbe potuto assicurare l\u2019incarico, visto che, prima del conferimento, sono necessari diversi passaggi formali.<\/p>\n<p>Alla domanda sul perch\u00e9 avessero atteso cos\u00ec tanto, la risposta \u00e8 stata spiazzante, nella sua trasparenza. <strong><em>\u201cSinceramente i giorni sono passati e non ce ne siamo accorti\u2026 poi ci siamo ricordati e ora stiamo facendo in fretta e furia\u2026<\/em><\/strong>\u201d.<\/p>\n<p><strong>Questa frase, che potrebbe sembrare una banale scusa, rivela quanto sia necessaria una adeguata preparazione delle coppie, non solo dal punto di vista emotivo e psicologico, ma anche formale<\/strong>. Questi due aspiranti genitori, ora, rischiano di perdere l\u2019opportunit\u00e0 di accogliere un figlio per una mera dimenticanza di carattere burocratico. Che, per\u00f2, rischia di pesare tantissimo sul loro futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per conferire l&rsquo;incarico a un ente autorizzato bisogna sempre tenere d&rsquo;occhio la scadenza del decreto Il decreto di idoneit&agrave; all&rsquo;adozione internazionale ha una scadenza, che deve essere presa attentamente in considerazione quando si decide di conferire l&rsquo;incarico a un ente autorizzato. Capita, purtroppo, che a volte qualcuno si dimentichi. A [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":157320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[347],"class_list":["post-169574","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-adozione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d. Bisogna sempre tenere d&#039;occhio la scadenza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0&quot;\" \/>\n<meta property=\"og:description\" content=\"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d. Bisogna sempre tenere d&#039;occhio la scadenza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-21T10:17:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d\" \/>\n<meta name=\"twitter:description\" content=\"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d. Bisogna sempre tenere d&#039;occhio la scadenza.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d\",\"datePublished\":\"2019-11-21T10:17:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\\\/\"},\"wordCount\":264,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/coppia-idonea_700x460.jpg\",\"keywords\":[\"Adozione Internazionale\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\\\/\",\"name\":\"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/coppia-idonea_700x460.jpg\",\"datePublished\":\"2019-11-21T10:17:28+00:00\",\"description\":\"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d. Bisogna sempre tenere d'occhio la scadenza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/coppia-idonea_700x460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/coppia-idonea_700x460.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d - Ai.Bi. Amici dei Bambini","description":"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d. Bisogna sempre tenere d'occhio la scadenza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\"","og_description":"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d. Bisogna sempre tenere d'occhio la scadenza.","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2019-11-21T10:17:28+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d","twitter_description":"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d. Bisogna sempre tenere d'occhio la scadenza.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d","datePublished":"2019-11-21T10:17:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/"},"wordCount":264,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460.jpg","keywords":["Adozione Internazionale"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/","name":"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460.jpg","datePublished":"2019-11-21T10:17:28+00:00","description":"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d. Bisogna sempre tenere d'occhio la scadenza.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/coppia-idonea_700x460.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-mamma-mia-e-gia-trascorso-un-anno-e-ci-scade-lidoneita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozione internazionale. \u201cMamma mia, \u00e8 gi\u00e0 trascorso un anno e ci scade l\u2019idoneit\u00e0\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:48:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/169574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=169574"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/169574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/157320"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=169574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=169574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=169574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}