﻿


{"id":169930,"date":"2019-12-04T12:43:39","date_gmt":"2019-12-04T11:43:39","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=169930"},"modified":"2019-12-04T14:46:44","modified_gmt":"2019-12-04T13:46:44","slug":"adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/","title":{"rendered":"Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa"},"content":{"rendered":"<h2>Ancora sconcerto per il taglio al Fondo adozioni, ma si spera negli emendamenti del senatore Collina<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-155803 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>Il crollo delle <strong>adozioni internazionali<\/strong> \u00e8 talmente vertiginoso da catturare, ormai, anche l\u2019interesse delle pagine principali della grande stampa. Che, finalmente, inizia ad accorgersi di una situazione sempre pi\u00f9 drammatica. Cos\u00ec, nella giornata di ieri, il quotidiano <strong><em>La Stampa<\/em><\/strong> \u00e8 uscito con un articolo sulla tragica flessione che, nel 2019, porter\u00e0 l\u2019Italia al di sotto della soglia di un migliaio di pratiche concluse.<\/p>\n<p>Meno di mille nuove famiglie adottive, quando, solo nove anni fa, erano ben oltre le tremila l\u2019anno. In questo scenario si \u00e8 inserita la contestatissima decisione, da parte del Governo, di operare, in sede di legge di bilancio, un taglio sul Fondo adozioni per il prossimo triennio. Taglio pari a circa due milioni di euro.<\/p>\n<p>Una riduzione che ha generato le proteste della cabina di regia<strong> Adozioni 3.0<\/strong>, che riunisce i 49 enti autorizzati in Italia. \u201c<em>Una scelta assurda<\/em> \u2013 avevano protestato gli enti autorizzati \u2013 <em>nel momento in cui le famiglie hanno un bisogno disperato di supporto alla genitorialit\u00e0, di qualsiasi tipo<\/em>\u201d. E, soprattutto, dopo che lo stesso ministro della Famiglia, Elena Bonetti, aveva dichiarato che bisognava rilanciare le adozioni.<\/p>\n<p><em>\u201cIl crollo delle adozioni internazionali<\/em> \u2013 spiega l\u2019articolo de<em> La Stampa<\/em>, firmato da <strong>Filippo Femia<\/strong> e <strong>Nicola Pinna<\/strong> &#8211; <em>\u00e8 un fenomeno progressivo. Le cause sono aumentate negli anni. La crisi economica ha provocato il primo rallentamento. Perch\u00e9 adottare fuori dai confini italiani costa molto: dai 15 mila ai 25 mila euro, a seconda dei Paesi e del numero di viaggi richiesti. Per questo gli enti chiedono un sostegno da parte del Governo\u201d.<\/em><\/p>\n<p>\u201c<em>Ora gli enti<\/em> \u2013 prosegue l\u2019articolo &#8211; <em>sperano negli emendamenti alla manovra presentati dal senatore Stefano Collina (PD). Uno di questi finanzia con 75 milioni in tre anni il Fondo per le adozioni. Una boccata d&#8217;ossigeno che nel 2020 potrebbe riportare le adozioni sopra quota mille\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ancora sconcerto per il taglio al Fondo adozioni, ma si spera negli emendamenti del senatore Collina Il crollo delle adozioni internazionali &egrave; talmente vertiginoso da catturare, ormai, anche l&rsquo;interesse delle pagine principali della grande stampa. Che, finalmente, inizia ad accorgersi di una situazione sempre pi&ugrave; drammatica. Cos&igrave;, nella giornata di [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":155803,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[372],"class_list":["post-169930","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-adozioni-internazionali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Ancora sconcerto per il taglio di due milioni di euro al Fondo adozioni, ma si spera negli emendamenti del senatore Collina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa\" \/>\n<meta property=\"og:description\" content=\"Ancora sconcerto per il taglio di due milioni di euro al Fondo adozioni, ma si spera negli emendamenti del senatore Collina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-04T11:43:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-04T13:46:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa\" \/>\n<meta name=\"twitter:description\" content=\"Ancora sconcerto per il taglio di due milioni di euro al Fondo adozioni, ma si spera negli emendamenti del senatore Collina.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa\",\"datePublished\":\"2019-12-04T11:43:39+00:00\",\"dateModified\":\"2019-12-04T13:46:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\\\/\"},\"wordCount\":326,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/laura-laera-adozioni_700x460.jpg\",\"keywords\":[\"adozioni internazionali\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\\\/\",\"name\":\"Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/laura-laera-adozioni_700x460.jpg\",\"datePublished\":\"2019-12-04T11:43:39+00:00\",\"dateModified\":\"2019-12-04T13:46:44+00:00\",\"description\":\"Ancora sconcerto per il taglio di due milioni di euro al Fondo adozioni, ma si spera negli emendamenti del senatore Collina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/laura-laera-adozioni_700x460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/laura-laera-adozioni_700x460.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa - Ai.Bi. Amici dei Bambini","description":"Ancora sconcerto per il taglio di due milioni di euro al Fondo adozioni, ma si spera negli emendamenti del senatore Collina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa","og_description":"Ancora sconcerto per il taglio di due milioni di euro al Fondo adozioni, ma si spera negli emendamenti del senatore Collina.","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2019-12-04T11:43:39+00:00","article_modified_time":"2019-12-04T13:46:44+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa","twitter_description":"Ancora sconcerto per il taglio di due milioni di euro al Fondo adozioni, ma si spera negli emendamenti del senatore Collina.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa","datePublished":"2019-12-04T11:43:39+00:00","dateModified":"2019-12-04T13:46:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/"},"wordCount":326,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460.jpg","keywords":["adozioni internazionali"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/","name":"Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460.jpg","datePublished":"2019-12-04T11:43:39+00:00","dateModified":"2019-12-04T13:46:44+00:00","description":"Ancora sconcerto per il taglio di due milioni di euro al Fondo adozioni, ma si spera negli emendamenti del senatore Collina.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/laura-laera-adozioni_700x460.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sotto-quota-mille-allanno-e-della-crisi-si-accorge-anche-la-grande-stampa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni internazionali sotto quota mille all\u2019anno. E della crisi si accorge anche la grande stampa"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:59:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/169930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=169930"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/169930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/155803"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=169930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=169930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=169930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}