﻿


{"id":170129,"date":"2019-12-11T14:12:16","date_gmt":"2019-12-11T13:12:16","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=170129"},"modified":"2019-12-11T16:16:27","modified_gmt":"2019-12-11T15:16:27","slug":"adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/","title":{"rendered":"Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec?"},"content":{"rendered":"<h2>Una burocrazia rigida e fredda e poca preparazione rischiano di scoraggiare le coppie<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-152598 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460-457x300.jpg\" alt=\"tribunale di livorno\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>Un incontro come tanti ne capitano, nelle sedi di <strong>Ai.Bi. \u2013 Amici dei Bambini<\/strong>, ente autorizzato all\u2019adozione internazionale. La coppia arriva e, in apertura di colloquio, dice di aver trovato Ai.Bi. facendo la ricerca degli enti sul sito <strong>CAI<\/strong> e di aver visto poi il sito dell\u2019organizzazione. A quel punto inizia la descrizione della fase preliminare con i servizi sociali: l\u2019iter descritto \u00e8 molto deludente e con informazioni tutte da costruire.<\/p>\n<p>Quando vanno al <strong>Tribunale per i Minorenni<\/strong> a depositare la domanda di idoneit\u00e0, la cancelliera li tratta malissimo e loro che erano andati pieni di gioia per il percorso che stavano intraprendendo dicono di essere tornati a casa con l\u2019idea di andarsi a riprendere i documenti il giorno seguente e non fare pi\u00f9 nulla.<\/p>\n<p>Dicono, per\u00f2, che loro desiderano adottare e quindi hanno preso coscienza di come questo sia <em>\u201cstato il primo banco di prova della nostra tenacia<\/em>\u201d. Il percorso di gruppo lo descrivono molto istruttivo. Raccontano, per\u00f2, che, siccome abitano in un paese molto lontano dalla sede del corso, la psicologa e l\u2019assistente sociale che poi hanno fatto loro i colloqui sono state inviate dal Comune di residenza e la loro preparazione era piuttosto scarsa, inferiore anche a quella della coppia. Che, fortunatamente, in questo caso specifico, pur avendolo pensato, non si \u00e8 arenata alle prime difficolt\u00e0.<\/p>\n<p>Insomma, il primo contatto, con il mondo dell\u2019adozione, \u00e8 il pi\u00f9 importante. Il banco di prova. Tuttavia, in Italia, questo contatto avviene con un freddo tribunale. L\u2019Italia \u00e8 rimasta anche l\u2019unico Paese europeo a conservare l\u2019idoneit\u00e0 giudiziaria. Ma \u00e8 normale tutto questo? Ed \u00e8 normale che, anzich\u00e9 la formazione delle coppie sulle necessit\u00e0 del bambino che aspira a tornare \u201cfiglio\u201d, a prevalere sia l\u2019aspetto freddo e burocratico? <strong>Aspetto che, peraltro, rischia di scoraggiare le coppie medesime, proprio perch\u00e9 non ancora preparate, sul nascere&#8230;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una burocrazia rigida e fredda e poca preparazione rischiano di scoraggiare le coppie Un incontro come tanti ne capitano, nelle sedi di Ai.Bi. &ndash; Amici dei Bambini, ente autorizzato all&rsquo;adozione internazionale. La coppia arriva e, in apertura di colloquio, dice di aver trovato Ai.Bi. facendo la ricerca degli enti sul [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":152598,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[347,344],"class_list":["post-170129","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-adozione-internazionale","tag-tribunale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Una burocrazia rigida e fredda e poca preparazione rischiano di scoraggiare le coppie. Adozione internazionale. Il primo banco di prova? Con il Tribunale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec?\" \/>\n<meta property=\"og:description\" content=\"Una burocrazia rigida e fredda e poca preparazione rischiano di scoraggiare le coppie. Adozione internazionale. Il primo banco di prova? Con il Tribunale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-11T13:12:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-11T15:16:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec?\" \/>\n<meta name=\"twitter:description\" content=\"Una burocrazia rigida e fredda e poca preparazione rischiano di scoraggiare le coppie. Adozione internazionale. Il primo banco di prova? Con il Tribunale.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec?\",\"datePublished\":\"2019-12-11T13:12:16+00:00\",\"dateModified\":\"2019-12-11T15:16:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\\\/\"},\"wordCount\":336,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/livorno-tribunale_700X460.jpg\",\"keywords\":[\"Adozione Internazionale\",\"tribunale\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\\\/\",\"name\":\"Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/livorno-tribunale_700X460.jpg\",\"datePublished\":\"2019-12-11T13:12:16+00:00\",\"dateModified\":\"2019-12-11T15:16:27+00:00\",\"description\":\"Una burocrazia rigida e fredda e poca preparazione rischiano di scoraggiare le coppie. Adozione internazionale. Il primo banco di prova? Con il Tribunale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/livorno-tribunale_700X460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/livorno-tribunale_700X460.jpg\",\"width\":700,\"height\":460,\"caption\":\"tribunale di livorno\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec? - Ai.Bi. Amici dei Bambini","description":"Una burocrazia rigida e fredda e poca preparazione rischiano di scoraggiare le coppie. Adozione internazionale. Il primo banco di prova? Con il Tribunale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec?","og_description":"Una burocrazia rigida e fredda e poca preparazione rischiano di scoraggiare le coppie. Adozione internazionale. Il primo banco di prova? Con il Tribunale.","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2019-12-11T13:12:16+00:00","article_modified_time":"2019-12-11T15:16:27+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec?","twitter_description":"Una burocrazia rigida e fredda e poca preparazione rischiano di scoraggiare le coppie. Adozione internazionale. Il primo banco di prova? Con il Tribunale.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec?","datePublished":"2019-12-11T13:12:16+00:00","dateModified":"2019-12-11T15:16:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/"},"wordCount":336,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460.jpg","keywords":["Adozione Internazionale","tribunale"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/","name":"Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460.jpg","datePublished":"2019-12-11T13:12:16+00:00","dateModified":"2019-12-11T15:16:27+00:00","description":"Una burocrazia rigida e fredda e poca preparazione rischiano di scoraggiare le coppie. Adozione internazionale. Il primo banco di prova? Con il Tribunale.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/livorno-tribunale_700X460.jpg","width":700,"height":460,"caption":"tribunale di livorno"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-il-primo-banco-di-prova-quello-con-il-tribunale-ma-e-giusto-che-sia-cosi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozione internazionale. Il primo banco di prova? Quello con il Tribunale. Ma \u00e8 giusto che sia cos\u00ec?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:50:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=170129"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/152598"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=170129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=170129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=170129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}