﻿


{"id":170209,"date":"2019-12-13T19:46:24","date_gmt":"2019-12-13T18:46:24","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=170209"},"modified":"2019-12-13T19:46:24","modified_gmt":"2019-12-13T18:46:24","slug":"mon-tremolada-benedisce-laccoglienza-di-villa-capitanio","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/","title":{"rendered":"Mon. Tremolada benedisce l&#8217;accoglienza di &#8220;Villa Capitanio&#8221;"},"content":{"rendered":"<p>Il vescovo della Diocesi di Brescia Mons.Tremolada fa visita al nostro progetto di accoglienza e protezione per mamme sole e in difficolt\u00e0 insieme ai propri figli di Ai.Bi. e AIBC, \u201cVilla Capitanio\u201d.<\/p>\n<p style=\"padding-left: 40px;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-170195\" src=\"https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb-571x300.jpg\" alt=\"\" width=\"571\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb-105x55.jpg 105w, https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb.jpg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/p>\n<p>Il presidente di AIBC, Ermes Carretta, ha ripercorso le tappe che hanno portato alla realizzazione di un\u2019opera di accoglienza fondata sul welfare di comunit\u00e0 e di condominio solidale, sperimentata con successo sul territorio bresciano grazie al supporto di una rete di volontari e famiglie di supporto.<\/p>\n<p>Mons. Tremolada ha benedetto la nuova opera di accoglienza e pregato per quanti sostengono il diritto di ogni bambino di vivere e crescere in famiglia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il vescovo della Diocesi di Brescia Mons.Tremolada fa visita al nostro progetto di accoglienza e protezione per mamme sole e in difficolt&agrave; insieme ai propri figli di Ai.Bi. e AIBC, &ldquo;Villa Capitanio&rdquo;. Il presidente di AIBC, Ermes Carretta, ha ripercorso le tappe che hanno portato alla realizzazione di un&rsquo;opera di [&hellip;]<\/p>\n","protected":false},"author":75,"featured_media":170195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-170209","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mon. Tremolada benedisce l&#039;accoglienza di &quot;Villa Capitanio&quot; - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mon. Tremolada benedisce l&#039;accoglienza di &quot;Villa Capitanio&quot;\" \/>\n<meta property=\"og:description\" content=\"Il vescovo della Diocesi di Brescia Mons.Tremolada fa visita al nostro progetto di accoglienza e protezione per mamme sole e in difficolt&agrave; insieme ai propri figli di Ai.Bi. e AIBC, &ldquo;Villa Capitanio&rdquo;. Il presidente di AIBC, Ermes Carretta, ha ripercorso le tappe che hanno portato alla realizzazione di un&rsquo;opera di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-13T18:46:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"stefaniaP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"stefaniaP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\\\/\"},\"author\":{\"name\":\"stefaniaP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/dfce5bd678ad0f650527cc2172949970\"},\"headline\":\"Mon. Tremolada benedisce l&#8217;accoglienza di &#8220;Villa Capitanio&#8221;\",\"datePublished\":\"2019-12-13T18:46:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\\\/\"},\"wordCount\":114,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/inaugurazione-villa-capitanio-vescovo_fb.jpg\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\\\/\",\"name\":\"Mon. Tremolada benedisce l'accoglienza di \\\"Villa Capitanio\\\" - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/inaugurazione-villa-capitanio-vescovo_fb.jpg\",\"datePublished\":\"2019-12-13T18:46:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/inaugurazione-villa-capitanio-vescovo_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/inaugurazione-villa-capitanio-vescovo_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mon. Tremolada benedisce l&#8217;accoglienza di &#8220;Villa Capitanio&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/dfce5bd678ad0f650527cc2172949970\",\"name\":\"stefaniaP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/stefaniap\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mon. Tremolada benedisce l'accoglienza di \"Villa Capitanio\" - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/","og_locale":"it_IT","og_type":"article","og_title":"Mon. Tremolada benedisce l'accoglienza di \"Villa Capitanio\"","og_description":"Il vescovo della Diocesi di Brescia Mons.Tremolada fa visita al nostro progetto di accoglienza e protezione per mamme sole e in difficolt&agrave; insieme ai propri figli di Ai.Bi. e AIBC, &ldquo;Villa Capitanio&rdquo;. Il presidente di AIBC, Ermes Carretta, ha ripercorso le tappe che hanno portato alla realizzazione di un&rsquo;opera di [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2019-12-13T18:46:24+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb.jpg","type":"image\/jpeg"}],"author":"stefaniaP","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"stefaniaP","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/"},"author":{"name":"stefaniaP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/dfce5bd678ad0f650527cc2172949970"},"headline":"Mon. Tremolada benedisce l&#8217;accoglienza di &#8220;Villa Capitanio&#8221;","datePublished":"2019-12-13T18:46:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/"},"wordCount":114,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb.jpg","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/","url":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/","name":"Mon. Tremolada benedisce l'accoglienza di \"Villa Capitanio\" - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb.jpg","datePublished":"2019-12-13T18:46:24+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/inaugurazione-villa-capitanio-vescovo_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/mon-tremolada-benedisce-laccoglienza-di-villa-capitanio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"Mon. Tremolada benedisce l&#8217;accoglienza di &#8220;Villa Capitanio&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/dfce5bd678ad0f650527cc2172949970","name":"stefaniaP","url":"https:\/\/www.aibi.it\/ita\/author\/stefaniap\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:20:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=170209"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/170195"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=170209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=170209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=170209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}