﻿


{"id":170396,"date":"2019-12-24T06:03:18","date_gmt":"2019-12-24T05:03:18","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=170396"},"modified":"2019-12-24T10:18:30","modified_gmt":"2019-12-24T09:18:30","slug":"lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/","title":{"rendered":"Lettera di Aniel a Babbo Natale \u201cPer i miei amici di Haiti vorrei una mamma e un pap\u00e0 come i miei\u201d"},"content":{"rendered":"<h2>&#8220;<em>Mamma, pap\u00e0,\u00a0 mi date un foglio di carta colorata per favore? Voglio scrivere a Babbo Natale! E ancora una volta ci lascia senza fiato<\/em>\u201d racconta mamma Elena per Aibinews<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-170377\" src=\"https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460-165x109.jpg 165w, https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460.jpg 700w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/><\/p>\n<p>&#8220;Aniel e&#8217; arrivato in Italia da circa 9 mesi.\u201d &#8211; raccontano emozionati e orgogliosi mamma Elena e pap\u00e0 Mauro per Aibinews . \u201cNostro figlio \u00e8 arrivato da Haiti: un Paese molto povero, dalle mille contraddizioni, dai mille colori e sapori, un Paese che stupisce, sempre. E questa stessa capacit\u00e0 di stupire la si ritrova proprio nei suoi meravigliosi bambini. Aniel \u00e8 ogni giorno una scoperta, una baraonda di emozioni. Aniel ha un cuore grande, cos\u00ec come i suoi occhi: grandi, profondi e neri. Ci avviciniamo al Natale e, per la prima volta nella sua vita, anche lui scrive una letterina a Babbo Natale&#8230; E ancora una volta ci lascia senza fiato.\u201d<\/p>\n<p><em>&#8220;Caro Babbo Natale, e&#8217; il mio primo anno in Italia\u201d<\/em> \u2013 si legge nella sua letterina \u201c<em>E mi piacerebbe ricevere questi regali: Lego city treno passeggeri, Lego city\u00a0 eliambulanza, Lego city aereo da carico, trattore con telecomando, scarpe da ginnastica, maglia di lana, libro del re Leone, libro di Frozen \u2026 e per i miei amici di Haiti vorrei una mamma e un pap\u00e0 come i miei<\/em>.\u201d<\/p>\n<p>\u201cE\u2019 questo\u201d \u2013 continua Elena \u2013 \u201cIl<em> vero significato del Natale visto con gli occhi di un bambino; un bambino di 8 anni che arriva da lontano e che \u00e8 cos\u00ec profondamente consapevole. E ci commuoviamo ancora e ancora rileggendola<\/em>.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&ldquo;Mamma, pap&agrave;,&nbsp; mi date un foglio di carta colorata per favore? Voglio scrivere a Babbo Natale! E ancora una volta ci lascia senza fiato&rdquo; racconta mamma Elena per Aibinews &ldquo;Aniel e&rsquo; arrivato in Italia da circa 9 mesi.&rdquo; &ndash; raccontano emozionati e orgogliosi mamma Elena e pap&agrave; Mauro per Aibinews [&hellip;]<\/p>\n","protected":false},"author":75,"featured_media":170377,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-170396","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lettera di Aniel a Babbo Natale \u201cPer i miei amici di Haiti vorrei una mamma e un pap\u00e0 come i miei\u201d - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"&quot;Mamma, pap\u00e0,\u00a0 mi date un foglio di carta colorata per favore? Voglio scrivere a Babbo Natale! E ancora una volta ci lascia senza fiato\u201d racconta mamma Elena per Aibinews\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lettera di Aniel a Babbo Natale \u201cPer i miei amici di Haiti vorrei una mamma e un pap\u00e0 come i miei\u201d\" \/>\n<meta property=\"og:description\" content=\"&quot;Mamma, pap\u00e0,\u00a0 mi date un foglio di carta colorata per favore? Voglio scrivere a Babbo Natale! E ancora una volta ci lascia senza fiato\u201d racconta mamma Elena per Aibinews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-24T05:03:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-24T09:18:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"stefaniaP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"stefaniaP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\\\/\"},\"author\":{\"name\":\"stefaniaP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/dfce5bd678ad0f650527cc2172949970\"},\"headline\":\"Lettera di Aniel a Babbo Natale \u201cPer i miei amici di Haiti vorrei una mamma e un pap\u00e0 come i miei\u201d\",\"datePublished\":\"2019-12-24T05:03:18+00:00\",\"dateModified\":\"2019-12-24T09:18:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\\\/\"},\"wordCount\":258,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-regalo-di-natale_700x460.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\\\/\",\"name\":\"Lettera di Aniel a Babbo Natale \u201cPer i miei amici di Haiti vorrei una mamma e un pap\u00e0 come i miei\u201d - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-regalo-di-natale_700x460.jpg\",\"datePublished\":\"2019-12-24T05:03:18+00:00\",\"dateModified\":\"2019-12-24T09:18:30+00:00\",\"description\":\"\\\"Mamma, pap\u00e0,\u00a0 mi date un foglio di carta colorata per favore? Voglio scrivere a Babbo Natale! E ancora una volta ci lascia senza fiato\u201d racconta mamma Elena per Aibinews\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-regalo-di-natale_700x460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-regalo-di-natale_700x460.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lettera di Aniel a Babbo Natale \u201cPer i miei amici di Haiti vorrei una mamma e un pap\u00e0 come i miei\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/dfce5bd678ad0f650527cc2172949970\",\"name\":\"stefaniaP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/stefaniap\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lettera di Aniel a Babbo Natale \u201cPer i miei amici di Haiti vorrei una mamma e un pap\u00e0 come i miei\u201d - Ai.Bi. Amici dei Bambini","description":"\"Mamma, pap\u00e0,\u00a0 mi date un foglio di carta colorata per favore? Voglio scrivere a Babbo Natale! E ancora una volta ci lascia senza fiato\u201d racconta mamma Elena per Aibinews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/","og_locale":"it_IT","og_type":"article","og_title":"Lettera di Aniel a Babbo Natale \u201cPer i miei amici di Haiti vorrei una mamma e un pap\u00e0 come i miei\u201d","og_description":"\"Mamma, pap\u00e0,\u00a0 mi date un foglio di carta colorata per favore? Voglio scrivere a Babbo Natale! E ancora una volta ci lascia senza fiato\u201d racconta mamma Elena per Aibinews","og_url":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2019-12-24T05:03:18+00:00","article_modified_time":"2019-12-24T09:18:30+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_fb.jpg","type":"image\/jpeg"}],"author":"stefaniaP","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"stefaniaP","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/"},"author":{"name":"stefaniaP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/dfce5bd678ad0f650527cc2172949970"},"headline":"Lettera di Aniel a Babbo Natale \u201cPer i miei amici di Haiti vorrei una mamma e un pap\u00e0 come i miei\u201d","datePublished":"2019-12-24T05:03:18+00:00","dateModified":"2019-12-24T09:18:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/"},"wordCount":258,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/","url":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/","name":"Lettera di Aniel a Babbo Natale \u201cPer i miei amici di Haiti vorrei una mamma e un pap\u00e0 come i miei\u201d - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460.jpg","datePublished":"2019-12-24T05:03:18+00:00","dateModified":"2019-12-24T09:18:30+00:00","description":"\"Mamma, pap\u00e0,\u00a0 mi date un foglio di carta colorata per favore? Voglio scrivere a Babbo Natale! E ancora una volta ci lascia senza fiato\u201d racconta mamma Elena per Aibinews","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-regalo-di-natale_700x460.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/lettera-di-aniel-a-babbo-natale-per-i-miei-amici-di-haiti-vorrei-una-mamma-e-un-papa-come-i-miei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Lettera di Aniel a Babbo Natale \u201cPer i miei amici di Haiti vorrei una mamma e un pap\u00e0 come i miei\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/dfce5bd678ad0f650527cc2172949970","name":"stefaniaP","url":"https:\/\/www.aibi.it\/ita\/author\/stefaniap\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:46:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=170396"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170396\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/170377"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=170396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=170396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=170396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}