﻿


{"id":170472,"date":"2020-01-03T12:34:34","date_gmt":"2020-01-03T11:34:34","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=170472"},"modified":"2020-01-03T12:34:51","modified_gmt":"2020-01-03T11:34:51","slug":"milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/","title":{"rendered":"Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d"},"content":{"rendered":"<h2>Esperienza aperta alle famiglie adottive della Lombardia, si terr\u00e0 nella chiesa di Santa Giustina. Ulteriore passaggio del cammino spirituale delle famiglie di Ai.Bi. \u2013 Amici dei Bambini e de \u201cLa Pietra Scartata\u201d<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-162188 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>Tutte le famiglie adottive della Lombardia sono invitate a partecipare al \u201c<strong><em>Rito della Benedizione delle adozioni\u201d<\/em><\/strong>, che si terr\u00e0 <strong>domenica 2 febbraio 2020 alle ore 11.30 presso la chiesa di Santa Giustina a Milano, in piazza Santa Giustina.<\/strong> Il Rito della Benedizione delle adozioni raccoglie ed esprime un ulteriore passaggio del cammino spirituale che le famiglie adottive dell\u2019<strong>Associazione La Pietra Scartata<\/strong> e di <strong>Ai.Bi. &#8211; Amici dei Bambini,<\/strong> organizzazione nata oltre trent\u2019anni la cui mission \u00e8 la lotta contro l\u2019abbandono minorile in Italia e in diversi Paesi del mondo, hanno vissuto in questi anni.<\/p>\n<p>Celebrato per la prima volta a Roma il 7 dicembre 2008 dalle famiglie dell\u2019associazione di fedeli La Pietra Scartata (costituita nel 2007 dal \u201ccuore\u201d e dal \u201cpatrimonio genetico\u201d di Ai.Bi. &#8211; Amici dei Bambini), <strong>il Rito della Benedizione delle adozioni intende esprimere il senso cristiano dell\u2019accoglienza con un\u2019adozione vissuta nel nome del Signore e condivisa con la comunit\u00e0 ecclesiale.<\/strong><\/p>\n<p>Si tratta di un appuntamento, dedicato ai figli e ai genitori adottivi, in cui anche la liturgia del Rito consente di riconoscere e celebrare comunitariamente, l\u2019accoglienza vissuta quale \u201cnascita adottiva\u201d, per integrare con un autentico significato spirituale il profilo civile e anagrafico dell\u2019adozione.<\/p>\n<p><em>\u201cIl cammino sino a oggi percorso<\/em> \u2013 spiegano <strong>Cristina e Paolo Pellini, coordinatori di Ai.Bi. per la Regione Lombardia<\/strong> &#8211; <em>ci ha permesso di riconoscere ed esprimere, con sempre pi\u00f9 consapevolezza, l\u2019identit\u00e0 e il carisma del nostro movimento di famiglie accoglienti, sollecitandoci nella ricerca di tutte quelle esperienze ecclesiali che nella realt\u00e0 adottiva sono capaci di cogliere una scelta in grado di esprimere una particolare fecondit\u00e0 dell\u2019esperienza coniugale\u201d.<\/em><\/p>\n<p>Per ragioni organizzative chi volesse partecipare dovr\u00e0 comunicare l\u2019adesione oltre il 10 gennaio 2020, all\u2019indirizzo mail <a href=\"mailto:cristina.riccardi@aibi.it\" target=\"_blank\" rel=\"noopener noreferrer\">cristina.riccardi@aibi.it<\/a>. Raccolte le iscrizioni, alle coppie verr\u00e0 proposto un brevissimo percorso di preparazione che<strong> si terr\u00e0 l\u201911 e il 25 gennaio 2020 presso il Centro Servizi alla Famiglia \u201cFidarsi della Vita\u201d in viale Affori 12, Milano, alle ore 17,00,<\/strong> con la possibilit\u00e0 di incontrare famiglie che hanno gi\u00e0 vissuto l\u2019esperienza del Rito della Benedizione delle adozioni con i loro figli.<\/p>\n<p><strong>Domenica 2 febbraio 2020<\/strong> il ritrovo \u00e8 previsto presso il <strong>Centro Servizi alla Famiglia \u201cFidarsi della Vita\u201d<\/strong> <strong>alle ore 9,30<\/strong>; mentre i bambini giocheranno nella ludoteca del Centro, i genitori avranno un momento di preparazione al Rito con D<strong>on Massimiliano Sabbadini, consigliere spirituale de La Pietra Scartata.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esperienza aperta alle famiglie adottive della Lombardia, si terr&agrave; nella chiesa di Santa Giustina. Ulteriore passaggio del cammino spirituale delle famiglie di Ai.Bi. &ndash; Amici dei Bambini e de &ldquo;La Pietra Scartata&rdquo; Tutte le famiglie adottive della Lombardia sono invitate a partecipare al &ldquo;Rito della Benedizione delle adozioni&rdquo;, che si [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":162188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[347,502],"class_list":["post-170472","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-adozione-internazionale","tag-la-pietra-scartata"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Esperienza aperta alle famiglie adottive della Lombardia, si terr\u00e0 nella chiesa di Santa Giustina. Ulteriore passaggio del cammino spirituale di Ai.Bi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d\" \/>\n<meta property=\"og:description\" content=\"Esperienza aperta alle famiglie adottive della Lombardia, si terr\u00e0 nella chiesa di Santa Giustina. Ulteriore passaggio del cammino spirituale di Ai.Bi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-03T11:34:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-03T11:34:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d\" \/>\n<meta name=\"twitter:description\" content=\"Esperienza aperta alle famiglie adottive della Lombardia, si terr\u00e0 nella chiesa di Santa Giustina. Ulteriore passaggio del cammino spirituale di Ai.Bi.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d\",\"datePublished\":\"2020-01-03T11:34:34+00:00\",\"dateModified\":\"2020-01-03T11:34:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\\\/\"},\"wordCount\":429,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/incontro-cammino-benedizione-adozioni-milano_700x460.jpg\",\"keywords\":[\"Adozione Internazionale\",\"La Pietra Scartata\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\\\/\",\"name\":\"Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/incontro-cammino-benedizione-adozioni-milano_700x460.jpg\",\"datePublished\":\"2020-01-03T11:34:34+00:00\",\"dateModified\":\"2020-01-03T11:34:51+00:00\",\"description\":\"Esperienza aperta alle famiglie adottive della Lombardia, si terr\u00e0 nella chiesa di Santa Giustina. Ulteriore passaggio del cammino spirituale di Ai.Bi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/incontro-cammino-benedizione-adozioni-milano_700x460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/incontro-cammino-benedizione-adozioni-milano_700x460.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d - Ai.Bi. Amici dei Bambini","description":"Esperienza aperta alle famiglie adottive della Lombardia, si terr\u00e0 nella chiesa di Santa Giustina. Ulteriore passaggio del cammino spirituale di Ai.Bi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/","og_locale":"it_IT","og_type":"article","og_title":"Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d","og_description":"Esperienza aperta alle famiglie adottive della Lombardia, si terr\u00e0 nella chiesa di Santa Giustina. Ulteriore passaggio del cammino spirituale di Ai.Bi.","og_url":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-01-03T11:34:34+00:00","article_modified_time":"2020-01-03T11:34:51+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d","twitter_description":"Esperienza aperta alle famiglie adottive della Lombardia, si terr\u00e0 nella chiesa di Santa Giustina. Ulteriore passaggio del cammino spirituale di Ai.Bi.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d","datePublished":"2020-01-03T11:34:34+00:00","dateModified":"2020-01-03T11:34:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/"},"wordCount":429,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460.jpg","keywords":["Adozione Internazionale","La Pietra Scartata"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/","url":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/","name":"Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460.jpg","datePublished":"2020-01-03T11:34:34+00:00","dateModified":"2020-01-03T11:34:51+00:00","description":"Esperienza aperta alle famiglie adottive della Lombardia, si terr\u00e0 nella chiesa di Santa Giustina. Ulteriore passaggio del cammino spirituale di Ai.Bi.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/incontro-cammino-benedizione-adozioni-milano_700x460.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/milano-domenica-2-febbraio-il-rito-della-benedizione-delle-adozioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Milano: domenica 2 febbraio il \u201cRito della Benedizione delle adozioni\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:42:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=170472"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/162188"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=170472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=170472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=170472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}