﻿


{"id":170559,"date":"2020-01-08T14:47:12","date_gmt":"2020-01-08T13:47:12","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=170559"},"modified":"2020-01-08T15:04:18","modified_gmt":"2020-01-08T14:04:18","slug":"kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/","title":{"rendered":"Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema"},"content":{"rendered":"<h2>Sessioni dedicate ai genitori per sviluppare la capacit\u00e0 parentale e la gestione dello stress<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-170563 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2-165x109.jpg 165w, https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2.jpg 700w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>Durante le vacanze natalizie le scuole sono chiuse, certo. Ma le attivit\u00e0 di <strong>Ai.Bi. \u2013 Amici dei Bambini,<\/strong> finanziate dalla<strong> Provincia di Bolzano<\/strong>, alla scuola <strong>Utu Wema di Mukuru<\/strong>, in <strong>Kenya<\/strong>, sono proseguite. Il progetto <em>\u201cCrescere Protetti \u2013 educazione formale ed informale, promozione delle competenze genitoriali per la protezione dei minori della baraccopoli di Mukuru in Kenya\u201d,<\/em> va avanti al meglio.<\/p>\n<p>Nei mesi di ottobre, novembre e dicembre si sono tenuti importanti <em>training<\/em> per adulti e minori. I beneficiari si sono dimostrati entusiasti di iniziare questo percorso. I bambini hanno iniziato le prime lezioni riguardanti la gestione dello studio, dello stress e delle relazioni interpersonali. Vivendo in una baraccopoli gli educatori hanno iniziato a trattare di tematiche delicate quali la sicurezza e gli abusi, proseguiranno il prossimo anno con molte altre tra le quali la salute riproduttiva.<\/p>\n<p>I genitori sono stati coinvolti nelle prime due sessioni introduttive alla capacit\u00e0 parentale, alla gestione dello stress e molto altro. Il prossimo trimestre impareranno inoltre come gestire al meglio i risparmi e un business.<\/p>\n<p>Gli insegnanti e il <em>management<\/em> della scuola sono e saranno attivamente coinvolti cos\u00ec che anche al termine delle attivit\u00e0, a settembre del prossimo anno, saranno in grado di proseguire quanto fatto dagli educatori. Il programma dispone di un fondo per il cibo che ha aiutato molto la scuola Utu Wema a gestire in modo regolare l\u2019alimentazione degli studenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sessioni dedicate ai genitori per sviluppare la capacit&agrave; parentale e la gestione dello stress Durante le vacanze natalizie le scuole sono chiuse, certo. Ma le attivit&agrave; di Ai.Bi. &ndash; Amici dei Bambini, finanziate dalla Provincia di Bolzano, alla scuola Utu Wema di Mukuru, in Kenya, sono proseguite. Il progetto &ldquo;Crescere [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":170563,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[306],"class_list":["post-170559","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-kenya"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"A Natale in Kenya le scuole sono chiuse. Ma le attivit\u00e0 di Ai.Bi. \u2013 Amici dei Bambini, finanziate dalla Provincia di Bolzano sono proseguite.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema\" \/>\n<meta property=\"og:description\" content=\"A Natale in Kenya le scuole sono chiuse. Ma le attivit\u00e0 di Ai.Bi. \u2013 Amici dei Bambini, finanziate dalla Provincia di Bolzano sono proseguite.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T13:47:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-08T14:04:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema\" \/>\n<meta name=\"twitter:description\" content=\"A Natale in Kenya le scuole sono chiuse. Ma le attivit\u00e0 di Ai.Bi. \u2013 Amici dei Bambini, finanziate dalla Provincia di Bolzano sono proseguite.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa1.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema\",\"datePublished\":\"2020-01-08T13:47:12+00:00\",\"dateModified\":\"2020-01-08T14:04:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\\\/\"},\"wordCount\":256,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia_Africa2.jpg\",\"keywords\":[\"Kenya\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\\\/\",\"name\":\"Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia_Africa2.jpg\",\"datePublished\":\"2020-01-08T13:47:12+00:00\",\"dateModified\":\"2020-01-08T14:04:18+00:00\",\"description\":\"A Natale in Kenya le scuole sono chiuse. Ma le attivit\u00e0 di Ai.Bi. \u2013 Amici dei Bambini, finanziate dalla Provincia di Bolzano sono proseguite.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia_Africa2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia_Africa2.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema - Ai.Bi. Amici dei Bambini","description":"A Natale in Kenya le scuole sono chiuse. Ma le attivit\u00e0 di Ai.Bi. \u2013 Amici dei Bambini, finanziate dalla Provincia di Bolzano sono proseguite.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/","og_locale":"it_IT","og_type":"article","og_title":"Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema","og_description":"A Natale in Kenya le scuole sono chiuse. Ma le attivit\u00e0 di Ai.Bi. \u2013 Amici dei Bambini, finanziate dalla Provincia di Bolzano sono proseguite.","og_url":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-01-08T13:47:12+00:00","article_modified_time":"2020-01-08T14:04:18+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa1.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema","twitter_description":"A Natale in Kenya le scuole sono chiuse. Ma le attivit\u00e0 di Ai.Bi. \u2013 Amici dei Bambini, finanziate dalla Provincia di Bolzano sono proseguite.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa1.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema","datePublished":"2020-01-08T13:47:12+00:00","dateModified":"2020-01-08T14:04:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/"},"wordCount":256,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2.jpg","keywords":["Kenya"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/","url":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/","name":"Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2.jpg","datePublished":"2020-01-08T13:47:12+00:00","dateModified":"2020-01-08T14:04:18+00:00","description":"A Natale in Kenya le scuole sono chiuse. Ma le attivit\u00e0 di Ai.Bi. \u2013 Amici dei Bambini, finanziate dalla Provincia di Bolzano sono proseguite.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/famiglia_Africa2.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/kenya-proseguono-le-attivita-finanziate-dalla-provincia-di-bolzano-alla-scuola-utu-wema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Kenya. Proseguono le attivit\u00e0 finanziate dalla Provincia di Bolzano alla scuola Utu Wema"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:50:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=170559"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/170563"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=170559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=170559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=170559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}