﻿


{"id":170724,"date":"2020-01-15T10:25:17","date_gmt":"2020-01-15T09:25:17","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=170724"},"modified":"2020-01-15T17:27:18","modified_gmt":"2020-01-15T16:27:18","slug":"un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/","title":{"rendered":"Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi."},"content":{"rendered":"<h2>Si comincia il 2 febbraio con il rito di benedizione delle adozioni. Si chiude ad agosto con la tradizionale settimana estiva<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-167206 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>Si prospetta un anno di appuntamenti per il <strong>Gruppo delle Famiglie di Ai.Bi. \u2013 Amici dei Bambini di Mestre.<\/strong> L\u2019organizzazione \u00e8 infatti nata, oltre trent\u2019anni fa, proprio da un movimento di famiglie adottive e affidatarie. Ogni anno diversi sono gli incontri cui i nuclei familiari di Ai.Bi. partecipano. Incontri di formazione, ma non solo.<\/p>\n<p><strong>Domenica 2 febbraio 2020<\/strong>, ad esempio, si terr\u00e0, a Mestre, il <strong><em>\u201cRito di benedizione delle adozioni<\/em> <\/strong>\u201c, dedicato alle famiglie adottive. Un altro incontro si terr\u00e0 <strong>domenica 8 marzo 2020<\/strong>, con il titolo \u201c<strong><em>La legittimit\u00e0 della genitorialit\u00e0: la bellezza di essere parte di una \u2018famiglia nuova\u2019<\/em><\/strong>. <strong>Domenica 5 aprile 2020<\/strong> si terr\u00e0 invece un altro seminario dal titolo \u201c<strong><em>Fragilit\u00e0 e tenuta in una societ\u00e0 che non offre spazi di protezione e tutela: la ripartenza culturale parte dalle nostre testimonianze<\/em><\/strong>\u201d.<\/p>\n<p><strong>Domenica 10 maggio 2020 <\/strong>si avr\u00e0 invece l\u2019appuntamento \u201c<strong><em>I nostri dubbi e le nostre proposte: incontro con l&#8217;esperto\u201d<\/em><\/strong>. Sempre in maggio si terr\u00e0 la partecipazione alla<strong> Fiera4Passi<\/strong> di <strong>Treviso<\/strong>. L\u2019uscita conclusiva dell\u2019anno si terr\u00e0 dal 22 al 29 agosto 2020, in occasione della X<strong>XIX Settimana Estiva di Amici dei Bambini<\/strong> a <strong>Casino di Terra (PI).<\/strong><\/p>\n<p><em>\u201cNell&#8217;ottica dell&#8217;accoglienza e della rilevanza sociale dell&#8217;adozione<\/em> \u2013 spiega il p<strong>residente di Ai.Bi. \u2013 Amici dei Bambini, Marco Griffini<\/strong> &#8211; <em>il nostro incontrarci non vuole essere solo fine a se stesso, ma aprirsi a quanti possano e desiderino aprire le porte del proprio cuore e della propria casa ad un bambino da accogliere. Proprio per questo abbiamo pensato di creare, a partire dall\u2019incontro di marzo, dei momenti informativi e di condivisione, che inizino la domenica alle 10.30 e si concludano con l\u2019incontro del gruppo famiglie alle 15.30. La sede degli incontri verr\u00e0 comunicata di volta in volta e ai partecipanti verr\u00e0 chiesto un contributo per l&#8217;organizzazione\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comincia il 2 febbraio con il rito di benedizione delle adozioni. Si chiude ad agosto con la tradizionale settimana estiva Si prospetta un anno di appuntamenti per il Gruppo delle Famiglie di Ai.Bi. &ndash; Amici dei Bambini di Mestre. L&rsquo;organizzazione &egrave; infatti nata, oltre trent&rsquo;anni fa, proprio da un [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":167206,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[279,297],"class_list":["post-170724","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-adozione","tag-famiglia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi. - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Si comincia il 2 febbraio con il rito di benedizione delle adozioni. Si chiude ad agosto con la tradizionale settimana estiva.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi.\" \/>\n<meta property=\"og:description\" content=\"Si comincia il 2 febbraio con il rito di benedizione delle adozioni. Si chiude ad agosto con la tradizionale settimana estiva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-15T09:25:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-15T16:27:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/AiBiraduno1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi.\" \/>\n<meta name=\"twitter:description\" content=\"Si comincia il 2 febbraio con il rito di benedizione delle adozioni. Si chiude ad agosto con la tradizionale settimana estiva.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/AiBiraduno1.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi.\",\"datePublished\":\"2020-01-15T09:25:17+00:00\",\"dateModified\":\"2020-01-15T16:27:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\\\/\"},\"wordCount\":324,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/AiBiraduno2.jpg\",\"keywords\":[\"adozione\",\"famiglia\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\\\/\",\"name\":\"Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi. - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/AiBiraduno2.jpg\",\"datePublished\":\"2020-01-15T09:25:17+00:00\",\"dateModified\":\"2020-01-15T16:27:18+00:00\",\"description\":\"Si comincia il 2 febbraio con il rito di benedizione delle adozioni. Si chiude ad agosto con la tradizionale settimana estiva.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/AiBiraduno2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/AiBiraduno2.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi. - Ai.Bi. Amici dei Bambini","description":"Si comincia il 2 febbraio con il rito di benedizione delle adozioni. Si chiude ad agosto con la tradizionale settimana estiva.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/","og_locale":"it_IT","og_type":"article","og_title":"Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi.","og_description":"Si comincia il 2 febbraio con il rito di benedizione delle adozioni. Si chiude ad agosto con la tradizionale settimana estiva.","og_url":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-01-15T09:25:17+00:00","article_modified_time":"2020-01-15T16:27:18+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/AiBiraduno1.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi.","twitter_description":"Si comincia il 2 febbraio con il rito di benedizione delle adozioni. Si chiude ad agosto con la tradizionale settimana estiva.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/AiBiraduno1.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi.","datePublished":"2020-01-15T09:25:17+00:00","dateModified":"2020-01-15T16:27:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/"},"wordCount":324,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2.jpg","keywords":["adozione","famiglia"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/","url":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/","name":"Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi. - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2.jpg","datePublished":"2020-01-15T09:25:17+00:00","dateModified":"2020-01-15T16:27:18+00:00","description":"Si comincia il 2 febbraio con il rito di benedizione delle adozioni. Si chiude ad agosto con la tradizionale settimana estiva.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/AiBiraduno2.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/un-2020-di-appuntamenti-per-il-gruppo-famiglie-di-mestre-di-ai-bi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Un 2020 di appuntamenti per il Gruppo Famiglie di Mestre di Ai.Bi."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:39:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=170724"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/167206"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=170724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=170724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=170724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}