﻿


{"id":170827,"date":"2020-01-20T15:32:35","date_gmt":"2020-01-20T14:32:35","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=170827"},"modified":"2020-01-20T15:32:35","modified_gmt":"2020-01-20T14:32:35","slug":"panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/","title":{"rendered":"Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte\u201d"},"content":{"rendered":"<h2>Appuntamento oggi pomeriggio alle ore 16 nella sala teatro dell\u2019istituto di Salerno per lo spettacolo inserito nel progetto di contrasto alla povert\u00e0 educativa<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-163800 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>Quattordici studenti in scena per raccontare le vicende dell\u2019eroe di <strong>Miguel de Cervantes Saavedra.<\/strong> Ad ognuno il suo ruolo per sperimentare il teatro come occasione di crescita. E cos\u00ec oggi pomeriggio, alle ore 16, nella sala teatro dell<strong>\u2019Istituto Comprensivo \u201cRita Levi Montalcini\u201d di Salerno<\/strong> andr\u00e0 in scena <strong><em>\u201cLe avventure di Don Chisciotte\u201d<\/em><\/strong>. Gli attori in erba interpreteranno una riduzione del celebre testo, a cura di <strong>Carla Avarista,<\/strong> dando prova delle competenze acquisite nel corso condotto dalla stessa Avarista e da <strong>Virna Prescenzo<\/strong> del <strong>Piccolo Teatro del Giullare<\/strong> nell\u2019ambito del progetto \u201c<strong><em>Panthak\u00f9. Educare dappertutto\u201d,<\/em> <\/strong>selezionato dall\u2019<strong>Impresa Sociale Con i Bambini<\/strong> nell\u2019ambito del Fondo per il contrasto della povert\u00e0 educativa minorile. Capofila \u00e8 <strong>Ai.Bi. Associazione Amici dei Bambini<\/strong> e 24 sono le realt\u00e0 pubbliche e private partner di un progetto selezionato insieme ad <strong>altri 85<\/strong> tra gli oltre 800 presentati sul <strong>Bando Adolescenza<\/strong> in tutta Italia.<\/p>\n<p>Dallo scorso ottobre, ogni luned\u00ec, per tre ore di fila, i ragazzi si sono confrontati con le docenti per apprendere le regole fondamentali della dizione e della recitazione. A pochi giorni dal debutto<em> \u201csono particolarmente galvanizzati<\/em> \u2013 spiega Virna Prescenzo \u2013<em> perch\u00e9 non vedono l\u2019ora di salire sul palcoscenico\u201d<\/em>. <em>\u201cAbbiamo iniziato spiegando loro dei principi base di dizione, aiutandoci con le filastrocche, in modo da rendere le lezioni sempre giocose<\/em> \u2013 continua Prescenzo \u2013 <em>Credo che i laboratori teatrali siano di fondamentale importanza nelle scuole perch\u00e9 aiutano i giovani a superare timidezze e paure, li rendono pi\u00f9 consapevoli, pi\u00f9 maturi e questo servir\u00e0, in futuro, anche per il loro percorso scolastico\u201d.<\/em><\/p>\n<p>Carla Avarista \u00e8 stata l\u2019anima della parte teatrale, occupandosi della dizione e dell\u2019uso della voce nella recitazione, mentre Virna Prescenzo ha focalizzato l\u2019attenzione sulla centralit\u00e0 del corpo. Parola e movimento, per fare del Don Chisciotte un nuovo simbolo dei linguaggi contemporanei. In scena ci saranno: <strong>Giulia Barone, Francesca Cesarano, Luca Cioffi, Claudia Coda, Giorgia Pia De Simone, Soraya Longo, Giovanna Pagano, Giorgia Pappalardo, Anna Pascale, Kesia Ricco, Ciro Salmieri, Sofia Scannapieco, Matteo Trezza, Rosario Pio Vitale<\/strong>. In platea non mancher\u00e0 la dirigente della scuola, <strong>Carla Romano,<\/strong> insieme alle famiglie invitate a partecipare.<\/p>\n<p><strong>LA RETE.<\/strong> Sono partner di progetto, insieme ad <strong>Ai.Bi. Associazione Amici dei Bambini<\/strong> capofila: <strong>Comune di Salerno, Comune di Castellammare di Stabia (NA), Comune di S.Maria Capua Vetere (CE), IC Calcedonia e IC Rita Levi Montalcini di Salerno, IC Denza di Castellammare di Stabia, IC Principe di Piemonte di S.Maria Capua Vetere, Human Foundation, Fondazione Carisal \u2013 Fondazione Cassa di Risparmio Salernitana, ACLI \u2013 Associazioni Cristiane Lavoratori Italiani di Salerno, Associazione Vela Centro Servizi Sociali, Acli Service Salerno, Associazione Campania Danza, Associazione Culturale Saremo Alberi \u2013 Libroteca, Associazione Compagnia del Giullare, Associazione Culturale Funneco \u2013 Culture Hub, CNA \u2013 Confederazione Nazionale dell\u2019Artigianato e della Piccola e Media Impresa di Salerno, CNA Campania Nord (sedi di Napoli e Caserta), ASD Rari Nantes Nuoto Salerno, CSI \u2013 Centro Sportivo Italiano Comitati Provinciali di Salerno, Napoli e Caserta, Associazione Agape Fraterna Onlus, Associazione Casa Babylon Teatro.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Appuntamento oggi pomeriggio alle ore 16 nella sala teatro dell&rsquo;istituto di Salerno per lo spettacolo inserito nel progetto di contrasto alla povert&agrave; educativa Quattordici studenti in scena per raccontare le vicende dell&rsquo;eroe di Miguel de Cervantes Saavedra. Ad ognuno il suo ruolo per sperimentare il teatro come occasione di crescita. [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":163800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[450],"class_list":["post-170827","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-panthaku"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte\u201d - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Appuntamento alle ore 16 nella sala teatro dell\u2019istituto di Salerno per lo spettacolo inserito nel progetto di contrasto alla povert\u00e0 educativa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte\u201d\" \/>\n<meta property=\"og:description\" content=\"Appuntamento alle ore 16 nella sala teatro dell\u2019istituto di Salerno per lo spettacolo inserito nel progetto di contrasto alla povert\u00e0 educativa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-20T14:32:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte&quot;\" \/>\n<meta name=\"twitter:description\" content=\"Appuntamento alle ore 16 nella sala teatro dell\u2019istituto di Salerno per lo spettacolo inserito nel progetto di contrasto alla povert\u00e0 educativa.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte\u201d\",\"datePublished\":\"2020-01-20T14:32:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\\\/\"},\"wordCount\":525,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/panthaku-educare-1_700x460.jpg\",\"keywords\":[\"Panthaku\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\\\/\",\"name\":\"Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte\u201d - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/panthaku-educare-1_700x460.jpg\",\"datePublished\":\"2020-01-20T14:32:35+00:00\",\"description\":\"Appuntamento alle ore 16 nella sala teatro dell\u2019istituto di Salerno per lo spettacolo inserito nel progetto di contrasto alla povert\u00e0 educativa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/panthaku-educare-1_700x460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/panthaku-educare-1_700x460.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte\u201d - Ai.Bi. Amici dei Bambini","description":"Appuntamento alle ore 16 nella sala teatro dell\u2019istituto di Salerno per lo spettacolo inserito nel progetto di contrasto alla povert\u00e0 educativa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/","og_locale":"it_IT","og_type":"article","og_title":"Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte\u201d","og_description":"Appuntamento alle ore 16 nella sala teatro dell\u2019istituto di Salerno per lo spettacolo inserito nel progetto di contrasto alla povert\u00e0 educativa.","og_url":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-01-20T14:32:35+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte\"","twitter_description":"Appuntamento alle ore 16 nella sala teatro dell\u2019istituto di Salerno per lo spettacolo inserito nel progetto di contrasto alla povert\u00e0 educativa.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte\u201d","datePublished":"2020-01-20T14:32:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/"},"wordCount":525,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460.jpg","keywords":["Panthaku"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/","url":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/","name":"Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte\u201d - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460.jpg","datePublished":"2020-01-20T14:32:35+00:00","description":"Appuntamento alle ore 16 nella sala teatro dell\u2019istituto di Salerno per lo spettacolo inserito nel progetto di contrasto alla povert\u00e0 educativa.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/panthaku-educare-1_700x460.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/panthaku-gli-alunni-dellic-montalcini-al-debutto-con-le-avventure-di-don-chisciotte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Panthak\u00f9. Gli alunni dell\u2019IC Montalcini al debutto con \u201cLe avventure di Don Chisciotte\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:49:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=170827"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170827\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/163800"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=170827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=170827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=170827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}