﻿


{"id":170849,"date":"2020-01-21T10:41:05","date_gmt":"2020-01-21T09:41:05","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=170849"},"modified":"2020-01-21T10:41:05","modified_gmt":"2020-01-21T09:41:05","slug":"adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/","title":{"rendered":"Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini"},"content":{"rendered":"<h2>Necessaria per tutte le coppie che intendono conferire mandato ad Ai.Bi. la partecipazione al corso \u201c<a href=\"https:\/\/www.aibi.it\/ita\/attivita\/adozione-internazionale\/#icmf\" target=\"_blank\" rel=\"noopener noreferrer\">L\u2019incontro con mio figlio\u201d<\/a>. Il presidente Marco Griffini: \u201cLa formazione, pi\u00f9 che la cultura della selezione, purtroppo maggioritaria, \u00e8 fondamentale per ottenere coppie preparate ed evitare fallimenti adottivi\u201d<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-154207 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>Nelle sedi di <strong>Ai.Bi. \u2013 Amici dei Bambini,<\/strong> organizzazione nata oltre trent\u2019anni fa da un movimento di famiglie adottive e affidatarie, sono al via i primi corsi di preparazione del 2020, intitolati \u201cL\u2019incontro con mio figlio\u201d e dedicati a tutte quelle coppie che hanno deciso di intraprendere il meraviglioso percorso dell\u2019adozione internazionale e che intendono prepararsi nel migliore dei modi all\u2019incontro con i propri figli.<\/p>\n<p>La novit\u00e0 pi\u00f9 importante rispetto al passato \u00e8 che la partecipazione a tali corsi, organizzati in coordinamento con <a href=\"https:\/\/www.fondazioneaibi.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fondazione Ai.Bi.<\/a>, \u00e8 stata ora resa necessaria per tutti gli aspiranti genitori adottivi che intendono conferire mandato ad Amici dei Bambini.<\/p>\n<p><em>\u201cLa formazione<\/em> \u2013 spiega il<strong> presidente di Ai.Bi. \u2013 Amici dei Bambini, Marco Griffini<\/strong> &#8211; <em>pi\u00f9 che la cultura della selezione, purtroppo maggioritaria, \u00e8 fondamentale per ottenere coppie preparate all\u2019affascinante ma complesso iter dell\u2019adozione internazionale. Ci \u00e8 pi\u00f9 volte accaduto di prendere in carico coppie che ritenevano di essere preparate, ma che, in realt\u00e0 e non per colpa loro, non conoscevano neanche il profilo reale dei minori disponibili per l\u2019adozione internazionale! La formazione obbligatoria pre-mandato serve a rendere tutti pi\u00f9 consapevoli e ad aumentare la possibilit\u00e0 di evitare fallimenti adottivi\u201d<\/em><\/p>\n<p>Il format del corso <a href=\"https:\/\/www.aibi.it\/ita\/attivita\/adozione-internazionale\/#icmf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><em>\u201cL\u2019incontro con mio figlio\u201d<\/em><\/strong><\/a> \u00e8 quello gi\u00e0 collaudato con successo nel recente passato: la conduzione \u00e8 affidata a psicologhe specialiste in adozione internazionale e a famiglie adottive esperte che attraverso lavori ed esercitazioni personali e di gruppo che si svolgono nell\u2019arco di un fine settimana consentono alla coppia di misurarsi rispetto alla propria storia, ai propri sogni e alla realt\u00e0 , ai vissuti ed ai problemi dei bambini stranieri in stato di abbandono.<\/p>\n<p>Il corso <strong><em>\u201cL\u2019incontro con mio figlio\u201d<\/em><\/strong> \u00e8 solo uno dei momenti che Ai.Bi. considera indispensabile per le coppie che vogliono prepararsi all\u2019iter adottivo. Presso le sedi e i punti famiglia Ai.Bi. vengono organizzati incontri informativi dal titolo <strong><em>\u201c<a href=\"https:\/\/www.aibi.it\/ita\/attivita\/adozione-internazionale\/#incontri-informativi-adozione\" target=\"_blank\" rel=\"noopener noreferrer\">L\u2019incontro con l\u2019adozione internazionale<\/a><\/em><\/strong>\u201d in cui si approfondisce la conoscenza dell\u2019adozione internazionale, dell\u2019associazione e delle procedure di adozione. Solo dopo avere effettuato un ultimo colloquio di restituzione individuale, infine, in cui alla presenza di un operatore tecnico e di una psicologa si discute delle reali possibilit\u00e0 di adozione con Ai.Bi., le coppie che lo vorranno potranno procedere con il conferimento del mandato.<\/p>\n<p>Per quanto riguarda le prime date del corso \u201c<strong><em>L\u2019incontro con mio figlio<\/em><\/strong>\u201d, nelle sedi territoriali di <strong>Ai.Bi.,<\/strong> queste sono previste: il <strong>25 e 26 gennaio<\/strong> a <strong>Bolzano e Salerno<\/strong>; l\u2019<strong>1 e 2 febbraio a Barletta,<\/strong> <strong>San Giuliano Milanese e Cagliari;<\/strong> <strong>l\u20198 e 9 febbraio a Firenze e Roma; il 15 e 16 febbraio a Mestre.<\/strong><\/p>\n<p>Per maggiori informazioni si pu\u00f2 cliccare sul link <a href=\"https:\/\/www.aibi.it\/ita\/attivita\/adozione-internazionale\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.aibi.it\/ita\/attivita\/adozione-internazionale\/<\/a>, oppure telefonare allo<strong> 02988221<\/strong>. Via e-mail \u00e8 possibile contattare l\u2019ufficio adozioni di <strong>Ai.Bi. \u2013 Amici dei Bambini<\/strong> all\u2019indirizzo <a href=\"mailto:adozioni@aibi.it\" target=\"_blank\" rel=\"noopener noreferrer\">adozioni@aibi.it<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Necessaria per tutte le coppie che intendono conferire mandato ad Ai.Bi. la partecipazione al corso &ldquo;L&rsquo;incontro con mio figlio&rdquo;. Il presidente Marco Griffini: &ldquo;La formazione, pi&ugrave; che la cultura della selezione, purtroppo maggioritaria, &egrave; fondamentale per ottenere coppie preparate ed evitare fallimenti adottivi&rdquo; Nelle sedi di Ai.Bi. &ndash; Amici dei [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":154207,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-170849","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Necessaria per tutte le coppie che intendono conferire mandato ad Ai.Bi. la partecipazione al corso \u201cL\u2019incontro con mio figlio\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini\" \/>\n<meta property=\"og:description\" content=\"Necessaria per tutte le coppie che intendono conferire mandato ad Ai.Bi. la partecipazione al corso \u201cL\u2019incontro con mio figlio\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-21T09:41:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini\" \/>\n<meta name=\"twitter:description\" content=\"Necessaria per tutte le coppie che intendono conferire mandato ad Ai.Bi. la partecipazione al corso \u201cL\u2019incontro con mio figlio\u201d\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini\",\"datePublished\":\"2020-01-21T09:41:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\\\/\"},\"wordCount\":524,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/corso-formazione-ptva-aibi_700X460.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\\\/\",\"name\":\"Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/corso-formazione-ptva-aibi_700X460.jpg\",\"datePublished\":\"2020-01-21T09:41:05+00:00\",\"description\":\"Necessaria per tutte le coppie che intendono conferire mandato ad Ai.Bi. la partecipazione al corso \u201cL\u2019incontro con mio figlio\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/corso-formazione-ptva-aibi_700X460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/corso-formazione-ptva-aibi_700X460.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini - Ai.Bi. Amici dei Bambini","description":"Necessaria per tutte le coppie che intendono conferire mandato ad Ai.Bi. la partecipazione al corso \u201cL\u2019incontro con mio figlio\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini","og_description":"Necessaria per tutte le coppie che intendono conferire mandato ad Ai.Bi. la partecipazione al corso \u201cL\u2019incontro con mio figlio\u201d","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-01-21T09:41:05+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini","twitter_description":"Necessaria per tutte le coppie che intendono conferire mandato ad Ai.Bi. la partecipazione al corso \u201cL\u2019incontro con mio figlio\u201d","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini","datePublished":"2020-01-21T09:41:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/"},"wordCount":524,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/","name":"Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460.jpg","datePublished":"2020-01-21T09:41:05+00:00","description":"Necessaria per tutte le coppie che intendono conferire mandato ad Ai.Bi. la partecipazione al corso \u201cL\u2019incontro con mio figlio\u201d.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/corso-formazione-ptva-aibi_700X460.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-al-via-i-primi-corsi-preparatori-2020-di-ai-bi-amici-dei-bambini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozione internazionale. Al via i primi corsi preparatori 2020 di Ai.Bi. \u2013 Amici dei Bambini"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:15:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=170849"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/170849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/154207"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=170849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=170849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=170849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}