﻿


{"id":17094,"date":"2010-11-08T11:54:17","date_gmt":"2010-11-08T10:54:17","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=17094"},"modified":"2011-04-15T12:47:37","modified_gmt":"2011-04-15T11:47:37","slug":"bello-che-fa-bene-serata-di-gala","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/","title":{"rendered":"Bello che fa Bene: Serata inaugurale"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9773\" title=\"Serata di gala\" src=\"https:\/\/www.aibi.it\/ita\/images\/bb2009\/header_serata.jpg\" alt=\"Il Bello che fa Bene\" width=\"684\" height=\"140\" \/><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/news_bello.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-17513\" style=\"margin: 5px;\" title=\"news_bello\" src=\"https:\/\/www.aibi.it\/ita\/images\/news_bello.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Luned\u00ec 22 Novembre<\/strong>, nella prestigiosa cornice delle Officine del Volo di Milano, si \u00e8 tenuta la serata inaugurale della <strong>nona edizione <\/strong>di <strong>\u201cIl Bello che fa Bene\u201d,<\/strong> uno splendido evento di gala a sostegno delle attivit\u00e0 di <strong>Ai.Bi. Associazione Amici dei Bambini<\/strong> in Italia e nel mondo, finalizzate a dare ai bambini abbandonati una famiglia.<\/p>\n<p>Oltre 250 invitati, ospiti illustri e personaggi famosi hanno preso parte a questo gal\u00e0 della solidariet\u00e0 che ha visto i tre chef stellati <strong>Carlo Cracco, Pietro Leemann e Loretta Fanella<\/strong> cimentarsi nel <strong>Kitchen Aid<\/strong> <strong>Cooking Show dal vivo<\/strong>, realizzato in collaborazione proprio con<strong> <\/strong>l\u2019azienda<strong> KitchenAid<\/strong>, da sempre marchio sinonimo di professionalit\u00e0 e passione in cucina. Il raffinato men\u00f9 della serata ha visto protagonisti eleganti piatti creati dai tre chef come la <strong>panzanella di pane e crudit\u00e0 con un cuore di cannellini e wasabi <\/strong>cucinata da <strong>Pietro Leemann<\/strong>, <strong>un timballo di merluzzo e verza con salsa di baccal\u00e0<\/strong> preparata da Carlo <strong>Cracco<\/strong> e <strong>una sfera di cioccolato al latte con purea di cachi e biscotto di castagna <\/strong>proposta<strong> da Loretta Fanella. Dulcis in fundo\u2026l\u2019alta pasticceria di Natale di Alma.<\/strong><\/p>\n<p>La serata, che si aperta alle ore 19 con il cocktail e un\u2019asta silenziosa, \u00e8 proseguita con la cena di gala organizzata insieme ad ALMA, Scuola Internazionale di Cucina Italiana il cui Rettore \u00e8 <strong>Gualtiero Marchesi. <\/strong><\/p>\n<p>Tra piatti succulenti e comiche battute di <strong>Did\u00ec Mazzilli, <\/strong>comico di<strong> <\/strong>Colorado Caf\u00e8, la cena \u00e8 stata animata da <strong>Max Laudadio e Tania Zamparo<\/strong> che hanno presentato anche <strong>l\u2019asta benefica<\/strong>.<\/p>\n<p>Tra i prodotti messi all\u2019asta,<strong> il pallone del Milan e dell\u2019Inter firmati dai giocatori delle squadre, la maglia del capitano del Milan Ambrosini e del giocatore dell\u2019Inter Sneijder<\/strong>, le lezioni di cucina <strong>con Pietro Leemann <\/strong>e con<strong> Carlo Cracco<\/strong>, la<strong> palla di Natale di cioccolato scolpita da Loretta Fanella<\/strong>, il<strong> Panettone da 5 kg creato dall\u2019Alma\u2026 ma su tutti\u2026 in estremis \u2026 vince il Tapiro!!!!<\/strong><\/p>\n<p><strong>Il famoso tapiro<\/strong> protagonista di \u201cStriscia la Notizia\u201d \u00e8 stato donato come porta fortuna da <strong>Max<\/strong> <strong>Laudadio<\/strong> al Presidente di Ai.Bi. Marco Griffini, che ha poi scelto di donarlo agli ospiti presenti mettendolo all\u2019asta. <strong>Il tapiro \u00e8 stato l\u2019oggetto pi\u00f9 conteso e ha ricevuto l\u2019offerta pi\u00f9 alta della serata. <\/strong><\/p>\n<p>Al Presidente Griffini \u00e8 stata donata anche la <strong>Maglietta<\/strong><strong> delle Iene autografata<\/strong>\u2026 che si sa\u2026 portano bene, nella speranza che i milioni di bambini abbandonati nel Mondo possano trovare un famiglia.<\/p>\n<p><em>\u201cC\u2019\u00e8 grande soddisfazione per la riuscita di questa serata,<\/em> commenta il <strong>Presidente di Ai.Bi. Marco Griffini; <\/strong><em>ancora una volta abbiamo dimostrato che \u201cil bello\u201d pu\u00f2 far anche \u201cbene\u201de che, con il supporto di aziende che credono nella solidariet\u00e0 si possono fare grandi cose.<\/em><\/p>\n<p><em>Ringrazio tutti coloro che ci hanno aiutato nella riuscita dell\u2019evento: le aziende partner, KitchenAid, i tre chef stellati, ALMA, Max Laudadio, Tania Zamparo, Did\u00ec\u2019 Mazzilli e tutti coloro che ci hanno donato il loro prezioso contributo\u201d.<\/em><\/p>\n<p><a href=\"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2010\/\">&lt;&lt; torna alla pagina principale de &#8220;Il Bello che fa Bene&#8221;<\/a><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><\/p>\n[tab: Gallery cena]\n<h3>Le foto della cena e dei protagonisti della serata<\/h3>\n[nggallery id=6]\n[tab: Gallery asta]\n<h3>Le foto dell&#8217;asta e dei prodotti<\/h3>\n[nggallery id=7]\n[tab: Video]\n<h3>Il video intervista al Presidente di Ai.Bi. Marco Griffini<\/h3>\n[flv:https:\/\/www.aibi.it\/ita\/fla2\/aibi22112010cb.flv 300 250]\n[tab: Gli Chef]\n<ul>\n<li><strong>Pietro Leeman<\/strong> &#8211; <em>Joia<\/em> &#8211; 1 stella Michelin<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-17114\" title=\"leeman\" src=\"https:\/\/www.aibi.it\/ita\/images\/bb2009\/leeman_pic.jpg\" alt=\"chef\" width=\"80\" height=\"80\" \/>Patron e chef del ristorante Joia di Milano, aperto nel 1989 con un gruppo di amici ed insignito nel 1996 di una stella Michelin, \u00e8 considerato a buon diritto il padre della cucina naturale nonch\u00e8 il detentore di un primato di tutto rispetto: Joia, infatti, \u00e8 stato il primo ristorante vegetariano europeo ad ottenere il prestigioso riconoscimento Michelin.<br \/>\nE\u2019 nato in Svizzera nel 1961 e si \u00e8 formato i in ristoranti italiani e francesi ed al cospetto di illustri maestri come Fredy Girardet e Gualtiero Marchesi, che hanno indirizzato la sua personalit\u00e0 culinaria verso la perfetta armonia tra nouvelle cuisine e cucina creativa.<\/li>\n<li><strong>Carlo Cracco<\/strong> &#8211; <em>Il Ristorante Cracco<\/em> &#8211; 2 stelle Michelin<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-17114\" title=\"Cracco\" src=\"https:\/\/www.aibi.it\/ita\/images\/bb2009\/cracco_pic.jpg\" alt=\"chef\" width=\"80\" height=\"80\" \/>Nato a Vicenza. Nel 1986 ha cominciato la sua carriera professionale da Gualtiero Marchesi a Milano, il primo ristorante italiano che ha raggiunto le tre stelle Michelin.<br \/>\nHa vissuto per 3 anni in Francia dove ha imparato la cucina francese c\/o Alain Ducasse e Lucas Carton. Poi Firenze all&#8217;Enoteca Pinchiorri come chef di cucina (tre stelle Michelin). Poi di nuovo Marchesi all&#8217;Albereta di Erbusco (altre tre stelle Michelin) dove ci rimane per tre anni. Infine approda a Milano, da Peck, in via Victor Hugo, dove nel 2001 apre Cracco Peck, ristorante legato alla storica gastronomia del marchio Peck della famiglia Stoppani.<br \/>\nIl Ristorante Cracco \u00e8 aperto dal 2001 e la sua cucina rivisita in modo contemporaneo le specialit\u00e0 tradizionali milanesi, guadagnando le due stelle Michelin, e 2 forchette per il Gambero Rosso. Dal 2007 \u00e8 tra i 50 migliori Ristoranti al mondo.<\/li>\n<li><strong>Loretta Fanella<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-17114\" title=\"Fanella\" src=\"https:\/\/www.aibi.it\/ita\/images\/bb2009\/fanella_pic.jpg\" alt=\"chef\" width=\"80\" height=\"80\" \/>Loretta Fanella \u00e8 giovane, brava da morire, e con una fantasia da fare invidia ad uno scultore. E\u2019 una chef pasticciera, la migliore d\u2019Italia. Ha vinto premi, ha ottenuto riconoscimenti, ed \u00e8 stata chiamata pure in tv ( alla \u201cProva del Cuoco\u201c). Ora viaggia per il mondo: tutti la vogliono, tutti la cercano&#8230;<br \/>\nDopo aver frequentato l\u2019istituto alberghiero di Fiuggi, la Fanella \u00e8 per tre anni a Verona per scoprire i segreti della banchettistica per approdare nel 2002 da Cracco-Peck a Milano dove Carlo Cracco la invita a cambiare la carta dei dolci e la piccola pasticceria coniugando la massima attenzione per i dettagli con un\u2019arte dolciaria il pi\u00f9 innovativa possibile. Poi la Spagna, il Bulli dei fratelli Ferran e Albert Adri\u00e0, dove deve dimostrarsi sempre collaborativi con gli altri chef, in una continua ricerca di tecniche nuove, gusti e abbinamenti nuovi, testure e temperature nuove.<\/li>\n<\/ul>\n[tab: Gli ospiti VIP]\n<p>Con la speciale partecipazione di: <strong>Max Laudadio<\/strong> (<em>Striscia la Notizia<\/em>), <strong>Tania Zamparo<\/strong> (<em>presentatrice SKY<\/em>), <strong>Roberta Lanfranchi<\/strong> (<em>attrice<\/em>), <strong>Did\u00ec Mazzilli<\/strong> (<em>Colorado Caf\u00e8<\/em>)<\/p>\n<figure id=\"attachment_17464\" aria-describedby=\"caption-attachment-17464\" style=\"width: 100px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17464\" title=\"Max Laudadio\" src=\"https:\/\/www.aibi.it\/ita\/images\/bb2009\/max_laudadio_pic.jpg\" alt=\"\" width=\"100\" height=\"119\" \/><figcaption id=\"caption-attachment-17464\" class=\"wp-caption-text\">Max Laudadio<\/figcaption><\/figure>\n<figure id=\"attachment_17464\" aria-describedby=\"caption-attachment-17464\" style=\"width: 100px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17464\" title=\"tania_zamparo\" src=\"https:\/\/www.aibi.it\/ita\/images\/tania_zamparo.jpg\" alt=\"\" width=\"100\" height=\"119\" \/><figcaption id=\"caption-attachment-17464\" class=\"wp-caption-text\">Tania Zamparo<\/figcaption><\/figure>\n<figure id=\"attachment_17464\" aria-describedby=\"caption-attachment-17464\" style=\"width: 100px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17464\" title=\"Roberta Lanfranchi\" src=\"https:\/\/www.aibi.it\/ita\/images\/bb2009\/lanfranchi.jpg\" alt=\"\" width=\"100\" height=\"119\" \/><figcaption id=\"caption-attachment-17464\" class=\"wp-caption-text\">Roberta Lanfranchi<\/figcaption><\/figure>\n<figure id=\"attachment_17464\" aria-describedby=\"caption-attachment-17464\" style=\"width: 100px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17464\" title=\"Didi Mazzilli\" src=\"https:\/\/www.aibi.it\/ita\/images\/bb2009\/didi_mazzilli.jpg\" alt=\"\" width=\"100\" height=\"119\" \/><figcaption id=\"caption-attachment-17464\" class=\"wp-caption-text\">Didi Mazzilli<\/figcaption><\/figure>\n<p><span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><\/p>\n[tab: Gli sponsor]\n<h3>Gli Sponsor<\/h3>\n<p>In collaborazione con:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"AZIENDE-PARTECIPANTI\" src=\"https:\/\/www.aibi.it\/ita\/images\/bb2009\/partecipano.jpg\" alt=\"AZIENDE-PARTECIPANTI\" width=\"250\" height=\"34\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" title=\"sponsor\" src=\"https:\/\/www.aibi.it\/ita\/images\/bb2010\/sponsor_roll.jpg\" alt=\"sponsor\" width=\"499\" height=\"374\" \/><\/p>\n[tab: Le Aziende]\n<h3>Le aziende partecipanti<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"AZIENDE-PARTECIPANTI\" src=\"https:\/\/www.aibi.it\/ita\/images\/bb2009\/aziende.gif\" alt=\"AZIENDE-PARTECIPANTI\" width=\"488\" height=\"265\" \/><\/p>\n[tab: Comunicato]\n<a href=\"https:\/\/www.aibi.it\/ita\/images\/bb2009\/bb_serata_gala.pdf\" target=\"_blank\">Scarica il comunicato stampa della serata di gala &gt;&gt;<\/a><\/p>\n[tab:END]\n","protected":false},"excerpt":{"rendered":"<p>.. Luned&igrave; 22 Novembre, nella prestigiosa cornice delle Officine del Volo di Milano, si &egrave; tenuta la serata inaugurale della nona edizione di &ldquo;Il Bello che fa Bene&rdquo;, uno splendido evento di gala a sostegno delle attivit&agrave; di Ai.Bi. Associazione Amici dei Bambini in Italia e nel mondo, finalizzate a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-17094","post","type-post","status-publish","format-standard","category-campagne-ed-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bello che fa Bene: Serata inaugurale - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bello che fa Bene: Serata inaugurale\" \/>\n<meta property=\"og:description\" content=\".. Luned&igrave; 22 Novembre, nella prestigiosa cornice delle Officine del Volo di Milano, si &egrave; tenuta la serata inaugurale della nona edizione di &ldquo;Il Bello che fa Bene&rdquo;, uno splendido evento di gala a sostegno delle attivit&agrave; di Ai.Bi. Associazione Amici dei Bambini in Italia e nel mondo, finalizzate a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-11-08T10:54:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-04-15T11:47:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/bb2009\/header_serata.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bello-che-fa-bene-serata-di-gala\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bello-che-fa-bene-serata-di-gala\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Bello che fa Bene: Serata inaugurale\",\"datePublished\":\"2010-11-08T10:54:17+00:00\",\"dateModified\":\"2011-04-15T11:47:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bello-che-fa-bene-serata-di-gala\\\/\"},\"wordCount\":1035,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bello-che-fa-bene-serata-di-gala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bb2009\\\/header_serata.jpg\",\"articleSection\":[\"Campagne ed Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bello-che-fa-bene-serata-di-gala\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bello-che-fa-bene-serata-di-gala\\\/\",\"name\":\"Bello che fa Bene: Serata inaugurale - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bello-che-fa-bene-serata-di-gala\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bello-che-fa-bene-serata-di-gala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bb2009\\\/header_serata.jpg\",\"datePublished\":\"2010-11-08T10:54:17+00:00\",\"dateModified\":\"2011-04-15T11:47:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bello-che-fa-bene-serata-di-gala\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bello-che-fa-bene-serata-di-gala\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bello-che-fa-bene-serata-di-gala\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bb2009\\\/header_serata.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bb2009\\\/header_serata.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bello-che-fa-bene-serata-di-gala\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne ed Eventi\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/campagne-ed-eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bello che fa Bene: Serata inaugurale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bello che fa Bene: Serata inaugurale - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/","og_locale":"it_IT","og_type":"article","og_title":"Bello che fa Bene: Serata inaugurale","og_description":".. Luned&igrave; 22 Novembre, nella prestigiosa cornice delle Officine del Volo di Milano, si &egrave; tenuta la serata inaugurale della nona edizione di &ldquo;Il Bello che fa Bene&rdquo;, uno splendido evento di gala a sostegno delle attivit&agrave; di Ai.Bi. Associazione Amici dei Bambini in Italia e nel mondo, finalizzate a [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-11-08T10:54:17+00:00","article_modified_time":"2011-04-15T11:47:37+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/bb2009\/header_serata.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Bello che fa Bene: Serata inaugurale","datePublished":"2010-11-08T10:54:17+00:00","dateModified":"2011-04-15T11:47:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/"},"wordCount":1035,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bb2009\/header_serata.jpg","articleSection":["Campagne ed Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/","url":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/","name":"Bello che fa Bene: Serata inaugurale - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bb2009\/header_serata.jpg","datePublished":"2010-11-08T10:54:17+00:00","dateModified":"2011-04-15T11:47:37+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/bb2009\/header_serata.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/bb2009\/header_serata.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-serata-di-gala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Campagne ed Eventi","item":"https:\/\/www.aibi.it\/ita\/category\/campagne-ed-eventi\/"},{"@type":"ListItem","position":3,"name":"Bello che fa Bene: Serata inaugurale"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 16:17:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/17094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=17094"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/17094\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=17094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=17094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=17094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}