﻿


{"id":171706,"date":"2020-02-15T11:00:58","date_gmt":"2020-02-15T10:00:58","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=171706"},"modified":"2020-02-17T09:17:11","modified_gmt":"2020-02-17T08:17:11","slug":"salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/","title":{"rendered":"Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012"},"content":{"rendered":"<h2>Il laboratorio fornisce ai genitori una soluzione per occupare in maniera valida il tempo libero dei loro figli<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-156219 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460-457x300.jpg\" alt=\"\" width=\"457\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460-457x300.jpg 457w, https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460-150x99.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460-84x55.jpg 84w, https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460-200x131.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460-350x230.jpg 350w, https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460-500x329.jpg 500w, https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460-334x219.jpg 334w, https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460-165x109.jpg 165w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/>Il<strong> Pan di Zucchero<\/strong> di <strong>Salerno<\/strong> \u00e8 un luogo di incontro e crescita attivo dal 2012, anno di nascita del Punto Famiglia <strong>ACLI<\/strong> di Salerno. \u00c8 proprio all\u2019interno del Punto Famiglia che il Pan di Zucchero viene pensato e realizzato, grazie alla disponibilit\u00e0 delle ACLI, per una serie di funzionalit\u00e0: in primis quella di dare un luogo di ritrovo alle famiglie adottive e affidatarie del movimento di <strong>Ai.Bi. \u2013 Amici dei Bambini<\/strong>, ma anche per informare e formare nuove coppie per l\u2019adozione internazionale, supportare con incontri di gruppo e counseling individuale i genitori e, da settembre 2018, ospitare alcune importanti attivit\u00e0 del progetto \u201cPanthak\u00f9. Educare dappertutto\u201d, selezionato da Con i Bambini nell\u2019ambito del Fondo per il contrasto della povert\u00e0 educativa minorile.<\/p>\n<p>Fiore all\u2019occhiello del Pan di Zucchero \u00e8 il laboratorio creativo ed espressivo, gratuito, come tutti gli altri servizi erogati, per bambini dai 4 ai 10 anni che si svolge ogni mercoled\u00ec dalle 17.30 alle 19.15 e vede attualmente una frequenza di circa 10 bambini seguiti da due operatrici di Ai.Bi.: Italia De Michele e Federica D\u2019Ambro.<\/p>\n<p>Le famiglie si trovano con l\u2019esigenza di \u201dinventare\u201d una soluzione per occupare in maniera valida il tempo libero dei propri figli. Nonni e baby-sitter possono diventare un\u2019alternativa, ma in alcuni casi non sempre praticabile . E\u2019 in questo contesto che si inserisce il laboratorio, con il preciso intento di strutturare proposte valide che rispondano alla voglia dei minori di uno spazio per gioco e divertimento, ma anche di sperimentazione e di crescita. In tal senso il laboratorio si pone come proposta interessante anche per le famiglie che non si trovano ad affrontare particolari problemi organizzativi ma che semplicemente desiderano offrire ai propri figli un\u2019opportunit\u00e0 piacevole e costruttiva.<\/p>\n<p>Scopo principale \u00e8 la soddisfazione di alcuni bisogni fondamentali dei minori. Primo fra tutti l\u2019espressione di s\u00e9, promuovendo la creativit\u00e0 come mezzo di comunicazione, capace di evidenziare le risorse di ogni bambino e svilupparle al meglio, attraverso la costruzione di giocattoli, il bricolage, l\u2019uso di materiale di riciclo, con giochi legati ad attivit\u00e0 di manipolazione di materiali semplici, quali argilla, pasta di sale . Non ultimo, imparando, attraverso il gioco, a socializzare tra di loro, rispettare le regole, i tempi di ognuno, il rispetto verso gli altri e le idee altrui, nonch\u00e9 il rispetto verso l\u2019ambiente e il mondo che ci circonda.<\/p>\n<p>La creazione di oggetti da materiali facilmente reperibili, stimola particolarmente la fantasia, la creativit\u00e0, l\u2019intelligenza generativa e la capacit\u00e0 di adattarsi ai mezzi disponibili per realizzare i propri progetti. Attraverso questa attivit\u00e0, i ragazzi sperimentano le proprie risorse e guadagnano fiducia in se stessi e nelle proprie qualit\u00e0.<\/p>\n<p>Altra utilit\u00e0 sociale del laboratorio cos\u00ec pensato, basato molto su giochi inerenti il riciclo di materiali semplici, \u00e8 quella legata all\u2019ambiente. L\u2019obiettivo delle attivit\u00e0 giocose e creative del laboratorio \u00e8 infatti anche quella di contribuire alla nascita di una coscienza ambientale fin dalla pi\u00f9 tenera et\u00e0, trasmettendo ai bambini i primi concetti relativi ai diversi materiali industriali, (la carta, la plastica, il vetro\u2026) alla loro origine e, soprattutto, all\u2019importanza del loro riutilizzo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il laboratorio fornisce ai genitori una soluzione per occupare in maniera valida il tempo libero dei loro figli Il Pan di Zucchero di Salerno &egrave; un luogo di incontro e crescita attivo dal 2012, anno di nascita del Punto Famiglia ACLI di Salerno. &Egrave; proprio all&rsquo;interno del Punto Famiglia che [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":156219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[448],"class_list":["post-171706","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-salerno"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012 - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Pan di Zucchero Salerno. Il laboratorio fornisce ai genitori una soluzione per occupare in maniera valida il tempo libero dei loro figli.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012\" \/>\n<meta property=\"og:description\" content=\"Pan di Zucchero Salerno. Il laboratorio fornisce ai genitori una soluzione per occupare in maniera valida il tempo libero dei loro figli.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-15T10:00:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-17T08:17:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012\" \/>\n<meta name=\"twitter:description\" content=\"Pan di Zucchero Salerno. Il laboratorio fornisce ai genitori una soluzione per occupare in maniera valida il tempo libero dei loro figli.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012\",\"datePublished\":\"2020-02-15T10:00:58+00:00\",\"dateModified\":\"2020-02-17T08:17:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\\\/\"},\"wordCount\":540,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/pan-di-zucchero-brescia_700x460.jpg\",\"keywords\":[\"Salerno\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\\\/\",\"name\":\"Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012 - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/pan-di-zucchero-brescia_700x460.jpg\",\"datePublished\":\"2020-02-15T10:00:58+00:00\",\"dateModified\":\"2020-02-17T08:17:11+00:00\",\"description\":\"Pan di Zucchero Salerno. Il laboratorio fornisce ai genitori una soluzione per occupare in maniera valida il tempo libero dei loro figli.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/pan-di-zucchero-brescia_700x460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/pan-di-zucchero-brescia_700x460.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012 - Ai.Bi. Amici dei Bambini","description":"Pan di Zucchero Salerno. Il laboratorio fornisce ai genitori una soluzione per occupare in maniera valida il tempo libero dei loro figli.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/","og_locale":"it_IT","og_type":"article","og_title":"Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012","og_description":"Pan di Zucchero Salerno. Il laboratorio fornisce ai genitori una soluzione per occupare in maniera valida il tempo libero dei loro figli.","og_url":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-02-15T10:00:58+00:00","article_modified_time":"2020-02-17T08:17:11+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012","twitter_description":"Pan di Zucchero Salerno. Il laboratorio fornisce ai genitori una soluzione per occupare in maniera valida il tempo libero dei loro figli.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012","datePublished":"2020-02-15T10:00:58+00:00","dateModified":"2020-02-17T08:17:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/"},"wordCount":540,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460.jpg","keywords":["Salerno"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/","url":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/","name":"Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012 - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460.jpg","datePublished":"2020-02-15T10:00:58+00:00","dateModified":"2020-02-17T08:17:11+00:00","description":"Pan di Zucchero Salerno. Il laboratorio fornisce ai genitori una soluzione per occupare in maniera valida il tempo libero dei loro figli.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/pan-di-zucchero-brescia_700x460.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/salerno-pan-di-zucchero-un-luogo-di-incontro-e-crescita-per-le-famiglie-attivo-dal-2012\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Salerno. Pan di Zucchero. Un luogo di incontro e crescita per le famiglie attivo dal 2012"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:18:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/171706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=171706"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/171706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/156219"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=171706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=171706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=171706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}