﻿


{"id":171717,"date":"2020-02-15T11:45:48","date_gmt":"2020-02-15T10:45:48","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=171717"},"modified":"2020-02-15T11:54:09","modified_gmt":"2020-02-15T10:54:09","slug":"aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/","title":{"rendered":"&#8220;Aggiungi un posto a tavola\u201d al Gran Teatro Geox di Padova. Si alza il sipario sul dramma dell\u2019abbandono"},"content":{"rendered":"<div id=\"line_space\" dir=\"auto\">\n<h1 class=\"entry-title\">Due gli appuntamenti: stasera, sabato 15, alle 21.15, e domenica 16 febbraio, alle 16.30. Spettacolo prodotto da Viola Produzioni e OTI \u2013 Officine di Teatro Italiano<\/h1>\n<\/div>\n<div id=\"line_space\" dir=\"auto\">\n<article id=\"post-171636\" class=\"post-171636 post type-post status-publish format-standard has-post-thumbnail category-aibinews\">\n<div class=\"post-area\">\n<div class=\"post-inner\">\n<div class=\"entry-content\">\n<p><strong><em><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-169370\" src=\"https:\/\/www.aibi.it\/ita\/images\/aggiungi_posto_a_tavola1-211x300.jpg\" alt=\"\" width=\"211\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/aggiungi_posto_a_tavola1-211x300.jpg 211w, https:\/\/www.aibi.it\/ita\/images\/aggiungi_posto_a_tavola1-105x150.jpg 105w, https:\/\/www.aibi.it\/ita\/images\/aggiungi_posto_a_tavola1-39x55.jpg 39w, https:\/\/www.aibi.it\/ita\/images\/aggiungi_posto_a_tavola1.jpg 447w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/><\/em><\/strong><\/p>\n<p><strong><em>Aggiungi un posto a tavola\u201d<\/em><\/strong>\u00a0\u00e8 il titolo di una commedia musicale di\u00a0<strong>Garinei\u00a0<\/strong>e\u00a0<strong>Giovannini,<\/strong>\u00a0che far\u00e0 tappa stasera\u00a0<strong>sabato 15 e domenica 16 febbraio al\u00a0 Gran Teatro\u00a0 Geox di Padova.\u00a0<\/strong>Lo spettacolo, portato in scena da<strong>\u00a0Viola Produzioni<\/strong>,\u00a0<strong>OTI \u2013 Officine di Teatro Italiano<\/strong>\u00a0e\u00a0<strong>Alessandro Longobardi<\/strong>, fu scritto tra il 1973 e il 1974 con<strong>\u00a0Jaja Fiastr<\/strong>i ed \u00e8 liberamente ispirato al romanzo\u00a0<strong><em>After me the Deluge<\/em><\/strong>\u00a0di\u00a0<strong>David Forrest<\/strong>. Le musiche sono di\u00a0<strong>Armando Trovajoli.<\/strong><\/p>\n<p>Ambientata in un paesino di campagna, la storia ha come protagonista il parroco, che deve farsi\u00a0<strong><em>\u201cnovello No\u00e8\u201d<\/em><\/strong>\u00a0e salvare la sua comunit\u00e0 da un secondo diluvio universale. Il finale, ovviamente, \u00e8 positivo. Nel cast dello spettacolo gli attori\u00a0<strong>Gianluca Guidi, Marco Simeoli, Piero Di Blasio, Camilla Nigro<\/strong>\u00a0e\u00a0<strong>Francesca Nunzi<\/strong>\u00a0e vi sar\u00e0 inoltre la partecipazione straordinaria di\u00a0<strong>Lorenza Mario.<\/strong><\/p>\n<p>Due le repliche previste: sabato (stasera) alle 21.15 e domenica 16 febbraio alle 16.30. Nel\u00a0<strong><em>foyer<\/em><\/strong>\u00a0del teatro saranno presenti dei volontari che proporranno il\u00a0<strong>Portachiavi Girotondo<\/strong>realizzato dall\u2019azienda<strong>\u00a0Alessi<\/strong>\u00a0quale simbolo del diritto di ogni minore ad essere figlio. Acquistandolo sar\u00e0 possibile sostenere i progetti di\u00a0<strong>Ai.Bi. \u2013 Amici di Bambini<\/strong>, organizzazione nata da un movimento di famiglie adottive e affidatarie che da oltre trent\u2019anni lotta in Italia e nel mondo contro l\u2019abbandono minorile, e in particolare il progetto\u00a0<strong><em>\u201cAccendiamo i riflettori sull\u2019abbandono\u201d<\/em><\/strong>, che vuole, per l\u2019appunto, porre l\u2019accento su questo dramma che investe<strong>\u00a0168 milioni di bambini<\/strong>\u00a0nel mondo e circa\u00a0<strong>30mila di minori fuori famiglia solo in Italia.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Due gli appuntamenti: stasera, sabato 15, alle 21.15, e domenica 16 febbraio, alle 16.30. Spettacolo prodotto da Viola Produzioni e OTI &ndash; Officine di Teatro Italiano Aggiungi un posto a tavola&rdquo;&nbsp;&egrave; il titolo di una commedia musicale di&nbsp;Garinei&nbsp;e&nbsp;Giovannini,&nbsp;che far&agrave; tappa stasera&nbsp;sabato 15 e domenica 16 febbraio al&nbsp; Gran Teatro&nbsp; Geox [&hellip;]<\/p>\n","protected":false},"author":75,"featured_media":169370,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-171717","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Aggiungi un posto a tavola\u201d al Gran Teatro Geox di Padova. Si alza il sipario sul dramma dell\u2019abbandono - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Aggiungi un posto a tavola\u201d al Gran Teatro Geox di Padova. Si alza il sipario sul dramma dell\u2019abbandono\" \/>\n<meta property=\"og:description\" content=\"Due gli appuntamenti: stasera, sabato 15, alle 21.15, e domenica 16 febbraio, alle 16.30. Spettacolo prodotto da Viola Produzioni e OTI &ndash; Officine di Teatro Italiano Aggiungi un posto a tavola&rdquo;&nbsp;&egrave; il titolo di una commedia musicale di&nbsp;Garinei&nbsp;e&nbsp;Giovannini,&nbsp;che far&agrave; tappa stasera&nbsp;sabato 15 e domenica 16 febbraio al&nbsp; Gran Teatro&nbsp; Geox [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-15T10:45:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-15T10:54:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/aggiungi_posto_a_tavola1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"447\" \/>\n\t<meta property=\"og:image:height\" content=\"637\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"stefaniaP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/grazie-aggiungi-un-posto-a-tavola_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"stefaniaP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\\\/\"},\"author\":{\"name\":\"stefaniaP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/dfce5bd678ad0f650527cc2172949970\"},\"headline\":\"&#8220;Aggiungi un posto a tavola\u201d al Gran Teatro Geox di Padova. Si alza il sipario sul dramma dell\u2019abbandono\",\"datePublished\":\"2020-02-15T10:45:48+00:00\",\"dateModified\":\"2020-02-15T10:54:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\\\/\"},\"wordCount\":284,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aggiungi_posto_a_tavola1.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\\\/\",\"name\":\"\\\"Aggiungi un posto a tavola\u201d al Gran Teatro Geox di Padova. Si alza il sipario sul dramma dell\u2019abbandono - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aggiungi_posto_a_tavola1.jpg\",\"datePublished\":\"2020-02-15T10:45:48+00:00\",\"dateModified\":\"2020-02-15T10:54:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aggiungi_posto_a_tavola1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aggiungi_posto_a_tavola1.jpg\",\"width\":447,\"height\":637},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"&#8220;Aggiungi un posto a tavola\u201d al Gran Teatro Geox di Padova. Si alza il sipario sul dramma dell\u2019abbandono\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/dfce5bd678ad0f650527cc2172949970\",\"name\":\"stefaniaP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/stefaniap\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Aggiungi un posto a tavola\u201d al Gran Teatro Geox di Padova. Si alza il sipario sul dramma dell\u2019abbandono - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/","og_locale":"it_IT","og_type":"article","og_title":"\"Aggiungi un posto a tavola\u201d al Gran Teatro Geox di Padova. Si alza il sipario sul dramma dell\u2019abbandono","og_description":"Due gli appuntamenti: stasera, sabato 15, alle 21.15, e domenica 16 febbraio, alle 16.30. Spettacolo prodotto da Viola Produzioni e OTI &ndash; Officine di Teatro Italiano Aggiungi un posto a tavola&rdquo;&nbsp;&egrave; il titolo di una commedia musicale di&nbsp;Garinei&nbsp;e&nbsp;Giovannini,&nbsp;che far&agrave; tappa stasera&nbsp;sabato 15 e domenica 16 febbraio al&nbsp; Gran Teatro&nbsp; Geox [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-02-15T10:45:48+00:00","article_modified_time":"2020-02-15T10:54:09+00:00","og_image":[{"width":447,"height":637,"url":"https:\/\/www.aibi.it\/ita\/images\/aggiungi_posto_a_tavola1.jpg","type":"image\/jpeg"}],"author":"stefaniaP","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/grazie-aggiungi-un-posto-a-tavola_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"stefaniaP","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/"},"author":{"name":"stefaniaP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/dfce5bd678ad0f650527cc2172949970"},"headline":"&#8220;Aggiungi un posto a tavola\u201d al Gran Teatro Geox di Padova. Si alza il sipario sul dramma dell\u2019abbandono","datePublished":"2020-02-15T10:45:48+00:00","dateModified":"2020-02-15T10:54:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/"},"wordCount":284,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aggiungi_posto_a_tavola1.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/","url":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/","name":"\"Aggiungi un posto a tavola\u201d al Gran Teatro Geox di Padova. Si alza il sipario sul dramma dell\u2019abbandono - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aggiungi_posto_a_tavola1.jpg","datePublished":"2020-02-15T10:45:48+00:00","dateModified":"2020-02-15T10:54:09+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/aggiungi_posto_a_tavola1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/aggiungi_posto_a_tavola1.jpg","width":447,"height":637},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/aggiungi-un-posto-a-tavola-al-gran-teatro-geox-di-padova-si-alza-il-sipario-sul-dramma-dellabbandono\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"&#8220;Aggiungi un posto a tavola\u201d al Gran Teatro Geox di Padova. Si alza il sipario sul dramma dell\u2019abbandono"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/dfce5bd678ad0f650527cc2172949970","name":"stefaniaP","url":"https:\/\/www.aibi.it\/ita\/author\/stefaniap\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:17:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/171717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=171717"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/171717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/169370"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=171717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=171717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=171717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}