﻿{"id":174290,"date":"2020-05-07T14:50:29","date_gmt":"2020-05-07T12:50:29","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=174290"},"modified":"2020-05-19T17:50:21","modified_gmt":"2020-05-19T15:50:21","slug":"affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/","title":{"rendered":"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte"},"content":{"rendered":"<h2>Una preziosissima risorsa che permette a tanti bambini di poter essere accuditi in famiglia<\/h2>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-142631 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_400x286-300x215.jpg\" alt=\"neonato\" width=\"300\" height=\"215\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_400x286-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_400x286-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_400x286-77x55.jpg 77w, https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_400x286.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>&#8220;Ai.Bi. buon giorno&#8221;<\/em>, rispondo con il mio solito piglio al telefono. Dall&#8217;altra parte la voce conosciuta di una donna, \u00e8 un&#8217;operatrice del servizio sociale di un comune con cui collaboriamo da tempo. Dopo i saluti iniziali mi chiede se abbiamo famiglie di pronta accoglienza per Haidi, una bambina di qualche mese. Mi spiega a grandi linee la situazione: la sua mamma, \u00e8 giovane e ha dei problemi di salute importanti e deve essere ricoverata nel giro di poche ore. Nella sua rete parentale nessuno parrebbe in grado di prendersi cura della bimba. La bimba \u00e8 sana, \u00e8 stata poco stimolata e per questo dorme molto. Abbiamo bisogno, mi dice, di una famiglia che la possa accudire per qualche mese, disponibile ad accompagnarla agli incontri settimanali con i familiari, cos\u00ec come previsto dal decreto del Tribunale per i Minorenni.<\/p>\n<h3>Affido e famiglie di pronta accoglienza. Un&#8217;esperienza che potrebbe durare qualche mese<\/h3>\n<p>L&#8217;accoglienza potrebbe durare qualche mese, ma molto dipende da come la situazione della madre evolver\u00e0. Prendo nota di tutto e le dico che le facciamo sapere a breve. Mi confronto con la nostra equipe che si occupa della formazione della conoscenza delle famiglie, chiedo se abbiamo qualcuno che potrebbe andare bene.<\/p>\n<p>Ragioniamo su tutti in base alla disponibilit\u00e0 e alle caratteristiche che nei colloqui di conoscenza sono emerse: chi ha figli, chi non ne ha, chi lavora, chi \u00e8 casa e chi \u00e8 vicino e chi meno. Ma certo: Fabiana e Corrado, loro s\u00ec che potrebbero andare bene. Spieghiamo loro la situazione al telefono. Sono mesi che aspettano l&#8217;abbinamento giusto e adesso devono rispondere in poche ore, dopo neanche mezz&#8217;ora richiamano e accettano. Il resto sono telefonate organizzative per capire come, dove, quando incontrare la piccola e l&#8217;inizio di una nuova avventura.<\/p>\n<p>E anche oggi ringrazio per le famiglie di pronta accoglienza: una preziosissima risorsa che permette ai bambini come Haidi di poter stare in famiglia.<\/p>\n<p>Risorse che non bastano mai perch\u00e9 i bambini che hanno bisogno sono tanti. Ai.Bi. &#8211; Amici dei Bambini \u00e8 sempre alla ricerca di nuove famiglie affidatarie che vogliano aprire le braccia all&#8217;accoglienza.<\/p>\n<p>Chi fosse interessato pu\u00f2 contattare il numero 02\/988221 o inviare una e-mail a: <a href=\"mailto:affido@aibi.it\">affido@aibi.it<\/a>. <a href=\"https:\/\/www.aibi.it\/ita\/io-resto-a-casa\/#distance\">Ai.Bi. organizza, anche in questa fase di emergenza sanitaria, incontri informativi a distanza per approcciarsi a questo mondo. Il prossimo \u00e8 previsto per il 14 maggio alle ore 21 su Zoom.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una preziosissima risorsa che permette a tanti bambini di poter essere accuditi in famiglia &ldquo;Ai.Bi. buon giorno&rdquo;, rispondo con il mio solito piglio al telefono. Dall&rsquo;altra parte la voce conosciuta di una donna, &egrave; un&rsquo;operatrice del servizio sociale di un comune con cui collaboriamo da tempo. Dopo i saluti iniziali [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":142631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[652,71],"tags":[320],"class_list":["post-174290","post","type-post","status-publish","format-standard","has-post-thumbnail","category-affido","category-aibinews","tag-affido"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte. Affido famiglie pronta accoglienza, come funziona.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte\" \/>\n<meta property=\"og:description\" content=\"Una preziosissima risorsa che permette a tanti bambini di poter essere accuditi in famiglia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-07T12:50:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-19T15:50:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte\" \/>\n<meta name=\"twitter:description\" content=\"Una preziosissima risorsa che permette a tanti bambini di poter essere accuditi in famiglia\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte\",\"datePublished\":\"2020-05-07T12:50:29+00:00\",\"dateModified\":\"2020-05-19T15:50:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\\\/\"},\"wordCount\":422,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/neonato-tragedia_400x286.jpg\",\"keywords\":[\"affido\"],\"articleSection\":[\"Affido &amp; Accoglienza Familiare\",\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\\\/\",\"name\":\"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/neonato-tragedia_400x286.jpg\",\"datePublished\":\"2020-05-07T12:50:29+00:00\",\"dateModified\":\"2020-05-19T15:50:21+00:00\",\"description\":\"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte. Affido famiglie pronta accoglienza, come funziona.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/neonato-tragedia_400x286.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/neonato-tragedia_400x286.jpg\",\"width\":400,\"height\":286,\"caption\":\"neonato\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affido &amp; Accoglienza Familiare\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/affido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte - Ai.Bi. Amici dei Bambini","description":"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte. Affido famiglie pronta accoglienza, come funziona.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/","og_locale":"it_IT","og_type":"article","og_title":"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte","og_description":"Una preziosissima risorsa che permette a tanti bambini di poter essere accuditi in famiglia","og_url":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-05-07T12:50:29+00:00","article_modified_time":"2020-05-19T15:50:21+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte","twitter_description":"Una preziosissima risorsa che permette a tanti bambini di poter essere accuditi in famiglia","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte","datePublished":"2020-05-07T12:50:29+00:00","dateModified":"2020-05-19T15:50:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/"},"wordCount":422,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_400x286.jpg","keywords":["affido"],"articleSection":["Affido &amp; Accoglienza Familiare","AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/","url":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/","name":"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_400x286.jpg","datePublished":"2020-05-07T12:50:29+00:00","dateModified":"2020-05-19T15:50:21+00:00","description":"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte. Affido famiglie pronta accoglienza, come funziona.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_400x286.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/neonato-tragedia_400x286.jpg","width":400,"height":286,"caption":"neonato"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/affido-e-famiglie-di-pronta-accoglienza-a-cosa-servono-e-come-vengono-scelte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Affido &amp; Accoglienza Familiare","item":"https:\/\/www.aibi.it\/ita\/category\/affido\/"},{"@type":"ListItem","position":3,"name":"Affido e famiglie di pronta accoglienza: a cosa servono e come vengono scelte"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 03:12:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/174290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=174290"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/174290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/142631"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=174290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=174290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=174290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}