﻿


{"id":174345,"date":"2020-05-08T18:00:58","date_gmt":"2020-05-08T16:00:58","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=174345"},"modified":"2020-05-08T18:00:58","modified_gmt":"2020-05-08T16:00:58","slug":"donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/","title":{"rendered":"Donazioni 2019: se non ricevo la certificazione fiscale, che cosa devo fare?"},"content":{"rendered":"<blockquote><p>Cara Ai.Bi. buongiorno,<\/p>\n<p>nella speranza che stiate tutti bene, vi scrivo per chiedere informazioni sulla certificazione fiscale per le donazioni effettuate nel 2019 (quindi anche per la mia <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/\">Adozione a Distanza<\/a>) per la compilazione della mia dichiarazione dei redditi: ho notato che quest\u2019anno non l\u2019avete ancora spedita in cartaceo.<\/p>\n<p>Come mai? Cosa devo fare per chiederla?<\/p>\n<p>Grazie<\/p>\n<p>Alessio<\/p><\/blockquote>\n<p>Caro Alessio,<\/p>\n<p>grazie per averci scritto e ci auguriamo che anche lei e la sua famiglia stiate bene. Le confermiamo che non abbiamo fatto l\u2019invio cartaceo di Aprile solo per motivi logistici come pu\u00f2 immaginare in questo periodo. A causa dell\u2019emergenza Coronavirus le spedizioni massive via posta sono molto limitate e il nostro personale non \u00e8 presente in sede. Tutti i desk di Ai.Bi. sono sempre operativi ma in modalit\u00e0 smartworking. Potr\u00e0 pertanto richiedere la certificazione fiscale delle sue donazioni via mail.<\/p>\n<p>Telefoni allo <strong>02988221<\/strong> o scriva una mail a <a href=\"mailto:donatori@aibi.it\">donatori@aibi.it<\/a> con la richiesta di certificazione fiscale e in pochissime ore ricever\u00e0, sempre via mail, il riepilogo versamenti in formato pdf da stampare o da inoltrare al commercialista o al CAAF.<\/p>\n<p>Le ricordiamo che tutte le donazioni liberali e quelle per i sostegni a distanza di Ai.Bi. sono tutte deducibili. Per potere godere per\u00f2 delle agevolazioni fiscali \u00e8 necessario conservare per cinque anni la documentazione comprovante il versamento (bollettino c.c.p., contabile di bonifico, estratto conto bancario). Non godono delle agevolazioni fiscali i versamenti effettuati in contanti.<\/p>\n<p>Quest\u2019anno, data la situazione di emergenza sanitaria, spediremo il riepilogo versamento cartaceo nei prossimi mesi. E\u2019 doveroso da parte nostra tranquillizzare tutti i nostri donatori e sostenitori sulla scadenza della presentazione della dichiarazione dei redditi che \u00e8 stata prorogata al 30 settembre 2020.<\/p>\n<p>Inoltre si ricordi che potr\u00e0 sostenere la mission di Amici dei Bambini anche tramite la sua dichiarazione dei redditi, senza costi aggiuntivi: baster\u00e0 una firma per devolvere il suo 5 x mille. Ebbene s\u00ec, ci sono firme importanti nella vita: ma mai come quella del 5 x mille grazie alla quale regaler\u00e0 il calore di una famiglia a un bambino abbandonato.<\/p>\n<p>Grazie al suo aiuto potr\u00e0 sostenere Ai.Bi. nei paesi in cui opera nella lotta contro l\u2019abbandono, per restituire a milioni di bambini il loro diritto ad essere figli!<\/p>\n<p><strong>Doni il suo 5 x mille ad Ai.Bi.<\/strong> Firmi sulla sua dichiarazione dei redditi, nel riquadro dedicato alle organizzazioni non lucrative di utilit\u00e0 sociale e indichi il codice fiscale di Ai.Bi.: 92504680155. Una semplice firma potr\u00e0 cambiare il destino di milioni di bambini che aspettano l\u2019amore di una mamma e un pap\u00e0 ma soprattutto aspettano che il loro diritto di essere figli gli venga finalmente restituito!<\/p>\n<p>Grazie ancora per tutto quello che fa e per tutto quella che potr\u00e0 fare<\/p>\n<p>Un caro saluto<\/p>\n<p><strong>Staff Donatori &#8211; Ai.Bi. &#8211; Amici dei Bambini<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cara Ai.Bi. buongiorno, nella speranza che stiate tutti bene, vi scrivo per chiedere informazioni sulla certificazione fiscale per le donazioni effettuate nel 2019 (quindi anche per la mia Adozione a Distanza) per la compilazione della mia dichiarazione dei redditi: ho notato che quest&rsquo;anno non l&rsquo;avete ancora spedita in cartaceo. Come [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":174297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[454,615,318,300],"class_list":["post-174345","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lettere-al-direttore","tag-adozione-a-distanza","tag-donazioni","tag-lettere-al-direttore","tag-sostegno-a-distanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Donazioni 2019: cosa fare se non ricevo certificazione fiscale?<\/title>\n<meta name=\"description\" content=\"Donazioni 2019: cosa devo fare se non ricevo la certificazione fiscale? Donazioni 2019 tutto quello che bisogna sapere da Amici dei Bambini.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donazioni 2019: se non ricevo la certificazione fiscale, che cosa devo fare?\" \/>\n<meta property=\"og:description\" content=\"Cara Ai.Bi. buongiorno, nella speranza che stiate tutti bene, vi scrivo per chiedere informazioni sulla certificazione fiscale per le donazioni effettuate nel 2019...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-08T16:00:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/a6-07-05-2020-1200x630-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Donazioni 2019: se non ricevo la certificazione fiscale, che cosa devo fare?\" \/>\n<meta name=\"twitter:description\" content=\"Cara Ai.Bi. buongiorno, nella speranza che stiate tutti bene, vi scrivo per chiedere informazioni sulla certificazione fiscale per le donazioni effettuate nel 2019...\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/a6-07-05-2020-1200x630-1.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Donazioni 2019: se non ricevo la certificazione fiscale, che cosa devo fare?\",\"datePublished\":\"2020-05-08T16:00:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\\\/\"},\"wordCount\":475,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/05\\\/a6-07-05-2020-700x460-1.jpg\",\"keywords\":[\"adozione a distanza\",\"donazioni\",\"Lettere al Direttore\",\"sostegno a distanza\"],\"articleSection\":[\"Lettere al direttore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\\\/\",\"name\":\"Donazioni 2019: cosa fare se non ricevo certificazione fiscale?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/05\\\/a6-07-05-2020-700x460-1.jpg\",\"datePublished\":\"2020-05-08T16:00:58+00:00\",\"description\":\"Donazioni 2019: cosa devo fare se non ricevo la certificazione fiscale? Donazioni 2019 tutto quello che bisogna sapere da Amici dei Bambini.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/05\\\/a6-07-05-2020-700x460-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/05\\\/a6-07-05-2020-700x460-1.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettere al direttore\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/lettere-al-direttore\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Donazioni 2019: se non ricevo la certificazione fiscale, che cosa devo fare?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Donazioni 2019: cosa fare se non ricevo certificazione fiscale?","description":"Donazioni 2019: cosa devo fare se non ricevo la certificazione fiscale? Donazioni 2019 tutto quello che bisogna sapere da Amici dei Bambini.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/","og_locale":"it_IT","og_type":"article","og_title":"Donazioni 2019: se non ricevo la certificazione fiscale, che cosa devo fare?","og_description":"Cara Ai.Bi. buongiorno, nella speranza che stiate tutti bene, vi scrivo per chiedere informazioni sulla certificazione fiscale per le donazioni effettuate nel 2019...","og_url":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-05-08T16:00:58+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/a6-07-05-2020-1200x630-1.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Donazioni 2019: se non ricevo la certificazione fiscale, che cosa devo fare?","twitter_description":"Cara Ai.Bi. buongiorno, nella speranza che stiate tutti bene, vi scrivo per chiedere informazioni sulla certificazione fiscale per le donazioni effettuate nel 2019...","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/a6-07-05-2020-1200x630-1.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Donazioni 2019: se non ricevo la certificazione fiscale, che cosa devo fare?","datePublished":"2020-05-08T16:00:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/"},"wordCount":475,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/a6-07-05-2020-700x460-1.jpg","keywords":["adozione a distanza","donazioni","Lettere al Direttore","sostegno a distanza"],"articleSection":["Lettere al direttore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/","url":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/","name":"Donazioni 2019: cosa fare se non ricevo certificazione fiscale?","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/a6-07-05-2020-700x460-1.jpg","datePublished":"2020-05-08T16:00:58+00:00","description":"Donazioni 2019: cosa devo fare se non ricevo la certificazione fiscale? Donazioni 2019 tutto quello che bisogna sapere da Amici dei Bambini.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/a6-07-05-2020-700x460-1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/a6-07-05-2020-700x460-1.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/donazioni-2019-se-non-ricevo-la-certificazione-fiscale-che-cosa-devo-fare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Lettere al direttore","item":"https:\/\/www.aibi.it\/ita\/category\/lettere-al-direttore\/"},{"@type":"ListItem","position":3,"name":"Donazioni 2019: se non ricevo la certificazione fiscale, che cosa devo fare?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:27:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/174345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=174345"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/174345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/174297"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=174345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=174345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=174345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}