﻿


{"id":174625,"date":"2020-05-15T15:17:48","date_gmt":"2020-05-15T13:17:48","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=174625"},"modified":"2020-05-15T15:17:48","modified_gmt":"2020-05-15T13:17:48","slug":"adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/","title":{"rendered":"Adolescenti senza famiglia. Perch\u00e9 adottare a distanza un care leaver?"},"content":{"rendered":"<blockquote><p>Cara Ai.Bi.,<\/p>\n<p>in questo periodo, dove si trascorre pi\u00f9 tempo a casa, mi \u00e8 capitato di rileggere il vostro giornalino AiBinotizie, di qualche mese fa, che ricevo periodicamente. Mi sono soffermata su un articolo che parlava della possibilit\u00e0 di adottare a distanza uno tra i tanti adolescenti senza famiglia alle soglie dell&#8217;et\u00e0 adulta, cio\u00e8 un care leaver; colgo l\u2019occasione per avere dei chiarimenti a riguardo, quale tipo di aiuto si dona ad un care leaver adottandolo a distanza?<\/p>\n<p>Mi piacerebbe avere qualche info in pi\u00f9<\/p>\n<p>Grazie mille<\/p>\n<p>Giulia<\/p><\/blockquote>\n<p>Cara Giulia,<\/p>\n<p>Innanzitutto grazie per la possibilit\u00e0 che ci sta dando di poter parlare di questi giovani ragazzi, spesso dimenticati da tutto e da tutti.<\/p>\n<p>Si pensa, infatti, che siano i bambini piccoli ad avere bisogno di un sostegno e di aiuto maggiore. Sono, invece, i pi\u00f9 grandi, che hanno passato nella maggior parte dei casi, la quasi totalit\u00e0 della loro vita in uno o addirittura in pi\u00f9 istituti, che si sentono pi\u00f9 soli e che hanno poche speranze per il futuro che li aspetta.<\/p>\n<p>Noi li chiamiamo care leaver per dare proprio l\u2019idea di un ragazzo che al compimento del diciottesimo anno di et\u00e0 lascia tutto quel sistema che si era preso cura di lui fino a quel momento. L\u2019unico mondo che conosce, quello dell\u2019istituto, lo abbandona a se stesso e da un giorno all\u2019altro deve arrangiarsi da solo in tutto e per tutto.<\/p>\n<p>Spesso gli unici che sono disposti ad accoglierli sono il mondo della prostituzione e della malavita organizzata.<\/p>\n<p>Hanno un grosso bisogno di aiuto, e non possiamo aspettare che sia troppo tardi\u2026<br \/>\nIniziamo, infatti, a lavorare con loro fin dal compimento dei 14 anni di et\u00e0 in modo da poter pensare a un piano di vita che rispetti le loro attitudini e le loro capacit\u00e0 per cercare di accompagnarli poi anche nella loro vita fuori dall\u2019istituto che spesso \u00e8 l\u2019unica realt\u00e0 che conoscono.<\/p>\n<h3>Care leaver: quegli adolescenti senza famiglia che studiano da adulti, grazie ad Ai.Bi.<\/h3>\n<p>Chi un corso professionale da sarta, chi l\u2019universit\u00e0, chi l\u2019ottenimento di tutti i documenti necessari a trovare un lavoro regolare o a ottenere un sussidio statale\u2026ognuno di loro ha sogni e problematiche specifiche che con la nostra equipe cerchiamo di risolvere. Se volesse sostenere uno di questi ragazzi, in Africa, all\u2019interno dei nostri progetti, abbiamo diversi care leaver che non vedono l\u2019ora di avere qualcuno che li possa aiutare e star loro vicino, non solo dal punto di vista economico, ma soprattutto dal punto di vista della relazione e dell\u2019appoggio morale.<\/p>\n<p>Per sostenerli basta compilare il modulo di adozione a distanza <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/\">che si trova sul nostro sito<\/a> specificando nelle note di volere sostenere un care leaver o over 13. O semplicemente facendo una telefonata allo <strong>02\/988221<\/strong> e scegliendo insieme il paese del ragazzo da sostenere.<\/p>\n<p>Grazie ancora e speriamo a presto<\/p>\n<p><strong>Staff Sostegno a distanza &#8211; Ai.Bi. &#8211; Amici dei Bambini<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cara Ai.Bi., in questo periodo, dove si trascorre pi&ugrave; tempo a casa, mi &egrave; capitato di rileggere il vostro giornalino AiBinotizie, di qualche mese fa, che ricevo periodicamente. Mi sono soffermata su un articolo che parlava della possibilit&agrave; di adottare a distanza uno tra i tanti adolescenti senza famiglia alle [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":174604,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[614,454,559,600,318],"class_list":["post-174625","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lettere-al-direttore","tag-accoglienzanonsiferma","tag-adozione-a-distanza","tag-care-leaver","tag-coronavirus","tag-lettere-al-direttore"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Care leaver: perch\u00e9 adottare a distanza adolescenti senza famiglia<\/title>\n<meta name=\"description\" content=\"Care leaver: ecco perch\u00e9 adottare a distanza adolescenti senza famiglia. Care leaver sono adolescenti senza famiglia che crescono in istituto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adolescenti senza famiglia. Perch\u00e9 adottare a distanza un care leaver?\" \/>\n<meta property=\"og:description\" content=\"In questo periodo, dove si trascorre pi\u00f9 tempo a casa, mi \u00e8 capitato di rileggere il vostro giornalino AiBinotizie, di qualche mese fa, che ricevo periodicamente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-15T13:17:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/marocco-adozione-aibi-coronavirus_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Adolescenti senza famiglia. Perch\u00e9 adottare a distanza un care leaver?\" \/>\n<meta name=\"twitter:description\" content=\"In questo periodo, dove si trascorre pi\u00f9 tempo a casa, mi \u00e8 capitato di rileggere il vostro giornalino AiBinotizie, di qualche mese fa, che ricevo periodicamente.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/marocco-adozione-aibi-coronavirus_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Adolescenti senza famiglia. Perch\u00e9 adottare a distanza un care leaver?\",\"datePublished\":\"2020-05-15T13:17:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\\\/\"},\"wordCount\":501,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/05\\\/marocco-adozione-aibi-coronavirus_700x460.jpg\",\"keywords\":[\"#accoglienzanonsiferma\",\"adozione a distanza\",\"care leaver\",\"coronavirus\",\"Lettere al Direttore\"],\"articleSection\":[\"Lettere al direttore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\\\/\",\"name\":\"Care leaver: perch\u00e9 adottare a distanza adolescenti senza famiglia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/05\\\/marocco-adozione-aibi-coronavirus_700x460.jpg\",\"datePublished\":\"2020-05-15T13:17:48+00:00\",\"description\":\"Care leaver: ecco perch\u00e9 adottare a distanza adolescenti senza famiglia. Care leaver sono adolescenti senza famiglia che crescono in istituto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/05\\\/marocco-adozione-aibi-coronavirus_700x460.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/05\\\/marocco-adozione-aibi-coronavirus_700x460.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettere al direttore\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/lettere-al-direttore\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adolescenti senza famiglia. Perch\u00e9 adottare a distanza un care leaver?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Care leaver: perch\u00e9 adottare a distanza adolescenti senza famiglia","description":"Care leaver: ecco perch\u00e9 adottare a distanza adolescenti senza famiglia. Care leaver sono adolescenti senza famiglia che crescono in istituto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/","og_locale":"it_IT","og_type":"article","og_title":"Adolescenti senza famiglia. Perch\u00e9 adottare a distanza un care leaver?","og_description":"In questo periodo, dove si trascorre pi\u00f9 tempo a casa, mi \u00e8 capitato di rileggere il vostro giornalino AiBinotizie, di qualche mese fa, che ricevo periodicamente.","og_url":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-05-15T13:17:48+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/marocco-adozione-aibi-coronavirus_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Adolescenti senza famiglia. Perch\u00e9 adottare a distanza un care leaver?","twitter_description":"In questo periodo, dove si trascorre pi\u00f9 tempo a casa, mi \u00e8 capitato di rileggere il vostro giornalino AiBinotizie, di qualche mese fa, che ricevo periodicamente.","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/marocco-adozione-aibi-coronavirus_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Adolescenti senza famiglia. Perch\u00e9 adottare a distanza un care leaver?","datePublished":"2020-05-15T13:17:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/"},"wordCount":501,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/marocco-adozione-aibi-coronavirus_700x460.jpg","keywords":["#accoglienzanonsiferma","adozione a distanza","care leaver","coronavirus","Lettere al Direttore"],"articleSection":["Lettere al direttore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/","url":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/","name":"Care leaver: perch\u00e9 adottare a distanza adolescenti senza famiglia","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/marocco-adozione-aibi-coronavirus_700x460.jpg","datePublished":"2020-05-15T13:17:48+00:00","description":"Care leaver: ecco perch\u00e9 adottare a distanza adolescenti senza famiglia. Care leaver sono adolescenti senza famiglia che crescono in istituto.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/marocco-adozione-aibi-coronavirus_700x460.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/marocco-adozione-aibi-coronavirus_700x460.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adolescenti-senza-famiglia-perche-adottare-a-distanza-un-care-leaver\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Lettere al direttore","item":"https:\/\/www.aibi.it\/ita\/category\/lettere-al-direttore\/"},{"@type":"ListItem","position":3,"name":"Adolescenti senza famiglia. Perch\u00e9 adottare a distanza un care leaver?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:16:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/174625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=174625"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/174625\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/174604"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=174625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=174625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=174625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}