﻿{"id":175209,"date":"2020-05-29T14:50:27","date_gmt":"2020-05-29T12:50:27","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=175209"},"modified":"2020-06-05T16:07:41","modified_gmt":"2020-06-05T14:07:41","slug":"influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/","title":{"rendered":"Influencer adottano bambino autistico. Dopo averlo esposto sui social lo abbandonano&#8230;"},"content":{"rendered":"<h2>L&#8217;adozione internazionale \u00e8 una scelta che va fatta considerando i bisogni dei bambini. Non i capricci degli aspiranti genitori<\/h2>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-145605 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_400x286-300x215.jpg\" alt=\"\" width=\"300\" height=\"215\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_400x286-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_400x286-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_400x286-77x55.jpg 77w, https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_400x286.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Myka Stauffer<\/strong> e il marito <strong>James<\/strong> sono due <strong>influencer,<\/strong> con<strong> oltre 400mila follower.<\/strong> Il piccolo <strong>Huxley<\/strong>, un bimbo autistico, era arrivato a casa loro quattro anni fa, dalla lontana <strong>Cina<\/strong>. Tutta la sua crescita nella famiglia era stata documentata dai genitori adottivi attraverso i <em>social<\/em>, facendo crescere visualizzazioni e, di conseguenza, sponsorizzazioni pubblicitarie. Cos\u00ec, d&#8217;altro canto, lavorano gli influencer.<\/p>\n<p>Eppure, dopo averlo esposto al circo dei <em>social media<\/em>, i due hanno deciso di abbandonare Huxley. Un secondo abbandono, la sorte pi\u00f9 terribile che possa toccare a un bambino. Il piccolo ora sarebbe tornato in Cina, affidato a una nuova famiglia.<\/p>\n<p>La coppia ha provato a giustificarsi con un video: <em>\u201cNon eravamo pronti<\/em> &#8211; hanno detto &#8211; <em>Aveva molte esigenze di cui non eravamo a conoscenza. Abbiamo cercato di soddisfare i suoi bisogni e aiutarlo il pi\u00f9 possibile. Non c\u2019\u00e8 stato un minuto in cui non abbiamo cercato di fare il nostro meglio. Gli ultimi due mesi sono stati la cosa pi\u00f9 difficile che avremmo mai immaginato\u201d.<\/em><\/p>\n<p><em>\u201cMi sento un fallimento come mamma &#8211;<\/em> ha detto Myka, che \u00e8 madre di altri quattro figli biologici &#8211; <em>Non abbiamo adottato Huxley solo per mostrarlo pubblicamente. Mostravamo il 5% della nostra vita con lui, le restanti lotte rimanevano private. Molti professionisti ci hanno detto che aveva bisogno di aiuto. La nuova mamma ha una formazione medica professionale e una casa attrezzata a dovere. Speriamo che se ne prenda cura come il piccolo merita\u201d<\/em>.<\/p>\n<p>Ovviamente, per\u00f2, il gesto della coppia ha provocato una mare di indignazione, con tanto di insulti social indirizzati ai due. Un dramma, quello del piccolo Huxley, che pone l&#8217;accento su quale sia l&#8217;importanza dell&#8217;accoglienza di un minore in adozione internazionale: un gesto che va preparato nel cuore e con la giusta formazione alle spalle su quelli che sono i bisogni del bambino e su quale sia la realt\u00e0 dell&#8217;adozione: non una &#8220;fabbrica&#8221; di figli a comando, ma una scelta importante e profonda.<\/p>\n<p><strong>Una scelta che va fatta considerando prioritariamente le necessit\u00e0 dei bambini. E non, di certo, i capricci degli aspiranti genitori.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;adozione internazionale &egrave; una scelta che va fatta considerando i bisogni dei bambini. Non i capricci degli aspiranti genitori Myka Stauffer e il marito James sono due influencer, con oltre 400mila follower. Il piccolo Huxley, un bimbo autistico, era arrivato a casa loro quattro anni fa, dalla lontana Cina. Tutta [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":145605,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[347,434],"class_list":["post-175209","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-adozione-internazionale","tag-cina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Influencer adottano e poi abbandonano bambino autistico<\/title>\n<meta name=\"description\" content=\"Influencer adottano e poi abbandonano bambino autistico: l&#039;indignazione e il vero concetto di adozione internazionale. Influencer abbandonano bambino\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Influencer adottano bambino autistico. Dopo averlo esposto sui social lo abbandonano...\" \/>\n<meta property=\"og:description\" content=\"L&#039;adozione internazionale \u00e8 una scelta che va fatta considerando i bisogni dei bambini. Non i capricci degli aspiranti genitori\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-29T12:50:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-05T14:07:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Influencer adottano bambino autistico. Dopo averlo esposto sui social lo abbandonano...\" \/>\n<meta name=\"twitter:description\" content=\"L&#039;adozione internazionale \u00e8 una scelta che va fatta considerando i bisogni dei bambini. Non i capricci degli aspiranti genitori\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Influencer adottano bambino autistico. Dopo averlo esposto sui social lo abbandonano&#8230;\",\"datePublished\":\"2020-05-29T12:50:27+00:00\",\"dateModified\":\"2020-06-05T14:07:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\\\/\"},\"wordCount\":375,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/foto-social-bambini_400x286.jpg\",\"keywords\":[\"Adozione Internazionale\",\"Cina\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\\\/\",\"name\":\"Influencer adottano e poi abbandonano bambino autistico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/foto-social-bambini_400x286.jpg\",\"datePublished\":\"2020-05-29T12:50:27+00:00\",\"dateModified\":\"2020-06-05T14:07:41+00:00\",\"description\":\"Influencer adottano e poi abbandonano bambino autistico: l'indignazione e il vero concetto di adozione internazionale. Influencer abbandonano bambino\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/foto-social-bambini_400x286.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/foto-social-bambini_400x286.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Influencer adottano bambino autistico. Dopo averlo esposto sui social lo abbandonano&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Influencer adottano e poi abbandonano bambino autistico","description":"Influencer adottano e poi abbandonano bambino autistico: l'indignazione e il vero concetto di adozione internazionale. Influencer abbandonano bambino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/","og_locale":"it_IT","og_type":"article","og_title":"Influencer adottano bambino autistico. Dopo averlo esposto sui social lo abbandonano...","og_description":"L'adozione internazionale \u00e8 una scelta che va fatta considerando i bisogni dei bambini. Non i capricci degli aspiranti genitori","og_url":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-05-29T12:50:27+00:00","article_modified_time":"2020-06-05T14:07:41+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Influencer adottano bambino autistico. Dopo averlo esposto sui social lo abbandonano...","twitter_description":"L'adozione internazionale \u00e8 una scelta che va fatta considerando i bisogni dei bambini. Non i capricci degli aspiranti genitori","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Influencer adottano bambino autistico. Dopo averlo esposto sui social lo abbandonano&#8230;","datePublished":"2020-05-29T12:50:27+00:00","dateModified":"2020-06-05T14:07:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/"},"wordCount":375,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_400x286.jpg","keywords":["Adozione Internazionale","Cina"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/","url":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/","name":"Influencer adottano e poi abbandonano bambino autistico","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_400x286.jpg","datePublished":"2020-05-29T12:50:27+00:00","dateModified":"2020-06-05T14:07:41+00:00","description":"Influencer adottano e poi abbandonano bambino autistico: l'indignazione e il vero concetto di adozione internazionale. Influencer abbandonano bambino","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_400x286.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/foto-social-bambini_400x286.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/influencer-adottano-bambino-autistico-dopo-averlo-esposto-sui-social-lo-abbandonano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Influencer adottano bambino autistico. Dopo averlo esposto sui social lo abbandonano&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:49:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/175209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=175209"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/175209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/145605"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=175209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=175209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=175209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}