﻿


{"id":175496,"date":"2020-06-07T18:59:10","date_gmt":"2020-06-07T16:59:10","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=175496"},"modified":"2020-06-08T09:45:42","modified_gmt":"2020-06-08T07:45:42","slug":"griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/","title":{"rendered":"Griffini (Ai.Bi.):  &#8220;Mario Balotelli, il grande testimonial mancato dell\u2019adozione\u201d"},"content":{"rendered":"<h2><strong>&#8220;Ed ora caro Mario&#8230; \u00a0i nostri giovani adottati che cosa ricorderanno di te? Il senso di una illusione ferita, la realt\u00e0 di un ennesimo fallimento o il monito a non seguire il tuo esempio?\u201d. <\/strong><strong>L\u2019editoriale di Marco Griffini, presidente di Ai.Bi.<\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-113378 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/balotelli1-300x215.jpg\" alt=\"\" width=\"300\" height=\"215\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/balotelli1-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/balotelli1-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/balotelli1-77x55.jpg 77w, https:\/\/www.aibi.it\/ita\/images\/balotelli1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Mi ha colpito profondamente leggere oggi la notizia dell\u2019ultima bravata di <strong>Mario Balotelli<\/strong> il suo <strong>licenziamento dal Brescia Calcio.<\/strong> A nulla sono valse le spiegazioni del calciatore su una sua presunta gastroenterite che non gli aveva dato modo di partecipare agli allenamenti. <strong>Massimo Cellini<\/strong>, presidente del club ha preferito la linea dura, recapitando al calciatore la lettera che mette fine al rapporto con \u201csuper Mario\u201d per troppe assenze ingiustificate.<\/p>\n<p>Come credo abbia fatto ogni <strong>genitore adottivo<\/strong> ,anche io ho sempre seguito le vicende di Mario Balotelli, fin dal suo esordio, giovane 18nne nel campionato di calcio con la maglia dell\u2019Inter.<br \/>\nNon potevo farne a meno, era diventato un argomento di discussione quotidiana con l\u2019ultimo dei miei tre <strong>figli adottivi,<\/strong> Francesco, il &#8220;brasiliano&#8221;, accanito sostenitore del Milan, in ci\u00f2 tradendo le tradizioni della nostra famiglia, dedita da tre generazioni al culto della maglia interista.<\/p>\n<p>Mi piaceva osservare Francesco quando il &#8220;grande&#8221; Mario scendeva in campo, guardare il suo viso illuminarsi&#8230; era come se fosse sceso in campo un &#8220;dio\u201d&#8230; non importava che indossasse una maglia differente, che fosse di un\u2019altra squadra&#8230; quello era un ragazzo adottato, pure nero come lui&#8230; soprattutto bravo&#8230;<\/p>\n<p>Come non ricordare il petto nudo con tutto i muscoli gonfiati, mostrato alle tv di tutto il mondo dopo il secondo clamoroso gol alla &#8220;odiata&#8221; Germania nella <strong>semifinale del campionato europeo<\/strong> del 2012 e subito dopo la sua corsa sulle tribune ad abbracciare la mamma adottiva&#8230; eccolo&#8230; il trionfo della adozione.<\/p>\n<p>La gioia vera, il sorriso spontaneo, il <strong>riscatto dall\u2019abbandono<\/strong>, un definitivo colpo a quel dramma della bassa o nulla autostima, compagna inesorabile e maligna di tanti, troppi ragazzi e giovani adottati&#8230;<\/p>\n<p>Eccolo il <strong>perfetto testimonial dell\u2019 <a href=\"http:\/\/www.aibi.it\/adozione\">adozione<\/a><\/strong>: un modello da indicare a chi continua a blaterare che l\u2019adozione, specie quella internazionale \u00e8 un fallimento; che questi bambini adottati, una volta adulti, non riusciranno a combinare nulla di buono e di valido nella vita; che, specialmente se di colore, non si integreranno mai nella nostra societ\u00e0 e saranno sempre emarginati&#8230;<\/p>\n<p>Lui, Mario, era l\u00ec in carne ed ossa, con tutta la sua prestanza, con le immense capacit\u00e0 regalategli da madre natura, ad urlare che &#8220;l\u2019abbandono non \u00e8 l\u2019ultima parola nella vita di un bambino abbandonato&#8221;, che l\u2019<strong>accoglienza<\/strong> di una famiglia ti pu\u00f2 far superare anche il tremendo ricordo &#8220;di una mamma che ti abbandona&#8221;&#8230;<\/p>\n<p>Ma vedevo anche sul volto di mio figlio &#8211; e questo accadeva, purtroppo, sempre pi\u00f9 spesso- e sentivo, nelle sue parole, il vero dispiacere nell\u2019apprendere dell\u2019ultima bravata di Mario: le feste dissennate in discoteca, le macchine di lusso sfasciate. La Maserati rimossa per 27 volte dalla polizia perch\u00e9 parcheggiata in sosta vietata nella stagione del Manchester City. Le freccette tirate alle giovani promesse della Primavera del Liverpool per evadere dalla noia. I 2 mila euro consegnati al proprietario di un bar a Mergellina perch\u00e9 si tuffasse con lo scooter dentro il mare di Napoli\u2026 le risse immotivate in campo.<\/p>\n<p>Lo sentivo soffrire, veramente, ed era una sofferenza sincera&#8230; come se il suo &#8220;<strong>fratello maggiore<\/strong>&#8221; lo avesse tradito, avesse tradito quella speranza, quella fiducia che con tanta passione, entusiasmo, trasporto aveva posto in lui&#8230;<\/p>\n<p>Ed ora caro Mario&#8230; i nostri giovani adottati che cosa ricorderanno di te?<\/p>\n<p><strong>Marco Griffini<\/strong><\/p>\n<p><strong>Presidente &#8211; Ai.Bi. &#8211; Amici dei Bambini<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&ldquo;Ed ora caro Mario&hellip; &nbsp;i nostri giovani adottati che cosa ricorderanno di te? Il senso di una illusione ferita, la realt&agrave; di un ennesimo fallimento o il monito a non seguire il tuo esempio?&rdquo;. L&rsquo;editoriale di Marco Griffini, presidente di Ai.Bi. Mi ha colpito profondamente leggere oggi la notizia dell&rsquo;ultima [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":113378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[279],"class_list":["post-175496","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-adozione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Balotelli: licenziamento dal Brescia. Un testimonial dell&#039;adozione mancato<\/title>\n<meta name=\"description\" content=\"Griffini (AiBi) &quot; Mi ha colpito leggere del licenziamento di Balotelli dal Brescia. Ora caro Mario i nostri giovani adottati che cosa ricorderanno di te?&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Balotelli: licenziamento dal Brescia. Un testimonial dell&#039;adozione mancato\" \/>\n<meta property=\"og:description\" content=\"Griffini (AiBi) &quot; Mi ha colpito leggere del licenziamento di Balotelli dal Brescia. Ora caro Mario i nostri giovani adottati che cosa ricorderanno di te?&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-07T16:59:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-08T07:45:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Balotelli.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Griffini (Ai.Bi.): &quot;Mario Balotelli, il grande testimonial mancato dell\u2019adozione\u201d\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Balotelli.png\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Griffini (Ai.Bi.): &#8220;Mario Balotelli, il grande testimonial mancato dell\u2019adozione\u201d\",\"datePublished\":\"2020-06-07T16:59:10+00:00\",\"dateModified\":\"2020-06-08T07:45:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\\\/\"},\"wordCount\":601,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/balotelli1.jpg\",\"keywords\":[\"adozione\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\\\/\",\"name\":\"Balotelli: licenziamento dal Brescia. Un testimonial dell'adozione mancato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/balotelli1.jpg\",\"datePublished\":\"2020-06-07T16:59:10+00:00\",\"dateModified\":\"2020-06-08T07:45:42+00:00\",\"description\":\"Griffini (AiBi) \\\" Mi ha colpito leggere del licenziamento di Balotelli dal Brescia. Ora caro Mario i nostri giovani adottati che cosa ricorderanno di te?\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/balotelli1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/balotelli1.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Griffini (Ai.Bi.): &#8220;Mario Balotelli, il grande testimonial mancato dell\u2019adozione\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Balotelli: licenziamento dal Brescia. Un testimonial dell'adozione mancato","description":"Griffini (AiBi) \" Mi ha colpito leggere del licenziamento di Balotelli dal Brescia. Ora caro Mario i nostri giovani adottati che cosa ricorderanno di te?\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/","og_locale":"it_IT","og_type":"article","og_title":"Balotelli: licenziamento dal Brescia. Un testimonial dell'adozione mancato","og_description":"Griffini (AiBi) \" Mi ha colpito leggere del licenziamento di Balotelli dal Brescia. Ora caro Mario i nostri giovani adottati che cosa ricorderanno di te?\"","og_url":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-06-07T16:59:10+00:00","article_modified_time":"2020-06-08T07:45:42+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/Balotelli.png","type":"image\/png"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_title":"Griffini (Ai.Bi.): \"Mario Balotelli, il grande testimonial mancato dell\u2019adozione\u201d","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/Balotelli.png","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Griffini (Ai.Bi.): &#8220;Mario Balotelli, il grande testimonial mancato dell\u2019adozione\u201d","datePublished":"2020-06-07T16:59:10+00:00","dateModified":"2020-06-08T07:45:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/"},"wordCount":601,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/balotelli1.jpg","keywords":["adozione"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/","url":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/","name":"Balotelli: licenziamento dal Brescia. Un testimonial dell'adozione mancato","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/balotelli1.jpg","datePublished":"2020-06-07T16:59:10+00:00","dateModified":"2020-06-08T07:45:42+00:00","description":"Griffini (AiBi) \" Mi ha colpito leggere del licenziamento di Balotelli dal Brescia. Ora caro Mario i nostri giovani adottati che cosa ricorderanno di te?\"","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/balotelli1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/balotelli1.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-mario-balotelli-il-grande-testimonial-mancato-delladozione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Griffini (Ai.Bi.): &#8220;Mario Balotelli, il grande testimonial mancato dell\u2019adozione\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:45:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/175496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=175496"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/175496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/113378"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=175496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=175496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=175496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}