﻿


{"id":176118,"date":"2020-06-21T09:00:58","date_gmt":"2020-06-21T07:00:58","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=176118"},"modified":"2020-06-19T16:29:21","modified_gmt":"2020-06-19T14:29:21","slug":"italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/","title":{"rendered":"Italiani favorevoli alle adozioni e all&#8217;accoglienza. Ma la burocrazia rimane &#8220;miope&#8221;"},"content":{"rendered":"<h2>L&#8217;indagine: il 40% consiglierebbe di adottare. Eppure il calo continua. Griffini (Ai.Bi.): &#8220;Coppie devono sostenere oltre 20 colloqui. Come fossero psicopatici&#8221;<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-176089 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb-571x300.jpg\" alt=\"\" width=\"571\" height=\"300\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb-105x55.jpg 105w, https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb.jpg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/>Nonostante la burocrazia, gli italiani hanno fiducia nelle adozioni e, anzi, sono pronti a consigliarle alle tante coppie senza figli. A pari merito, come consiglio, c&#8217;\u00e8 quello della fecondazione omologa. A seguire fecondazione eterologa e affido. Questa classifica \u00e8 il risultato di un&#8217;indagine sulla percezione dell&#8217;istituto adottivo, condotta da un gruppo di docenti universitari di sette atenei italiani e promossa dall&#8217;associazione <strong>Italia Adozioni.<\/strong> Positive sono anche le emozioni con cui gli italiani reagiscono di fronte al concetto di adozione: sentimenti come ammirazione o gioia sono infatti per l&#8217;80% pi\u00f9 rappresentati, di fronte alla prospettiva di adottare, rispetto a paura, vergogna o imbarazzo.<\/p>\n<p>Il 40% degli intervistati sono quelli che suggerirebbero a coppie senza figli l&#8217;adozione. Inoltre oltre il 70% del campione ha affermato di conoscere famiglie adottive e di ammirarle. L&#8217;80% invece conosce l&#8217;adozione attraverso storie o libri. Questo anche se la percentuale di esperienze dirette di adozione nel campione era pari solo a circa il 10%. Per l&#8217;adozione insomma, i sentimenti degli italiani sono soprattutto positivi. Un sentimento confermato dal fatto che, pur in una generale situazione di flessione delle adozioni, l&#8217;Italia resta saldamente dal 2008 il primo paese in Europa e il secondo al mondo (dopo gli Stati Uniti) per numero di adozioni di minori.<\/p>\n<p>Negli anni tra il 2000 e il 2018 sono stati 50.152 i bambini accolti dalle famiglie italiane, anche se dal 2011 \u00e8 iniziato un calo vertiginoso, che ha portato, per fare un esempio, il numero delle adozioni internazionali realizzate ogni anno dalle circa 4mila unit\u00e0 dello stesso 2011 al numero inferiore a 1000 del 2019. Bambini che sono italiani a tutti gli effetti per l&#8217;ordinamento giuridico.<\/p>\n<h3>Adozioni e burocrazia: cosa penalizza l&#8217;istituto adottivo<\/h3>\n<p>Ma, se l&#8217;Italia \u00e8 cos\u00ec accogliente, cos&#8217;\u00e8 che penalizza l&#8217;istituto adottivo allora? &#8220;<em>Finch\u00e9 avremo in Italia una miope burocrazia per le adozioni internazionali<\/em> &#8211; commenta il <strong>presidente di Ai.Bi. &#8211; Amici dei Bambini, Marco Griffini<\/strong> &#8211; <em>saranno ben poche le famiglie che decideranno di avventurarsi su un percorso cos\u00ec irto di ostacoli. Ricordo che l\u2019Italia \u00e8 ancora l\u2019unico paese europeo ad avere un percorso giudiziario per ottenere l\u2019idoneit\u00e0 all\u2019Adozione Internazionale. Inoltre magistratura minorile e servizi sociali sono permeati da una cultura negativa che vede l\u2019adozione internazionale come un potenziale fallimento. Ci sono coppie che devono sostenere per ottenere una relazione dei servizi sociali addirittura pi\u00f9 di 20 colloqui con psicologi quasi fossero degli psicopatici. Occorre una massa impressionante di documenti da inviare al Paese straniero, che dopo sei mesi scadono e occorre rinnovarli tutti. Non vengano rispettati i tempi previsti dalla legge e soprattutto aldil\u00e0 di sporadici rimborsi, occorre che l\u2019adozione internazionale sia sostenuta in maniera strutturale dal Governo. Cosa che, al momento, non avviene&#8221;.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;indagine: il 40% consiglierebbe di adottare. Eppure il calo continua. Griffini (Ai.Bi.): &ldquo;Coppie devono sostenere oltre 20 colloqui. Come fossero psicopatici&rdquo; Nonostante la burocrazia, gli italiani hanno fiducia nelle adozioni e, anzi, sono pronti a consigliarle alle tante coppie senza figli. A pari merito, come consiglio, c&rsquo;&egrave; quello della fecondazione [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":176089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-176118","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni: italiani favorevoli. Nonostante la burocrazia miope<\/title>\n<meta name=\"description\" content=\"Adozioni: italiani favorevoli. Nonostante la burocrazia miope. Adozioni e burocrazia: quel fardello che frena la voglia di accogliere.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Italiani favorevoli alle adozioni e all&#039;accoglienza. Ma la burocrazia rimane &quot;miope&quot;\" \/>\n<meta property=\"og:description\" content=\"L&#039;indagine: il 40% consiglierebbe di adottare. Eppure il calo continua. Griffini (Ai.Bi.): &quot;Coppie devono sostenere oltre 20 colloqui. Come fossero psicopatici&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-21T07:00:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Italiani favorevoli alle adozioni e all&#039;accoglienza. Ma la burocrazia rimane &quot;miope&quot;\" \/>\n<meta name=\"twitter:description\" content=\"L&#039;indagine: il 40% consiglierebbe di adottare. Eppure il calo continua. Griffini (Ai.Bi.): &quot;Coppie devono sostenere oltre 20 colloqui. Come fossero psicopatici&quot;\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Italiani favorevoli alle adozioni e all&#8217;accoglienza. Ma la burocrazia rimane &#8220;miope&#8221;\",\"datePublished\":\"2020-06-21T07:00:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\\\/\"},\"wordCount\":480,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/06\\\/adozione-internazionale-aibi_fb.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\\\/\",\"name\":\"Adozioni: italiani favorevoli. Nonostante la burocrazia miope\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/06\\\/adozione-internazionale-aibi_fb.jpg\",\"datePublished\":\"2020-06-21T07:00:58+00:00\",\"description\":\"Adozioni: italiani favorevoli. Nonostante la burocrazia miope. Adozioni e burocrazia: quel fardello che frena la voglia di accogliere.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/06\\\/adozione-internazionale-aibi_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/06\\\/adozione-internazionale-aibi_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Italiani favorevoli alle adozioni e all&#8217;accoglienza. Ma la burocrazia rimane &#8220;miope&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni: italiani favorevoli. Nonostante la burocrazia miope","description":"Adozioni: italiani favorevoli. Nonostante la burocrazia miope. Adozioni e burocrazia: quel fardello che frena la voglia di accogliere.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/","og_locale":"it_IT","og_type":"article","og_title":"Italiani favorevoli alle adozioni e all'accoglienza. Ma la burocrazia rimane \"miope\"","og_description":"L'indagine: il 40% consiglierebbe di adottare. Eppure il calo continua. Griffini (Ai.Bi.): \"Coppie devono sostenere oltre 20 colloqui. Come fossero psicopatici\"","og_url":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-06-21T07:00:58+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Italiani favorevoli alle adozioni e all'accoglienza. Ma la burocrazia rimane \"miope\"","twitter_description":"L'indagine: il 40% consiglierebbe di adottare. Eppure il calo continua. Griffini (Ai.Bi.): \"Coppie devono sostenere oltre 20 colloqui. Come fossero psicopatici\"","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Italiani favorevoli alle adozioni e all&#8217;accoglienza. Ma la burocrazia rimane &#8220;miope&#8221;","datePublished":"2020-06-21T07:00:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/"},"wordCount":480,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/","url":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/","name":"Adozioni: italiani favorevoli. Nonostante la burocrazia miope","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb.jpg","datePublished":"2020-06-21T07:00:58+00:00","description":"Adozioni: italiani favorevoli. Nonostante la burocrazia miope. Adozioni e burocrazia: quel fardello che frena la voglia di accogliere.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/06\/adozione-internazionale-aibi_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/italiani-favorevoli-alle-adozioni-e-allaccoglienza-ma-la-burocrazia-rimane-miope\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Italiani favorevoli alle adozioni e all&#8217;accoglienza. Ma la burocrazia rimane &#8220;miope&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:48:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/176118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=176118"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/176118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/176089"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=176118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=176118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=176118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}