﻿{"id":176781,"date":"2020-07-02T14:48:02","date_gmt":"2020-07-02T12:48:02","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=176781"},"modified":"2022-07-28T14:26:21","modified_gmt":"2022-07-28T12:26:21","slug":"kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/","title":{"rendered":"Kenya. John torna a casa dopo tre anni: cos\u00ec una mamma ritrova suo figlio"},"content":{"rendered":"<h2>I grandi risultati del <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Kenya\">Sostegno a Distanza<\/a> di Amici dei Bambini : la reintegrazione in famiglia dei bambini di strada<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-148615 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb-300x158.jpg\" alt=\"incontro con assistenti sociali e reinserimento nella societ\u00e0\" width=\"300\" height=\"158\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb-300x158.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb-1024x538.jpg 1024w, https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb-105x55.jpg 105w, https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>In <strong>Kenya<\/strong>, <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Kenya\">grazie al Sostegno a Distanza<\/a>, le attivit\u00e0 di <strong>Ai.Bi. &#8211; Amici dei Bambini<\/strong> proseguono proficuamente. A beneficiarne sono bambini come John, un bambino di strada che, dopo tre anni, \u00e8 finalmente potuto tornare a casa. <a href=\"https:\/\/www.aibi.it\/ita\/kenya-gli-angeli-del-sostegno-a-distanza-felistus-da-minore-vulnerabile-ad-avvocato-per-la-difesa-dei-minori-di-ai-bi\/\">Felistus, avvocato dei minori di Ai.Bi.<\/a> nel Paese africano e l&#8217;assistente sociale del centro <strong>Kwetu,<\/strong> sono infatti recentemente riusciti a rintracciare la famiglia di questo bambino che era ospite del centro di riabilitazione temporaneo. Rintracciare le famiglie d&#8217;origine di questi minori, ai tempi del Coronavirus, non \u00e8 cosi semplice: servono permessi particolari per potersi spostare e sopratutto per oltrepassare i confini della contea di Nairobi. \u00c8 molto importante per\u00f2, per ogni istituto, avere le carte in regola e ottenere il consenso legale da parte del genitore o del tutore a ospitare il minore.<\/p>\n<h3>Kenya e Sostegno a Distanza: un viaggio in moto fino a Kikuyu per trovare la casa di John<\/h3>\n<p>Per trovare la mamma di John, Felistus e il collaboratore di Kwetu sono andati fino a Kikuyu, un villaggio nella limitrofa contea di Kiambu, a circa mezz\u2019ora da Nairobi. John si ricordava la via di casa e ha dato lui le indicazioni per arrivarci. A causa delle piogge era molto fangoso e la moto che guidavano non riusciva a portarli fino all&#8217;edificio, cosi, a un certo punto, hanno dovuto proseguire a piedi. Una volta arrivati sul posto, all\u2019esterno c\u2019erano le sorelle minori di John che non l\u2019hanno riconosciuto e hanno chiamato la mamma dicendo che c\u2019era un ospite. Quando questa \u00e8 uscita di casa per vedere chi fosse e ha rivisto suo figlio \u00e8 scoppiata a piangere, facendo commuovere tutti i presenti, tranne le piccole che continuavano a chiederle perch\u00e8 uno sconosciuto la facesse piangere tanto.<\/p>\n<p>Dal racconto dei famigliari di solito si riesce ad avere un quadro completo di cosa sia davvero successo e a comprendere i motivi dell&#8217;abbandono. La mamma ha raccontato che John si chiama in realt\u00e0 Brian ed \u00e8 il terzogenito di sette figli. I primi tre figli, due femmine e Brian appunto, sono rimasti senza padre e la mamma si \u00e8 risposata con un altro uomo dando alla luce altri quattro figli. L&#8217;uomo ha sempre trattato bene i figli del primo marito e ha sempre contribuito alle loro spese, alla loro istruzione, cura e protezione. La mamma ha spiegato che Brian era un bravo bambino, che si dava da fare, che aiutava in casa e che era sempre pronto e rapido a far tutto, ma all\u2019et\u00e0 di 10 anni ha iniziato a comportarsi male, a tal punto che i vicini si lamentavano di lui perch\u00e8 rubava il cibo di altre persone, finch\u00e8 non \u00e8 stato pi\u00f9 volte portato alla locale stazione di polizia. Il padre lo ha punito per quel comportamento nella speranza di disciplinarlo, usando la bacchetta come spesso succede nelle famiglie in Kenya. Questo metodo educativo non ha avuto alcun risultato positivo e Brian ha continuato a rubare, finch\u00e8 nel 2017 si \u00e8 dileguato e non \u00e8 pi\u00f9 tornato a casa. La madre ha provato a cercarlo andando in diverse stazioni di polizia, arrivando fino a Nairobi dove ha vagato per due giorni per provare a trovarlo, ma senza successo.<\/p>\n<p>\u00c8 stato un momento davvero emozionate l\u2019incontro tra mamma e figlio. Lei era davvero al settimo cielo, ringraziando Dio per aver risposto alle sue preghiere e ringraziando la squadra che le ha riportato il suo ragazzo. Il patrigno non c\u2019era, ma John o, per meglio dire, Brian, gli ha lasciato un messagio in cui gli ha chiesto perdono per tutti gli errori che ha commesso promettendo sia a lui che alla madre di cambiare in meglio il suo comportamento, provando cos\u00ec a essere una persona migliore.<\/p>\n<h3>Kenya e Sostegno a Distanza: mai presentarsi a mani vuote nelle case altrui!<\/h3>\n<p>La mamma ha concesso e firmato il conseso della presa in carico legale del minore a Kwetu. E ora che sa dove si trova il figlio lo andr\u00e0 a trovare. Alla famiglia son stati donati qualche pacco di farina, riso e lenticchie: in Kenya non si va mai a mani vuote nelle case altrui. Anche perch\u00e8 \u00e8 una famiglia numerosa, i genitori vivono alla giornata, non hanno un lavoro formale, inoltre la mamma di Brian si \u00e8 trovata a prendersi cura anche della nipotina, figlia della defunta sorella, rimasta orfana e positiva all&#8217;HIV.<\/p>\n<p>Anche tu puoi contribuire al lavoro che Ai.Bi. svolge in Kenya a favore dei bambini di strada. Attivando un <a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Kenya\">Sostegno a Distanza<\/a> puoi cambiare la vita di un bimbo come John.<\/p>\n<p><a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/attivazione-adozione-a-distanza\/?scelta=25&amp;progetto=Kenya\">Pensaci.<\/a><\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\">\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342 .btnsx-text-secondary{}\n#btnsx-168342 .btnsx-icon{}\n#btnsx-168342 .btnsx-icon-img{}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:before{background-color:#eab20b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342-dropdown .menu-item a{}\n#btnsx-168342-dropdown{border-top-width:px;border-bottom-width:px;border-left-width:px;border-right-width:px;}\n#btnsx-168342-dropdown:before{border-width:8px;margin-left:-8px;border-bottom-color:}\n#btnsx-168342-dropdown:after{}\n#btnsx-168342-dropdown{}\n@media screen and (max-width: 768px) {\n#btnsx-168342 {display:inline-block;}\n#btnsx-168342 .btnsx-text-primary {}\n#btnsx-168342 .btnsx-text-secondary {}\n#btnsx-168342 .btnsx-icon {}\n#btnsx-168342 .btnsx-divider {}\n}@media screen and (max-width: 480px) {\n#btnsx-168342 {display:inline-block;}\n#btnsx-168342 .btnsx-text-primary {}\n#btnsx-168342 .btnsx-text-secondary {}\n#btnsx-168342 .btnsx-icon {}\n#btnsx-168342 .btnsx-divider {}\n}\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn  btnsx-btn-embossed\"  data-font-primary=\"Montserrat\" data-animation-type=\"\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>I grandi risultati del Sostegno a Distanza di Amici dei Bambini : la reintegrazione in famiglia dei bambini di strada In Kenya, grazie al Sostegno a Distanza, le attivit&agrave; di Ai.Bi. &ndash; Amici dei Bambini proseguono proficuamente. A beneficiarne sono bambini come John, un bambino di strada che, dopo tre [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":148615,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[306,300],"class_list":["post-176781","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-kenya","tag-sostegno-a-distanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kenya e Sostegno a Distanza: John torna a casa dopo tre anni<\/title>\n<meta name=\"description\" content=\"Kenya e Sostegno a Distanza: John torna a casa dopo tre anni. Kenya e Sostegno a Distanza, la reintegrazione famigliare di John.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kenya. John torna a casa dopo tre anni: cos\u00ec una mamma ritrova suo figlio\" \/>\n<meta property=\"og:description\" content=\"I grandi risultati del Sostegno a Distanza di Amici dei Bambini : la reintegrazione in famiglia dei bambini di strada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-02T12:48:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-28T12:26:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristianoP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Kenya. John torna a casa dopo tre anni: cos\u00ec una mamma ritrova suo figlio\" \/>\n<meta name=\"twitter:description\" content=\"I grandi risultati del Sostegno a Distanza di Amici dei Bambini : la reintegrazione in famiglia dei bambini di strada\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristianoP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\\\/\"},\"author\":{\"name\":\"cristianoP\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\"},\"headline\":\"Kenya. John torna a casa dopo tre anni: cos\u00ec una mamma ritrova suo figlio\",\"datePublished\":\"2020-07-02T12:48:02+00:00\",\"dateModified\":\"2022-07-28T12:26:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\\\/\"},\"wordCount\":800,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/maurizio-kenya_fb.jpg\",\"keywords\":[\"Kenya\",\"sostegno a distanza\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\\\/\",\"name\":\"Kenya e Sostegno a Distanza: John torna a casa dopo tre anni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/maurizio-kenya_fb.jpg\",\"datePublished\":\"2020-07-02T12:48:02+00:00\",\"dateModified\":\"2022-07-28T12:26:21+00:00\",\"description\":\"Kenya e Sostegno a Distanza: John torna a casa dopo tre anni. Kenya e Sostegno a Distanza, la reintegrazione famigliare di John.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/maurizio-kenya_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/maurizio-kenya_fb.jpg\",\"width\":1200,\"height\":630,\"caption\":\"incontro con assistenti sociali e reinserimento nella societ\u00e0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kenya. John torna a casa dopo tre anni: cos\u00ec una mamma ritrova suo figlio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/b9065848ca5b5cf9a80fad6f849d2c17\",\"name\":\"cristianoP\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cristianop\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kenya e Sostegno a Distanza: John torna a casa dopo tre anni","description":"Kenya e Sostegno a Distanza: John torna a casa dopo tre anni. Kenya e Sostegno a Distanza, la reintegrazione famigliare di John.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/","og_locale":"it_IT","og_type":"article","og_title":"Kenya. John torna a casa dopo tre anni: cos\u00ec una mamma ritrova suo figlio","og_description":"I grandi risultati del Sostegno a Distanza di Amici dei Bambini : la reintegrazione in famiglia dei bambini di strada","og_url":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-07-02T12:48:02+00:00","article_modified_time":"2022-07-28T12:26:21+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb.jpg","type":"image\/jpeg"}],"author":"cristianoP","twitter_card":"summary_large_image","twitter_title":"Kenya. John torna a casa dopo tre anni: cos\u00ec una mamma ritrova suo figlio","twitter_description":"I grandi risultati del Sostegno a Distanza di Amici dei Bambini : la reintegrazione in famiglia dei bambini di strada","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"cristianoP","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/"},"author":{"name":"cristianoP","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17"},"headline":"Kenya. John torna a casa dopo tre anni: cos\u00ec una mamma ritrova suo figlio","datePublished":"2020-07-02T12:48:02+00:00","dateModified":"2022-07-28T12:26:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/"},"wordCount":800,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb.jpg","keywords":["Kenya","sostegno a distanza"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/","url":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/","name":"Kenya e Sostegno a Distanza: John torna a casa dopo tre anni","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb.jpg","datePublished":"2020-07-02T12:48:02+00:00","dateModified":"2022-07-28T12:26:21+00:00","description":"Kenya e Sostegno a Distanza: John torna a casa dopo tre anni. Kenya e Sostegno a Distanza, la reintegrazione famigliare di John.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/maurizio-kenya_fb.jpg","width":1200,"height":630,"caption":"incontro con assistenti sociali e reinserimento nella societ\u00e0"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/kenya-john-torna-a-casa-dopo-tre-anni-cosi-una-mamma-ritrova-suo-figlio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Kenya. John torna a casa dopo tre anni: cos\u00ec una mamma ritrova suo figlio"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/b9065848ca5b5cf9a80fad6f849d2c17","name":"cristianoP","url":"https:\/\/www.aibi.it\/ita\/author\/cristianop\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 10:33:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/176781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=176781"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/176781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/148615"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=176781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=176781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=176781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}