﻿


{"id":17695,"date":"2010-12-01T16:08:16","date_gmt":"2010-12-01T15:08:16","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=17695"},"modified":"2010-12-01T16:08:16","modified_gmt":"2010-12-01T15:08:16","slug":"kenya-festa-al-centro-kwetu","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/","title":{"rendered":"Kenya: festa al centro Kwetu"},"content":{"rendered":"<p><em>La notizia queste settimana arriva da Annalisa Deiuri, una nuova volontaria di collabora con Amici dei Bambini Kenya. <\/em><\/p>\n<p><em>Chi lo avrebbe mai detto che ci potessero essere cos\u00ec tanti talenti?<\/em><\/p>\n<p><em>Il pomeriggio comincia con i soliti discorsi di rito e di ringraziamento agli insegnanti, ai sostenitori, ai presenti, e con una proiezione di immagini sulla storia di Kwetu Home of peace\u2026. Sembra la tipica recita di fine anno dei nostri bambini o fratellini\u2026.<\/em><\/p>\n<p><em>Ma quando i bambini conquistano il palco e comincia il vero spettacolo, la musica cambia. Raramente mi \u00e8 capitato di vedere tale livello e bravura in artisti cos\u00ec in erba!<\/em><\/p>\n<p><em>I primi sono il gruppo delle danze tradizionali\u2026 ritmo, forza, e un sorriso radioso nei due bambini in prima fila che guidano il gruppo. <\/em><\/p>\n<p><em>Subito segue la rappresentazione teatrale. Narra la storia di due ragazzi di strada che accusati di un piccolo furto vengono arrestati e picchiati dalla polizia. Qualcuno parte alla loro ricerca ma viene sbattuto da prigione in prigione nella compiaciuta indifferenza delle forse dell\u2019ordine che da questo racconto emergono come figure crudeli e arroganti. \u00c8 solo grazie all\u2019intervento del direttore di Kwetu che la polizia decide di rilasciare i due ragazzi. Questa brutta avventura li convince a tentare il cambiamento e entrare a Kwetu. Li trovano amici, accoglienza e occasione per esprimersi ed imparare\u2026 \u00e8 un nuovo inizio. Il pezzo \u00e8 recitato kiswahili tranne qualche breve canzone, ma anche per chi come me ha bisogno della traduzione non \u00e8 difficile capire il senso dei dialoghi tale \u00e8 l\u2019intensit\u00e0 delle espressione dei volti\u2026 e un brivido scende lungo la schiena pensando che la storia che stanno raccontando \u00e8 la loro storia.<\/em><\/p>\n<p><em>L\u2019atmosfera si fa di nuovo eccitante quando \u00e8 il turno degli acrobati e mangiafuoco\u2026 ma sono davvero bambini? Ma da quanto tempo si esercitano?<\/em><\/p>\n<p><em>L\u2019entusiasmo sale fra i bambini quando sul palco sale una band di musica rap, sono ragazzi che come loro hanno vissuto a Kwetu Home of Peace e grazie alla musica hanno trovato il loro riscatto.<\/em><\/p>\n<p><em>Elena mi dice che gli insegnati hanno cominciato le lezioni a luglio. Questo fa pensare\u2026 quanto a volte il successo nella via sia solo una questione di fortuna.. la fortuna di avere delle opportunit\u00e0. Questi sono gli stessi bambini che fino a uno o due anni fa vagavano per strade di Nairobi chiedendo qualche scellino per mangiare o scippando qualche borsello per sopravvivere.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La notizia queste settimana arriva da Annalisa Deiuri, una nuova volontaria di collabora con Amici dei Bambini Kenya. Chi lo avrebbe mai detto che ci potessero essere cos&igrave; tanti talenti? Il pomeriggio comincia con i soliti discorsi di rito e di ringraziamento agli insegnanti, ai sostenitori, ai presenti, e con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-17695","post","type-post","status-publish","format-standard","category-cooperazione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kenya: festa al centro Kwetu - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kenya: festa al centro Kwetu\" \/>\n<meta property=\"og:description\" content=\"La notizia queste settimana arriva da Annalisa Deiuri, una nuova volontaria di collabora con Amici dei Bambini Kenya. Chi lo avrebbe mai detto che ci potessero essere cos&igrave; tanti talenti? Il pomeriggio comincia con i soliti discorsi di rito e di ringraziamento agli insegnanti, ai sostenitori, ai presenti, e con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-01T15:08:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-festa-al-centro-kwetu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-festa-al-centro-kwetu\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Kenya: festa al centro Kwetu\",\"datePublished\":\"2010-12-01T15:08:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-festa-al-centro-kwetu\\\/\"},\"wordCount\":400,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-festa-al-centro-kwetu\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-festa-al-centro-kwetu\\\/\",\"name\":\"Kenya: festa al centro Kwetu - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2010-12-01T15:08:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-festa-al-centro-kwetu\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-festa-al-centro-kwetu\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-festa-al-centro-kwetu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kenya: festa al centro Kwetu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kenya: festa al centro Kwetu - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/","og_locale":"it_IT","og_type":"article","og_title":"Kenya: festa al centro Kwetu","og_description":"La notizia queste settimana arriva da Annalisa Deiuri, una nuova volontaria di collabora con Amici dei Bambini Kenya. Chi lo avrebbe mai detto che ci potessero essere cos&igrave; tanti talenti? Il pomeriggio comincia con i soliti discorsi di rito e di ringraziamento agli insegnanti, ai sostenitori, ai presenti, e con [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-12-01T15:08:16+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Kenya: festa al centro Kwetu","datePublished":"2010-12-01T15:08:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/"},"wordCount":400,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/","url":"https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/","name":"Kenya: festa al centro Kwetu - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2010-12-01T15:08:16+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/kenya-festa-al-centro-kwetu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Kenya: festa al centro Kwetu"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:15:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/17695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=17695"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/17695\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=17695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=17695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=17695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}