﻿


{"id":177299,"date":"2020-07-13T12:57:54","date_gmt":"2020-07-13T10:57:54","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=177299"},"modified":"2022-07-28T14:20:35","modified_gmt":"2022-07-28T12:20:35","slug":"kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/","title":{"rendered":"Kenya. Abbandonata con i suoi 3 figli&#8230; poi l\u2019incontro del destino"},"content":{"rendered":"<h2>La storia di Eunice, da ragazza madre a donna determinata,ora lotta per il benessere dei suoi figli: un successo grazie al <a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\">Adozione a Distanza in Kenya<\/a>.<\/h2>\n<p>Eunice si \u00e8 sposata quando aveva solo 16 anni, era incinta del suo primo figlio. Per anni ha subito maltrattamenti e abusi, sia fisici che mentali dal marito che andava e veniva come e quando voleva. Finch\u00e8 4 anni fa lui se ne and\u00f2 definitivamente, sparendo nel nulla, mai nessuna chiamata e nessuna visita per sapere come stanno i suoi 3 figli.<\/p>\n<p>Eunice \u00e8 rimasta sola con tre figli piccoli da mantenere.<\/p>\n<p>Ha iniziato il nuovo capitolo della sua vita vendendo pannocchie di mais per strada, fino a quando, per riuscire a sfamare tutti si \u00e8 sentita costretta a lavorare in un club, pur odiando quel nuovo lavoro che sapeva essere pericoloso. Per una donna sola, Nairobi non \u00e8 una citt\u00e0 sicura, infatti una notte rientrando a casa dal Club ha rischiato di essere violentata. Ha deciso di non continuare pi\u00f9 con quel lavoro ed \u00e8 tornata a vendere cibo per strada. E\u2019 stata la sua fortuna, il destino le ha fatto incontrare la direttrice della scuola Sancare e da quel giorno la sua vita \u00e8 finalmente cambiata.<\/p>\n<p>La direttrice della scuola ha capito quanto Eunice si fosse impegnata negli anni per garantire ai figli un\u2019istruzione e ha deciso di aiutarla. Tramite il programma di <strong>Adozione a Distanza di Ai.Bi,<\/strong> una delle sue figlie ha trovato dei sostenitori davvero speciali che hanno supportato la bambina e la mamma fin dal primo giorno.<\/p>\n<p>Questa giovane donna e i suoi figli si meritano davvero aiuto e amore. Nel caso di Eunice e della sua famiglia la spalla su cui appoggiarsi \u00e8 quella di un sostenitore italiano che le ha offerto l\u2019appoggio di cui aveva bisogno e che si merita.<\/p>\n<p>Il giorno in cui abbiamo consegnato il regalo da parte del sostenitore di Grace, la figlia di Eunice, la donna era felicissima, sia per aver ricevuto alimenti che le dureranno per due mesi dandole un po\u2019 di respiro e sia per aver finalmente realizzato il desiderio della figlia: un vestito e delle scarpe, da principessa!<\/p>\n<p>Grazie al sostegno e all&#8217;adozione a distanza non solo i bambini nel programma hanno accesso a un\u2019educazione di qualit\u00e0 e a tutto il materiale e all&#8217;abbigliamento necessario per frequentare la scuola, ma hanno anche accesso a una dieta sana ed equilibrata e a cure mediche.<\/p>\n<p>Alcuni bambini nel programma non vivono in istituto, ma sono supportati nelle loro case assieme al tutore o genitore biologico.<\/p>\n<p>Ai bambini e ai loro genitori fa molto piacere comunicare con i sostenitori italiani, poter scrivere lettere e messaggi di affetto e gratitudine per tutto quello che fanno per loro.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>La storia di Eunice, da ragazza madre a donna determinata,ora lotta per il benessere dei suoi figli: un successo grazie al Adozione a Distanza in Kenya. Eunice si &egrave; sposata quando aveva solo 16 anni, era incinta del suo primo figlio. Per anni ha subito maltrattamenti e abusi, sia fisici [&hellip;]<\/p>\n","protected":false},"author":96,"featured_media":177296,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[454,306,636,300],"class_list":["post-177299","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-adozione-a-distanza","tag-kenya","tag-sancare","tag-sostegno-a-distanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kenya. Abbandonata con i suoi 3 figli... poi l\u2019incontro del destino - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kenya. Abbandonata con i suoi 3 figli ..poi l\u2019incontro del destino\" \/>\n<meta property=\"og:description\" content=\"La storia di Eunice, da ragazza madre a donna determinata,ora lotta per il benessere dei suoi figli: un successo grazie al Adozione a Distanza in Kenya. Eunice si &egrave; sposata quando aveva solo 16 anni, era incinta del suo primo figlio. Per anni ha subito maltrattamenti e abusi, sia fisici [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-13T10:57:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-28T12:20:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/storia-bimba-kenya-compleanno_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maraA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Kenya. Abbandonata con i suoi 3 figli ..poi l\u2019incontro del destino\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/storia-bimba-kenya-compleanno_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"maraA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\\\/\"},\"author\":{\"name\":\"maraA\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/fadff90824724a76348891dedf691e46\"},\"headline\":\"Kenya. Abbandonata con i suoi 3 figli&#8230; poi l\u2019incontro del destino\",\"datePublished\":\"2020-07-13T10:57:54+00:00\",\"dateModified\":\"2022-07-28T12:20:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\\\/\"},\"wordCount\":477,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/07\\\/storia-bimba-kenya-compleanno_fb.jpg\",\"keywords\":[\"adozione a distanza\",\"Kenya\",\"Sancare\",\"sostegno a distanza\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\\\/\",\"name\":\"Kenya. Abbandonata con i suoi 3 figli... poi l\u2019incontro del destino - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/07\\\/storia-bimba-kenya-compleanno_fb.jpg\",\"datePublished\":\"2020-07-13T10:57:54+00:00\",\"dateModified\":\"2022-07-28T12:20:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/07\\\/storia-bimba-kenya-compleanno_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2020\\\/07\\\/storia-bimba-kenya-compleanno_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kenya. Abbandonata con i suoi 3 figli&#8230; poi l\u2019incontro del destino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/fadff90824724a76348891dedf691e46\",\"name\":\"maraA\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/maraa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kenya. Abbandonata con i suoi 3 figli... poi l\u2019incontro del destino - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/","og_locale":"it_IT","og_type":"article","og_title":"Kenya. Abbandonata con i suoi 3 figli ..poi l\u2019incontro del destino","og_description":"La storia di Eunice, da ragazza madre a donna determinata,ora lotta per il benessere dei suoi figli: un successo grazie al Adozione a Distanza in Kenya. Eunice si &egrave; sposata quando aveva solo 16 anni, era incinta del suo primo figlio. Per anni ha subito maltrattamenti e abusi, sia fisici [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-07-13T10:57:54+00:00","article_modified_time":"2022-07-28T12:20:35+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/storia-bimba-kenya-compleanno_fb.jpg","type":"image\/jpeg"}],"author":"maraA","twitter_card":"summary_large_image","twitter_title":"Kenya. Abbandonata con i suoi 3 figli ..poi l\u2019incontro del destino","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/storia-bimba-kenya-compleanno_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"maraA","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/"},"author":{"name":"maraA","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/fadff90824724a76348891dedf691e46"},"headline":"Kenya. Abbandonata con i suoi 3 figli&#8230; poi l\u2019incontro del destino","datePublished":"2020-07-13T10:57:54+00:00","dateModified":"2022-07-28T12:20:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/"},"wordCount":477,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/storia-bimba-kenya-compleanno_fb.jpg","keywords":["adozione a distanza","Kenya","Sancare","sostegno a distanza"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/","url":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/","name":"Kenya. Abbandonata con i suoi 3 figli... poi l\u2019incontro del destino - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/storia-bimba-kenya-compleanno_fb.jpg","datePublished":"2020-07-13T10:57:54+00:00","dateModified":"2022-07-28T12:20:35+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/storia-bimba-kenya-compleanno_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2020\/07\/storia-bimba-kenya-compleanno_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/kenya-abbandonata-con-i-suoi-3-figli-poi-lincontro-del-destino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Kenya. Abbandonata con i suoi 3 figli&#8230; poi l\u2019incontro del destino"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/fadff90824724a76348891dedf691e46","name":"maraA","url":"https:\/\/www.aibi.it\/ita\/author\/maraa\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 15:44:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/177299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/96"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=177299"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/177299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/177296"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=177299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=177299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=177299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}