﻿


{"id":177602,"date":"2020-07-21T13:32:02","date_gmt":"2020-07-21T11:32:02","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=177602"},"modified":"2021-06-17T16:51:01","modified_gmt":"2021-06-17T14:51:01","slug":"griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/","title":{"rendered":"Recovery fund. Griffini (Ai.Bi.) \u201cOra via alla riforma dell\u2019Adozione Internazionale&#8221;"},"content":{"rendered":"<h2><em>\u00a0<\/em><strong><em>Griffini: \u201c\u00c8 venuto il momento di\u00a0riformare anche\u00a0l\u2019Adozione Internazionale nel nostro Paese, ripartendo da dieci semplici regole<\/em><\/strong><em>: meno burocrazia, bonus alle famiglie e dal 2021 la gratuit\u00e0 delle Adozioni Internazionali\u201d.<\/em> Ecco il decalogo stilato dal presidente di Ai.Bi. per\u00a0una concreta e possibile\u00a0ripartenza.<\/h2>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-168876 aligncenter\" src=\"https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb-571x300.jpg\" alt=\"\" width=\"662\" height=\"348\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb.jpg 1200w, https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb-105x55.jpg 105w\" sizes=\"auto, (max-width: 662px) 100vw, 662px\" \/>\u00a0<\/em><\/p>\n<p>\u00c8\u00a0arrivato il momento della ripartenza. L\u2019accordo sui <strong>209 miliardi del recovery fund,<\/strong> che giungeranno in Italia\u00a0pu\u00f2 segnare una svolta per la ripresa del settore delle Adozioni Internazionali, <strong>ma occorre urgentemente una riforma.<\/strong><\/p>\n<p><strong>L\u2019Europa ci chiede di fare delle riforme per non sprecare i fondi in arrivo<\/strong> e per investirli bene, trasformando l\u2019Italia da un Paese con una natalit\u00e0 vicina allo zero ad una Nazione che investe nel futuro, nelle nuove generazioni e nei figli. In Italia, un Paese dove l\u2019Adozione Internazionale, \u00e8 stata da sempre il fiore all\u2019occhiello dell\u2019accoglienza familiare si \u00e8 passati dalle oltre 4 mila adozioni annuali del 2010 alle meno di mille del 2019 e si rischia, per il 2020, di scendere sotto quota 500. Sembra evidente quindi la necessit\u00e0 di attuare urgentemente una riforma e <strong>l\u2019Adozione Internazionale pu\u00f2 essere un\u2019ottima opportunit\u00e0 per costruire il futuro dell\u2019Italia.<\/strong><\/p>\n<p>\u201c<strong><em>Questi soldi ci sono stati dati per essere spesi bene<\/em>\u00a0\u2013 sottolinea Marco Griffini presidente di Ai.Bi. <\/strong>\u2013<em>Il nostro Paese \u00e8 ancora\u00a0oggi\u00a0secondo solo\u00a0agli Stati Uniti, nel mondo per numero di Adozioni Internazionali,\u00a0anche se, negli ultimi anni il sistema ha vissuto un momento di stallo su cui non ha giovato l\u2019emergenza sanitaria in atto<\/em>. \u2013 continua il Presidente Ai.Bi. \u2013\u00a0<em>\u00e8 ora di ripartire. <strong>L\u2019adozione internazionale pu\u00f2 essere una ottima opportunit\u00e0 per contribuire a costruire il futuro dell\u2019Italia:<\/strong> se sostenute le famiglie italiane hanno dimostrato di &#8220;sapercela fare&#8221;, non per niente l\u2019Italia \u00e8 stata sempre la prima nelle classifiche dell&#8217; Adozione Internazionale in proporzione alla sua\u00a0popolazione e seconda assoluta dopo gli Stati Uniti. Occorre per\u00f2 una urgente riforma\u201d<\/em>\u00a0.<\/p>\n<h3>Una riforma che per essere efficacie dovr\u00e0 tenere conto di <strong>10 principi fondamentali.<\/strong><\/h3>\n<ol>\n<li><strong>Sburocratizzazione del sistema <\/strong>che si ottiene con la banale applicazione della legge 476\/98, totalmente disattesa in questi ultimi anni, da servizi pubblici e Tribunali dei minorenni , per quanto riguarda l\u2019obiettivo della stessa che era fissare dei tempi certi e sicuri affinch\u00e9 la burocrazia non potesse rallentare il percorso.<\/li>\n<li>La <strong>realizzazione di un sistema di canali paralleli<\/strong> tra i servizi degli enti pubblici e quelli degli enti autorizzati, per la gestione dell\u2019attivit\u00e0 di formazione delle coppie.<\/li>\n<li><strong>L\u2019eliminazione del passaggio burocratico dell\u2019idoneit\u00e0 giudiziaria, rilasciata dal Tribunale per i minorenni,<\/strong> a beneficio di una commissione regionale che valuti il percorso di formazione compiuto dalla coppia candidata, in ci\u00f2 adeguandoci a quanto avviene, oramai da anni, in tutti gli altri paesi europei.<\/li>\n<li>L\u2019erogazione di <strong>un bonus di 10mila euro<\/strong> per tutte le coppie che abbiano compiuto un adozione nell\u2019anno in corso.<\/li>\n<li><strong>La\u00a0\u00a0completa gratuit\u00e0<\/strong> delle stesse a partire dal 2021, inserendo l\u2019Adozione Internazionale nell\u2019ambito della politica estera dell\u2019Italia. In tale ottica i fondi necessari per la gratuit\u00e0 saranno a carico del ministero degli Affari esteri, essendo l\u2019Adozione Internazionale un vero e proprio progetto di cooperazione internazionale,<\/li>\n<li><strong>Il passaggio della Commissione Adozioni Internazionali dalla Presidenza del Consiglio dei Ministri al Ministero degli Affari Esteri\u00a0<\/strong>\u00e8 poi altro punto fondamentale.<\/li>\n<li>La Commissione Adozioni Internazionali\u00a0\u00a0dovr\u00e0 essere presieduta da un <strong>ambasciatore.<\/strong><\/li>\n<li>Per ogni ambasciata italiana dovr\u00e0 essere prevista la figura di un funzionario addetto in modo esclusivo alle pratiche di adozione internazionale.<\/li>\n<li>Vanno poi elevati i requisiti per gli enti autorizzati, affinch\u00e9 sia eliminata la realt\u00e0 di enti \u201cpersonali&#8221; e favorita al massimo la <strong>creazione di consorzi fra enti, <\/strong>al fine di creare economie di sistema. Inoltre ogni ente autorizzato dovr\u00e0 poter operare in tutto il mondo purch\u00e9 venga accreditato dalle autorit\u00e0 locali dei Paesi esteri. Non dovr\u00e0 pi\u00f9 essere necessaria un\u2019autorizzazione specifica per ogni singolo Paese.<\/li>\n<li>Infine si dovr\u00e0 <strong>istituire un gruppo di lavoro parlamentare<\/strong> al fine di stabilire linee operative per arrivare all\u2019attivazione dell\u2019adozione europea mediante la quale le coppie di un singolo Paese membro potranno adottare in qualsiasi Paese europeo senza dover ricorrere alle procedure dell\u2019Adozione Internazionale. Dovr\u00e0 essere istituita a tale fine una banca dati europea dei minori dichiarati adottabili in tutti i 27 stati membri.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Griffini: &ldquo;&Egrave; venuto il momento di&nbsp;riformare anche&nbsp;l&rsquo;Adozione Internazionale nel nostro Paese, ripartendo da dieci semplici regole: meno burocrazia, bonus alle famiglie e dal 2021 la gratuit&agrave; delle Adozioni Internazionali&rdquo;. Ecco il decalogo stilato dal presidente di Ai.Bi. per&nbsp;una concreta e possibile&nbsp;ripartenza. &nbsp; &Egrave;&nbsp;arrivato il momento della ripartenza. L&rsquo;accordo sui 209 [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":168876,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347],"class_list":["post-177602","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Recovery fund. Griffini (Ai.Bi.) \u201cOra via alla riforma dell\u2019Adozione Internazionale&quot; - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Meno burocrazia, bonus alle famiglie e gratuit\u00e0 delle Adozioni Internazionali: \u00e8 venuto il momento di\u00a0riformare\u00a0l\u2019Adozione Internazionale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recovery fund. Griffini (Ai.Bi.) \u201cOra via alla riforma dell\u2019Adozione Internazionale&quot;\" \/>\n<meta property=\"og:description\" content=\"Meno burocrazia, bonus alle famiglie e gratuit\u00e0 delle Adozioni Internazionali: \u00e8 venuto il momento di\u00a0riformare\u00a0l\u2019Adozione Internazionale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-21T11:32:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-17T14:51:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Recovery fund. Griffini (Ai.Bi.) \u201cOra via alla riforma dell\u2019Adozione Internazionale&#8221;\",\"datePublished\":\"2020-07-21T11:32:02+00:00\",\"dateModified\":\"2021-06-17T14:51:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\\\/\"},\"wordCount\":707,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/marco-griffini-aibi-1_fb.jpg\",\"keywords\":[\"Adozione Internazionale\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\\\/\",\"name\":\"Recovery fund. Griffini (Ai.Bi.) \u201cOra via alla riforma dell\u2019Adozione Internazionale\\\" - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/marco-griffini-aibi-1_fb.jpg\",\"datePublished\":\"2020-07-21T11:32:02+00:00\",\"dateModified\":\"2021-06-17T14:51:01+00:00\",\"description\":\"Meno burocrazia, bonus alle famiglie e gratuit\u00e0 delle Adozioni Internazionali: \u00e8 venuto il momento di\u00a0riformare\u00a0l\u2019Adozione Internazionale\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/marco-griffini-aibi-1_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/marco-griffini-aibi-1_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recovery fund. Griffini (Ai.Bi.) \u201cOra via alla riforma dell\u2019Adozione Internazionale&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Recovery fund. Griffini (Ai.Bi.) \u201cOra via alla riforma dell\u2019Adozione Internazionale\" - Ai.Bi. Amici dei Bambini","description":"Meno burocrazia, bonus alle famiglie e gratuit\u00e0 delle Adozioni Internazionali: \u00e8 venuto il momento di\u00a0riformare\u00a0l\u2019Adozione Internazionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/","og_locale":"it_IT","og_type":"article","og_title":"Recovery fund. Griffini (Ai.Bi.) \u201cOra via alla riforma dell\u2019Adozione Internazionale\"","og_description":"Meno burocrazia, bonus alle famiglie e gratuit\u00e0 delle Adozioni Internazionali: \u00e8 venuto il momento di\u00a0riformare\u00a0l\u2019Adozione Internazionale","og_url":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2020-07-21T11:32:02+00:00","article_modified_time":"2021-06-17T14:51:01+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Recovery fund. Griffini (Ai.Bi.) \u201cOra via alla riforma dell\u2019Adozione Internazionale&#8221;","datePublished":"2020-07-21T11:32:02+00:00","dateModified":"2021-06-17T14:51:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/"},"wordCount":707,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb.jpg","keywords":["Adozione Internazionale"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/","url":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/","name":"Recovery fund. Griffini (Ai.Bi.) \u201cOra via alla riforma dell\u2019Adozione Internazionale\" - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb.jpg","datePublished":"2020-07-21T11:32:02+00:00","dateModified":"2021-06-17T14:51:01+00:00","description":"Meno burocrazia, bonus alle famiglie e gratuit\u00e0 delle Adozioni Internazionali: \u00e8 venuto il momento di\u00a0riformare\u00a0l\u2019Adozione Internazionale","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/marco-griffini-aibi-1_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/griffini-ai-bi-ora-via-alla-riforma-delladozione-internazionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Recovery fund. Griffini (Ai.Bi.) \u201cOra via alla riforma dell\u2019Adozione Internazionale&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:22:48","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/177602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=177602"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/177602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/168876"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=177602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=177602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=177602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}